{"id":9979,"date":"2019-07-22T17:22:17","date_gmt":"2019-07-22T17:22:17","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9979"},"modified":"2023-07-21T14:51:23","modified_gmt":"2023-07-21T19:51:23","slug":"botella-al-mar-24","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/botella-al-mar-24\/","title":{"rendered":"Botella al Mar"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Los hombres asesinos y agresores lo hacen por voluntad propia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Cada dos horas y media una mujer es asesinada<\/strong><\/p>\n\n\n\n<pre style=\"text-align:right\" class=\"wp-block-verse\"><strong><em>Para H\u00e9ctor<\/em><\/strong><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Martha Canseco Gonz\u00e1lez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 22 julio 2019.- Hace muchos a\u00f1os, mi\nhermana gemela estaba en los \u00faltimos a\u00f1os de la carrera de Psicolog\u00eda, aunque\nsab\u00eda que su especialidad era la Neuropsicolog\u00eda, estaba segura que alguna cosa\nm\u00e1s habr\u00eda aprendido, entonces continuamente le expresaba mis dudas sobre\ndistintos temas, que con el tiempo sabr\u00eda eran producto de mi incipiente malestar\nde g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alguna vez le pregunt\u00e9: \u00bfLos agresores est\u00e1n\nconscientes del enorme da\u00f1o f\u00edsico y emocional que le hacen a las mujeres y a\nlas ni\u00f1as cuando las violan o abusan de ellas sexualmente? Su respuesta me dej\u00f3\ncon la boca abierta: \u00a1Si no fuera as\u00ed, no lo har\u00edan!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He de confesar que para m\u00ed fue un tremendo golpe\ncultural, darme cuenta que algunos hombres en M\u00e9xico, por desgracia demasiados,\nno nos quieren a las mujeres en el planeta tierra y buscan hacernos el mayor\nda\u00f1o posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que quiero resaltar aqu\u00ed, es que los hombres asesinos\ny agresores lo hacen por voluntad propia, buscan justificarse arguyendo celos,\nalcohol, enga\u00f1o o drogas, as\u00ed entonces y en buena parte, terminaremos con la\nviolencia de g\u00e9nero cuando ellos decidan dejar de violentarnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico es ya el pa\u00eds con mayor n\u00famero de\nfeminicidios en el mundo, tan s\u00f3lo en lo que va del a\u00f1o, mil 119 mexicanas han\nsido asesinadas, as\u00ed de f\u00e1cil cada dos horas y media una mujer es asesinada a\nmanos de qui\u00e9n prometi\u00f3 en un altar quererla y cuidarla, o de hombres cercanos\ny conocidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dec\u00eda mi querida amiga Nora Sosa cuando fue\nDirectora de la UEPAVF (Unidad Especializada para la Atenci\u00f3n de la Violencia\nde G\u00e9nero y en la Familia): \u201cNo hemos ni siquiera empezado a enfrentar una\nviolencia, cuando a los machistas ya se les ocurri\u00f3 otra\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y como comunic\u00f3loga tengo que reconocer el papel que\njuegan los medios de comunicaci\u00f3n para fomentar la violencia contra las mujeres\ny no s\u00f3lo porque los medios son la caja de resonancia de los roles y los\nestereotipos de g\u00e9nero sino porque los recrean, los exageran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dice la antrop\u00f3loga feminista Rita Segato que no es\ncasualidad que en los principales centros de producci\u00f3n cinematogr\u00e1fica y\ntelevisiva del planeta se est\u00e9n produciendo tantos programas y pel\u00edculas de\ncorte policiaco e investigaci\u00f3n, donde generalmente las v\u00edctimas son mujeres.\nSe trata dice, Segato de una pedagog\u00eda de la crueldad, ense\u00f1an cu\u00e1l es la\nmanera m\u00e1s cruel de acabar con las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y aunado a \u00e9sta, ya de por s\u00ed, terrible situaci\u00f3n\nhay que agregar los vaivenes y la simulaci\u00f3n del sistema de justicia mexicano,\nque termina dejando a la mayor\u00eda de las mujeres en total indefensi\u00f3n y sin\nacceso a la justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e9ste marco quiero comentar algunos detalles de la\ncolumna de H\u00e9ctor De Maule\u00f3n que escribi\u00f3 para El Universal el pasado 17 de julio\ny que titul\u00f3 \u201cMatar mujeres: la epidemia sin control\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una epidemia es una enfermedad que se propaga\ndurante un cierto per\u00edodo de tiempo en una zona geogr\u00e1fica determinada y que\nafecta de manera simult\u00e1nea a cualquier persona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El femigenocidio que se est\u00e1 llevando a cabo en\nM\u00e9xico no es una enfermedad, los hombres que lo llevan a cabo, no est\u00e1n\nenfermos, son hijos sanos del machismo m\u00e1s cerril, primitivo y aldeano. Decir\nque es una epidemia es quitar responsabilidad a los asesinos de mujeres. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El exterminio de mexicanas no est\u00e1 ocurriendo en una\nzona determinada del pa\u00eds, es en general en todo el territorio, ciertos estados\npresentan m\u00e1s casos que otros, pero esto s\u00f3lo resulta anecd\u00f3tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una epidemia afecta por igual a hombres que a\nmujeres, en \u00e9ste caso s\u00f3lo son mujeres las v\u00edctimas, as\u00ed que H\u00e9ctor hay que\nnombrar a las cosas por su nombre: En M\u00e9xico hay una guerra contra las mujeres,\npura violencia de g\u00e9nero. Seguramente como t\u00fa sabes, la violencia de g\u00e9nero es\naquella dirigida, orientada y exclusiva contra mujeres y ni\u00f1as, por el mero\nhecho de ser mujeres y ni\u00f1as, no hay ninguna otra raz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la violencia de g\u00e9nero cumple un objetivo\nsocial: CONTROLAR Y DOMINAR A LAS MUJERES.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed entonces H\u00e9ctor, se debe declarar una emergencia\nnacional si no queremos que ocurra lo que en China, en \u00e9se pa\u00eds asi\u00e1tico hay un\nd\u00e9ficit de mujeres debido a los abortos selectivos, es decir no dejaron nacer a\nmillones de mujeres. Aqu\u00ed en M\u00e9xico nos dejan nacer, pero no nos dejan vivir,\n\u00a1yo no s\u00e9 qu\u00e9 es peor!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">botellalmar2017@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hombres asesinos y agresores lo hacen por voluntad propia<\/p>\n","protected":false},"author":3,"featured_media":9095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,98,84],"tags":[],"class_list":["post-9979","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-botella-al-mar","category-martha-canseco"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9979"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9095"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}