{"id":99305,"date":"2025-10-08T11:38:45","date_gmt":"2025-10-08T17:38:45","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=99305"},"modified":"2025-10-08T11:38:46","modified_gmt":"2025-10-08T17:38:46","slug":"los-capitales-las-estafas-ciberneticas-han-afectado-a-mas-de-la-mitad-de-la-poblacion-mundial","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-las-estafas-ciberneticas-han-afectado-a-mas-de-la-mitad-de-la-poblacion-mundial\/","title":{"rendered":"Los capitales | Las estafas cibern\u00e9ticas han afectado a m\u00e1s de la mitad de la poblaci\u00f3n mundial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar\u00a0 Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 8 de octubre, 2025.-\u00a0Global Anti-Scam Alliance (GASA), en colaboraci\u00f3n con Feedzai, analizaron la problem\u00e1tica, que dio paso al informe \u00abGlobal State of Scams 2025\u00bb (Estado mundial de las estafas en 2025). Basado en una encuesta realizada a 46.000 personas en 42 mercados: el informe ofrece un an\u00e1lisis exhaustivo de la prevalencia, el impacto y los retos pol\u00edticos de las estafas en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos 12 meses, el 57% de las personas de todo el mundo sufri\u00f3 alguna estafa y el 23% perdi\u00f3 dinero. Las estafas relacionadas con compras afectaron al 54% de las v\u00edctimas, mientras que las estafas relacionadas con inversiones y las estafas relacionadas con dinero inesperado afectaron al 48% en cada caso. Las estafas fueron m\u00e1s frecuentes en Sudam\u00e9rica, \u00c1frica y Ocean\u00eda, donde hasta uno de cada cuatro personas perdi\u00f3 dinero en el \u00faltimo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n tambi\u00e9n destaca el impacto emocional de las estafas. El 69% de las v\u00edctimas declar\u00f3 haber sufrido estr\u00e9s como consecuencia de ellas, mientras que el 17% declar\u00f3 haber perdido la confianza y el 14% afirm\u00f3 que las estafas hab\u00edan creado una mayor tensi\u00f3n dentro de su unidad familiar. A pesar de ello, muchas estafas siguen sin denunciarse, siendo la incertidumbre sobre d\u00f3nde denunciarlas la principal barrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 93 % de las personas de todo el mundo afirma tomar al menos una medida para verificar si una oferta es leg\u00edtima o no. Sin embargo, muchos suelen recurrir a m\u00e9todos menos eficaces, como comprobar si hay errores ortogr\u00e1ficos y gramaticales (27%), buscar opiniones en el mismo sitio web (24%) y comprobar si la empresa est\u00e1 presente en las redes sociales (21%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que casi tres cuartas partes de los adultos de todo el mundo se sienten seguros de su capacidad para reconocer una estafa, estas siguen siendo frecuentes, y muchas v\u00edctimas pierden dinero y una proporci\u00f3n significativa nunca denuncia lo sucedido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abraham, director general de GASA, comenta: \u00abNos enfrentamos a un gran reto: el 73% de las personas en todo el mundo se sienten seguras de poder reconocer las estafas, sin embargo, casi una cuarta parte sigui\u00f3 perdiendo dinero durante el a\u00f1o pasado. Las estafas no solo agotan las finanzas, sino que tambi\u00e9n erosionan la confianza y crean un estr\u00e9s significativo dentro de las familias. Estamos aprendiendo que las campa\u00f1as de concienciaci\u00f3n sobre las estafas por s\u00ed solas no son suficientes. Necesitamos educar continuamente a los consumidores, crear mejores soluciones para reconocer y bloquear las estafas (IA) y colaborar m\u00e1s estrechamente a nivel internacional para atrapar a los estafadores\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl fraude ya no se limita a las transacciones. Se trata de la intenci\u00f3n. Los delincuentes se aprovechan de la confianza, el comportamiento y la tecnolog\u00eda en tiempo real. Para detenerlos no basta con detectar anomal\u00edas, sino que es necesario comprender los patrones humanos. Ning\u00fan banco ni proveedor de pagos puede hacerlo por s\u00ed solo. La \u00fanica forma de avanzar es la colaboraci\u00f3n entre las instituciones financieras y los equipos de ciberseguridad. As\u00ed es como protegemos a los consumidores en todo el mundo\u00bb, a\u00f1ade Nuno Sebasti\u00e3o, director ejecutivo de Feedzai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El informe Global State of Scams 2025 destaca que las estafas ya no son delitos aislados, sino una amenaza global para la seguridad de los consumidores, la estabilidad financiera y la confianza en las econom\u00edas digitales. GASA y Feedzai piden una mayor colaboraci\u00f3n internacional, mejores herramientas de prevenci\u00f3n de estafas y responsabilidad por parte de las plataformas, los gobiernos y las industrias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" rel=\"noreferrer noopener\" target=\"_blank\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">twiter: @ Edgar4712<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar\u00a0 Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico, 8 de octubre, 2025.-\u00a0Global Anti-Scam Alliance (GASA), en colaboraci\u00f3n con Feedzai, analizaron la problem\u00e1tica, que dio paso al informe \u00abGlobal State of Scams 2025\u00bb (Estado mundial de las estafas en 2025). Basado en una encuesta realizada a 46.000 personas en 42 mercados: el informe ofrece un an\u00e1lisis exhaustivo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[750,35],"tags":[],"class_list":["post-99305","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/99305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=99305"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/99305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=99305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=99305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=99305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}