{"id":99077,"date":"2025-09-29T20:53:34","date_gmt":"2025-09-30T02:53:34","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=99077"},"modified":"2025-09-29T20:54:53","modified_gmt":"2025-09-30T02:54:53","slug":"palabra-de-antigona-teresa-ulloa-ziaurritz-contra-la-esclavitud-moderna","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/palabra-de-antigona-teresa-ulloa-ziaurritz-contra-la-esclavitud-moderna\/","title":{"rendered":"Palabra de Ant\u00edgona| Teresa Ulloa Zia\u00farritz: contra la esclavitud \u201cmoderna\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sara Lovera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 29 de septiembre, 2025.- La imagino al otro lado del tel\u00e9fono, habl\u00e1ndome y recrimin\u00e1ndome, indignada, me dir\u00eda, desesperada: \u00bfc\u00f3mo es posible la indiferencia frente a algo tan inhumano? No entiendo el silencio y el ocultamiento. De nada sirve hablar tanto de derechos humanos, igualdad y justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teresa Ulloa Zia\u00farritz muri\u00f3 la tarde-noche del 28 de septiembre. Conocedora del horrendo asunto del uso y abuso de nuestros cuerpos, formada a ras de tierra, litig\u00f3 25 mil casos de violencia feminicida. Supo y conoci\u00f3 todo lo que saben las autoridades, particip\u00f3 en diagn\u00f3sticos que servir\u00edan para pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00edtica y testaruda, pensaba que leyes y tratados estaban prendidos de alfileres. Interpel\u00f3 sin recato a las autoridades, conscientes y responsables de la violencia contra las mujeres. La recuerdo sonre\u00edr burlonamente al hablar de c\u00f3mo se hacen las cuentas de las desapariciones, convertidas en estad\u00edsticas manipuladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su trabajo fue global y particular. Siempre estuvo en riesgo porque sus denuncias atentaban contra un negocio mundial que, solo en prostituci\u00f3n, afecta a 50 millones de personas y produce ganancias de m\u00e1s de 236 mil millones de d\u00f3lares cada a\u00f1o, seg\u00fan Naciones Unidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue una activista contumaz: investig\u00f3, organiz\u00f3 personas, se propuso hacer conciencia. Durante m\u00e1s de 30 a\u00f1os gestion\u00f3 ante la opini\u00f3n p\u00fablica y los tomadores de decisiones acciones para frenar el comercio del cuerpo femenino. Se opuso a la superficialidad y al cinismo que justifican la pr\u00e1ctica de la prostituci\u00f3n en todas las \u201cdemocracias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luch\u00f3 contra lo que eufem\u00edsticamente se llama esclavitud \u201cmoderna\u201d, expresada en la regulaci\u00f3n del trabajo forzado, la prostituci\u00f3n y la venta de vientres de alquiler, pr\u00e1cticas enarboladas por algunas corrientes \u201cfeministas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abogada, pedagoga, dirigente sindical y egresada de El Colegio de M\u00e9xico, se adentr\u00f3 en la condici\u00f3n femenina. Estudi\u00f3, litig\u00f3 en las barandillas del Ministerio P\u00fablico, organiz\u00f3 a las mujeres y puso en pr\u00e1ctica los primeros grupos de defensoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca ocup\u00f3 un cargo p\u00fablico. Su energ\u00eda fue envidiable hasta sus 75 a\u00f1os. Colabor\u00f3 y particip\u00f3 en cientos de reuniones, congresos y discusiones sobre la defensa de las agendas feministas. Su tarea fue defender el cuerpo esclavizado de las mujeres en un patriarcado que desde\u00f1a a la mitad de la poblaci\u00f3n. Su muerte ya gener\u00f3 reacciones doloridas de decenas de grupos y personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De car\u00e1cter fuerte, de habla directa, provoc\u00f3 reacciones muy diversas entre el gremio de la abogac\u00eda y el feminismo. Supongo que, por poco \u201ccomedida\u201d, no fue invitada a las mesas del poder y los partidos pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deteriorada en su salud por la emoci\u00f3n y la angustia, atendi\u00f3 los peque\u00f1os y grandes asuntos: desde la tortura de una trabajadora a manos de su marido hasta las denuncias colectivas. Dialog\u00f3 con las autoridades, elabor\u00f3 propuestas y estudios, sin buscar simpat\u00edas. Con firmeza defendi\u00f3 sus hallazgos, reflexiones y puntos de vista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 recordada por su feminismo, sus posturas controvertidas y su convicci\u00f3n inalterable de que las mujeres en condici\u00f3n de prostituci\u00f3n viven la peor de las violencias de g\u00e9nero. Tambi\u00e9n por sostener que es inadmisible regular los vientres de alquiler. Encarna la frase: \u201cnuestro cuerpo no es una mercanc\u00eda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De biograf\u00eda extensa, baste decir que dio procedimiento a las 16 Unidades de Prevenci\u00f3n y Atenci\u00f3n de la Violencia Familiar en la Ciudad de M\u00e9xico \u2014ya desaparecidas\u2014; fue coautora del estudio Violaci\u00f3n y violencia sexual como cr\u00edmenes de guerra y de lesa humanidad; colaboradora en el libro La Corte Penal Internacional: Una visi\u00f3n iberoamericana, adem\u00e1s de cientos de art\u00edculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maestra en Ciencias de la Educaci\u00f3n por la Universidad de Londres, diplomada en Bruselas en \u201cLos Derechos Humanos de las Mujeres y el Desarrollo\u201d y en la Sorbona de Par\u00eds en \u201cG\u00e9nero y Derecho\u201d y \u201cDerecho Internacional Humanitario\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con todo lo que vendr\u00e1 de homenajes, biograf\u00edas y opiniones, ya es un acicate para las feministas que luchan contra la violencia feminicida y la impunidad. Veremos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Periodista. Editora de G\u00e9nero en la OEM y directora del portal informativo semmexico.mx<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sara Lovera SemM\u00e9xico, Cd. de M\u00e9xico, 29 de septiembre, 2025.- La imagino al otro lado del tel\u00e9fono, habl\u00e1ndome y recrimin\u00e1ndome, indignada, me dir\u00eda, desesperada: \u00bfc\u00f3mo es posible la indiferencia frente a algo tan inhumano? No entiendo el silencio y el ocultamiento. De nada sirve hablar tanto de derechos humanos, igualdad y justicia. Teresa Ulloa Zia\u00farritz [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,95,69],"tags":[],"class_list":["post-99077","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-palabra-de-antigona","category-sara-lovera"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/99077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=99077"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/99077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/70950"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=99077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=99077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=99077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}