{"id":98950,"date":"2025-09-25T16:43:14","date_gmt":"2025-09-25T22:43:14","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=98950"},"modified":"2025-09-25T16:43:15","modified_gmt":"2025-09-25T22:43:15","slug":"tras-la-puerta-del-poder-que-siempre-si-habra-consulta-publica-sobre-la-reforma-del-amparo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-que-siempre-si-habra-consulta-publica-sobre-la-reforma-del-amparo\/","title":{"rendered":"Tras la puerta del poder| Que siempre s\u00ed habr\u00e1 consulta p\u00fablica sobre la reforma del amparo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Roberto Vizca\u00edno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 25 de septiembre, 2025.- Estos ejercicios de consulta p\u00fablica se realizar\u00e1n rapidito, apresuradamente en el Senado y los primeros que participen ser\u00e1n escuchados ma\u00f1ana viernes y los segundos, y \u00faltimos, el lunes, y sin la garant\u00eda de que sirvan para algo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con&nbsp;<strong>Ad\u00e1n Augusto L\u00f3pez<\/strong>, coordinador de la mayor\u00eda de Morena y presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica -quien muy a rega\u00f1adientes y reticencias-, esta apertura de \u00faltima hora a escuchar a interesados y representantes de sectores y barras de abogados, investigadores de jur\u00eddicas y acad\u00e9micos, s\u00f3lo es un ejercicio para escuchar no para modificar o revertir la iniciativa de reforma al amparo propuesto por la presidenta&nbsp;<strong>Claudia Sheinbaum<\/strong>. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026 no es&nbsp;<strong>parlamento abierto<\/strong>,&nbsp;<strong>no es conversatorio<\/strong>, es en un formato distinto\u201d aclar\u00f3 el senador L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al preguntarle si ese ejercicio podr\u00eda derivar en alg\u00fan cambio, modificaci\u00f3n, agregado del proyecto, agreg\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2026 desde mi punto de vista, creo que no requiere ninguna modificaci\u00f3n de fondo ni de forma\u2026 pero hay que escuchar las opiniones, y hay que esperar la decisi\u00f3n de quienes integran las comisiones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comisiones que \u00e9l sabe bien tienen mayor\u00eda de senadores de Morena, PT y Verde y cuyo dictamen deber\u00e1 luego ser votado por el Pleno que igual tiene mayor\u00eda para realizar reformas constitucionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En este contexto la invitaci\u00f3n a estas audiencias dijo, ser\u00e1 abierta. Para que participen acad\u00e9micos, organizaciones civiles, barras y colegios de abogados, entre otros a fin de que los senadores que integran las comisiones dictaminadoras escuchen opiniones ciudadanas y luego tomen sus decisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Senado, quien desde un inicio rechaz\u00f3 la propuesta del expanista y neomorenista&nbsp;<strong>Javier Corral<\/strong>, presidente de la Comisi\u00f3n de Justicia, quien ped\u00eda ir a un&nbsp;ejercicio de parlamento abierto, termin\u00f3 por dar el paso a una consulta no vinculatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodas las iniciativas son perfectibles\u2026 (pero) desde mi punto de vista,&nbsp;<em>creo que no requiere ninguna modificaci\u00f3n de fondo ni de forma<\/em>, pero hay que escuchar las opiniones y hay que esperar la decisi\u00f3n de quienes integran las comisiones\u201d, acept\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez cumplido este ejercicio, aclar\u00f3, se continuar\u00e1 con el proyecto de que la iniciativa presentada por la presidenta&nbsp;<strong>Claudia Sheinbaum<\/strong>&nbsp;<em>se desahogue la pr\u00f3xima semana<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de que el lunes se escuche a los segundos ponentes, el martes 30 de septiembre, las comisiones unidas de Justicia, de Hacienda y Cr\u00e9dito P\u00fablico, y de Estudios Legislativos estar\u00edan en posibilidad de dictaminar el asunto para que el mi\u00e9rcoles o jueves el dictamen pase al Pleno del Senado y se apruebe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nada pues cambia de la idea original de sacar adelante esta reforma al amparo lo m\u00e1s r\u00e1pido posible para que la nueva Suprema Corte&nbsp;<em>ajusticie<\/em>&nbsp;en&nbsp;<em>fast-track<\/em>&nbsp;a quienes deben impuestos, como por ejemplo&nbsp;<strong>Ricardo Salinas Pliego,<\/strong>&nbsp;ese empresario que se ha convertido en un dolor de muelas para el expresidente&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>&nbsp;y la presidenta&nbsp;<strong>Claudia Sheinbaum<\/strong>, y algunos otros concesionarios de radio y TV o medios informativos digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LA PRESIDENTA SHEINBAUM EN UN JARDIN PLAGADO DE CONFLICTOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los problemas le brotan a la presidenta&nbsp;<strong>Sheinbaum<\/strong>&nbsp;todos los d\u00edas y en todos los niveles y espacios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1les los m\u00e1s importantes o graves?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso lo calificar\u00e1n quienes los sufren y enfrentan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hoy lo del asesinato de dos j\u00f3venes colombianos -un m\u00fasico y un DJ- podr\u00eda asumirse como un asunto de Estado al ser debatido p\u00fablica e internacionalmente por ella y por el presidente de Colombia&nbsp;<strong>Gustavo Petro<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro es el reclamo del pago de viejas deudas multimillonarias a proveedores en Pemex y a farmac\u00e9uticas que tienen parado el abasto urgente de medicinas reclamadas por amplios sectores de la poblaci\u00f3n derechohabiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno m\u00e1s grave y profundo es el del proceso abierto por la mayor red delincuencial alrededor del robo y distribuci\u00f3n de gasolinas que hoy no solo ha da\u00f1ado a la c\u00fapula de la marina, sino que amenaza con avanzar hasta el mismo expresidente&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>&nbsp;y sus hijos, y la red de gasolineras en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al parejo corre sin que disminuya nada el caso del cartel de La Barredora, donde muchos exigen ir a fondo en las investigaciones sobre la relaci\u00f3n delincuencial entre el l\u00edder de ese grupo el exsecretario de Seguridad de Tabasco,&nbsp;<strong>Hern\u00e1n Berm\u00fadez Requena<\/strong>&nbsp;-ya en el penal del altiplano- y su exjefe el exgobernador&nbsp;<strong>Ad\u00e1n Augusto L\u00f3pez<\/strong>&nbsp;hoy l\u00edder de la mayor\u00eda de Morena en el Senado. Este caso le ha significado al gobierno de&nbsp;<strong>Sheinbaum<\/strong>&nbsp;un gran deterioro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este mismo contexto se&nbsp;<strong>incuba una efervescencia opositora<\/strong>&nbsp;-que se manifiesta con el surgimiento de grupos diversos que llaman a la poblaci\u00f3n a unirse, como es el caso del propio due\u00f1o de Electra, Banco Azteca y TV Azteca&nbsp;<strong>Ricardo Salinas<\/strong>&nbsp;(quien ya se autodestap\u00f3 como posible prospecto a la presidencial de 2030); la alcaldesa de Cuauht\u00e9moc&nbsp;<strong>Alessandra Rojo de la Vega<\/strong>&nbsp;con su incipiente movimiento por la Resistencia; &nbsp;el exgobernador de Oaxaca y exoperador electoral del PRI Ulises Ruiz con su movimiento de M\u00e9xico Nuevo y el del experredista&nbsp;<strong>Guadalupe Acosta Naranjo-, que son apenas algunos de muchos otros que brotan por todo el pa\u00eds y que con seguridad terminar\u00e1n por unirse en un solo nuevo frente nacional antes de las elecciones de 2027 para enfrentar a la alianza oficialista Morena, PT y Verde que quiz\u00e1 no llegue ya unida a ese proceso intermedio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Y como si fuese todo eso poco, la presidenta Sheinbaum le entra a nuevos pleitos como el que abri\u00f3 ayer contra el embajador de EU en M\u00e9xico, Ron Johnson<\/strong>, a quien se le hizo f\u00e1cil decir que su gobierno ve\u00eda que la mandataria hab\u00eda hecho ya un \u00ab<em>cambio audaz<\/em>\u00bb en la estrategia contra los c\u00e1rteles de la droga. Sheinbaum sali\u00f3 de inmediato a decir que no aceptaba tal cosa, porque eso era aceptar que el gobierno de&nbsp;<strong>Donald Trump<\/strong>&nbsp;la estaba distanciando de su antecesor&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>&nbsp;y, como en la canci\u00f3n, ella y \u00e9l expresidente son la misma cosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1UPS!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twitter: @_Vizcaino \/ Facebook<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Roberto Vizca\u00edno SemM\u00e9xico, Ciudad de M\u00e9xico, 25 de septiembre, 2025.- Estos ejercicios de consulta p\u00fablica se realizar\u00e1n rapidito, apresuradamente en el Senado y los primeros que participen ser\u00e1n escuchados ma\u00f1ana viernes y los segundos, y \u00faltimos, el lunes, y sin la garant\u00eda de que sirvan para algo De acuerdo con&nbsp;Ad\u00e1n Augusto L\u00f3pez, coordinador de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-98950","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/98950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=98950"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/98950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=98950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=98950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=98950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}