{"id":9842,"date":"2019-07-18T16:59:42","date_gmt":"2019-07-18T16:59:42","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9842"},"modified":"2023-07-21T14:50:40","modified_gmt":"2023-07-21T19:50:40","slug":"guerrero-2","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/guerrero-2\/","title":{"rendered":"Sin presupuesto programas dirigidos a mujeres del campo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* Reacomodos de pol\u00edticas p\u00fablicas federales afectan a las guerrerenses<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Gobierno estatal no ha determinado si seguir\u00e1n operando algunos programas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Josefina Aguilar Pastor<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Chilpancingo,\nGro., 18 julio 2019.- Cambios y reacomodos de las pol\u00edticas p\u00fablicas del nuevo\ngobierno federal, mantienen en espera programas dirigidos a mujeres que\ntrabajan en el campo, algunos incluso han desaparecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00e1s de un a\u00f1o de\nla \u00faltima reuni\u00f3n -13 de julio de 2018-, este mi\u00e9rcoles, volvi\u00f3 a sesionar la\nComisi\u00f3n de la Mujer Rural, que encabeza la Secretar\u00eda de Agricultura,\nGanader\u00eda, Pesca, y Desarrollo Rural del Estado de Guerrero (Sagadegro), la\ncual est\u00e1 conformada por ocho representantes de igual n\u00famero de dependencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al compartir sus\npropuestas de trabajo, Susana Nava Ocampo, representante de la Sagadegro, dio a\nconocer que, con las pol\u00edticas p\u00fablicas implementadas por el nuevo gobierno\nfederal, hay un reacomodo en dicha dependencia estatal, no solo del personal,\nsino del presupuesto, pero sobre todo de los programas federales, que ya no son\noperados por esa oficina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a este\nreacomodo que inici\u00f3 desde el mes de diciembre, no cuentan con la aprobaci\u00f3n de\nun presupuesto de egresos e ingresos como ocurr\u00eda en a\u00f1os anteriores, no hay\naprobaci\u00f3n de programas, operan solo algunos de concurrencia; el gobierno del\nEstado a\u00fan no ha determinado si podr\u00e1n seguir operando debido a la\ninsuficiencia presupuestal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos en <em>standby<\/em> en muchas cosas, hay cierres\ntotales de programas que se ven\u00edan operando desde hace muchos a\u00f1os\u201d, expuso la\ntambi\u00e9n titular de la unidad de g\u00e9nero de la Sagadegro.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo al orden\ndel d\u00eda, las representantes institucionales, tendr\u00edan que llevar sus propuestas\nde trabajo, de los cuales solo de la Secretaria de la Mujer (Semujer), de\nAsuntos Ind\u00edgenas y Comunidades Afromexicanas (Saica) y del Trabajo y Previsi\u00f3n\nSocial (STyPS), dieron a conocer acciones que han venido realizando, dos m\u00e1s\ndijeron desconocer que deb\u00edan presentar dichos proyectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los acuerdos,\ntomados al interior de esta comisi\u00f3n, se encuentra la calendarizaci\u00f3n de la\npr\u00f3xima sesi\u00f3n, el 8 agosto, en la que socializaran las propuestas de trabajo,\nde cada una de las dependencias que conforman esta delegaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/jap\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reacomodos de pol\u00edticas p\u00fablicas federales afectan a las guerrerenses<\/p>\n","protected":false},"author":3,"featured_media":9843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,51],"tags":[],"class_list":["post-9842","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9842"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9843"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}