{"id":98289,"date":"2025-09-01T17:58:29","date_gmt":"2025-09-01T23:58:29","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=98289"},"modified":"2025-09-01T17:58:47","modified_gmt":"2025-09-01T23:58:47","slug":"advierten-por-falsos-cirujanos-plasticos-en-nuevo-leon-problema-denunciado-hace-5-anos-donde-las-jovenes-al-cambiar-su-apariencia-viven-violencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/advierten-por-falsos-cirujanos-plasticos-en-nuevo-leon-problema-denunciado-hace-5-anos-donde-las-jovenes-al-cambiar-su-apariencia-viven-violencia\/","title":{"rendered":"Advierten por falsos cirujanos pl\u00e1sticos \u00a0en Nuevo Le\u00f3n problema denunciado hace 5 a\u00f1os, donde\u00a0 las \u00a0j\u00f3venes al \u00a0cambiar su apariencia\u00a0 viven violencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ilustraci\u00f3n: Liliana Pedraza<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con datos del CCPERNL, al menos cinco de cada 10 procedimientos est\u00e9ticos en Nuevo Le\u00f3n los hacen quienes no son especialistas y hay \u201cseudocl\u00ednicas\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades desde 2018 sab\u00edan, ten\u00edan denuncias y diagn\u00f3stico y no hicieron nada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Libertad L\u00f3pez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 1\u00ba. de septiembre, 2025.- La muerte de una joven de 25 a\u00f1os tras una cirug\u00eda pl\u00e1stica en Monterrey, abri\u00f3 una realidad que pone en riesgo la vida de muchas mueres, un asunto &nbsp;ligado a un mal entendimiento de belleza femenina, a una &nbsp;idea de control &nbsp;e identidad femenina falsos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Nuevo Le\u00f3n,&nbsp;Morras feministas de Monterrey se\u00f1alaron que&nbsp; las cirug\u00edas est\u00e9ticas son &nbsp;una forma de violencia simb\u00f3lica que perpet\u00faa la cosificaci\u00f3n y los mandatos de belleza sobre las mujeres.&nbsp;Es violencia simb\u00f3lica, dijeron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata ahora, dicen autoridades, de crear ley par un &nbsp;nuevo crimen contra las mujeres. Los hechos, reiterados,&nbsp; por la muerte de esa joven el 12 de agosto, a&nbsp; dos semanas desat\u00f3 &nbsp;informaci\u00f3n reveladora, puesto que estas pr\u00e1cticas no s\u00f3lo suceden en Nuevo Le\u00f3n, y &nbsp;el peligro est\u00e1 latente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente en agosto &nbsp;oficialmente se habla de &nbsp;acci\u00f3n de las autoridades, a pesar que desde 2021 se conocieron de casos en Nuevo Le\u00f3n, ahora cerraron 10 cl\u00ednicas entre el 19 y 25 de agosto pasado, COFERPIS anuncia an\u00e1lisis de irregularidades, despu\u00e9s de 5 a\u00f1os de las primeras denuncias, as\u00ed como informaci\u00f3n p\u00fablica que dice que M\u00e9xico est\u00e1 en cuarto lugar en acciones o cirug\u00edas de este tipo, sin control sanitario;&nbsp; organizaciones internacionales ya advierten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-02.jpg\" alt=\"\" class=\"wp-image-98293\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-02.jpg 225w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-02-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo cierto es que en Nuevo Le\u00f3n, 50% de las cirug\u00edas est\u00e9ticas&nbsp;que se realizan pasan por manos de&nbsp;m\u00e9dicos sin certificaci\u00f3n&nbsp;ni&nbsp;especialidad, poniendo en&nbsp;riesgo de muerte&nbsp;a los&nbsp;pacientes, como fue el caso de la joven&nbsp;Jaqueline Yamileth Briones Torres, quien perdi\u00f3 la vida durante una&nbsp;liposucci\u00f3n&nbsp;en&nbsp;Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datos del&nbsp;Colegio de Cirug\u00eda Pl\u00e1stica, Est\u00e9tica y Reconstructiva&nbsp;de Nuevo Le\u00f3n (CCPERNL) indican que, en la entidad, al menos cinco de cada 10&nbsp;procedimientos est\u00e9ticos&nbsp;se realizan por m\u00e9dicos generales que se ostentan como especialistas o bien en&nbsp;seudocl\u00ednicas, seg\u00fan investigaciones period\u00edsticas, nadie se ocup\u00f3 de las denuncias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Colectivos feministas advierten que&nbsp; estos abusos se fundan&nbsp; en una cultura de la belleza construida por una visi\u00f3n de control patriarcal, ligado a la desvaloraci\u00f3n de las mujeres, no como humanas, sino como objetos sexuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente del&nbsp;CCPERNL, el doctor&nbsp;Jorge Alfredo Reyna Flores, se\u00f1al\u00f3 que la&nbsp;pr\u00e1ctica irregular&nbsp;tambi\u00e9n se realiza por personas que no cuentan ni con una&nbsp;c\u00e9dula&nbsp;de&nbsp;M\u00e9dico Cirujano Partero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSon tratados por m\u00e9dicos o no m\u00e9dicos, incluso que no tienen el entrenamiento de las t\u00e9cnicas, de la medicina y cirug\u00eda para poder ofrecer seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA veces no pasa nada porque el cuerpo es fuerte y resiste los golpes, pero cuando la agresi\u00f3n es muy grande, pues no le queda de otra al cuerpo m\u00e1s que tronar y morir\u201d, coment\u00f3 el cirujano pl\u00e1stico, est\u00e9tico y reconstructivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reyna Flores&nbsp;inform\u00f3 que, en los \u00faltimos cuatro a\u00f1os, en Nuevo Le\u00f3n se han registrado al menos cinco&nbsp;muertes confirmadas&nbsp;de pacientes que se realizaron una&nbsp;cirug\u00eda est\u00e9tica irregular.&nbsp;Mencion\u00f3 que la cirug\u00eda m\u00e1s demandada es la liposucci\u00f3n en todos los grupos de edad, en un segundo lugar, el&nbsp;<strong>aumento de busto<\/strong>, despu\u00e9s el&nbsp;<strong>rejuvenecimiento facial&nbsp;<\/strong>y la&nbsp;<strong>rinoplastia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que dichos procedimientos requieren una&nbsp;anestesia general&nbsp;y que, de no conocer el cuerpo y las condiciones del paciente, las consecuencias adversas son las&nbsp;hemorragias internas y externas, invasi\u00f3n de vasos sangu\u00edneos,&nbsp;lesiones de \u00f3rganos,&nbsp;embolia pulmonar&nbsp;e&nbsp;infecciones posteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn los \u00faltimos a\u00f1os hemos visto pacientes que han perdido la vida en manos de m\u00e9dicos esteticistas, de enfermeras y enfermeros que est\u00e1n haciendo el procedimiento est\u00e9tico, e incluso con personas que ni siquiera m\u00e9dicos son.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn un quir\u00f3fano se requieren m\u00e1quinas de anestesia y las m\u00e1quinas de \u00faltima generaci\u00f3n son enormemente m\u00e1s caras que las m\u00e1quinas de anestesia de hace a\u00f1os, pero lo que ahora te brinda esa tecnolog\u00eda es la seguridad en el evento, con los medicamentos y con la monitorizaci\u00f3n del paciente\u201d, se\u00f1al\u00f3 el especialista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Jaqueline, de 25 a\u00f1os, la autopsia revel\u00f3 la perforaci\u00f3n del h\u00edgado y un pulm\u00f3n durante un procedimiento de liposucci\u00f3n a manos del m\u00e9dico identificado como&nbsp;Sergio \u201cN\u201d, quien no estaba certificado ante el Colegio de Cirug\u00eda Pl\u00e1stica, Est\u00e9tica y Reconstructiva, y que actualmente se encuentra&nbsp;pr\u00f3fugo de la justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Transformaci\u00f3n mortal<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las muertes por cirug\u00edas est\u00e9ticas se han duplicado en la \u00faltima d\u00e9cada en todo el pa\u00eds, seg\u00fan informaci\u00f3n del Colegio de Cirug\u00eda Est\u00e9tica, Pl\u00e1stica y Reconstructiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el presidente del organismo, en el caso de Monterrey, el incremento de muertes obedece tambi\u00e9n al&nbsp;<strong>crecimiento poblacional<\/strong>&nbsp;y la demanda de pacientes por&nbsp;<strong>modificar su cuerpo<\/strong>, aun sin contar con el recurso econ\u00f3mico para dichos procedimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMonterrey ha crecido exponencialmente, hoy somos una ciudad muy grande, tenemos muchos millones de habitantes y si nos comparamos con lo que hab\u00eda en el 2000, hay much\u00edsimas m\u00e1s personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe ha incrementado considerablemente la cantidad de muertes y complicaciones, en los \u00faltimos 10 a\u00f1os se incrementaron con la llegada de escuelas patito, centros que ofrecen diplomados en medicina est\u00e9tica y empezaron a emerger estos m\u00e9dicos que dicen que son especialistas\u201d, se\u00f1al\u00f3 Reyna Flores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, inform\u00f3 que en lo que va del a\u00f1o se han presentado al menos 20 defunciones de personas durante procedimientos est\u00e9ticos en manos de m\u00e9dicos no certificados, en los estados de&nbsp;Nuevo Le\u00f3n, Chiapas y Tamaulipas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Del total de los fallecimientos, precis\u00f3, 100% se realizaron en&nbsp;instalaciones no reguladas&nbsp;por la&nbsp;Secretar\u00eda de Salud, donde los costos suelen ser 10 veces menores al de una&nbsp;cirug\u00eda legal.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay una presi\u00f3n social y medi\u00e1tica muy grande hacia la est\u00e9tica y eso se traduce en la proliferaci\u00f3n de m\u00e9dicos irregulares. Si t\u00fa haces una operaci\u00f3n bien hecha en un buen hospital, un buen centro de cirug\u00eda ambulatoria te puede costar 10 veces m\u00e1s caro que hacerlo en la cochera de una casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9? Porque hacerlo en la cochera de la casa te vas a ahorrar muchos gastos y costos, pero tambi\u00e9n vas a incrementar mucho el riesgo que pueda pasar el paciente\u201d, extern\u00f3 Reyna Flores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Entidad en la mira<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a las advertencias, los m\u00e9dicos sin certificaci\u00f3n y las cl\u00ednicas sin regulaci\u00f3n contin\u00faan operando en la impunidad en Nuevo Le\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reynaldo Cant\u00fa Shay<\/strong>, subsecretario de Regulaci\u00f3n y Fomento Sanitario de Nuevo Le\u00f3n, explic\u00f3 que, muchos de los seudom\u00e9dicos rentan espacios para realizar los procedimientos sin el conocimiento necesario de la anatom\u00eda humana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo tienen cl\u00ednica, generalmente lo que buscan es la clandestinidad, ellos rentan quir\u00f3fanos que s\u00ed cumplen con la normativa y si fueran a los hospitales regulados no los van a recibir porque en los hospitales s\u00ed les piden su registro en la Conacem\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi no est\u00e1n registrados no se les permite hacer la operaci\u00f3n, sin embargo, ellos buscan la clandestinidad y buscan los quir\u00f3fanos que no cumplen y andan burlando la ley\u201d, se\u00f1al\u00f3 el funcionario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme a la&nbsp;<strong>Secretar\u00eda de Salud<\/strong>&nbsp;de Nuevo Le\u00f3n, en el estado se tiene el registro de 118 establecimientos dedicados a la cirug\u00eda est\u00e9tica y 586 que hacen&nbsp;<strong>medicina est\u00e9tica<\/strong>&nbsp;y&nbsp;<strong>SPA<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que va de 2025, la dependencia ha realizado 84 visitas a los centros est\u00e9ticos, de las cuales, tres terminaron en la&nbsp;<strong>suspensi\u00f3n de actividades o clausura<\/strong>. En 2024, la Secretar\u00eda de Salud realiz\u00f3 250 visitas y 47 clausuras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHemos escuchado de algunos casos en donde a veces el m\u00e9dico es como influencer, hace como que \u00e9l es el que realizar\u00e1 la operaci\u00f3n y en realidad la operaci\u00f3n la realiza otra persona, entonces es bien importante que exista esa comunicaci\u00f3n entre el paciente y el m\u00e9dico\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros lo que verificamos cuando emitimos una licencia para un quir\u00f3fano es que tengan bien delimitadas sus \u00e1reas grises, negras, blancas, todo el procedimiento administrativo que implica y para obtener la licencia tambi\u00e9n debes tener protocolos y procesos establecidos\u201d, explic\u00f3&nbsp;Cant\u00fa Shay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Maestr\u00edas patito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Investigaciones del Colegio de Cirug\u00eda Pl\u00e1stica, Est\u00e9tica y Reconstructiva arrojan que, por cada m\u00e9dico certificado, existen otros 20 que operan de manera irregular la medicina est\u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Nuevo Le\u00f3n se tiene el registro de 200 cirujanos especialistas que cursaron hasta 14 a\u00f1os de carrera para realizar un procedimiento est\u00e9tico, a diferencia de los otros m\u00e9dicos que cursan una maestr\u00eda est\u00e9tica de un a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOcupamos alrededor de 12 o 14 a\u00f1os para poder salir y de ah\u00ed empezar una pr\u00e1ctica privada, ante todo nosotros queremos ofrecer seguridad y no hacer da\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos la responsabilidad de velar ante todo por la integridad f\u00edsica de nuestros pacientes, nosotros como capitanes de este barco que es la cirug\u00eda, tenemos un equipo de especialistas, anestesi\u00f3logos, enfermer\u00eda quir\u00fargica y todos ellos con el firme prop\u00f3sito de hacer lo mejor para nuestro paciente\u201d, mencion\u00f3 el presidente del CCPERNL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el subsecretario de regulaci\u00f3n sanitaria en el estado, Reynaldo Cant\u00fa, reiter\u00f3 que, en el pa\u00eds, existen universidades que ofrecen dichos estudios que no corresponden a la especialidad de cirug\u00eda pl\u00e1stica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros en el sector salud, ni en el estado, ni en la Federaci\u00f3n reconocemos esa carrera y ning\u00fan hospital la reconoce como una carrera con aptitudes para realizar un procedimiento de cirug\u00eda y ese es el principal problema del que estamos viviendo en los \u00faltimos a\u00f1os, que hay mucho m\u00e9dico est\u00e9tico y que se confunde con el cirujano pl\u00e1stico que es el que s\u00ed est\u00e1 en las condiciones para realizar este tipo de procedimientos\u201d, se\u00f1al\u00f3 el subsecretario.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"991\" height=\"521\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03.jpg\" alt=\"\" class=\"wp-image-98290\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03.jpg 991w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03-300x158.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03-768x404.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03-150x79.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-03-696x366.jpg 696w\" sizes=\"auto, (max-width: 991px) 100vw, 991px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, el CCPERNL present\u00f3 un exhorto al&nbsp;<strong>Congreso Local&nbsp;<\/strong>para reformar la&nbsp;<strong>Ley Estatal de Salud<\/strong>&nbsp;y&nbsp;<strong>tipificar<\/strong>&nbsp;como&nbsp;<strong>delito<\/strong>, no s\u00f3lo la&nbsp;<strong>usurpaci\u00f3n de funciones<\/strong>&nbsp;profesionales, sino la de especialistas pl\u00e1sticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Fallecimiento tras liposucci\u00f3n alerta a M\u00e9xico, pa\u00eds con m\u00e1s de 1&#8217;200.000 procedimientos est\u00e9ticos al a\u00f1o<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En octubre de 2021, la periodista Amapola Nava relat\u00f3 que tras someterse a una liposucci\u00f3n&nbsp;en Monterrey, M\u00e9xico, el 5 de octubre falleci\u00f3 una paciente de 22 a\u00f1os. Las investigaciones indican que la persona que realiz\u00f3 el procedimiento no contaba con un t\u00edtulo de medicina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, en&nbsp;entrevista&nbsp;para&nbsp;<em>Telediario Monterrey<\/em>, el &nbsp;doctor &nbsp;Luis Fernando Lira Men\u00e9ndez, expresidente del Colegio de Cirujanos Pl\u00e1sticos de Nuevo Le\u00f3n, revel\u00f3 que ya hab\u00edan reportado a las autoridades que esta y otras 80 cl\u00ednicas del estado presentaban irregularidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este no es un caso aislado, ya en 2018 la Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (COFEPRIS) public\u00f3&nbsp;una alerta sanitaria donde advert\u00eda que de 4.322 cl\u00ednicas con prestaci\u00f3n de servicios de cirug\u00eda est\u00e9tica en el pa\u00eds, 510 presentaron anomal\u00edas y en 264 se procedi\u00f3 a la suspensi\u00f3n de actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las anomal\u00edas inclu\u00edan no contar con autorizaci\u00f3n sanitaria, personal no profesional de la salud, cirujanos sin certificado de especialidad, condiciones sanitarias inadecuadas, f\u00e1rmacos caducos, equipo m\u00e9dico sin registro sanitario, no permitir acceso para constatar condiciones sanitarias y contar con quir\u00f3fano dentro del consultorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>M\u00e9xico 4\u00ba. Lugar en este tipo de procedimientos de \u201cbelleza\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto sucede en el pa\u00eds con el cuarto lugar del mundo en n\u00famero de procedimientos est\u00e9ticos quir\u00fargicos y no quir\u00fargicos, seg\u00fan la Sociedad Internacional de Cirug\u00eda Pl\u00e1stica Est\u00e9tica ISAPS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n,&nbsp;<em>Medscape en espa\u00f1ol<\/em>&nbsp;presenta una serie de interactivos, realizados con Flourishque detallan la cantidad y tipo de procedimientos est\u00e9ticos que se realizan en M\u00e9xico. Cabe considerar que las cifras solo toman en consideraci\u00f3n los procedimientos que llevan a cabo cirujanos certificados en el pa\u00eds. Asimismo, se calcula que 22% de todas estas intervenciones se realiza en pacientes extranjeros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"300\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04.jpg\" alt=\"\" class=\"wp-image-98291\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04.jpg 700w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04-300x129.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04-150x64.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/falsos-cirujanos-04-696x298.jpg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e1fico 1: Procedimientos est\u00e9ticos en el mundo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El da\u00f1o a la salud puede ser permanente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El da\u00f1o a la salud por someterse a un procedimiento quir\u00fargico est\u00e9tico con personas no especializadas o en lugares sin las condiciones adecuadas puede ser permanente o llevar al fallecimiento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/alan-gabriel-01.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"156\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/09\/alan-gabriel-01.jpg\" alt=\"\" class=\"wp-image-98294\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">doctor Allan Gabriel Ceballos Pressler<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLas cirug\u00edas pl\u00e1sticas, est\u00e9ticas o reconstructivas son procedimientos muy complejos. Por ejemplo, la liposucci\u00f3n es una intervenci\u00f3n riesgosa para la que se requiere un amplio conocimiento, que solo se aprende en la subespecialidad. Adem\u00e1s las personas pueden sufrir complicaciones durante un procedimiento m\u00e9dico, que el profesional de la salud debe saber atender y resolver. Pero un individuo no capacitado no tiene las herramientas para responder en ese caso\u00bb, coment\u00f3 el Dr. Allan Gabriel Ceballos Pressler, cirujano pl\u00e1stico, est\u00e9tico y reconstructivo certificado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perspectivas feministas cr\u00edticas est\u00e1n a debate 2 posturas<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia simb\u00f3lica:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Feministas consideran que las cirug\u00edas est\u00e9ticas son una manifestaci\u00f3n de violencia simb\u00f3lica, ya que educan a las mujeres para cumplir con un est\u00e1ndar de belleza irreal, lo que puede llevar a la falta de aceptaci\u00f3n de sus cuerpos y la creencia err\u00f3nea de que su valor radica en su apariencia.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Disfraz de libertad:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El feminismo &nbsp;argumenta que estas pr\u00e1cticas, que buscan la normalizaci\u00f3n del cuerpo femenino a trav\u00e9s de la modificaci\u00f3n, son una forma de disciplinar a las mujeres, impidiendo que se liberen realmente de los mandatos de la heteronormatividad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras mujeres, consideran que es una forma de defender la autonom\u00eda&nbsp; de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1alan que es parte del \u201ce<strong>mpoderamiento y libertad de elecci\u00f3n\u201d, <\/strong>&nbsp;sostienen que la decisi\u00f3n de hacerse una cirug\u00eda est\u00e9tica es un acto de empoderamiento y una expresi\u00f3n de la libertad individual para hacer con el cuerpo lo que se desea, siempre y cuando se haga de forma consciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde esta visi\u00f3n, el feminismo busca la igualdad y la autonom\u00eda, y el uso de la cirug\u00eda o la b\u00fasqueda de la belleza no son acciones que vayan en contra de estos objetivos, sino que son parte de la autodeterminaci\u00f3n de la mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contexto en Nuevo Le\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Colectivo \u00abMorras Feministas MTY\u00bb, ante el conocimiento de hechos y muertes, declar\u00f3 &nbsp;que las cirug\u00edas est\u00e9ticas representan violencia simb\u00f3lica, aline\u00e1ndose con las posturas m\u00e1s cr\u00edticas dentro del movimiento feminista.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La discusi\u00f3n se da en un contexto donde las cirug\u00edas est\u00e9ticas son cada vez m\u00e1s accesibles, lo que aumenta la relevancia de analizar las implicaciones sociales y de g\u00e9nero de estas pr\u00e1cticas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Gr\u00e1ficos: Amapola Nava\/Flourish<\/em><\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Medscape Noticias M\u00e9dicas&nbsp;\u00a9&nbsp;2021&nbsp;WebMD, LLC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Citar este art\u00edculo: Fallecimiento tras liposucci\u00f3n alerta a M\u00e9xico, pa\u00eds con m\u00e1s de 1&#8217;200.000 procedimientos est\u00e9ticos al a\u00f1o&nbsp;&#8211;&nbsp;Medscape&nbsp;&#8211;&nbsp;12 de oct de 2021.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ilustraci\u00f3n: Liliana Pedraza De acuerdo con datos del CCPERNL, al menos cinco de cada 10 procedimientos est\u00e9ticos en Nuevo Le\u00f3n los hacen quienes no son especialistas y hay \u201cseudocl\u00ednicas\u201d Las autoridades desde 2018 sab\u00edan, ten\u00edan denuncias y diagn\u00f3stico y no hicieron nada Libertad L\u00f3pez SemM\u00e9xico, Cd. de M\u00e9xico, 1\u00ba. de septiembre, 2025.- La muerte de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":98292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[694,63],"tags":[],"class_list":["post-98289","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas","category-reportajes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/98289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=98289"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/98289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/98292"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=98289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=98289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=98289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}