{"id":97434,"date":"2025-08-01T17:12:00","date_gmt":"2025-08-01T23:12:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=97434"},"modified":"2025-08-01T17:12:01","modified_gmt":"2025-08-01T23:12:01","slug":"feministas-abolicionistas-piden-a-la-onu-impedir-actos-de-discriminacion","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/feministas-abolicionistas-piden-a-la-onu-impedir-actos-de-discriminacion\/","title":{"rendered":"Feministas abolicionistas piden a la ONU impedir actos de discriminaci\u00f3n"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Dirigen una carta a Antonio Guterres en la v\u00edspera de la XVI Conferencia Regional de la Mujer de Am\u00e9rica Latina y el Caribe<\/li>\n\n\n\n<li>Acusan que se les neg\u00f3 el registro al Foro Alterno Feminista<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Micaela M\u00e1rquez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico. 1 de agosto, 2025.- Organizaciones y reconocidas feministas piden al Secretario General de Naciones, Unidas Antonio Guterres, su intervenci\u00f3n inmediata ante la convocatoria discriminatoria para el Foro Alterno Feminista a la XVI Conferencia Regional&nbsp; de la Mujer de Am\u00e9rica Latina y el Caribe, que se realizar\u00e1 del 11 a 15 de agosto en la Ciudad de M\u00e9xico, al excluir a quienes defienden el derecho de las mujeres y no est\u00e1n a favor de la legalizaci\u00f3n de la explotaci\u00f3n sexual, as\u00ed como a quienes no comparten la teor\u00eda del g\u00e9nero basada en la identidad auto percibida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta exclusi\u00f3n ya se ha materializado en la negaci\u00f3n del registro al foro a reconocidas feministas, lo que constituye un acto claro de censura ideol\u00f3gica y vulneraci\u00f3n del derecho a la participaci\u00f3n en espacios de deliberaci\u00f3n internacional\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConsideran que resulta inaudito y fuera de toda \u00e9tica, cancelar la libertad de expresi\u00f3n y reuni\u00f3n, el intercambio, sino que, adem\u00e1s, se promueve desde la convocatoria lo contrario a lo que la misma CEDAW establece\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una carta dirigida al secretario general de la ONU y con copia a todas las instancias internacionales que tienen que ver los derechos humanos y de las mujeres, le piden que se retire de la convocatoria cualquier criterio discriminatorio, que se garantice el acceso a todas las voces del movimiento feminista en su pluralidad y que se asegure un foro alterno verdaderamente inclusivo, como ha sido tradici\u00f3n en el sistema de Naciones Unidas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Profundamente indignadas y preocupadas porque por primera vez una conferencia de Naciones Unidas no garantiza el respeto irrestricto a la libertad de expresi\u00f3n, incluye en su convocatoria al foro alterno de la sociedad civil disposiciones que implican censura y exclusi\u00f3n hacia quienes defendemos los derechos de las mujeres consagrados en la CEDAW y en la Convenci\u00f3n de Bel\u00e9m do Par\u00e1 para prevenir, sancionar y erradicar la violencia contra las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Citan la exclusi\u00f3n de la convocatoria: \u201cLas personas y organizaciones que son bienvenidas en el espacio para participar de las discusiones son aquellas que sean feministas incluyentes, que respeten las demandas del movimiento de trabajadoras sexuales y de las personas trans\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las feministas detallan: \u201cExcluye expl\u00edcitamente a feministas que no est\u00e1n a favor de la legalizaci\u00f3n de la explotaci\u00f3n sexual, a la que se hace referencia en el documento como \u201ctrabajo sexual\u201d, as\u00ed como a quienes no compartimos la teor\u00eda del g\u00e9nero basada en la identidad auto percibida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le recuerdan que dicha convocatoria contraviene el compromiso asumido por ONU Mujeres en 2019, cuando en una carta inform\u00f3 la anterior directora ejecutiva de ONU Mujeres que: \u00abONU Mujeres no adopta una posici\u00f3n a favor o en contra de la despenalizaci\u00f3n\/legalizaci\u00f3n de la prostituci\u00f3n\/trabajo sexual\u201d. Este compromiso se aplica a todas las oficinas regionales de ONU Mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha carta fue en respuesta a una petici\u00f3n mundial de m\u00e1s de cuatro mil organizaciones y defensoras de derechos humanos, incluidas sobrevivientes de la trata y de la industria del sexo, dedicadas a poner fin a todas las formas de violencia y discriminaci\u00f3n contra las mujeres y ni\u00f1as. Resulta inaudito y fuera de toda \u00e9tica, cancelar la libertad de expresi\u00f3n y reuni\u00f3n, el intercambio, sino que, adem\u00e1s, se promueve desde la convocatoria lo contrario a lo que la misma CEDAW en su Art\u00edculo 6 establece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Firman la carta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alma Margarita Oceguera Rodr\u00edguez por el Frente Feminista Nacional; Olimpia Jaimes L\u00f3pez por Mujeres Guerrerenses por la Democracia; Magdalena Garc\u00eda Hern\u00e1ndez por Bufete de Estudios Interdisciplinarios; Ver\u00f3nica Palafox Gir\u00f3n por Las Constituyentes MX Feministas; Marcela Lagarde y de los R\u00edos, Mar\u00eda de Lourdes Garc\u00eda Acevedo, Andrea Medina Rosas, Yan Mar\u00eda Yaoy\u00f3lot, Ang\u00e9lica de la Pe\u00f1a G\u00f3mez, Ivonne de la Cruz Dom\u00ednguez y Guadalupe L\u00f3pez Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de Vanessa Mar\u00eda Cravioto, Laura Lecuona, Alejandra Rojas, Ana Bertha Campa Garc\u00eda, Yndira Sandoval S\u00e1nchez, Aim\u00e9e Vega Montiel, Pilar Alberti Manzanares, Gabriela Delgado Ballesteros y Mar\u00eda Guadalupe P\u00e9rez L\u00f3pez, Sara Valadez Montiel, Mar\u00eda Teresa Manzanares Cruz, Gudelia Delgado, Carolina Pacheco Luna, Leticia Burgos Ochoa, Nahela Becerril, Martha Gonz\u00e1lez Renter\u00eda y Claudia Quintero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La carta fue enviada con copia diversos funcionarios de Naciones Unidas, como J\u00fcrg Lauber, presidente del Consejo de Derechos Humanos de Naciones Unidas; Nahla Haidar, presidenta del Comit\u00e9 de CEDAW, Sima Bahous, directora ejecutiva de ONU Mujeres; Reem Alsalem, Relatora Especial sobre la violencia contra las mujeres y las ni\u00f1as; Ana G\u00fcezmes, jefa de la divisi\u00f3n de Asuntos de G\u00e9nero de la CEPAL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n a Jos\u00e9 Manuel Salazar-Xirinachs, secretario ejecutivo, CEPAL; Javier Medina V\u00e1squez, secretario ejecutivo adjunto CEPAL; Luis Fidel Y\u00e1\u00f1ez, secretario de la Comisi\u00f3n; Luc\u00eda Scuro Somma, de la Unidad de Autonom\u00eda de las Mujeres; Nicole Bidegain Ponte, jefa de la Unidad de Multilaterales y Macroeconom\u00eda, y Juan Ram\u00f3n de la Fuente, Secretar\u00eda de Relaciones Exteriores de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/mm\/sj<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Micaela M\u00e1rquez SemM\u00e9xico, Ciudad de M\u00e9xico. 1 de agosto, 2025.- Organizaciones y reconocidas feministas piden al Secretario General de Naciones, Unidas Antonio Guterres, su intervenci\u00f3n inmediata ante la convocatoria discriminatoria para el Foro Alterno Feminista a la XVI Conferencia Regional&nbsp; de la Mujer de Am\u00e9rica Latina y el Caribe, que se realizar\u00e1 del 11 a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":97435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-97434","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/97434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=97434"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/97434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/97435"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=97434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=97434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=97434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}