{"id":97239,"date":"2025-07-24T20:30:46","date_gmt":"2025-07-25T02:30:46","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=97239"},"modified":"2025-07-24T20:30:47","modified_gmt":"2025-07-25T02:30:47","slug":"van-por-500-grilletes-de-proximidad-para-agresores-de-mujeres","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/van-por-500-grilletes-de-proximidad-para-agresores-de-mujeres\/","title":{"rendered":"Van por 500 \u201cgrilletes\u201d de proximidad para agresores de mujeres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Guadalajara, Jalisco, 24 de julio, 2025.- Como parte de la estrategia para combatir la violencia contra las mujeres, el gobernador de Jalisco, Pablo Lemus Navarro, anunci\u00f3 este martes la adquisici\u00f3n de 500 dispositivos de geolocalizaci\u00f3n, conocidos como \u201cgrilletes\u201d de proximidad, destinados al monitoreo de agresores.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, el estado cuenta con solo 80 de estos aparatos, de los cuales menos de la mitad est\u00e1n en uso, a pesar de que existen m\u00e1s de 12 mil \u00f3rdenes de restricci\u00f3n activas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cEstoy ordenando la compra inmediata de 500 para poder empezar, son 500 los que vamos a comprar en estos momentos y tambi\u00e9n el presidente municipal de Zapopan se ofreci\u00f3 a comprar m\u00e1s de estos instrumentos tecnol\u00f3gicos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los dispositivos permiten alertar a las autoridades cuando el agresor se aproxima a menos de un kil\u00f3metro de su v\u00edctima, fortaleciendo la vigilancia de medidas cautelares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico, Guadalajara, Jalisco, 24 de julio, 2025.- Como parte de la estrategia para combatir la violencia contra las mujeres, el gobernador de Jalisco, Pablo Lemus Navarro, anunci\u00f3 este martes la adquisici\u00f3n de 500 dispositivos de geolocalizaci\u00f3n, conocidos como \u201cgrilletes\u201d de proximidad, destinados al monitoreo de agresores. Actualmente, el estado cuenta con solo 80 de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":97240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[700],"tags":[],"class_list":["post-97239","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estados"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/97239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=97239"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/97239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/97240"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=97239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=97239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=97239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}