{"id":9674,"date":"2019-07-10T23:23:55","date_gmt":"2019-07-10T23:23:55","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9674"},"modified":"2023-07-21T14:50:44","modified_gmt":"2023-07-21T19:50:44","slug":"tipifican-delitos-contra-la-intimidad-sexual","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tipifican-delitos-contra-la-intimidad-sexual\/","title":{"rendered":"Tipifican delitos contra la intimidad sexual"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> <strong><em>* Qui\u00e9n divulgue, publique o solicite im\u00e1genes, audios o videos de una persona<br>* La ley se aplicar\u00e1 para quienes cometan el delito contra menores de edad.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 10 junio 2019.\u2013 El Pleno de la LXIV Legislatura del Congreso del Estado de Oaxaca tipific\u00f3 delitos contra la intimidad sexual, imponiendo sanciones de cuatro a ocho a\u00f1os de prisi\u00f3n y multa de mil a dos mil veces el valor diario de la unidad de medida y actualizaci\u00f3n vigente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a las reformas estipuladas al C\u00f3digo Penal, el art\u00edculo 249 establece a letra expresa que comete el delito de violaci\u00f3n a la intimidad sexual quien por cualquier medio divulgue, comparta, distribuya, publique o solicite im\u00e1genes, audios o videos de una persona, de contenido intimo, er\u00f3tico o sexual, ya sea impreso, grabado o digital, son el consentimiento de la v\u00edctima.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dictamen emitido por la Comisi\u00f3n Permanente de Administraci\u00f3n y Procuraci\u00f3n de Justicia establece que las mismas penas se aumentar\u00e1n hasta en una mitad del m\u00e1ximo a quien cometa el delito contra su c\u00f3nyuge o en contra de la persona con la que est\u00e9 o haya estado unida por alguna relaci\u00f3n afectiva, aun sin convivencia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se sancionar\u00e1 tambi\u00e9n con la misma medida a quien mantenga una relaci\u00f3n laboral, social o pol\u00edtica con la v\u00edctima o a quien cometa el delito contra de una persona que por su situaci\u00f3n de discapacidad no comprenda el significado del hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ley se aplicar\u00e1 para quienes cometan el delito contra menores de edad, as\u00ed como a las personas que obliguen a la v\u00edctima a fabricar, hacer el contenido intimo, sexual o er\u00f3tico publicado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta fue retomada de las iniciativas planteadas por la diputada Elena Cuevas Hern\u00e1ndez, del diputado Arsenio Lorenzo Mej\u00eda Garc\u00eda, as\u00ed como las y los diputados No\u00e9 Doroteo Castillejos, Aleida Tonelly Serrano Rosado, Elim Antonio Aquino e Hilda Graciela P\u00e9rez Luis.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ley se aplicar\u00e1 para quienes cometan el delito contra menores de edad.<\/p>\n","protected":false},"author":3,"featured_media":9677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,50],"tags":[],"class_list":["post-9674","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9674"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9677"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}