{"id":96655,"date":"2025-07-01T15:52:26","date_gmt":"2025-07-01T21:52:26","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=96655"},"modified":"2025-07-01T15:52:27","modified_gmt":"2025-07-01T21:52:27","slug":"en-chihuahua-analizaran-reforma-sobre-el-matrimonio-igualitario-en-el-congreso-del-estado","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/en-chihuahua-analizaran-reforma-sobre-el-matrimonio-igualitario-en-el-congreso-del-estado\/","title":{"rendered":"En Chihuahua\u00a0 analizar\u00e1n reforma sobre el matrimonio igualitario en el Congreso del Estado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><sub>La b\u00fasqueda del matrimonio igualitario es una de las luchas de los colectivos LGBT+\u00a0\/\u00a0Foto: Pedro C\u00f3rdova \/ El Heraldo de Chihuahua<\/sub><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los congresistas y las organizaciones interesadas se reunir\u00e1n hoy en las instalaciones de la Torre Legislativa para darle seguimiento a las dos iniciativas existentes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cinco entidades est\u00e1n en la misma situaci\u00f3n que Chihuahua, aunque en 31 se acept\u00f3 legalmente el matrimonio igualitario<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Karla Isabel Carmona Espinoza<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/ El Heraldo de Chihuahua, Chihuahua, Chih., 1o. de julio, 2025.- Seg\u00fan informaci\u00f3n oficial del congreso local, el d\u00eda de hoy lunes 30 de junio la Comisi\u00f3n de Igualdad sesionar\u00e1 para continuar el an\u00e1lisis de dos iniciativas de reforma al C\u00f3digo Civil estatal con la intenci\u00f3n de visibilizar al matrimonio igualitario en Chihuahua y as\u00ed, garantizar el acceso de las&nbsp;personas LGBT+&nbsp;a los mismos derechos que una pareja heterosexual ante la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de los asuntos 490 y 651, promovidos por el&nbsp;Partido del Trabajo y la bancada de Morena, respectivamente, en conjunto con asociaciones y colectivos de defensa a los derechos humanos y de la comunidad LGBT+.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la \u00faltima reuni\u00f3n, realizada hace unos meses, se cont\u00f3 con la presencia del Comit\u00e9 de la Diversidad Sexual de Chihuahua, as\u00ed como de los&nbsp;colectivos&nbsp;Morrxs aut\u00f3nomxs, Uni\u00f3n y Fuerza de Mujeres Trans Chihuahuenses A.C., Aliados en Movimiento, Ju\u00e1rez Diversa, y del Observatorio de Participaci\u00f3n Pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante esa sesi\u00f3n, con fecha del 26 de febrero, se indic\u00f3 que si bien ambos dict\u00e1menes ten\u00edan una redacci\u00f3n muy similar, la redacci\u00f3n var\u00eda en diferentes art\u00edculos, por lo que se consider\u00f3 pertinente analizar y comparar ambos escritos para hacer&nbsp;un solo dictamen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, en la iniciativa propuesta por la bancada guinda y los grupos de defensa de los derechos humanos, uno de los art\u00edculos a reformar es el 150, donde se sugiere instituir que el&nbsp;domicilio familiar&nbsp;sea establecido de com\u00fan acuerdo entre los c\u00f3nyuges, mientras que en el dictamen presentado por el PT, directamente se deroga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese mismo sentido, en la redacci\u00f3n propuesta del PT del art\u00edculo 151 se indica que los c\u00f3nyuges ser\u00e1n equitativos en los temas del&nbsp;sostenimiento econ\u00f3mico y de las labores propias del hogar, mientras que en la otra iniciativa est\u00e1 redactada de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos c\u00f3nyuges contribuir\u00e1n econ\u00f3micamente al sostenimiento y cuidado del hogar, a su rec\u00edproca alimentaci\u00f3n y, en su caso, al de sus hijos, as\u00ed como a la educaci\u00f3n, cuidado y protecci\u00f3n de \u00e9stos (&#8230;)\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n se realiz\u00f3 este 30 de junio, a las cinco de la tarde, y se espera contar con la participaci\u00f3n del Comit\u00e9 de la Diversidad Sexual de Chihuahua, as\u00ed como de otras asociaciones civiles especializadas en el tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Actualmente,&nbsp;cinco estados&nbsp;se encuentran en esta situaci\u00f3n:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Aguascalientes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El matrimonio igualitario se permite en Aguascalientes desde el&nbsp;2 de abril de 2019, cuando una sentencia judicial oblig\u00f3 al estado a garantizar este derecho. A pesar de ello, no se ha aprobado una reforma legislativa que modifique el C\u00f3digo Civil local para reconocerlo formalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Chihuahua<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Chihuahua, el matrimonio igualitario es legal desde el&nbsp;11 de junio de 2015, cuando el gobernador en turno emiti\u00f3 una orden ejecutiva para que las oficinas del Registro Civil realizaran estas uniones. Sin embargo, el Congreso estatal no ha legislado al respecto para consolidar este derecho mediante una reforma. Ahora en revisi\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Guanajuato<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estado de Guanajuato permite el matrimonio igualitario desde el&nbsp;20 de diciembre de 2022, gracias a una decisi\u00f3n del ejecutivo que instruy\u00f3 a las oficinas del Registro Civil a aceptar estas uniones. A pesar de ello, el Congreso local no ha aprobado una ley para garantizarlo oficialmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Quintana Roo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El matrimonio igualitario se permite en Quintana Roo desde el&nbsp;3 de mayo de 2012, cuando se determin\u00f3 que las leyes existentes no especificaban restricciones sobre el g\u00e9nero de los contrayentes. Aunque desde entonces se realizan matrimonios igualitarios, la reforma legislativa que lo consolid\u00f3 formalmente no lleg\u00f3 hasta el&nbsp;29 de septiembre de 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Chiapas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Chiapas, este derecho fue reconocido mediante una sentencia judicial emitida el&nbsp;11 de julio de 2017, que oblig\u00f3 al estado a permitir el matrimonio igualitario. Posteriormente, el Congreso estatal aprob\u00f3 formalmente la reforma legislativa correspondiente el&nbsp;26 de diciembre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El avance del matrimonio igualitario en M\u00e9xico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que la&nbsp;Ciudad de M\u00e9xico&nbsp;fue pionera en aprobar el matrimonio igualitario en 2010, otras entidades han seguido este camino. Entre las primeras estuvieron&nbsp;Quintana Roo&nbsp;(2012),&nbsp;Coahuila&nbsp;(2014) y&nbsp;Chihuahua&nbsp;(2015). En a\u00f1os m\u00e1s recientes, estados como&nbsp;Jalisco,&nbsp;Durango&nbsp;y&nbsp;Tamaulipas&nbsp;hicieron lo propio en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la incorporaci\u00f3n de&nbsp; Chihuahua y&nbsp; Chiapas, 31 estados del pa\u00eds han aprobado esta legislaci\u00f3n, quedando pendiente una sola entidad por sumarse a la lista. La aprobaci\u00f3n en cada estado ha sido resultado de una combinaci\u00f3n de presi\u00f3n social, trabajo legislativo y participaci\u00f3n activa de organizaciones civiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el&nbsp;Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi), los matrimonios igualitarios han ido en aumento desde su legalizaci\u00f3n. En 2010, se registraron 689 uniones de este tipo en el pa\u00eds. Para 2021, la cifra ascendi\u00f3 a cuatro mil 341, con mil 845 uniones entre hombres y dos mil 496 entre mujeres.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este junio INEGI inform\u00f3 que en el pa\u00eds los matrimonios de personas contrayentes del mismo sexo representaron el 1.3 por ciento del total, es decir seis mil 606 personas y las entidades donde m\u00e1s se registraron son la Ciudad de M\u00e9xico, Baja California y Jalisco, en contraste las ciudades donde menos matrimonios se registraron fueron Veracruz, Guerrero y Chiapas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cinco millones de personas se autoidentificaron como LGBTI+, 3.2 millones declararon ser solteras, 1.5 millones estar casadas o vivir en uni\u00f3n libre, y 223.7 mil, separadas, divorciadas o viudas, de acuerdo con el Instituto Nacional de Geograf\u00eda y Estad\u00edstica (INEGI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, los matrimonios heterosexuales han mostrado una tendencia a la baja, pasando de 568 mil 632 en 2010 a 448 mil 774 en 2021. En cuanto a los divorcios, estos tambi\u00e9n han crecido, incluidos los de parejas del mismo sexo, que en 2021 sumaron 441 casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aprobaci\u00f3n del matrimonio igualitario&nbsp; no solo es un logro legal, sino tambi\u00e9n un s\u00edmbolo de justicia social y respeto a los derechos humanos. Aunque el camino hacia la igualdad plena no ha concluido, este avance representa un paso importante hacia una sociedad m\u00e1s inclusiva. El reto ahora es continuar transformando actitudes y promoviendo el respeto en todos los \u00e1mbitos del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La b\u00fasqueda del matrimonio igualitario es una de las luchas de los colectivos LGBT+\u00a0\/\u00a0Foto: Pedro C\u00f3rdova \/ El Heraldo de Chihuahua Los congresistas y las organizaciones interesadas se reunir\u00e1n hoy en las instalaciones de la Torre Legislativa para darle seguimiento a las dos iniciativas existentes Cinco entidades est\u00e1n en la misma situaci\u00f3n que Chihuahua, aunque [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":96656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-96655","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=96655"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/96656"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=96655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=96655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=96655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}