{"id":96409,"date":"2025-06-23T19:20:27","date_gmt":"2025-06-24T01:20:27","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=96409"},"modified":"2025-06-23T19:20:28","modified_gmt":"2025-06-24T01:20:28","slug":"palabra-de-antigona-como-llegamos-hasta-aqui","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/palabra-de-antigona-como-llegamos-hasta-aqui\/","title":{"rendered":"Palabra de Ant\u00edgona| \u00bfC\u00f3mo llegamos hasta aqu\u00ed?\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sara Lovera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 23 de junio, 2025.- En 1975, las mujeres \u00e9ramos otras. Ten\u00edamos clara nuestra funci\u00f3n: ser madres y cuidar de la familia. Votar y usar anticonceptivos era ya una posibilidad, pero la violencia contra las mujeres, el derecho a interrumpir un embarazo o el significado de ser libres y soberanas eran casi invisibles. As\u00ed lo recordaron cinco expertas reunidas por la UNAM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese entonces, el trabajo de las mujeres no era valorado. La doble jornada \u2014el trabajo dom\u00e9stico y de cuidados\u2014 ni siquiera ten\u00eda nombre. Eran pocas las que se hab\u00edan levantado contra los yugos patriarcales de la familia, la econom\u00eda y la sociedad. No hab\u00eda una conciencia sobre la discriminaci\u00f3n de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El feminismo de los a\u00f1os 70 era ignorado por los gobiernos, que desestimaban sus cr\u00edticas al poder. Era impensable hablar de una democracia con enfoque de g\u00e9nero. Lo que s\u00ed ten\u00eda impacto eran las marchas multitudinarias en Estados Unidos e Italia por el derecho al aborto, as\u00ed como la irrupci\u00f3n de mujeres en los movimientos sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los gobiernos, reunidos en Naciones Unidas, empezaron a interesarse por las mujeres, pero desde una l\u00f3gica capitalista: quer\u00edan integrarlas al consumo, a los negocios, a las f\u00e1bricas y a los servicios. Esa visi\u00f3n deriv\u00f3 en la convocatoria a la primera conferencia mundial sobre sus derechos. El resultado fue un plan de acci\u00f3n bajo el lema: Desarrollo y Paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ideas de Simone de Beauvoir en <em>El segundo sexo<\/em> (1949) influyeron en mujeres acad\u00e9micas, diplom\u00e1ticas y funcionarias, as\u00ed como en trabajadoras que enfrentaban la precariedad salarial. Nadie imaginaba que se avecinaba una revoluci\u00f3n femenina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Am\u00e9rica Latina, influyeron tambi\u00e9n la lucha social, la resistencia a las dictaduras, las guerrillas y los movimientos de liberaci\u00f3n nacional, as\u00ed como la lucha por los derechos civiles en Estados Unidos y la revuelta estudiantil de 1968. Estos movimientos abrieron espacio para que las mujeres nombraran sus propias demandas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso la Primera Conferencia Mundial de la Mujer, convocada por la ONU y celebrada en M\u00e9xico, sacudi\u00f3 al mundo: por primera vez se reflexion\u00f3 de manera global sobre la discriminaci\u00f3n espec\u00edfica contra&nbsp; las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cinco d\u00e9cadas despu\u00e9s, aquella conferencia provoc\u00f3 transformaciones a una velocidad inesperada. En 1979, la ONU adopt\u00f3 la Convenci\u00f3n sobre la Eliminaci\u00f3n de Todas las Formas de Discriminaci\u00f3n contra la Mujer (CEDAW), cre\u00f3 el fondo UNIFEM \u2014hoy ONU Mujeres\u2014 y fund\u00f3 el Instituto Internacional de Investigaciones y Capacitaci\u00f3n para la Promoci\u00f3n de la Mujer (INSTRAW). El reconocimiento de la violencia de g\u00e9nero lleg\u00f3 hasta 1992.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CEDAW, firmada por 189 pa\u00edses, es un compromiso vinculante y se convirti\u00f3 en el eje para combatir la discriminaci\u00f3n. Desde entonces, el Comit\u00e9 de Expertas da seguimiento a los gobiernos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la ruta internacional para proteger todos los derechos humanos de las mujeres. En M\u00e9xico, sin embargo, no se ha comprendido del todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a la CEDAW se visibilizaron la doble jornada, el derecho al aborto, la libertad y diversidad sexual, y la violencia de g\u00e9nero. Se crearon institutos y secretar\u00edas de las mujeres, surgieron an\u00e1lisis cient\u00edficos con perspectiva de g\u00e9nero, se impulsaron cambios culturales y pol\u00edticas p\u00fablicas. El Comit\u00e9 ha emitido m\u00e1s de 30 recomendaciones generales y cientos de observaciones puntuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hoy las expertas se preguntan: \u00bfc\u00f3mo llegamos a este momento oscuro y violento, al borde de una tercera guerra mundial? \u00bfC\u00f3mo ocurri\u00f3 que Donald Trump se metiera en una guerra? Est\u00e1n en riesgo todos los avances de las mujeres, y la vida misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEs un asunto nuestro? S\u00ed. Por eso el feminismo necesita repensar la igualdad, la democracia, la paz y el desarrollo. Urgen nuevas estrategias, renovar el pensamiento y la acci\u00f3n. Hoy m\u00e1s que nunca, es necesario transformar al Estado. Involucrarse en su estructura y en la toma de decisiones. Veremos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Periodista. Editora de G\u00e9nero en la OEM y directora del portal informativo semmexico.mx<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sara Lovera SemM\u00e9xico, Cd. de M\u00e9xico, 23 de junio, 2025.- En 1975, las mujeres \u00e9ramos otras. Ten\u00edamos clara nuestra funci\u00f3n: ser madres y cuidar de la familia. Votar y usar anticonceptivos era ya una posibilidad, pero la violencia contra las mujeres, el derecho a interrumpir un embarazo o el significado de ser libres y soberanas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[35,95,69],"tags":[],"class_list":["post-96409","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-palabra-de-antigona","category-sara-lovera"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=96409"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/70950"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=96409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=96409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=96409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}