{"id":9629,"date":"2019-07-09T22:54:11","date_gmt":"2019-07-09T22:54:11","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9629"},"modified":"2023-07-21T14:50:45","modified_gmt":"2023-07-21T19:50:45","slug":"por-la-cuarta-3","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/por-la-cuarta-3\/","title":{"rendered":"Por la Cuarta"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u201cSomos bellas siendo tal cual somos y con suerte, alg\u00fan d\u00eda\nseremos viejas y guapas\u201d<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Enriqueta Burelo Melgar<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. 09 de julio 2019.- Los Hor\u00f3scopos de Durango\ncantan: El tintalabio, toque de r\u00edmel. Moldeador como una artista de cine.\nPeluquer\u00eda, crema hidratante. Y maquillaje que belleza al instante en Antes\nMuerta que Sencilla. Una frase en boga es la siguiente; no hay mujeres feas solo\npobres, haciendo alusi\u00f3n que no todas pueden tener acceso a un buen cirujano\npl\u00e1stico, cuando subir chichis, te cuesta 30,000 pesos y subir otras cosas,\npues depende a cu\u00e1nto, muchas est\u00e1n dispuesta a correr los riesgos del\nquir\u00f3fano, con tal de tener el trasero de Jennifer L\u00f3pez, la naricita de Selena\nG\u00f3mez,&nbsp; los labios de Ang\u00e9lica Jolie, no\ns\u00e9 si estar\u00edan dispuestas a hacerse una mastectom\u00eda total, como ella, para\nevitar caer en las garras del c\u00e1ncer de mama, ya que hay predisposici\u00f3n\nfamiliar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto quienes somos simples mortales talla 40 o\nXXXL sufrimos cuando vamos a comprarnos un ouftit de presumir, mentalmente nos\nvemos enfundadas en un vestido sexi, sin mangas, de escote generoso, y me he\nvisto en la necesidad de&nbsp; terminar\ncomprando en la secci\u00f3n de maternidad, donde los senos tambi\u00e9n est\u00e1n de un\ntama\u00f1o generoso, gracias a la leche acumulada y no al cirujano pl\u00e1stico de la\nesquina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta lucha que libramos las gordibuenas como nos llamamos\nentre nosotras para disimular nuestro desencanto con nuestras curvas que\nparecen la antigua carretera a San Crist\u00f3bal. Una conocida marca de origen\nn\u00f3rdico, coloca la secci\u00f3n de tallas grandes en un lugar tan escondido que\nnecesitas lupa para encontrarle, aun cuando a manera de disculpa quiero agregar\nque es de las pocas tiendas donde he encontrado ropa atractiva para mi talla,\nes cuesti\u00f3n de hacer un safari en la tienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado hay marcas que se han atrevido a romper\nestereotipos, una de ellas es Nike. 2017 lanz\u00f3 una l\u00ednea que ampliaba las tallas\ndesde XL hasta 3XL. El mes pasado apost\u00f3 por darle una mayor visibilidad con la\ninauguraci\u00f3n de un nuevo espacio en su tienda de Londres, donde se puede\nencontrar ropa deportiva para atletas femeninas plus size e inmediatamente\nsurgieron las cr\u00edticas: \u201cEl nuevo maniqu\u00ed de Nike es inmenso, gigantesco y\njadea de grasa. Es obeso y no se est\u00e1 preparando para correr con su traje de\nNike\u201d, escribi\u00f3 una periodista brit\u00e1nica. Los usuarios de Twitter no tardaron\nen sumarse a un debate sobre c\u00f3mo debe ser un cuerpo saludable que, en el\nfondo, esconde un alegato gordof\u00f3bico, estigma y rechazo social que sufren las\npersonas cuyos cuerpos no se ajustan a las normas de belleza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cVivimos en una\nsociedad hip\u00f3crita que por un lado nos exige a las gordas hacer deporte, pero\ncuando mostramos que hacemos deporte tambi\u00e9n somos criticadas. Es un quiero y\nno puedo, \u00bfquieren que hagamos deporte a escondidas, de noche, cuando nadie nos\nvea para no ser objeto de insultos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte adelgazar no es f\u00e1cil. Te puedo hacer un resumen\nde nutri\u00f3logas, bariatras, m\u00e9dicos en Tuxtla Guti\u00e9rrez, que se dedican a bajar\nde peso, que es lo que hace que con unas funcione y otras no. Hoy hay quienes\ndesencantadas de dietas y masajes han recurrido a operaciones dr\u00e1sticas como el\nby pass, la dona, y etc., que en algunas personas funciona y en otras no, no es\nuna f\u00f3rmula m\u00e1gica el hecho de que te corten medio est\u00f3mago y dices -ya la hice\ntendr\u00e9 el cuerpo de Kate Mildleton, hasta la tumba-, pero resulta que si le\nentras de nuevo a las calor\u00edas y a la grasa puedes recuperar el peso y m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, siempre me he hecho la pregunta, si todos\nlas gorditas y gorditos estamos enfermos, en mi caso no podr\u00eda decir que soy\ntotalmente sana,&nbsp; despu\u00e9s de bailar sones\nchiapanecos, siento que me va a dar un ataque cardiaco, eso despu\u00e9s de chutarme\ndos horas de los \u00c1ngeles Azules, Menudo y la Sonora Margarita, si creo que debo\nmoverme m\u00e1s, los m\u00fasculos se atrofian cuando no los usas, tambi\u00e9n la cabeza y\nla panocha, perd\u00f3n, el cl\u00edtoris, la vulva, la vagina se llenan de telara\u00f1as y\nya no encuentras el punto g.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, hay puntos de vista con los que estoy muy de\nacuerdo, cada vez m\u00e1s psiquiatras y nutricionistas condenan el culto excesivo\nde la delgadez corporal y advierten contra los efectos nefastos de las dietas\ndescontroladas y otra cuesti\u00f3n ni todos las gordas est\u00e1n enfermos ni todos\ncomemos mal, para muestra basta un bot\u00f3n, un d\u00eda me hice una an\u00e1lisis\ncomplet\u00edsimo de sangre, y sal\u00ed s\u00faper saludable frente a unos flacos de mi\noficina con cara beige bur\u00f3crata, con colesterol, la banda de los triglic\u00e9ridos\nya hab\u00eda hecho de las suyas, presi\u00f3n alta, y hasta depresi\u00f3n, pues como no con\nese r\u00e9gimen de comida God\u00ednez y sin disfrutar de la vida, se ten\u00eda que decir y\nse dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y otras observaciones ya que estamos en caliente: \u00bfPor qu\u00e9\npara combatir la obesidad no se bajan los precios de los alimentos saludables o\naumentan los salarios de los m\u00e1s pobres? \u00bfPor qu\u00e9 no se evitan las largas\njornadas laborales, cada vez m\u00e1s sedentarias?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y volviendo a las tallas grandes, ser enormemente bella,\ntiene sus ventajas, regularmente las XXXL casi una pel\u00edcula porno, est\u00e1n en\nbarata, as\u00ed que aprovecha, algunos vestiditos de maternidad no est\u00e1n tan mal,\naprovecha la nueva colecci\u00f3n de Dolce &amp; Gabbana, quienes decidieron ampliar\nlas tallas de sus prendas a partir de su pr\u00f3xima colecci\u00f3n pre fall o sea antes\nde la temporada oto\u00f1al 2020, pasando de tener solo tallas para chicas cero a\nllegar hasta la XXXL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya han recibido su buena tunda v\u00eda Facebook; hay quienes\ndicen vivan las curvis, las mujeres reales y otras que es por negocio, que los\ndise\u00f1os no favorecen a las modelos, pero finalmente ah\u00ed est\u00e1n casas de moda que\nantes ni pensar\u00edan dise\u00f1ar para nosotras lo est\u00e1n haciendo por money o lo que\nsea, ya est\u00e1n ah\u00ed las tallas grandes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No olvidemos comer saludable, caminar es muy barato,\nderrites grasa, usar nuestro chocho como dir\u00edan las espa\u00f1olas y \u00a1ol\u00e9!, que la\nropa no nos apriete el chocho, como aquellos pantalones de mezclilla violadores\nque us\u00e1bamos en los 7Os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y dale a tu cuerpo alegr\u00eda Macarena y antes muerta que\nsencilla\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSomos bellas siendo tal cual somos y con suerte, alg\u00fan d\u00eda seremos viejas y guapas\u201d<\/p>\n","protected":false},"author":3,"featured_media":9630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,118,117],"tags":[],"class_list":["post-9629","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-enriqueta-burelo-melgar","category-por-la-cuarta"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9629"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9630"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}