{"id":9623,"date":"2019-07-09T21:53:28","date_gmt":"2019-07-09T21:53:28","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9623"},"modified":"2023-07-21T14:50:46","modified_gmt":"2023-07-21T19:50:46","slug":"renuncia-titular-de-shcp-indefinicion-en-presupuestos-de-genero","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/renuncia-titular-de-shcp-indefinicion-en-presupuestos-de-genero\/","title":{"rendered":"Renuncia titular de SHCP, indefinici\u00f3n en presupuestos de g\u00e9nero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* Argumenta imposici\u00f3n de funcionarios que desconocen de la Hacienda P\u00fablica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Cierre de estancias infantiles, triple golpe a las mujeres.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Sin claridad sobre el Programa de Igualdad tras desaparici\u00f3n de Proequidad.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sara Lovera y Soledad Jarqu\u00edn<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 9 julio 2019.- A siete meses del inicio del actual gobierno mexicano que encabeza Andr\u00e9s Manuel L\u00f3pez Obrador, esta ma\u00f1ana, a las 11:15, Carlos Manuel Urz\u00faa Mac\u00edas renunci\u00f3 a su cargo como secretario de Hacienda y Cr\u00e9dito P\u00fablico, ser\u00eda el segundo del gabinete en retirarse del encargo asignado en diciembre pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de L\u00f3pez Obrador suma, adem\u00e1s, otras cinco renuncias importantes m\u00e1s, entre ellos, el del titular del IMSS, German Mart\u00ednez C\u00e1zares; la directora de Estancias Infantiles, Clara Torres Armend\u00e1riz, y&nbsp;Sim\u00f3n Levy-Dabbah, subsecretario de Planeaci\u00f3n y Pol\u00edtica Tur\u00edstica de la Secretar\u00eda de Turismo del Gobierno de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ahora ex titular de Hacienda y Cr\u00e9dito P\u00fablico public\u00f3 en su twitter su renuncia, en la que se\u00f1ala:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDiscrepancias en materia econ\u00f3mica hubo muchas. Algunas de ellas porque en esta administraci\u00f3n se han tomado decisiones de pol\u00edtica p\u00fablica sin suficiente sustento. Estoy convencido de que toda pol\u00edtica econ\u00f3mica debe realizarse con base en evidencia, cuidando los diversos efectos que \u00e9sta pueda tener y libre de todo extremismo, sea este de derecha o de izquierda. Sin embargo, durante mi gesti\u00f3n las convicciones anteriores no encontraron eco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAunado a ello, me resulta inaceptable la imposici\u00f3n de funcionarios que no tienen conocimiento de la Hacienda P\u00fablica. Esto fue motivado por personajes influyentes del actual gobierno con aparente conflicto de inter\u00e9s\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, en cuatro p\u00e1rrafos, Urz\u00faa Mac\u00edas deja el cargo, tras agradecer la oportunidad. Una hora despu\u00e9s el gobierno federal anunci\u00f3 el relevo en el cargo al nombrar a Arturo Herrera Guti\u00e9rrez, quien hasta este mismo d\u00eda se desempe\u00f1aba como Subsecretario de Hacienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hacienda \u00bfY las mujeres qu\u00e9?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante estos primeros meses del gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador la pol\u00edtica presupuestaria no ha favorecido a las mujeres, los ejemplos m\u00e1s claros han sido la cancelaci\u00f3n del presupuesto para las estancias infantiles y la otra, la dilaci\u00f3n y no entrega completa de los recursos para refugios para salvaguardar la vida de mujeres que sufren violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el cierre de estancias infantiles se dio a las mujeres un golpe triple: por un lado las trabajadoras no tienen d\u00f3nde dejar a sus hijos lo que impide su desarrollo pleno en el \u00e1mbito laboral y tendr\u00edan que decidir entre lo familiar y lo profesional; por el otro, el despido de miles de mujeres que laboraban en las estancias infantiles de todo el pa\u00eds y finalmente deja a la deriva la educaci\u00f3n infantil en los primeros a\u00f1os vitales para el desarrollo de las ni\u00f1as y ni\u00f1os, como han se\u00f1alado las expertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas estas acciones, adem\u00e1s, son contrarias a las pol\u00edticas p\u00fablicas que en esta materia han puesto en pr\u00e1ctica en los pa\u00edses desarrollados y con una amplia perspectiva de igualdad de oportunidades para mujeres y hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consecuencia, el gobierno federal ha perdido m\u00e1s de cien demandas interpuesta ante los tribunales por el cierre de estas estancias infantiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el otro lado, apenas la semana pasada y luego de una serie de conversaciones, la Red Nacional de Refugios anunci\u00f3 que el 4 de julio se inici\u00f3 la transferencia de recursos de la primera ministraci\u00f3n del presupuesto a 45 refugios y 24 centros de atenci\u00f3n externa, mismo que estaba programado en el Presupuesto de Egresos de la Federaci\u00f3n 2019 y que se pretend\u00eda entregar por parte de las autoridades federales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, como informaron las Redes de Refugios Intercultural y Aut\u00f3nomos, a pesar de haber participado en la convocatoria para ser beneficiadas con el presupuesto establecido en el Anexo 13, Ramo 12, \u201cSubsidios para refugios y centros de atenci\u00f3n externa de refugios para mujeres v\u00edctimas de violencia\u201d, estos recursos no fueron ministrados al resto de los 72 refugios que hay en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el comienzo de la administraci\u00f3n hubo resistencia para los presupuestos para la igualdad; las diputadas rescataron parte de ese presupuesto, pero no se entregaron 90 millones para Proequidad; hubo recortes al programa de violencia, en el Paimef y se prohibi\u00f3 dar recursos a las organizaciones civiles, lo que dej\u00f3 sin apoyos a grupos de mujeres feministas. Est\u00e1 pendiente un programa de emergencia para la violencia. Desaparecieron los recursos para c\u00e1nceres femeninos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los \u201crecortes\u201d al personal de la administraci\u00f3n p\u00fablica afectaron a mayor\u00eda de trabajadoras y se hicieron recortes del personal del Instituto Nacional de las Mujeres (Inmujeres). Y todos los tuvo que aplicar la Secretar\u00eda de Hacienda, como en otros muchos proyectos de diversas instituciones y secretar\u00edas. Como los recortes a Inegi que ponen en riesgo encuestas de salud reproductiva y de condiciones de violencia en los hogares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cierre de estancias infantiles, triple golpe a las mujeres.<\/p>\n","protected":false},"author":3,"featured_media":9624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,51],"tags":[],"class_list":["post-9623","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9623"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9624"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}