{"id":96224,"date":"2025-06-16T14:50:05","date_gmt":"2025-06-16T20:50:05","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=96224"},"modified":"2025-06-16T17:26:50","modified_gmt":"2025-06-16T23:26:50","slug":"mujeres-y-politica-lilia-gemma-fue-asesinada-a-ines-le-quieren-desaparecer-poderes","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujeres-y-politica-lilia-gemma-fue-asesinada-a-ines-le-quieren-desaparecer-poderes\/","title":{"rendered":"Mujeres y pol\u00edtica| Lilia Gemma fue asesinada, a In\u00e9s le quieren desaparecer poderes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Soledad Jarqu\u00edn Edgar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 16 de junio, 2025.- La misoginia pol\u00edtica camina impune. Este domingo fue asesinada la primera presidenta municipal de San Mateo Pi\u00f1as, Lilia Gemma Garc\u00eda Soto y que todo indica podr\u00eda reelegirse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes pasado el Congreso, a trav\u00e9s de la Comisi\u00f3n Permanente de Gobierno y Asuntos Agrarios ten\u00eda previsto declarar procedente la suspensi\u00f3n del Ayuntamiento de Zapotitl\u00e1n Palmas, al haberse iniciado el procedimiento de desaparici\u00f3n. Un municipio que por primera vez es gobernado por una mujer, In\u00e9s L\u00f3pez Mart\u00ednez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY digo llegamos porque no llego sola, llegamos todas\u201d \u00bfse acuerdan? S\u00ed lo dijo Claudia Sheinbaum Pardo en su discurso de toma de protesta (p\u00e1rrafo 18) aquel hist\u00f3rico 1 de octubre del 2024. Quien le vendi\u00f3 esa idea no le mostr\u00f3 el otro lado, la calle oscura, y ella entusiasmada, perdi\u00f3 ese horizonte de violencia que viven cotidianamente las mujeres que no son presidentas, ni senadoras, ni diputadas, ni funcionarias p\u00fablicas de \u201cprimer nivel\u201d, el privilegio del poder que no incluye a las presidentas municipales, regidoras ni s\u00edndicas que despachan en la lejan\u00eda, sin reflectores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es curioso, las dos presidentas municipales fueron electas por sistemas normativos internos, en asambleas comunitarias electas para el periodo 2023-2025. Mientras San Mateo Pi\u00f1as es un referente de los pueblos cafetaleros de Oaxaca, el oro verde y el turismo, Zapotitl\u00e1n Palmas es un lugar donde mujeres y hombres por generaciones se dedican a la agricultura y tejen sombreros y otras artesan\u00edas, all\u00e1 en el basti\u00f3n reiterado de la pobreza, la mixteca oaxaque\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Mateo Pi\u00f1as<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo terrible de lo ocurrido la ma\u00f1ana de este domingo en la poblaci\u00f3n de San Mateo Pi\u00f1as es la presencia cada vez m\u00e1s com\u00fan de sicarios en este tipo de asesinatos. Algo que no se ha querido reconocer por parte de las autoridades, pero el sicariato es desde hace varios a\u00f1os una \u201cactividad\u201d m\u00e1s en Oaxaca como en muchas partes del pa\u00eds, aqu\u00ed en este estado que presume de tranquilidad y paz social, tambi\u00e9n se alquilan para matar y siempre hay quien paga por asesinar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cinco sicarios viajaron en dos motocicletas, vestidos de negro, encapuchados y con armas de alt\u00edsimo poder, en cosa de seis minutos se introdujeron hasta la oficina de la presidenta Lilia Gemma Garc\u00eda Soto para asesinarla, igual que otras autoridades, dispersando en el lugar 60 \u201ccasquillos percutidos\u201d (palabras que son ya del dominio p\u00fablico).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la informaci\u00f3n que este lunes dio a conocer la Fiscal\u00eda de Oaxaca, una de las l\u00edneas de investigaci\u00f3n ser\u00e1 el expresidente municipal, Tom\u00e1s Victorio Garc\u00eda quien fue denunciado por la presidenta Garc\u00eda Soto por el desv\u00edo de 25 millones de pesos que el gobierno federal hab\u00eda destinado a ese municipio para resarcir los da\u00f1os ocurridos por el paso del hurac\u00e1n Agatha que golpe\u00f3 la zona a finales de mayo de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momentos en los que para variar, dice la gente del pueblo, Tom\u00e1s Victorio Garc\u00eda no estaba en el municipio, andaba en una de sus acostumbradas juergas, tanto que fue el s\u00edndico Alejo Ram\u00edrez S\u00e1nchez, artesano, el que hizo frente en aquellas primeras horas, despu\u00e9s se percat\u00f3 que el dinero corr\u00eda hacia una cuenta bancaria ajena al municipio, para quienes tienen corta memoria, hay que recordar que el s\u00edndico tambi\u00e9n fue asesinado en febrero de 2024 en Santa Mar\u00eda Huatulco, casualmente con la intervenci\u00f3n de sicarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hago un par\u00e9ntesis. Si esa es la l\u00ednea de investigaci\u00f3n, en este momento la presidenta municipal estar\u00eda viva. Hay en la prensa local testimonios diversos sobre el desv\u00edo de recursos hechos por varios ex mun\u00edcipes de la zona (que dicen los vecinos solo vieron crecer los ranchitos de los potentados pol\u00edticos) a quienes el sistema de ese momento (PRI estatal, Morena nacional) no tocaron y uno de ellos fue el expresidente municipal Tom\u00e1s Victorio Garc\u00eda que, adem\u00e1s, era como dec\u00eda mi abuelita es \u201cun p\u00e1jaro de cuenta\u201d, adicto a las drogas y otras calamidades. Sobre \u00e9l pesaba una denuncia por tentativa de feminicidio que tampoco \u201cprosper\u00f3\u201d y que dejaron archivado por ah\u00ed en las bodegas de papeles de la Fiscal\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visto desde ese \u00e1ngulo la responsabilidad del asesinato de Lilia Gemma Garc\u00eda Soto tiene mar de fondo y en ese fondo se podr\u00e1 encontrar con nombres y apellidos a quienes lo protegieron, una actividad com\u00fan en el sexenio del gobernador priista y hoy senador morenista Alejandro Murat, y una pr\u00e1ctica que no desaparece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lilia Gemma, licenciada en Sociolog\u00eda, antes de ser presidenta municipal fue presidenta del comit\u00e9 de caminos de su municipio. Su trabajo permanece casi intacto, ni Agatha ni nada le han afectado. Un trabajo bien hecho, tanto que enorgulleci\u00f3 a su pueblo que hoy lamenta su asesinato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella fue la primera presidenta municipal de San Mateo Pi\u00f1as y ser\u00eda reelecta en el mismo cargo. Porque, aunque el pueblo bueno quiera presidentes municipales honestos, nada se puede hacer en contra las mafias del patriarcado que protegen a quienes se roban la tranquilidad, la paz y destrozan familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zapotitl\u00e1n Palmas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En septiembre del a\u00f1o pasado en entrevista para SemM\u00e9xico la presidenta municipal de Zapotitl\u00e1n Palmas denunci\u00f3 al regidor de Hacienda, Dami\u00e1n Reyes Longinos y al s\u00edndico municipal Jos\u00e9 Longinos Mart\u00ednez quienes entre muchas tropel\u00edas tomaron el palacio municipal desde el inicio de la gesti\u00f3n en diciembre del 2023, as\u00ed que ella despacha desde una casa particular; tambi\u00e9n se le atribuye la destrucci\u00f3n de la patrulla, as\u00ed como el cierre sistem\u00e1tico del acceso principal al pueblo impidiendo, incluso, el paso a personal m\u00e9dico que trabajan en la cl\u00ednica y al profesorado de las escuelas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mun\u00edcipe In\u00e9s L\u00f3pez Mart\u00ednez dio muchas vueltas para ser escuchada, Salom\u00f3n Jara prometi\u00f3 ayuda y se dirigi\u00f3 a sus colaboradores para que atendieran el caso, uno de ellos, el secretario de Gobierno, Jos\u00e9 de Jes\u00fas Romero L\u00f3pez, quien ahora ordena a la C\u00e1mara de Diputados que operen la desaparici\u00f3n de poderes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mun\u00edcipe que quiere dejar un buen ejemplo a las mujeres de Zapotitl\u00e1n Palmas ha enviado varias cartas a la presidenta de M\u00e9xico, pero no ha tenido ninguna respuesta, lo que me recuerda a Claudia Uruchurtu, quien tampoco le respondi\u00f3 el entonces presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador y hoy lleva m\u00e1s de cuatro a\u00f1os desaparecida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya lo dijo la diputada Concepci\u00f3n Rueda G\u00f3mez ninguna autoridad volte\u00f3 a ver a la presidenta municipal, se refiri\u00f3 al propio Congreso de Oaxaca, a la Secretar\u00eda de las Mujeres, por supuesto a la Defensor\u00eda de los Derechos Humanos del Pueblo de Oaxaca y claro a la Fiscal\u00eda General de Oaxaca, las mismas dependencias de siempre, que nada hicieron a pesar de que existe una resoluci\u00f3n del Tribunal Estatal Electoral de Oaxaca que se\u00f1ala al regidor de Hacienda y al s\u00edndico por ejercer lo que llaman violencia pol\u00edtica contra las mujeres en raz\u00f3n de g\u00e9nero, un ente escurridizo que nadie puede atrapar y el verdadero origen de lo que hoy quieren ejecutar en el Congreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actuaciones de las instituciones que ya no extra\u00f1an a nadie, todo indica que lo extraordinario ser\u00e1 que un d\u00eda hagan realmente su trabajo, por eso merecidamente la legisladora Rueda G\u00f3mez les dijo una verdad, porque tal parece que la&nbsp; burbuja en la que viven las y los funcionarios les impide o\u00edr: \u201c\u2026los discursos de g\u00e9nero, las fotograf\u00edas en territorio, los pronunciamientos, los mo\u00f1os naranja\u2026son acciones que se derrumban porque este Congreso arrebatar\u00e1 a la primera presidenta municipal de Zapotitl\u00e1n Palmas sus derechos pol\u00edticos\u2026\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Discurso que logr\u00f3 bajar el dictamen 1.17 del orden del d\u00eda o al menos durante la sesi\u00f3n del 10 de junio, con 30 de 42 votos a favor. Pero, sigue en pie, y ser\u00eda lamentable que esta semana el Congreso aprobara ese acto mis\u00f3gino de quitar la presidencia municipal a quien un grupo de machos no quiere por ser mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La orden viene de arriba. Es necesario quitarla de en medio. Un acto mis\u00f3gino tras otro. Primero los se\u00f1ores del pueblo que no se conformaron con ser parte del Cabildo, cuando por ser hombres ellos deber\u00edan mandar y no una se\u00f1ora. Luego un secretario de Gobierno que ve el fil\u00f3n de oro porque al poner un \u201cadministrador\u201d, tipo los viejos tiempos del PRI, podr\u00e1 acceder al dinero que la Secretar\u00eda de Finanzas no ha entregado a la presidenta, violando los derechos pol\u00edticos de la mun\u00edcipe, pero esencialmente, los derechos humanos de las y los habitantes de Zapotitl\u00e1n Palmas, que han sobrevivido a la barbarie del machismo pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos, la ciudadan\u00eda se pregunta \u00bfhasta cu\u00e1ndo la violencia pol\u00edtica se permitir\u00e1? La respuesta es simple, cuando dejen de proteger a los bandidos desde el poder pol\u00edtico y p\u00fablico, o dejen de protegerse entre ellos. Sea qui\u00e9n sea y caiga quien caiga. De lo contrario sumaremos un caso m\u00e1s, tendremos c\u00e1rceles llenas de \u201cpresuntos\u201d autores materiales sin los autores intelectuales de estos hechos que sangran el coraz\u00f3n de muchas familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soledad Jarqu\u00edn Edgar SemM\u00e9xico, Oaxaca, 16 de junio, 2025.- La misoginia pol\u00edtica camina impune. Este domingo fue asesinada la primera presidenta municipal de San Mateo Pi\u00f1as, Lilia Gemma Garc\u00eda Soto y que todo indica podr\u00eda reelegirse. El martes pasado el Congreso, a trav\u00e9s de la Comisi\u00f3n Permanente de Gobierno y Asuntos Agrarios ten\u00eda previsto declarar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[96,35,75],"tags":[],"class_list":["post-96224","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mujeres-y-politica","category-opinion","category-soledad-jarquin-edgar"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=96224"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8460"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=96224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=96224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=96224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}