{"id":96114,"date":"2025-06-13T13:26:26","date_gmt":"2025-06-13T19:26:26","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=96114"},"modified":"2025-06-13T13:26:27","modified_gmt":"2025-06-13T19:26:27","slug":"rafaga-le-crecen-los-enanos-a-la-presidenta-las-elecciones-del-2027-definitorias-del-sexenio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/rafaga-le-crecen-los-enanos-a-la-presidenta-las-elecciones-del-2027-definitorias-del-sexenio\/","title":{"rendered":"R\u00e1faga| Le crecen los enanos a la presidenta. Las elecciones del 2027, definitorias del sexenio."},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Reflexionar en torno a los comicios resientes. Gobernadores y legisladores se empoderan. Hay doce gobernadoras y una jefa en funciones<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Herrera Valenzuela<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 13 de junio, 2025.- A dos a\u00f1os de distancia de la renovaci\u00f3n de la C\u00e1mara de Diputados, la primera presidenta de M\u00e9xico debe analizar detalladamente c\u00f3mo debe mover sus fichas en el tablero de 500 diputaciones y jugarlas para alcanzar la mayor\u00eda de los triunfos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las elecciones intermedias, llamadas as\u00ed por celebrarse a la mitad del sexenio, en el pr\u00f3ximo 2027, son punto definitorio del futuro de la doctora Claudia Sheinbaum Pardo y de la proyecci\u00f3n de los comicios presidenciales, tres a\u00f1os despu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo 6 de junio de 2027 ser\u00e1 clave para la presidenta, si los candidatos a diputados federales no hacen mayor\u00eda \u201c<strong>claudista<\/strong>\u201d, tendr\u00e1 un sombr\u00edo panorama.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 16 Estados se elegir\u00e1n gobernadores y, l\u00f3gico, hay senadores, diputados y hasta presidentes municipales que buscar\u00e1n la candidatura. Estar\u00e1n en juego 669 presidencias municipales. Ser\u00e1n electos mil 88 diputados locales. Total, mil 773 cargos en los tres niveles de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los esca\u00f1os senatoriales tendr\u00e1n nuevos titulares, que tampoco son del equipo de la doctora Sheinbaum Pardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora el equipo cercano de la presidenta carece de operadores pol\u00edticos, de conciliadores y negociadores. Urgen asesores experimentados, te\u00f3ricos y pr\u00e1cticos, que, adem\u00e1s, sean escuchados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es imprescindible que Claudia se d\u00e9 cuenta que se crearon \u201cpolos de poder\u201d y son los gobernadores como Alfonso Durazo Monta\u00f1o, Salom\u00f3n Jara Cruz, Rub\u00e9n Moya Rocha, entre otros, que act\u00faan con absoluta autonom\u00eda o recurren a su verdadero jefe, el que dice vivir en Palenque, dedicado a escribir \u201csu\u201d historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prueba de que ese tr\u00edo no atendi\u00f3 los llamados ni cumpli\u00f3 las \u00f3rdenes, son los p\u00edrricos resultados de las elecciones judiciales. La presidenta les pidi\u00f3, sugiri\u00f3 u orden\u00f3 a los alfiles estatales que movieran a la gente para tener una copiosa votaci\u00f3n, sin reparar en gastos. Otro ejemplo, est\u00e1 en Tabasco donde los electores decidieron no salir a las casillas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conozcan los informes del Instituto Nacional Electoral, \u00fanico escrutador de los votos. Globalmente se habla de 13 millones de sufragios, pero no indican cu\u00e1ntos millones est\u00e1n anulados. Los chairos, en defensa aseguran, que X\u00f3chitl G\u00e1lvez tuvo menos electores a su favor y no lo criticaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A marchas forzadas, \u00a1Ya!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tiempo \u201cest\u00e1 encima\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que estar trabajando ya en la organizaci\u00f3n de las elecciones del 2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es tarea de la jefa del Poder Ejecutivo Federal, en cuanto a qui\u00e9nes ser\u00e1n las candidatas y los candidatos a las 300 curules, por voto popular y la lista de los 200 nombres seleccionados para recibir el regalo de una curul en el Palacio de San L\u00e1zaro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n, el proceso, realizaci\u00f3n, conteo y calificaci\u00f3n de los comicios, es responsabilidad del Instituto Nacional Electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es suponerse que las dirigencias partidistas, de \u201coposici\u00f3n\u201d, tienen sus propios programas para trabajar en las 16 entidades, formar sus cuadros y proyectar candidaturas. Los PETistas y los Verdes est\u00e1n sujetos a lo que diga el jefe tabasque\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La realidad que vivimos y lo que se observa despu\u00e9s de las elecciones judiciales, fue desmenuzada durante una reuni\u00f3n con la doctora Mar\u00eda Eugenia Alejandra del Valle Prieto Ortega, cuyos an\u00e1lisis pol\u00edticos guardan certidumbre cien por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coincidimos, en principio, en que es nulo el apoyo pol\u00edtico para la presidenta de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luisa Mar\u00eda Alcalde Luj\u00e1n, presidenta nacional de Morena, ni idea tiene para desarrollar su funci\u00f3n. Las decisiones fundamentales no las habr\u00e1 de dar ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jam\u00e1s ha estado en una dirigencia electoral. Diputada federal, sin ser militante del MRN ni hizo campa\u00f1a, porque figur\u00f3 en la LXII Legislatura como diputada de representaci\u00f3n proporcional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Claudia debe ser ella, presidenta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados de las elecciones del 1 de junio demuestran que la primerapresidenta de M\u00e9xico no tiene fuerza pol\u00edtica y el Movimiento de Regeneraci\u00f3n Nacional, MRN, convertido en partido pol\u00edtico, internamente est\u00e1 dividido. En m\u00e1s de 20 Estados y en la Ciudad de M\u00e9xico la votaci\u00f3n muy extremadamente baja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia debe tomar las riendas y preparar el terreno para junio de 2027, debe de actuar sin descanso. Un equipo de operadores, todos de ella, de su confianza, habr\u00e1 de recorrer desde municipios hasta el Estado completo para saber qui\u00e9nes pueden ser candidatos a diputados federales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque no tuvo el \u00e9xito que esperaba, \u201cAndy\u201d ya empez\u00f3 a crear su propia estructura y no quitar\u00e1 el dedo del rengl\u00f3n. En el partido que fund\u00f3 y dirige su pap\u00e1. El joven L\u00f3pez Beltr\u00e1n no cuenta con la simpat\u00eda de sus compa\u00f1eros y se sobrevalora. Claudia no puede ponerle freno y arrinconarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pedir que lo llamen por su nombre, Andr\u00e9s Manuel L\u00f3pez Beltr\u00e1n, le rest\u00f3 un buen n\u00famero de seguidores y olvida que no es inteligente, carece de experiencia pol\u00edtica, que no sabe hablar en p\u00fablico, no es audaz y mucho menos carism\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con los informes del Instituto Nacional Electoral, la sorpresa mayor es que en Coahuila, con gobernador PRIista, registr\u00f3 el mayor el porcentaje en las elecciones del 1 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acorde\u00f3n tuvo efecto positivo, porque hasta el oaxaque\u00f1o Hugo Ortiz recibi\u00f3 alta votaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pregunt\u00e9 a mis contactos en Saltillo sobre este hecho y la contestaci\u00f3n un\u00e1nime: \u201cvi en el acorde\u00f3n el nombre de ese se\u00f1or, lo tach\u00e9 en se\u00f1al de voto, no lo conozco ni s\u00e9 de d\u00f3nde sea\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coahuila arroj\u00f3 un porcentaje de 24.25 por ciento y le siguieron con menos del 20 por ciento y superior al 16, Veracruz, Durango, San Luis Potos\u00ed, Chiapas y Oaxaca, lugar de origen del virtual presidente de la Suprema Corte de Justicia de la Naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esos resultados dan margen a la presidenta Sheinbaum Pardo para determinar los pasos que habr\u00e1 de dar, as\u00ed como sus colaboradores enterarse de resultados en 9 entidades encabezadas por Campeche, 14.92 por ciento, hasta Baja California, 9.52 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Definitivamente la atenci\u00f3n principal estar\u00eda en los resultados en la Ciudad de M\u00e9xico y el Estado de M\u00e9xico, gobernado por mujeres morenistas. En la tierra toluque\u00f1a apenas obtuvo el 12.33 por ciento, la mitad de Coahuila. En la Capital Mexicana apenas el 14.76. Edomex tiene el mayor padr\u00f3n nacional electoral y \u201cchilangolandia\u201d es el punto neur\u00e1lgico de todo en el Pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Espada de Damocles pende sobre la jefa de Palacio Nacional. Apartarse de los lineamientos heredados, significa que desde Palenque muevan las fichas, en el Congreso de la Uni\u00f3n, para aplicar el \u201c<strong>mandato de revocaci\u00f3n<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Claudia Sheinbaum Pardo est\u00e1 en el momento de decidir el futuro de uno de los Pa\u00edses m\u00e1s importantes del planeta. Que no crea eso de que \u201c<strong>es la mejor presidenta del mundo<\/strong>\u201d. Lo ser\u00e1, si rompe los eslabones de la cadena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tarea pol\u00edtica nacional tit\u00e1nica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la presidenta Sheinbaum Pardo puede resultar muy dif\u00edcil recorrer el tramo de los pr\u00f3ximos 24 meses, porque dedicarse a gobernar un Pa\u00eds como el nuestro, conlleva m\u00faltiples caminos pedregosos, cruzar vados, atravesar cerros y todo ello requiere un entrenamiento previo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En palabras sencillas, para manejar la pol\u00edtica hay que tener los cimientos y la pr\u00e1ctica para atraer a los electores. Antiguamente se comenzaba desde saber pegar los carteles en las paredes, madrugar para visitar los barrios, las colonias, conocer a los l\u00edderes callejeros del rumbo y convivir con ellos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra presidenta salt\u00f3 de la noche a la ma\u00f1ana a una Delegaci\u00f3n Pol\u00edtica, Tlalpan. Se dice que actu\u00f3 en movimientos estudiantiles. Hizo trabajos burocr\u00e1ticos. Le falt\u00f3 andar en la calle, darse ba\u00f1os de pueblo. Experimentar grupos de aplausos y otros de chiflidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso ahora la tarea, de \u00e1mbito nacional, le es compleja. No hay, a la vista un equipo de colaboradores y la gente que milita en el partido en el poder est\u00e1 a lo suyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Beltr\u00e1n, \u201cno me digan Andy\u201d, no comulga con la presidenta y trabaja \u201cpara su santo\u201d, de acuerdo con las indicaciones paternales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las gubernaturas que estar\u00e1n en juego tienen trascendencia para el a\u00f1o de la sucesi\u00f3n presidencial. No conocer a fondo a los pol\u00edticos estatales, es dejar abierta la puerta para que el gobernador saliente proponga a su candidato o que \u00e9ste sea nominado, aunque no tenga carrera pol\u00edtico-administrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aumenta el poder del mandatario estatal, de ah\u00ed que este comentario period\u00edstico sea titulado \u201ccrecen los enanos\u201d, porque adem\u00e1s cubre los intereses del caciquismo empresarial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad hay 9 gobernadoras y la jefa de Gobierno de la Ciudad de M\u00e9xico, Clara Brugada, pertenecientes al partido en el poder. La excacique de Iztapalapa recientemente perdi\u00f3 a sus dos brazos, los de mayor confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La de Baja California, Marina del Pilar \u00c1vila, est\u00e1 en serios problemas, al serle retirada su visa por el gobierno de Estados Unidos. Se sabe que, en este caso, el enemigo est\u00e1 en casa. El gobierno federal enmudeci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Layda Sansores lleg\u00f3 a la gubernatura para cobrar venganza y los campechanos no est\u00e1n nada contentos; ella no es af\u00edn a la Presidenta de M\u00e9xico. Las mandatarias Indira Vizca\u00edno en Colima y Delfina G\u00f3mez en el Estado de M\u00e9xico no logran demostrar que conocen su responsabilidad. Mara Lezama, de Quintana Roo, dicen, no tiene problemas por sus buenas ligas con los narcos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Guerrero la situaci\u00f3n sigue tan violenta como en Veracruz. Evelyn Salgado no estuvo preparada para ser gobernadora y la zacatecana Roc\u00edo Nahle est\u00e1 en Veracruz por imposici\u00f3n del tabasque\u00f1o. Margarita Gonz\u00e1lez, en Morelos, da los primeros pasos, sin lograr aplicar la justicia al exfubolista Cuauht\u00e9moc Blanco, por el desv\u00edo del erario estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No la conozco personalmente, pero puedo afirmar que Lorena Cu\u00e9llar Cisneros es una brillante gobernadora y goza de la popularidad de sus paisanos los tlaxcaltecas. No est\u00e1 improvisada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una pol\u00edtica de carrera completa: directora estatal del DIF, dos veces diputada local, presidenta municipal de la capital tlaxcalteca, diputada federal, senadora y Delegada del Programa para el Desarrollo en Tlaxcala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es nieta del licenciado Joaqu\u00edn Cisneros Molina, senador, gobernador y secretario particular del presidente Gustavo D\u00edaz Ordaz. Su t\u00edo, Joaqu\u00edn Cisneros Fern\u00e1ndez, fue candidato del PRI a la gubernatura, pero la gan\u00f3 Alfonso S\u00e1nchez Anaya que dej\u00f3 el PRI y lo postul\u00f3 el PRD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tlaxcala ha tenido dos gobernadoras. La primera fue Beatriz Elena Paredes Rangel, segunda gobernadora en el Pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>jherrerav@live.com.mx<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Herrera Valenzuela SemM\u00e9xico, Ciudad de M\u00e9xico, 13 de junio, 2025.- A dos a\u00f1os de distancia de la renovaci\u00f3n de la C\u00e1mara de Diputados, la primera presidenta de M\u00e9xico debe analizar detalladamente c\u00f3mo debe mover sus fichas en el tablero de 500 diputaciones y jugarlas para alcanzar la mayor\u00eda de los triunfos. Las elecciones intermedias, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[94,35,107],"tags":[],"class_list":["post-96114","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jorge-herrera-valenzuela","category-opinion","category-rafaga"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=96114"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/96114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/7843"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=96114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=96114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=96114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}