{"id":9560,"date":"2019-07-08T20:37:55","date_gmt":"2019-07-08T20:37:55","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9560"},"modified":"2023-07-21T14:50:09","modified_gmt":"2023-07-21T19:50:09","slug":"presenta-mc-iniciativa-para-garantizar-servicios-de-salud-a-embarazadas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/presenta-mc-iniciativa-para-garantizar-servicios-de-salud-a-embarazadas\/","title":{"rendered":"Presenta MC iniciativa para garantizar servicios de salud a embarazadas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">* <strong>Pretende acabar con el maltrato y el abuso a embarazadas en las instituciones <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* <strong><em>Proponen que est\u00e9n acompa\u00f1adas durante el parto, post-parto, puerperio e, incluso, si se realizara una ces\u00e1rea <\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lorena Vaniezcot<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 8 julio 2019.- El Grupo Parlamentario\nde Movimiento Ciudadano Senado de la Rep\u00fablica presentaron la iniciativa de\nreforma a los Art\u00edculos 61 Bis y 64 de la Ley General de Salud para garantizar\na las embarazadas el derecho a servicios de salud y estar acompa\u00f1adas durante el\ntrabajo de parto, post-parto y puerperio, incluyendo el procedimiento de\nces\u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue presentada por los seis senadores de\nMovimiento Ciudadano, destaca el derecho de las embarazadas en los t\u00e9rminos a\nque se refiere el Cap\u00edtulo IV del T\u00edtulo Tercero de la ley General de Salud,\nque obliga, adem\u00e1s, a las autoridades y prestadores de servicios de salud a\ninformar clara y oportunamente a las mujeres sobre los derechos antes\ndescritos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunado\na ello, proponen acciones de orientaci\u00f3n y vigilancia\ninstitucional, capacitaci\u00f3n y fomento para la lactancia materna y amamantamiento,\nincentivando a que la leche materna sea alimento exclusivo durante seis meses y\ncomplementario hasta avanzado el segundo a\u00f1o de vida y, en su caso, la ayuda\nalimentaria directa tendiente a mejorar el estado nutricional del grupo materno\ninfantil, adem\u00e1s de impulsar, la instalaci\u00f3n de lactarios en los centros de\ntrabajo de los sectores p\u00fablico y privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al menos un banco de leche humana por cada entidad\nfederativa en alguno de sus establecimientos de salud que cuente con servicios\nneonatales; Acciones para controlar las enfermedades prevenibles por\nvacunaci\u00f3n, los procesos diarreicos y las infecciones respiratorias agudas de\nlos menores de 5 a\u00f1os; Acciones de diagn\u00f3stico y atenci\u00f3n temprana de la\ndisplasia en el desarrollo de cadera, durante el crecimiento y desarrollo de\nlos menores de 5 a\u00f1os, y Acciones de capacitaci\u00f3n para fortalecer la\ncompetencia t\u00e9cnica de las parteras tradicionales, para la atenci\u00f3n del\nembarazo, parto y puerperio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la exposici\u00f3n de motivos se\u00f1alan que la violencia obst\u00e9trica\nes una violaci\u00f3n a los derechos humanos, que se genera\nen el \u00e1mbito de la atenci\u00f3n del embarazo, parto y posparto en los servicios de\nsalud y consiste en cualquier acci\u00f3n u omisi\u00f3n por parte del personal que cause\nun da\u00f1o f\u00edsico y\/o psicol\u00f3gico a la mujer durante el embarazo, parto y\npuerperio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Violencia que se exresa en la falta de\nacceso a servicios de salud reproductiva, en un trato cruel, inhumano o\ndegradante, o en un abuso de medicalizaci\u00f3n, o menoscabado de su capacidad para\ndecidir de manera libre e informada sobre los procesos reproductivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se han\nidentificado dos modalidades de violencia obst\u00e9trica; por un lado, la f\u00edsica,\nque se configura cuando se realizan pr\u00e1cticas invasivas o el suministro de medicamentos\nno justificados por el estado de salud, o cuando no se respetan los tiempos ni\nlas posibilidades del parto biol\u00f3gico, y por otro lado, la psicol\u00f3gica, que\nincluye el trato deshumanizado, grosero, discriminatorio o humillante en el\ntranscurso de una pr\u00e1ctica obst\u00e9trica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las\nreferencias que contiene la iniciativa destaca la revisi\u00f3n Cochrane titulada\n\u201cApoyo continuo para las mujeres durante el parto\u201d, que se se\u00f1ala que \u201ces\nfrecuente ver en hospitales de pa\u00edses de medianos ingresos, especialmente en\nAm\u00e9rica Latina, a mujeres en trabajo de parto sin apoyo y bajo un modelo de\natenci\u00f3n medicalizado y deshumanizado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el\nmodelo de atenci\u00f3n prevalente en zonas urbanas, donde actualmente reside m\u00e1s\ndel 70 por ciento de la poblaci\u00f3n. En la actualidad, en M\u00e9xico m\u00e1s del 90 por\nciento de las mujeres que viven en las grandes ciudades tienen su parto en\nhospitales\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico,\nestudios realizados en los servicios de salud que brindan atenci\u00f3n\nginecobst\u00e9trica destacan que la proporci\u00f3n de mujeres que reportaron alg\u00fan tipo\nde abuso durante el trabajo de parto fue del 29 por ciento. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo,\ncon la Organizaci\u00f3n Mundial de la Salud, todos los d\u00edas mueren 830 mujeres en\nel mundo por causas relacionadas con el embarazo y el parto. Un 99 por ciento\nde la mortalidad materna corresponde a los pa\u00edses en desarrollo, y un\nporcentaje muy alto est\u00e1 relacionado con situaciones de vulnerabilidad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En muchos\ncasos, las fallas estructurales del sistema de salud se combinan con conductas\nde maltrato de parte del personal m\u00e9dico hacia las mujeres y sus familias. La\nviolencia obst\u00e9trica no constituye otra cosa m\u00e1s que una violaci\u00f3n al derecho a\nla vida, la salud, la igualdad y la no discriminaci\u00f3n, a la vida privada, a no\nser sometida a tratos crueles e inhumanos, y al goce de los beneficios del\nprogreso cient\u00edfico y tecnol\u00f3gico. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Refieren\ntambi\u00e9n al caso presentado por el Grupo de Informaci\u00f3n en Reproducci\u00f3n Elegida\n(GIRE) el pasado 27 de febrero, donde se ilustra \u201cla triste realidad que\nenfrentan muchas mujeres durante el parto\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los\naproximadamente 140 millones de nacimientos que ocurren a nivel mundial cada\na\u00f1o se dan en mujeres que no presentan factores de riesgo de tener\ncomplicaciones para ellas ni para sus beb\u00e9s, sin embargo, el momento del\nnacimiento es cr\u00edtico, ya que el riesgo de morbimortalidad puede aumentar\nconsiderablemente si surgen complicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello es\nfundamental contar con protocolos y mecanismos adecuados para impedir cualquier\npr\u00e1ctica m\u00e9dica que menoscabe los derechos y la salud de las mujeres. Muchas\nmujeres mueren de complicaciones que se producen durante el embarazo y el parto\no despu\u00e9s de ellos, y la mayor\u00eda de estos casos son prevenibles o tratables. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales\ncomplicaciones, causantes del 75 por ciento de las muertes maternas, son: las\nhemorragias graves (en su mayor\u00eda tras el parto), las infecciones (generalmente\ntras el parto), la hipertensi\u00f3n gestional (preeclampsia y eclampsia), y los\nabortos peligrosos. Las dem\u00e1s est\u00e1n asociadas a enfermedades como el paludismo\no la infecci\u00f3n por VIH en el embarazo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las\nRecomendaciones de la OMS, se\u00f1ala que, durante todo el trabajo de parto y el\nnacimiento, la mujer cuente con acompa\u00f1amiento por parte de una persona de su\nelecci\u00f3n, dado que ello contribuye a una experiencia de parto positiva y en un\nambiente seguro desde el punto de vista cl\u00ednico y psicol\u00f3gico. Es decir, estar\nacompa\u00f1ada en el momento del nacimiento y ser asistida por personal amable y\ncon competencias t\u00e9cnicas adecuadas, conlleva contar con apoyo pr\u00e1ctico y\nemocional continuo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es fundamental reconocer\nque el abuso por parte del personal de salud es una pr\u00e1ctica que existe en\nnuestro sistema y no puede ser normalizada. Resulta urgente este reconocimiento\npara plantear alternativas que puedan aplicarse a cabalidad en las diferentes\ninstituciones de salud.&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atendiendo las\nrecomendaciones de la OMS, para que el parto este centrado en la mujer y en el\nrespeto a sus decisiones, se requiere adecuar la Ley General de Salud para\nposibilitar que toda mujer embarazada pueda estar acompa\u00f1ada por alguien de su\nconfianza, que ella elija, siempre y cuando se tomen en cuenta las\ndisposiciones de vigilancia sanitaria y epidemiol\u00f3gica establecidas por la\nSecretar\u00eda.&nbsp;&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa es firmada por las y los senadores Ver\u00f3nica Delgadillo Garc\u00eda, Clemente Casta\u00f1eda Hoeflich, Patricia Mercado Castro, Samuel Garc\u00eda Sep\u00falveda, Indira Kempis Mart\u00ednez, Juan Qui\u00f1ones Ruiz, No\u00e9 Fernando Casta\u00f1\u00f3n Ram\u00edrez y Dante Delgado Rannauro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El siguiente cuadro comparativo muestra los cambios que propone la presente iniciativa: <\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td>\n  <strong>LEY\n  GENERAL DE SALUD<\/strong>\n  <\/td><\/tr><tr><td>\n  <strong>Texto\n  vigente<\/strong>\n  <\/td><td>\n  <strong>Propuesta\n  de modificaci\u00f3n<\/strong>\n  <\/td><\/tr><tr><td>\n  <strong>Art\u00edculo\n  61 Bis.\u2013 <\/strong>Toda mujer embarazada, tiene derecho a obtener\n  servicios de salud en los t\u00e9rminos a que se refiere el Cap\u00edtulo IV del T\u00edtulo\n  Tercero de esta Ley y con estricto respeto de sus derechos humanos. \n  &nbsp;\n  SIN CORRELATIVO\n  <\/td><td>\n  <strong>Art\u00edculo\n  61 Bis.\u2013 <\/strong>Toda mujer embarazada, tiene derecho a obtener\n  servicios de salud en los t\u00e9rminos a que se refiere el Cap\u00edtulo IV del T\u00edtulo\n  Tercero de esta Ley y con estricto respeto de sus derechos humanos.\n  <strong>&nbsp;<\/strong>\n  <strong>Durante\n  la prestaci\u00f3n de los servicios de salud, la mujer embarazada tendr\u00e1 derecho a\n  estar acompa\u00f1ada en todo momento por una persona de su confianza que ella\n  libremente elija, de conformidad con las disposiciones que a tal efecto emita\n  la Secretar\u00eda para garantizar el ejercicio de este derecho en cumplimiento a\n  lo establecido por la presente Ley para la prevenci\u00f3n y control de\n  enfermedades y accidentes. Es obligaci\u00f3n de las autoridades y prestadores de\n  los servicios de salud informar clara y oportunamente a la mujer embarazada\n  de este derecho.<\/strong>\n  <strong>&nbsp;<\/strong>\n  <\/td><\/tr><tr><td>\n  <strong>Art\u00edculo\n  64.-<\/strong> En la organizaci\u00f3n y operaci\u00f3n de los servicios\n  de salud destinados a la atenci\u00f3n materno-infantil, las autoridades sanitarias\n  competentes establecer\u00e1n:\n  &nbsp;\n  I. \u2026\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  &nbsp;\n  II. Acciones de orientaci\u00f3n y vigilancia institucional,\n  capacitaci\u00f3n y fomento para la lactancia materna y amamantamiento, incentivando\n  a que la leche materna sea alimento exclusivo durante seis meses y complementario\n  hasta avanzado el segundo a\u00f1o de vida y, en su caso, la ayuda alimentaria\n  directa tendiente a mejorar el estado nutricional del grupo materno infantil,\n  adem\u00e1s de impulsar, la instalaci\u00f3n de lactarios en los centros de trabajo de\n  los sectores p\u00fablico y privado; \n  &nbsp;\n  II Bis.&nbsp;\n  Al menos un banco de leche humana por cada entidad federativa en\n  alguno de sus establecimientos de salud que cuente con servicios neonatales;\n  &nbsp;\n  III. Acciones para controlar las enfermedades\n  prevenibles por vacunaci\u00f3n, los procesos diarreicos y las infecciones respiratorias\n  agudas de los menores de 5 a\u00f1os, y\n  &nbsp;\n  III Bis. Acciones de diagn\u00f3stico y\n  atenci\u00f3n temprana de la displasia en el desarrollo de cadera, durante el\n  crecimiento y desarrollo de los menores de 5 a\u00f1os, y\n  &nbsp;\n  IV. Acciones de capacitaci\u00f3n para\n  fortalecer la competencia t\u00e9cnica de las parteras tradicionales, para la\n  atenci\u00f3n del embarazo, parto y puerperio.\n  <\/td><td>\n  <strong>Art\u00edculo\n  64.- <\/strong>En la organizaci\u00f3n y operaci\u00f3n de los servicios\n  de salud destinados a la atenci\u00f3n materno-infantil, las autoridades\n  sanitarias competentes establecer\u00e1n:\n  <strong>&nbsp;<\/strong>\n  I. \u2026\n  <strong>&nbsp;<\/strong>\n  <strong>II.\n  Acciones para informar a las mujeres embarazadas el derecho de estar\n  acompa\u00f1ada por una persona de su confianza y elecci\u00f3n durante el trabajo de\n  parto, post-parto y puerperio, incluyendo el procedimiento de ces\u00e1rea; <\/strong>\n  <strong>&nbsp;<\/strong>\n  <strong>II\n  Bis. Acciones que posibiliten el acompa\u00f1amiento de las mujeres embarazadas\n  por una persona de su confianza y elecci\u00f3n durante el trabajo de parto,\n  post-parto y puerperio, incluyendo el procedimiento de ces\u00e1rea, en las\n  instituciones de salud p\u00fablicas y privadas;<\/strong>\n  <strong>&nbsp;<\/strong>\n  <strong>II.\n  Ter. <\/strong>Acciones de orientaci\u00f3n y vigilancia institucional,\n  capacitaci\u00f3n y fomento para la lactancia materna y amamantamiento, incentivando\n  a que la leche materna sea alimento exclusivo durante seis meses y complementario\n  hasta avanzado el segundo a\u00f1o de vida y, en su caso, la ayuda alimentaria\n  directa tendiente a mejorar el estado nutricional del grupo materno infantil,\n  adem\u00e1s de impulsar, la instalaci\u00f3n de lactarios en los centros de trabajo de\n  los sectores p\u00fablico y privado;\n  <strong>&nbsp;<\/strong>\n  <strong>III.<\/strong>&nbsp; Al menos un banco de leche humana por cada\n  entidad federativa en alguno de sus establecimientos de salud que cuente con\n  servicios neonatales;\n  &nbsp;\n  <strong>IV.<\/strong>\n  Acciones para controlar las enfermedades prevenibles por vacunaci\u00f3n, los\n  procesos diarreicos y las infecciones respiratorias agudas de los menores de\n  5 a\u00f1os, y\n  &nbsp;\n  <strong>V.<\/strong>\n  Acciones de diagn\u00f3stico y atenci\u00f3n temprana de la displasia en el desarrollo\n  de cadera, durante el crecimiento y desarrollo de los menores de 5 a\u00f1os, y\n  &nbsp;\n  <strong>VI.<\/strong>\n  Acciones de capacitaci\u00f3n para fortalecer la competencia t\u00e9cnica de las\n  parteras tradicionales, para la atenci\u00f3n del embarazo, parto y puerperio.\n  <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lv\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pretende acabar con el maltrato y el abuso a embarazadas en las instituciones<\/p>\n","protected":false},"author":3,"featured_media":9561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,50],"tags":[],"class_list":["post-9560","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9560"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9561"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}