{"id":95521,"date":"2025-05-23T18:41:43","date_gmt":"2025-05-24T00:41:43","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=95521"},"modified":"2025-05-23T18:41:44","modified_gmt":"2025-05-24T00:41:44","slug":"mujeres-y-politica-asesinatos-carne-asada-y-elecciones-sucias","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujeres-y-politica-asesinatos-carne-asada-y-elecciones-sucias\/","title":{"rendered":"Mujeres y Pol\u00edtica| Asesinatos, carne asada y elecciones sucias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Soledad Jarqu\u00edn Edgar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 23 de mayo, 2025.- Semana dif\u00edcil. Asesinatos de colaboradores de la jefa de gobierno en la Ciudad de M\u00e9xico y de una periodista en Veracruz, el \u201centra\u00f1able\u201d M\u00e9xico violento que nos muestra dos escenarios distintos y con pesos diferentes en los medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia Sheinbaum estaba muy apurada en limpiar el tiradero que dej\u00f3 la noticia de que los vecinos del norte le quitaron la visa a la mandataria de Baja California, cuando le lleg\u00f3 la noticia del asesinato de los dos funcionarios cercanos a Clara Brugada, su secretaria particular Ximena Guzm\u00e1n y su asesor Jos\u00e9 Mu\u00f1oz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este doble asesinato directo, ejecutado por un sicario, abre todo un laberinto de suposiciones por parte de los comunes mortales, porque all\u00e1 adentro, saben bien de d\u00f3nde y por qu\u00e9 vino el ataque. La violencia que azota cada d\u00eda a este M\u00e9xico violento les toc\u00f3 la puerta a quienes deciden el rumbo del pa\u00eds. Ojal\u00e1 que este crimen no se quede en la impunidad, ser\u00eda terrible que uno de los flagelos m\u00e1s grandes de la justicia tambi\u00e9n los avasallara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veracruz violento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avisack Douglas, quien formaba parte del equipo de trabajo de X\u00f3chitl Tress, candidata a la presidencia municipal de Juan Rodr\u00edguez Clara, fue asesinada la noche del martes, cuando la casa de campa\u00f1a de la emecista fue atacada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos hablando del mismo martes violento 20 de mayo. La fot\u00f3grafa y periodista es parte de una lista que no deber\u00eda existir. Art\u00edculo 19 document\u00f3 el asesinato de Jos\u00e9 Carlos Gonz\u00e1lez Herrera, el pasado 15 de mayo, en Guerrero, \u201ccomo el caso m\u00e1s reciente\u201d. Sin embargo, cinco d\u00edas fue asesinada Avisack Douglas. La acumulaci\u00f3n de cr\u00edmenes contra periodistas y pol\u00edticos de todos los niveles a lo largo y ancho del pa\u00eds, ha endurecido la piel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informar ha sido una tarea dif\u00edcil en M\u00e9xico y conste que ya lo dijimos antes, cuando el crimen organizado est\u00e1 presente, el peligro aumenta sustancialmente. Incluso esta semana Adela Navarro Bello, codirectora general del semanario ZETA, recibi\u00f3 amenazas telef\u00f3nicas. Ya se encendieron las alarmas porque el clima est\u00e1 muy revuelto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Salom\u00f3n le mete mano a la elecci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son 35 las y los candidatos &#8211; ministros-ministras, magistradas-magistrados y jueces-juezas- por los que el gobernador Salom\u00f3n Jara Cruz llama a votar en un claro delito electoral, lo que revela, una vez m\u00e1s, que el mandatario oaxaque\u00f1o, no tiene ni la m\u00e1s m\u00ednima idea de su chamba y volvemos con ese hecho a lo mismo de siempre y de lo que muchos militantes se quejaron siempre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese al des\u00e1nimo que existe por parte de las y los votantes, porque ni idea tienen ni idea de por qui\u00e9nes podr\u00edan votar, el oaxaque\u00f1o ofreci\u00f3 entregar unos miles votos a modo. Por ello anda en campa\u00f1a de promoci\u00f3n del voto, pero m\u00e1s que eso, se\u00f1ala abiertamente en \u201csu acorde\u00f3n\u201d, como ya le llaman a su papelito, por qui\u00e9n deben votar y como si fuera cadenita de oraci\u00f3n, los fieles est\u00e1n dispuestos a hacer realidad el sue\u00f1o del gobernador, a cambio de una m\u00f3dica cantidad (150 pesos).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"857\" height=\"995\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon.jpg\" alt=\"\" class=\"wp-image-95522\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon.jpg 857w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon-258x300.jpg 258w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon-768x892.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon-150x174.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon-300x348.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/el-acordeon-de-Salomon-696x808.jpg 696w\" sizes=\"auto, (max-width: 857px) 100vw, 857px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n trascendi\u00f3 en los medios locales y se difundi\u00f3 en redes sociales estos dos \u00faltimos d\u00edas, y s\u00ed la hemos verificado, testigos afirman que s\u00ed hubo reuni\u00f3n y ah\u00ed les dijeron a los mun\u00edcipes de Valles Centrales lo que ten\u00edan que hacer. Pero Salom\u00f3n no es el \u00fanico empe\u00f1ado en dirigir el voto de la ciudadan\u00eda, tambi\u00e9n est\u00e1 en eso el secretario municipal de Oaxaca de Ju\u00e1rez, es decir, Amador Jara Cruz, el hermano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tipo de hechos asesinan la democracia mexicana. El INE tendr\u00e1 que responder porque hay m\u00e1s de tres mil almas haciendo su luchita para ser electos y electas, pero la lista buena (al menos para Oaxaca) son solo 35, l\u00e1stima que algunas candidatas se hayan prestado a semejante simulaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"650\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-1024x650.jpg\" alt=\"\" class=\"wp-image-95524\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-1024x650.jpg 1024w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-300x191.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-768x488.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-150x95.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-696x442.jpg 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar-1068x678.jpg 1068w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/05\/lista-para-apuntar.jpg 1417w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carnita asada con sal marina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, Marina del Pilar \u00c1vila Olmeda es una gobernadora en aprietos, porque le gusta la falluca rusa y eso al presidente norteamericano le pone sus amarillos pelos de punta. El retiro de la visa fue la gota que derram\u00f3 el vaso del hartazgo de la ciudadan\u00eda bajacaliforniana, que para desahogarse armaron una singular pachanga que les qued\u00f3 para chuparse los dedos, con una carnita asada, y a la que ella responde con una fiesta en Tijuana y a la que la burocracia del poder ejecutivo est\u00e1 instruida para no faltar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La molestia no es nueva y cada d\u00eda suma m\u00e1s adeptos, porque los bajacalifornianos ven como su principal preocupaci\u00f3n la falta de seguridad y la ligereza de la gobernadora de esta entidad fronteriza que en el fondo no ha explicado por qu\u00e9 le quitaron la visa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras en el sureste del pa\u00eds y la propia presidenta Sheinbaum esperan que el magisterio que bloquea aqu\u00ed y all\u00e1 en la ciudad de M\u00e9xico y hasta impide el paso a la reina de las conferencias de prensa, es decir, la Ma\u00f1anera del Pueblo, tambi\u00e9n hagan una buena carne asada, lo cual se les agradecer\u00eda m\u00e1s y a lo mejor as\u00ed se pueden sentar a dialogar con las y los maestros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soledad Jarqu\u00edn Edgar SemM\u00e9xico, Oaxaca, 23 de mayo, 2025.- Semana dif\u00edcil. Asesinatos de colaboradores de la jefa de gobierno en la Ciudad de M\u00e9xico y de una periodista en Veracruz, el \u201centra\u00f1able\u201d M\u00e9xico violento que nos muestra dos escenarios distintos y con pesos diferentes en los medios de comunicaci\u00f3n. Claudia Sheinbaum estaba muy apurada en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[96,35,75],"tags":[],"class_list":["post-95521","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mujeres-y-politica","category-opinion","category-soledad-jarquin-edgar"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/95521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=95521"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/95521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/69812"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=95521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=95521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=95521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}