{"id":95483,"date":"2025-05-22T18:52:38","date_gmt":"2025-05-23T00:52:38","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=95483"},"modified":"2025-05-22T22:17:13","modified_gmt":"2025-05-23T04:17:13","slug":"acompanamiento-a-familiares-de-desaparecidos-se-compromete-cndh-ante-madres-buscadoras-de-sonora","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/acompanamiento-a-familiares-de-desaparecidos-se-compromete-cndh-ante-madres-buscadoras-de-sonora\/","title":{"rendered":"Acompa\u00f1amiento a familiares de desaparecidos se compromete CNDH ante madres buscadoras de Sonora\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Micaela M\u00e1rquez&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. M\u00e9xico, 22 de mayo, 2025.- La Comisi\u00f3n Nacional de Derechos Humanos se comprometi\u00f3 a atender las demandas y peticiones del colectivo Madres Buscadoras de Sonora as\u00ed como respaldar sus esfuerzos por localizar a sus familiares en el di\u00e1logo que han establecido.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosario Piedra Ibarra, presidenta de la CNDH, en la segunda reuni\u00f3n con Cecilia Patricia Flores reitero el compromiso de revisar las quejas que ante el organismo ha interpuesto para darles continuidad y que los funcionarios que no act\u00faen de acuerdo como defensores de los derechos humanos no tendr\u00e1n cabida, expres\u00f3 por las quejas espec\u00edficamente dirigidas al desempe\u00f1o de una persona titular, misma que est\u00e1 ya en tr\u00e1mite y ser\u00e1 desahogada como corresponde por el \u00d3rgano Interno de Control.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el di\u00e1logo, Ceci Patricia Flores e integrantes de su colectivo expusieron sus principales preocupaciones como el acompa\u00f1amiento y la presencia de autoridades en las b\u00fasquedas de sus familiares desaparecidos y el fortalecimiento de las medidas de protecci\u00f3n para periodistas y defensores de derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se acord\u00f3 que la CNDH revisar\u00e1 las quejas que previamente hab\u00edan sido presentadas al respecto y se les brindar\u00e1 la atenci\u00f3n y el acompa\u00f1amiento pertinentes.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta Piedra Ibarra reiter\u00f3 el compromiso de la CNDH con el colectivo para atender sus demandas y reconoci\u00f3 la relevancia de su esfuerzo para impulsar este espacio de di\u00e1logo. Asimismo se comprometi\u00f3 a que todo el personal del organismo ser\u00e1&nbsp; consecuente y privilegiar\u00e1n el compromiso con las v\u00edctimas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al destacarse la importancia de sumar esfuerzos en estos asuntos tan sensibles, se reiter\u00f3 la disposici\u00f3n de este organismo para agotar los recursos a su alcance para apoyar a todas las personas que soliciten su intervenci\u00f3n, atendiendo y acompa\u00f1ando a las v\u00edctimas y a sus familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dialogo se estableci\u00f3 el pasado 13 de mayo cuando Cecilia Patricia Flores ingreso sin autorizaci\u00f3n a las instalaciones de la CNDH junto con su hija Milagros y despu\u00e9s de algunos percances fue recibida por la presidenta Rosario Piedra Ibarra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvieron en el encuentro, la directora general de la Primera Visitadur\u00eda, Claudia Esperanza Franco Mart\u00ednez; el director general de la Sexta Visitadur\u00eda, \u00c1lvaro Romeo Cartagena Rivero; el director de Protecci\u00f3n y Defensa, Edgar Alejandro Mart\u00ednez Vargas, y la directora del Programa Especial de Personas Desaparecidas (PERDES), Jazm\u00edn Cisneros L\u00f3pez, quienes se comprometieron a dar seguimiento a todos los acuerdos y asuntos planteados.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Micaela M\u00e1rquez&nbsp; SemM\u00e9xico, Cd. M\u00e9xico, 22 de mayo, 2025.- La Comisi\u00f3n Nacional de Derechos Humanos se comprometi\u00f3 a atender las demandas y peticiones del colectivo Madres Buscadoras de Sonora as\u00ed como respaldar sus esfuerzos por localizar a sus familiares en el di\u00e1logo que han establecido.&nbsp; Rosario Piedra Ibarra, presidenta de la CNDH, en la segunda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":95484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[682],"tags":[],"class_list":["post-95483","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/95483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=95483"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/95483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/95484"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=95483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=95483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=95483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}