{"id":94790,"date":"2025-04-23T16:54:41","date_gmt":"2025-04-23T22:54:41","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=94790"},"modified":"2025-04-23T16:54:42","modified_gmt":"2025-04-23T22:54:42","slug":"deplorable-la-condicion-de-las-mujeres-en-veracruz-que-habra-de-enfrentar-la-nueva-directora-el-instituto-veracruzano-de-la-mujer","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/deplorable-la-condicion-de-las-mujeres-en-veracruz-que-habra-de-enfrentar-la-nueva-directora-el-instituto-veracruzano-de-la-mujer\/","title":{"rendered":"Deplorable la condici\u00f3n de las mujeres en Veracruz que habr\u00e1 de enfrentar la nueva\u00a0 \u00a0 \u00a0 \u00a0directora el Instituto Veracruzano de la Mujer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este martes la gobernadora de Veracruz design\u00f3 a Zaira del Toro Olivares como Directora del IVM<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era la encargada de la direcci\u00f3n,&nbsp; funcionaria y &nbsp; acad\u00e9mica, sin historia de activista ni feminista militante&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lucha por la justicia y por la vida de las personas desaparecidas contin\u00faa siendo una prioridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/, Xalapa, Ver., 23 de abril, 2025.-&nbsp; Luego de que el Instituto Veracruzano de las Mujeres (IVM) oper\u00f3 durante m\u00e1s de 7 a\u00f1os fuera de la ley, este martes 22 de abril la gobernadora de Veracruz, Roc\u00edo Nahle Garc\u00eda nombr\u00f3 a&nbsp; Zaira Del Toro Olivares como su nueva Directora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria estatal expres\u00f3 que segura est\u00e1 que desempe\u00f1ar\u00e1 la encomienda dignamente, con compromiso, profesionalismo y responsabilidad, mirando en todo momento por el respeto y promoci\u00f3n de los Derechos Humanos de las mujeres veracruzanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En comunicado el Gobierno de Veracruz dio a conocer que se fortalecer\u00e1n las pol\u00edticas de igualdad con&nbsp; el nuevo nombramiento y reiter\u00f3 el compromiso con la igualdad sustantiva y el fortalecimiento institucional del IVM como pieza clave en la atenci\u00f3n, protecci\u00f3n y empoderamiento de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veracruzanas en la peor situaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva directora enfrentar\u00e1 una situaci\u00f3n compleja, en una entidad con grandes rezagos respecto de la condici\u00f3n y los derechos humanos de las veracruzanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3lo en inseguridad&nbsp; y violencia los datos son contundentes. Apenas antier el INEGI inform\u00f3 del aumento de percepci\u00f3n de inseguridad entre mujeres de la&nbsp; entidad, se reporta el mayor n\u00famero de ni\u00f1as que viven violencia y&nbsp; embarazo temprano; hay un acumulado de casos de feminicidio en la impunidad y no obstante que el aborto es legal desde 2021, las veracruzanas son obstaculizadas para ejercer este derecho.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comunicado establece que : \u201cEn cumplimiento con la Ley 613 que crea el Instituto Veracruzano de las Mujeres (IVM), y tras un proceso transparente y democr\u00e1tico liderado por los consejos Consultivo y Social, la gobernadora Roc\u00edo Nahle Garc\u00eda, design\u00f3 a Zaira Fabiola del Toro Olivares como nueva Directora General\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n fue tomada por la jefa del ejecutivo luego de recibir formalmente la terna de candidatas que cumplieron con todos los requisitos legales establecidos, reconociendo el compromiso de los consejos para llevar a cabo este proceso con total imparcialidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Envi\u00f3 un oficio al consejo consultivo e igualmente incluy\u00f3 el punto de vista sobre su decisi\u00f3n. Ten\u00eda tres candidatas, las que seg\u00fan la Consejera Martha Mendoza Parissi, fueron consideradas como de igual capacidad y compromiso.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXfAOHfetasdemFX8Q85dnzvDIKrf0gMRMyKmt4bgnMXLVcWbY18AEWn2Ot38VkY3wRHPK6cMNR1ohZ7WuuzfOM4rDto7Grne5__5uj6dqc-rp73YFYhhv5moBqbddTQOcX6ZnrervKJBXtjaI3UdgY?key=j0bsJgJ1KE67KOo6LXaCfqpJ\" alt=\"Zaira del Toro Olivares, nueva directora del Instituto Veracruzano de la Mujer\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En Veracruz viven m\u00e1s de 4 millones de mujeres&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2025, la regi\u00f3n centro de Veracruz ha experimentado una alta incidencia de desapariciones de mujeres, con 417 casos registrados.&nbsp;A nivel estatal, se han reportado 133 personas localizadas con vida, de las cuales 57 son mujeres.&nbsp;Adem\u00e1s, 127 municipios veracruzanos han registrado al menos una desaparici\u00f3n de mujer.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la 3a entidad con mayor cantidad de ni\u00f1as, ni\u00f1os y adolescentes atendidas en hospitales por violencias de tipo familiar y sexual&nbsp;en 2023 (Salud, 2024); La 3a entidad con mayor porcentaje de personas de 5 a 17 a\u00f1os en condici\u00f3n de trabajo infantil en 2022 (INEGI, 2023).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;<\/em>Veracruz ocupa el tercer lugar a nivel nacional en casos de embarazo infantil, para los Servicios de Salud de Veracruz (Sesver), todos los embarazos en ni\u00f1as y adolescentes de entre 10 y 19 a\u00f1os se consideran de alto riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00e1ctica del&nbsp;aborto en Veracruz es legal desde 2021, pero la falta informaci\u00f3n y las trabas que pone el&nbsp;personal de salud&nbsp;p\u00fablica propicia que las mujeres tengan dificultades para acceder al servicio y que busquen otras v\u00edas para poder realizarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Actualmente, el&nbsp;C\u00f3digo Penal&nbsp;del estado de&nbsp;considera legal el aborto hasta las 12 semanas, as\u00ed como por violaci\u00f3n, peligro de salud de la madre o malformaciones del feto (sin l\u00edmite de tiempo para estas causales), pero la realidad supera las disposiciones legales, pues las entidades de salud p\u00fablica no garantizan el derecho de las mujeres a interrumpir un embarazo no deseado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la entidad, de marzo 2024 \u2013 marzo 2025, la percepci\u00f3n de inseguridad aument\u00f3: el puerto de Veracruz, pas\u00f3 de 55.7% a 59.7%; el puerto de Coatzacoalcos, pas\u00f3 de 76.2% 79.1% y la Capital Xalapa, de 57.3%, pas\u00f3 a 59.7%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Encuesta Nacional de Seguridad P\u00fablica Urbana (ENSU) del INEGI, publicada este martes&nbsp; abril, arroj\u00f3 que en M\u00e9xico hubo un ligero aumento en la percepci\u00f3n de inseguridad entre los pobladores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2025, las mujeres pol\u00edticas en Veracruz siguen siendo v\u00edctimas de violencia, especialmente en el \u00e1mbito local.&nbsp;El Tribunal Electoral de Veracruz no ha recibido denuncias de violencia de g\u00e9nero relacionadas con la paridad en las elecciones, lo que sugiere que muchas mujeres a\u00fan se sienten inseguras y no se atreven a participar.&nbsp;La violencia psicol\u00f3gica y f\u00edsica son las m\u00e1s comunes, y se han registrado casos de violencia pol\u00edtica en ayuntamientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un&nbsp; estudio del IMCO revela que 53 por ciento de las mujeres veracruzanas viven en pobreza laboral, lo que significa que sus ingresos no son suficientes para cubrir el costo de la canasta b\u00e1sica. Adem\u00e1s, el 37.8 por ciento no reciben ingresos monetarios directos, lo que resalta la precariedad econ\u00f3mica que enfrentan muchas mujeres en el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Detalles adicionales:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ni\u00f1as y adolescentes desaparecidas:<\/strong>\u00a0Se han reportado 1,054 ni\u00f1as, ni\u00f1os y adolescentes como desaparecidos o no localizados, de los cuales 14 han sido encontrados sin vida.\u00a0<\/li>\n\n\n\n<li><strong>Localizaci\u00f3n de mujeres:<\/strong>\u00a0En 2024, se localizaron 399 mujeres, 14 de las cuales fueron encontradas sin vida.\u00a0<\/li>\n\n\n\n<li><strong>Municipios con desapariciones:<\/strong>\u00a0En 127 municipios veracruzanos ha desaparecido al menos una mujer.\u00a0<\/li>\n\n\n\n<li><strong>Desapariciones de menores:<\/strong>\u00a0En 2024, un total de 376 menores de edad desaparecieron en Veracruz.\u00a0<\/li>\n\n\n\n<li><strong>Disminuci\u00f3n de desapariciones de ni\u00f1os y adolescentes:<\/strong>\u00a0Entre 2023 y 2024, la cantidad de ni\u00f1as, ni\u00f1os y adolescentes reportados como desaparecidos disminuy\u00f3 43.6%, seg\u00fan el informe RNPDNO 2025.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El contexto de la violencia contra las mujeres en Veracruz:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia pol\u00edtica:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz ocupa el segundo lugar nacional en violencia pol\u00edtica contra mujeres, con m\u00e1s casos registrados en el \u00e1mbito local.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia de g\u00e9nero:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El estado tiene un alto \u00edndice de violencia de g\u00e9nero, incluyendo violencia f\u00edsica, psicol\u00f3gica y sexual, que afecta a mujeres en diferentes \u00e1mbitos.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impacto en la participaci\u00f3n pol\u00edtica:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La violencia pol\u00edtica y de g\u00e9nero disuade a las mujeres de participar en la vida pol\u00edtica, lo que limita la representaci\u00f3n femenina y obstaculiza el avance de la paridad de g\u00e9nero.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Necesidad de atenci\u00f3n y protecci\u00f3n:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es crucial brindar a las mujeres v\u00edctimas de violencia un espacio seguro donde puedan buscar ayuda y protecci\u00f3n, as\u00ed como acceso a servicios de apoyo legal y psicol\u00f3gico.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Apoyo institucional:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Organizaciones como el Instituto Veracruzano de las Mujeres (IVM) y las PAIMEF (Unidades de Atenci\u00f3n Especializada del Programa de Apoyo a las Instancias de Mujeres en las Entidades Federativas) brindan asesor\u00eda y apoyo a mujeres v\u00edctimas de violencia,.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia psicol\u00f3gica:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El Sol de M\u00e9xico&nbsp;informa que la violencia psicol\u00f3gica, con 76 casos, fue la m\u00e1s registrada contra las mujeres en Veracruz entre enero y abril de 2024.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Denuncias de violencia:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El Tribunal Electoral de Veracruz no ha recibido denuncias relacionadas con la paridad de g\u00e9nero, lo que indica que muchas mujeres a\u00fan no se sienten seguras para participar en la pol\u00edtica, seg\u00fan imagen de Veracruz.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia en ayuntamientos:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz ocupa el segundo lugar nacional en violencia de g\u00e9nero en ayuntamientos, lo que sugiere que la violencia local es un problema significativo.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Violencia digital:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Un n\u00famero considerable de denuncias por violencia electoral en Veracruz se relacionan con violencia digital,.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acciones necesarias desde una pol\u00edtica de g\u00e9nero:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fortalecer la atenci\u00f3n a las mujeres v\u00edctimas:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario mejorar los servicios de apoyo y protecci\u00f3n para las mujeres v\u00edctimas de violencia, incluyendo asesor\u00eda legal, psicol\u00f3gica y refugios.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Promover la participaci\u00f3n pol\u00edtica de las mujeres:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se deben implementar medidas para garantizar que las mujeres puedan participar en la pol\u00edtica libremente y sin temor a ser violentadas.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Combatir la violencia de g\u00e9nero:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es fundamental abordar la violencia de g\u00e9nero en sus diferentes formas, incluyendo la violencia f\u00edsica, psicol\u00f3gica, sexual y econ\u00f3mica,.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Crear espacios seguros:<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario crear espacios seguros para las mujeres, tanto en el \u00e1mbito pol\u00edtico como en la vida cotidiana, donde puedan expresar sus ideas y participar sin miedo a ser agredidas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antecedentes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los consejos Consultivos y Social emitieron la convocatoria el pasado 31 de marzo para el registro de aspirantes poniendo como plazo l\u00edmite el d\u00eda 9 de abril tras una ampliaci\u00f3n en la que se inscribieron 10 perfiles de destacadas mujeres veracruzanas que han trabajado por los derechos de las mujeres en la entidad, de las cuales siete cumplieron con los requisitos establecidos en la convocatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo Consultivo de donde eman\u00f3 la terna lo integran Martha Mendoza Parissi, Lorena Redondo Delgado, Gloria L\u00f3pez Mora, Alma Ang\u00e9lica Fuertes Jara, Claudia Vel\u00e1zquez Aguilar, Daisy Iris J\u00e1come S\u00e1nchez, Ana\u00ed Rodr\u00edguez Garc\u00eda, Sandra Ang\u00e9lica Soto Rodr\u00edguez, Metzeri Itzel \u00c1vila San Mart\u00edn, Mar\u00eda Sabina Mart\u00ednez Pinto, Mar\u00eda Veda Paxtla Valdivia y Alma Rosa \u00c1lvarez Reyes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en el Consejo Social por Mar\u00eda Teresa Moreno Torres, Eva Pacheco Montalvo, Nancy Torres Casta\u00f1eda, Karla S\u00e1nchez Mart\u00ednez, Karina Santos M\u00e9ndez, Teresita de Jes\u00fas Cortina Mendoza, Aruna Rafaela Pulido Cano, Carolina Ram\u00edrez Su\u00e1rez, Magnolia Fuentes Jim\u00e9nez, Mireya Hern\u00e1ndez Hern\u00e1ndez, Mar\u00eda Florencia Tehuintle Cuicahua y M\u00f3nica Nereida Huerta Torres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQui\u00e9n es Zaira del Toro?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del Toro cuenta con una trayectoria en la administraci\u00f3n p\u00fablica y la defensa de los derechos de las mujeres. Desde diciembre de 2024 fue encargada de la Direcci\u00f3n General del IVM, cargo al que ahora ha sido formalmente nombrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previamente, fue Directora del Instituto Municipal de las Mujeres de Xalapa de enero de 2022 a noviembre de 2024, y se desempe\u00f1\u00f3 como asesora en la Secretar\u00eda de Trabajo y Previsi\u00f3n Social entre marzo de 2021 y noviembre de 2022. Tambi\u00e9n fue Jefa de la Unidad de G\u00e9nero en la Secretar\u00eda de Turismo y Cultura de Veracruz de diciembre de 2018 a enero de 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su experiencia ha sido reforzada por un amplio trabajo en formaci\u00f3n y sensibilizaci\u00f3n sobre temas de g\u00e9nero; entre las capacitaciones que ha impartido destacan talleres y conferencias sobre igualdad de g\u00e9nero, masculinidades positivas, hostigamiento y acoso sexual, as\u00ed como la Estrategia de Coordinaci\u00f3n Estatal Cero Tolerancia a la Violencia Contra las Mujeres y Ni\u00f1as en el Estado de Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Detalles adicionales:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ni\u00f1as y adolescentes desaparecidas:<\/strong>\u00a0Se han reportado 1,054 ni\u00f1as, ni\u00f1os y adolescentes como desaparecidos o no localizados, de los cuales 14 han sido encontrados sin vida.\u00a0<\/li>\n\n\n\n<li><strong>Localizaci\u00f3n de mujeres:<\/strong>\u00a0En 2024, se localizaron 399 mujeres, 14 de las cuales fueron encontradas sin vida.\u00a0<\/li>\n\n\n\n<li><strong>Municipios con desapariciones:<\/strong>\u00a0En 127 municipios veracruzanos ha desaparecido al menos una mujer.\u00a0<\/li>\n\n\n\n<li><strong>Desapariciones de menores:<\/strong>\u00a0En 2024, un total de 376 menores de edad desaparecieron en Veracruz.\u00a0<\/li>\n\n\n\n<li><strong>Disminuci\u00f3n de desapariciones de ni\u00f1os y adolescentes:<\/strong>\u00a0Entre 2023 y 2024, la cantidad de ni\u00f1as, ni\u00f1os y adolescentes reportados como desaparecidos disminuy\u00f3 43.6%, seg\u00fan el informe RNPDNO 2025.\u00a0<\/li>\n\n\n\n<li><strong>Mujeres Trabajadoras<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Beatriz Lira Rocas, economista y acad\u00e9mica de la Universidad Veracruzana (UV), en entrevista con La Jornada se\u00f1ala que en Veracruz aproximadamente 65 por ciento del trabajo informal es desempe\u00f1ado por mujeres, lo que en parte explica la disparidad salarial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta situaci\u00f3n refleja una condici\u00f3n econ\u00f3mica complicada en el estado, caracterizada por la desigualdad en la generaci\u00f3n de riqueza y la distribuci\u00f3n del ingreso. La mayor parte de los trabajos precarizados, mal remunerados, sin seguridad social y sin estabilidad laboral son desempe\u00f1ados por mujeres. Mientras tanto, los trabajos formales con mejores condiciones laborales est\u00e1n dominados en su mayor\u00eda por hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado Veracruz se encuentra por debajo de la media nacional en cuanto a niveles de escolaridad, ingresos y salario de las mujeres: \u201cSi una persona adulta que deber\u00eda poder desarrollar sus capacidades de manera independiente, generar un patrimonio y alcanzar estabilidad financiera no lo puede hacer por ser mujer\u201d&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el Instituto Mexicano para la Competitividad (IMCO), Veracruz ocupa el tercer lugar entre los estados con peores condiciones laborales para las mujeres, con un puntaje de 40.5 sobre 100. Esto lo coloca por encima de Oaxaca (33.1) y Chiapas (39.1), seg\u00fan el informe \u201cEstados Con Lupa De G\u00e9nero 2024\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nivel nacional, ning\u00fan estado ofrece condiciones laborales \u00f3ptimas para las mujeres, y solo el 46 por ciento de la poblaci\u00f3n femenina forma parte del mercado laboral. El estudio de IMCO revela que 53 por ciento de las mujeres veracruzanas viven en pobreza laboral, lo que significa que sus ingresos no son suficientes para cubrir el costo de la canasta b\u00e1sica. Adem\u00e1s, el 37.8 por ciento no reciben ingresos monetarios directos, lo que resalta la precariedad econ\u00f3mica que enfrentan muchas mujeres en el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que va del 2025 se ha reportado la desaparici\u00f3n de 138 mujeres en el estado de Veracruz, de las cuales 29 no han vuelto con sus familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema de las desapariciones en Veracruz refleja un fen\u00f3meno de violencia y descomposici\u00f3n institucional que afecta a todo M\u00e9xico, pero especialmente a aquellos estados que se encuentran en el centro de las disputas entre grupos criminales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los esfuerzos de la Consejo Estatal de B\u00fasqueda y las organizaciones civiles son valiosos, el desaf\u00edo sigue siendo grande, y la situaci\u00f3n requiere de una respuesta m\u00e1s efectiva por parte del gobierno estatal y federal. La lucha por la justicia y por la vida de las personas desaparecidas contin\u00faa siendo una prioridad.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXcXhz8gsbG_uzc10dPncf4jhvJcUPKKBMLlEhP3-BZO4lvedv4_sdfS2Rlvv5qSxBS6rQLRA9fR_KsEPXs2CTOqJqLp7RVX5vSFsZemz9OTiFPNIMgvYuJRKiVP6e32iqBjYoo-Dd56uZAtybxPcg?key=j0bsJgJ1KE67KOo6LXaCfqpJ\" alt=\"Texto, Carta\n\nEl contenido generado por IA puede ser incorrecto.\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este martes la gobernadora de Veracruz design\u00f3 a Zaira del Toro Olivares como Directora del IVM Era la encargada de la direcci\u00f3n,&nbsp; funcionaria y &nbsp; acad\u00e9mica, sin historia de activista ni feminista militante&nbsp; La lucha por la justicia y por la vida de las personas desaparecidas contin\u00faa siendo una prioridad. Sara Lovera&nbsp; SemM\u00e9xico\/, Xalapa, Ver., [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":94791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-94790","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/94790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=94790"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/94790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/94791"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=94790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=94790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=94790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}