{"id":93907,"date":"2025-03-19T23:14:58","date_gmt":"2025-03-20T05:14:58","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=93907"},"modified":"2025-03-21T15:55:34","modified_gmt":"2025-03-21T21:55:34","slug":"estados-unidos-no-aprueba-la-declaracion-politica-de-la-csw-69-y-se-pronuncia-contra-la-agenda-2030-por-blanda","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/estados-unidos-no-aprueba-la-declaracion-politica-de-la-csw-69-y-se-pronuncia-contra-la-agenda-2030-por-blanda\/","title":{"rendered":"Estados Unidos no aprueba la Declaraci\u00f3n Pol\u00edtica de la CSW 69 y se pronuncia contra la Agenda 2030 por blanda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se pronuncia contra la ideolog\u00eda de g\u00e9nero que no utiliza un lenguaje preciso y la ideolog\u00eda de fronteras abiertas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elda Montiel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Ciudad de M\u00e9xico. 19 de marzo 2025.- Estados Unidos bajo la administraci\u00f3n de Donald Trump expone que la Declaraci\u00f3n Pol\u00edtica de la Comisi\u00f3n de la Condici\u00f3n Jur\u00eddica y Social de la Mujer ( CSW) 69\u00ba&nbsp; no modifica el derecho internacional porque no implica que los Estados deban adherirse o cumplir obligaciones en virtud de los instrumentos internacionales de los pa\u00edses que no son parte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, advierte que si bien no son miembros de la CSW este a\u00f1o, participan en las negociaciones porque Estados Unidos apoya firmemente la protecci\u00f3n de las mujeres y las ni\u00f1as, la defensa de sus derechos y la promoci\u00f3n de su empoderamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos decepciona que la Declaraci\u00f3n Pol\u00edtica no se centrara en las necesidades y perspectivas de las mujeres y las ni\u00f1as mediante una terminolog\u00eda precisa<strong>\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La administraci\u00f3n Trump defienden a las mujeres y las ni\u00f1as de la ideolog\u00eda de g\u00e9nero perjudicial y extremista con un lenguaje preciso que reconozcan que las mujeres son biol\u00f3gicamente mujeres y los hombres son biol\u00f3gicamente hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se pronuncia contra la ideolog\u00eda de las fronteras abiertas porque tolera agresiones a las mujeres estadunidenses&nbsp; por delincuentes extranjeros que operan individualmente o en pandillas, por lo que protege a las mujeres al frenar la migraci\u00f3n masiva y asegurando fronteras.&nbsp; .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos agradece al Reino de Arabia Saudita y a los cofacilitadores Cabo Verde y Costa Rica, as\u00ed como a todas las delegaciones participantes y socios de la sociedad civil, por su labor en la elaboraci\u00f3n de la Declaraci\u00f3n Pol\u00edtica, al dar a conocer la posici\u00f3n de&nbsp; Estados Unidos en la CSW69 de&nbsp; Naciones Unidas en Nueva York donde se hace un balance sobre la situaci\u00f3n mundial de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos apoya la eliminaci\u00f3n de la discriminaci\u00f3n por motivos de raza, color, religi\u00f3n, sexo, edad, discapacidad, origen nacional e informaci\u00f3n gen\u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se pronuncian contra la reafirmaci\u00f3n de la Agenda 2030 y los Objetivos de Desarrollo Sostenible (ODS) porque promueven un programa de gobernanza global blanda que es incompatible con la soberan\u00eda estadounidense y contrario a los derechos e intereses de los estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto detallan que en las elecciones fue claro el mandato del pueblo enfocarse en los intereses de los estadounidenses.&nbsp; El presidente Trump tambi\u00e9n estableci\u00f3 una correcci\u00f3n de rumbo clara y necesaria en la ideolog\u00eda de \u00abg\u00e9nero\u00bb y clim\u00e1tica, que impregna los ODS. En pocas palabras, iniciativas globalistas como la Agenda 2030 y los ODS fracasaron en las urnas. Por lo tanto, Estados Unidos rechaza y denuncia la Agenda 2030 para el Desarrollo Sostenible y los ODS, y ya no los reafirmaremos como algo habitual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos comprende la intenci\u00f3n de incluir \u201cigualdad salarial por trabajo de igual valor\u201d para promover la igualdad salarial entre hombres y mujeres, y acepta la formulaci\u00f3n sobre esa base. Estados Unidos trabaja para lograr la igualdad salarial observando el principio de \u201cigualdad salarial por igual trabajo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se pronuncia contra la ideolog\u00eda de g\u00e9nero que no utiliza un lenguaje preciso y la ideolog\u00eda de fronteras abiertas Elda Montiel SemM\u00e9xico. Ciudad de M\u00e9xico. 19 de marzo 2025.- Estados Unidos bajo la administraci\u00f3n de Donald Trump expone que la Declaraci\u00f3n Pol\u00edtica de la Comisi\u00f3n de la Condici\u00f3n Jur\u00eddica y Social de la Mujer ( [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[897],"tags":[],"class_list":["post-93907","post","type-post","status-publish","format-standard","has-post-thumbnail","category-especial"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=93907"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/93908"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=93907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=93907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=93907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}