{"id":93743,"date":"2025-03-14T18:14:39","date_gmt":"2025-03-15T00:14:39","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=93743"},"modified":"2025-03-14T18:14:40","modified_gmt":"2025-03-15T00:14:40","slug":"mujer-y-poder-las-madres-buscadoras-y-la-sociedad-civil","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujer-y-poder-las-madres-buscadoras-y-la-sociedad-civil\/","title":{"rendered":"Mujer Y Poder| Las madres buscadoras y la sociedad civil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Natalia Vidales de Bitterlin<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 14 de marz0, 2025.- La semana pasada el mundo entero se horroriz\u00f3 con el macabro hallazgo que realizaron los integrantes -en su gran mayor\u00eda mujeres-&nbsp; del colectivo Guerrero Buscadores de Jalisco en un rancho ubicado a escasos kil\u00f3metros de la ciudad de Guadalajara, Jalisco, y&nbsp; que da muestra del&nbsp;&nbsp; grado de brutalidad y de&nbsp; violencia al que se he llegado en nuestro pa\u00eds \u2013y de la poca respuesta si no es que de la complicidad de las autoridades.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cual un campo de concentraci\u00f3n de la Alemania nazi, en el lugar se encontraron m\u00e1s de 200 pares de zapatos -evidencia dolorosa de la cantidad de personas -en su mayor\u00eda j\u00f3venes- que fueron sacrificados sin misericordia. &nbsp;&nbsp;Como ya es del conocimiento p\u00fablico, el lugar contaba con hornos crematorios, fosas clandestinas, osamentas, restos de pertenencias de quienes estuvieron ah\u00ed de manera forzada para adiestramiento de sicarios\u2026 todo, descubierto por ciudadanos organizados en uno de los colectivos que funcionan en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las madres cuyos hijos desaparecieron repentinamente -algunos desde hace a\u00f1os-, no se dar\u00e1n jam\u00e1s por vencidas &#8211;\u00bfc\u00f3mo podr\u00edan? &#8212; y han dedicado su vida a la b\u00fasqueda de sus seres queridos, sin parar ante nada ni nadie. Frente a lo que consideran el nulo inter\u00e9s y participaci\u00f3n del gobierno, decidieron emprender la b\u00fasqueda de los suyos desde hace a\u00f1os y son ya innumerables las fosas y cuerpos de desaparecidos que han descubierto. En esta ocasi\u00f3n, sin embargo, las im\u00e1genes de efectos personales de las v\u00edctimas Llegaron para quedarse en nuestras conciencias, alertando a toda la sociedad para exigirle un \u00a1ya basta! al gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Literalmente las buscadoras le han hecho la chamba a las autoridades y han exhibido, adem\u00e1s, a un gobierno insensible e inepto al no descubrir este campo de exterminio -ubicado frente a sus narices- a escasos kil\u00f3metros de Guadalajara. Se les deber\u00eda de caer la cara de verg\u00fcenza a las autoridades incompetentes y\/o corruptas porque ese centro de reclutamiento y muerte no debi\u00f3 haber existido\u2026o pasado desapercibido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico est\u00e1 de luto de nuevo y est\u00e1 ofendido por las autoridades y con la presidencia que, pese a la inmensa tragedia, ha continuado como si nada pasara con sus discursos de celebraci\u00f3n y de partidismo pol\u00edtico -como el del pasado domingo en el Z\u00f3calo. Supondr\u00e1 que tambi\u00e9n esta tragedia pasar\u00e1 pero todo indica que, por el contrario, seguir\u00e1 escalando en el \u00e1nimo ciudadano hasta que haya respuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No solo las madres buscadoras sufren sino millones de mujeres y familias enteras est\u00e1n hoy sumidas en la desesperaci\u00f3n y de nuevo removiendo sus heridas, las grandes heridas que han estado latentes por la tragedia de no encontrar a sus hijos.&nbsp;&nbsp; Solo un coraz\u00f3n insensible puede no ser emp\u00e1tico ante tanto dolor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ellas han logrado desenmascarar la extrema violencia y maldad existente en nuestro querido pa\u00eds; han mostrado al mundo que los campos de concentraci\u00f3n, como los de la Segunda Guerra Mundial a\u00fan persisten\u2026y aqu\u00ed en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y han mostrado tambi\u00e9n la urgencia de que tanto gobierno como sociedad debe trabajar fuerte para fomentar en la sociedad los valores universales de solidaridad y amor hacia el pr\u00f3jimo. Junto a las estrategias de seguridad deben existir campa\u00f1as que promuevan el bien com\u00fan sobre todo en las nuevas generaciones, para que vayan aprendiendo que el camino del mal solo conduce a la degradaci\u00f3n, optando \u2013y d\u00e1ndoles las oportunidades para que as\u00ed sea\u2014por una vida forjada en el fortalecimiento del esp\u00edritu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las madres buscadoras est\u00e1n haciendo una labor que no les corresponde por la falta de compromiso y\/o eficiencia del gobierno, pero la sociedad civil en general debe tambi\u00e9n trabajar en el n\u00facleo familiar y cercano para sembrar las semillas del bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo pronto, nuestra solidaridad para las madres buscadoras y las familias de quienes tuvieron la desgracia de toparse en el camino con estos delincuentes que les quitaron, de tajo, la vida.&nbsp; Descansen en Paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Periodista con mas de 40 a\u00f1os de ejercicio profesional. Activista social, fundadora y directora de la revista Mujer y Poder. Comentarios: whats 6621441440. <\/strong><a href=\"http:\/\/www.mujerypoder.com.mx\">www.mujerypoder.com.mx<\/a><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natalia Vidales de Bitterlin SemM\u00e9xico, Oaxaca, 14 de marz0, 2025.- La semana pasada el mundo entero se horroriz\u00f3 con el macabro hallazgo que realizaron los integrantes -en su gran mayor\u00eda mujeres-&nbsp; del colectivo Guerrero Buscadores de Jalisco en un rancho ubicado a escasos kil\u00f3metros de la ciudad de Guadalajara, Jalisco, y&nbsp; que da muestra del&nbsp;&nbsp; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[100,72,35],"tags":[],"class_list":["post-93743","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mujer-y-poder","category-natalia-vidales","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=93743"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38550"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=93743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=93743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=93743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}