{"id":93315,"date":"2025-03-06T18:34:00","date_gmt":"2025-03-07T00:34:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=93315"},"modified":"2025-03-06T18:34:01","modified_gmt":"2025-03-07T00:34:01","slug":"prioridad-garantizar-derechos-de-la-primera-infancia-lorena-villavicencio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/prioridad-garantizar-derechos-de-la-primera-infancia-lorena-villavicencio\/","title":{"rendered":"Prioridad garantizar derechos de la primera infancia, Lorena Villavicencio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">48% de la infancia en la pobreza, 30% no tienen el esquema de vacunaci\u00f3n completa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elda Montiel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, &nbsp;Ciudad de M\u00e9xico, 6 de marzo, 2025.- Es necesario garantizar los derechos de las infancias en materia de identidad, salud y educaci\u00f3n, ya que en M\u00e9xico existen 12 millones de ni\u00f1os y ni\u00f1as de entre cero y cinco a\u00f1os, de los cuales 48 por ciento est\u00e1n ubicados en la pobreza se\u00f1al\u00f3 Lorena Villavicencio Ayala, titular de la secretar\u00eda ejecutiva del Sistema Nacional de Protecci\u00f3n Integral de Ni\u00f1as, Ni\u00f1os y Adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al participar en el Senado en el&nbsp; Foro \u201cPrioridades de la atenci\u00f3n de la primera infancia 2024-2030\u201d destac\u00f3 que el 7.7 de los ni\u00f1os en esta etapa padecen sobrepeso, el 19 por ciento no tienen acta de nacimiento y el 50.4 por ciento fueron expuestos a alg\u00fan tipo de violencia en casa como m\u00e9todo de correcci\u00f3n y alrededor del 30 por ciento no tienen el esquema de vacunaci\u00f3n completo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora Alma Anah\u00ed Gonz\u00e1lez Hern\u00e1ndez revel\u00f3 que el 13.9 por ciento de los ni\u00f1os y ni\u00f1as menores de cinco a\u00f1os en M\u00e9xico padecen desnutrici\u00f3n cr\u00f3nica, y s\u00f3lo el 30 por ciento recibi\u00f3 lactancia materna exclusiva durante sus primeros seis meses de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Foro se&nbsp; realiz\u00f3 en conjunto con&nbsp; Early Institute, con el prop\u00f3sito de discutir sobre los problemas que enfrenta este sector de la sociedad y generar propuestas para su atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora general de Early Institute, Annayancy Varas Garc\u00eda, present\u00f3 el documento \u201cPrioridades de la Primera Infancia\u201d que contiene propuestas con acciones concretas para desterrar la violencia, la pobreza y la falta de servicios b\u00e1sicos de calidad que padecen los menores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora de Morena se\u00f1al\u00f3 que esta C\u00e1mara est\u00e1 \u201ctotalmente comprometida\u201d a atender desde el \u00e1mbito legislativo las necesidades de las ni\u00f1as y ni\u00f1os mexicanos, porque el desarrollo de la primera infancia es uno de los puntos m\u00e1s importantes en la \u201crevoluci\u00f3n del bienestar\u201d que se impulsa desde el gobierno de la presidenta Claudia Sheinbaum Pardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de la Comisi\u00f3n de los Derechos de la Ni\u00f1ez y de la Adolescencia, Laura Esquivel Torres, manifest\u00f3 el compromiso del Senado de atender a este sector de la poblaci\u00f3n, porque, a pesar de que M\u00e9xico es un pa\u00eds con avances legislativos, a\u00fan hay deudas pendientes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"664\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-1024x664.jpg\" alt=\"\" class=\"wp-image-93317\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-1024x664.jpg 1024w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-300x194.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-768x498.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-150x97.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-696x451.jpg 696w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02-1068x692.jpg 1068w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2025\/03\/garantia-derechos-02.jpg 1455w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora de Morena, Alejandra Berenice Arias Trevilla, reconoci\u00f3 que los menores sufren varios tipos de violencia, como la vicaria, el abuso sexual y la psicol\u00f3gica. Dijo que esto es una problem\u00e1tica importante que se tiene que erradicar, de ah\u00ed la importancia de este tipo de foros que representan una herramienta indispensable para generar acuerdos que ayuden a los legisladores a implementar medidas para resolver los problemas de los ni\u00f1os y las ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador morenista Juan Carlos Loera de la Rosa lament\u00f3 las tragedias sociales que se han registrado en varios estados de la rep\u00fablica, al considerar que son producto de la pobreza y la violencia que sufren las mujeres y sus hijos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, destac\u00f3 que ha sido una prioridad para el gobierno eliminar esto a trav\u00e9s de los programas sociales, de las reformas para garantizar la paridad salarial, la creaci\u00f3n en este gobierno de los centros de educaci\u00f3n y cuidados de ni\u00f1os y ni\u00f1as menores de cinco a\u00f1os, as\u00ed como el combate a la pobreza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>48% de la infancia en la pobreza, 30% no tienen el esquema de vacunaci\u00f3n completa Elda Montiel SemM\u00e9xico, &nbsp;Ciudad de M\u00e9xico, 6 de marzo, 2025.- Es necesario garantizar los derechos de las infancias en materia de identidad, salud y educaci\u00f3n, ya que en M\u00e9xico existen 12 millones de ni\u00f1os y ni\u00f1as de entre cero y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[703],"tags":[],"class_list":["post-93315","post","type-post","status-publish","format-standard","has-post-thumbnail","category-infancia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=93315"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/93316"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=93315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=93315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=93315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}