{"id":93171,"date":"2025-03-03T12:17:45","date_gmt":"2025-03-03T18:17:45","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=93171"},"modified":"2025-03-03T12:17:47","modified_gmt":"2025-03-03T18:17:47","slug":"los-capitales-lamentable-el-abandono-en-el-que-estan-los-estudiantes-de-posgrado-del-cinvestav","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-lamentable-el-abandono-en-el-que-estan-los-estudiantes-de-posgrado-del-cinvestav\/","title":{"rendered":"Los Capitales| Lamentable el abandono en el que est\u00e1n los estudiantes de posgrado del CINVESTAV"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 3 de marzo, 2025.- En mi \u00e9poca de estudiante yo era de los pocos afortunados que ten\u00edamos una beca de manutenci\u00f3n para estudiar en el ciclo \u201cProped\u00e9utico\u201d de El Colegio de M\u00e9xico. Y entiendo lo importante que es tener ese tipo de apoyo para dedicarse a estudiar en serio, y por supuesto, observaba con angustia aquellos estudiantes que no ten\u00edan la fortuna de contar con este apoyo econ\u00f3mico institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy me entero que, a los estudiantes de posgrado de Cinvestav, que contaban con ese tipo de apoyo de manutenci\u00f3n en la Ciudad de M\u00e9xico, se les ha suspendido desde el 26 de febrero de 2025, y nos escriben una carta, que recibimos con enorme preocupaci\u00f3n: \u201csomos 74 estudiantes de los programas de maestr\u00eda y doctorado del Cinvestav, de las unidades Zacatenco, Guadalajara, Saltillo, M\u00e9rida y Monterrey, los que nos hemos quedado desde enero sin beca de manutenci\u00f3n. Esto pone en riesgo la continuidad de nuestros estudios de posgrados y los proyectos de investigaci\u00f3n en los que trabajamos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los afectados nos describen como se lleg\u00f3 a la situaci\u00f3n que los aqueja. \u201cHasta septiembre de 2023 todos los estudiantes que ingresaban a un programa de posgrado del Cinvestav recib\u00edan una beca de manutenci\u00f3n por el Consejo Nacional de Ciencias y Tecnolog\u00eda (CONACYT). Sin embargo, a partir de esa fecha, se hicieron modificaciones estructurales y presupuestales en el CONACYT, que entonces se denomin\u00f3 CONAHCYT, y ya no se otorgaron al Cinvestav todas las becas que requer\u00eda. Por ello, el Cinvestav instaur\u00f3 el programa de becas SEP-Cinvestav que cubr\u00eda el n\u00famero de becas no otorgadas por el CONAHCYT. Cabe resaltar que los estudiantes que recibimos las becas SEP-Cinvestav cumpl\u00edamos todos los requisitos necesarios para la beca CONAHCYT. De esta manera, se gener\u00f3 una segregaci\u00f3n aleatoria de los estudiantes del Cinvestav en dos poblaciones: los beneficiarios de las becas CONACYT y los de las becas SEP-CINVESTAV\u201d. Las becas de manutenci\u00f3n SEP-Cinvestav para maestr\u00eda amparaban un periodo de hasta 24 meses, con un pago mensual equivalente a 4.5 UMAs, y las becas de doctorado eran de 6.0 UMAs por hasta 48 meses. Estas becas contaban adem\u00e1s con una actualizaci\u00f3n anual de las UMAs y los pagos se realizaban los primeros d\u00edas de cada mes. Los coordinadores acad\u00e9micos de los distintos programas de posgrado del Cinvestav, nos aseguraron que las becas SEP-Cinvestav cumplir\u00edan las mismas condiciones y modo de operaci\u00f3n que las becas otorgadas por el CONACYT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, en enero de 2024, se nos inform\u00f3 que deb\u00edamos de solicitar nuevamente la beca para contar con el apoyo de febrero a diciembre de 2024. Adem\u00e1s, se nos indic\u00f3 que la nueva beca de manutenci\u00f3n se entregar\u00eda a trav\u00e9s del programa de becas Elisa Acu\u00f1a. El problema se sucit\u00f3 en enero de 2025, ya que a partir de entonces no contamos con beca de manutenci\u00f3n o apoyo econ\u00f3mico del Cinvestav. Al respecto, en enero, la Ing. Paulina Alejandra Baldo Romero, del Departamento de Becas y Est\u00edmulos del Cinvestav, nos inform\u00f3 que a\u00fan no sal\u00eda la convocatoria para las becas Elisa Acu\u00f1a y que, por lo tanto, no se pod\u00eda estimar la fecha en que se realizar\u00edan los pagos. Posteriormente, se nos dijo que el presupuesto de las becas ya estaba contemplado por el Cinvestav y que solo se esperaba la publicaci\u00f3n de las reglas de operaci\u00f3n del programa de becas Elisa Acu\u00f1a para emitir la convocatoria. Sin embargo, el 5 de febrero, el secretario Acad\u00e9mico del Cinvestav, Dr. Abdel P\u00e9rez Lorenzana, nos envi\u00f3 un correo electr\u00f3nico indicando que la operaci\u00f3n del programa de becas Elisa Acu\u00f1a requiere la publicaci\u00f3n en el Diario Oficial de la Federaci\u00f3n de sus reglas de operaci\u00f3n, mismas que a\u00fan no hab\u00edan sido publicadas. Adem\u00e1s, nos inform\u00f3 que el Cinvestav no estar\u00eda incluido en las Reglas de Operaci\u00f3n que se publicar\u00edan en los pr\u00f3ximos d\u00edas, porque el Congreso de la Uni\u00f3n no asign\u00f3 al Cinvestav los recursos para este programa en el Presupuesto de Egresos de la Federaci\u00f3n. El 19 de febrero, el Dr. Abdel P\u00e9rez Lorenzana nos indic\u00f3 que a pesar de que el Cinvestav emplear\u00e1 recursos internos para el pago de las becas de manutenci\u00f3n Elisa Acu\u00f1a, la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SHCP) no autoriz\u00f3 el uso de dichos recursos pues el Cinvestav no estaba incluido en las reglas de operaci\u00f3n de dicho programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Efectivamente, el 21 de febrero las reglas de operaci\u00f3n del programa Elisa Acu\u00f1a se publicaron en el Diario Oficial de la Federaci\u00f3n, dejando al Cinvestav excluido de dicho documento. El Departamento de Becas y Est\u00edmulos del Cinvestav nos ha dicho que trabajan con la Coordinaci\u00f3n Nacional de Becas para el Bienestar para la integraci\u00f3n del Cinvestav en las Reglas de Operaci\u00f3n del programa Elisa Acu\u00f1a y su publicaci\u00f3n. Mientras tanto los estudiantes seguimos con gastos que no podemos solventar y con la incertidumbre de saber cu\u00e1ndo se podr\u00e1 resolver esta situaci\u00f3n. Adem\u00e1s, estamos desconcertados y preocupados porque se nos ha advertido que esta situaci\u00f3n se repetir\u00e1 al renovar cada a\u00f1o la beca Elisa Acu\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, y para evitar estos descalabros administrativos, solicitamos al Cinvestav, a la Secretar\u00eda de Ciencia, Humanidades, Tecnolog\u00eda e Innovaci\u00f3n (SECIHTI), a la SHCP, y a la Comisi\u00f3n de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n de la C\u00e1mara de Diputados, que a todos los estudiantes de posgrado del Cinvestav se nos otorgue como ocurr\u00eda antes, la beca de manutenci\u00f3n de CONAHCYT (hoy SECIHTI). A continuaci\u00f3n, listamos los 14 programas de posgrado del Cinvestav afectados por la situaci\u00f3n descrita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Maestr\u00eda en Biotecnolog\u00eda del departamento de Biotecnolog\u00eda y Bioingenier\u00eda, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Maestr\u00eda en Ciencias de la Computaci\u00f3n del departamento de Computaci\u00f3n, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Maestr\u00eda en Matem\u00e1ticas del departamento de Matem\u00e1ticas, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Maestr\u00eda en Gen\u00e9tica y Biolog\u00eda Molecular del departamento de Gen\u00e9tica y Biolog\u00eda Molecular, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Doctorado en Neurobiolog\u00eda Celular y Molecular, y Fisiolog\u00eda Celular y Molecular del departamento de Fisiolog\u00eda, Biof\u00edsica y Neurociencias, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Doctorado en Nanociencias y Nanotecnolog\u00eda, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. Doctorado en F\u00edsica del departamento de F\u00edsica, unidad Zacatenco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8. Doctorado en Ingenier\u00eda El\u00e9ctrica del departamento de Ciencias de la Computaci\u00f3n, unidad Guadalajara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9. Doctorado en Ingenier\u00eda en Sistemas El\u00e9ctricos de Potencia, unidad Guadalajara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10. Maestr\u00eda en Ciencias en Ingenier\u00eda Metal\u00fargica, unidad Saltillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11. Maestr\u00eda en Biolog\u00eda Marina del departamento de Recursos del Mar, unidad M\u00e9rida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12. Maestr\u00eda y doctorado en F\u00edsica Aplicada del departamento de F\u00edsica Aplicada, unidad M\u00e9rida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13. Maestr\u00eda en Ingenier\u00eda y F\u00edsica Biom\u00e9dicas, unidad Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14. Maestr\u00eda en Educaci\u00f3n en Biolog\u00eda para la Formaci\u00f3n Ciudadana, unidad Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" target=\"_blank\" rel=\"noreferrer noopener\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.agendadeinversiones.com.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.agendadeinversiones.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @Edgar4712<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico, 3 de marzo, 2025.- En mi \u00e9poca de estudiante yo era de los pocos afortunados que ten\u00edamos una beca de manutenci\u00f3n para estudiar en el ciclo \u201cProped\u00e9utico\u201d de El Colegio de M\u00e9xico. Y entiendo lo importante que es tener ese tipo de apoyo para dedicarse a estudiar en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[750,35],"tags":[],"class_list":["post-93171","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=93171"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/93171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=93171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=93171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=93171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}