{"id":92298,"date":"2025-01-29T11:15:51","date_gmt":"2025-01-29T17:15:51","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=92298"},"modified":"2025-01-29T11:15:52","modified_gmt":"2025-01-29T17:15:52","slug":"bellas-y-airosas-ellas-una-azotea-y-los-beatles","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/bellas-y-airosas-ellas-una-azotea-y-los-beatles\/","title":{"rendered":"Bellas y Airosas | Ellas, una azotea y los Beatles\u00a0"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Elvira Hern\u00e1ndez Carballido&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Pachuca, Hgo., 29 de enero, 2025.- El 30 de enero de 1969 el famoso cuarteto de Liverpool decidi\u00f3 dar un concierto en la parte alta de su estudio de grabaci\u00f3n. Testimonios reiteran que en esa \u00e9poca la fragmentaci\u00f3n del grupo estaba m\u00e1s que latente y dicho escenario represent\u00f3 una manera de hacer algo diferente. Pero, en ese espacio donde los Beatles eran las figuras centrales yo perfiero buscarlas a ellas, las mujeres que cada uno am\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cr\u00f3nicas de la \u00e9poca detallan que el abrigo que ese d\u00eda luci\u00f3 Lennon pertenec\u00eda a Yoko y el de Harrison a Pattie Boyd, hac\u00eda fr\u00edo y fueron solidarias al cubrirlos con sus prendas. Lo mismo hizo Maureen al ceder su gabardina a Ringo. Mientras Linda atrapaba im\u00e1genes de Paul con la c\u00e1mara, fiel a su vocaci\u00f3n de fot\u00f3grafa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, las historias de ellas marcan toda una \u00e9poca, formas distintas de ser mujer y de brillar con su propia luz aunque el hombre que estaba a su lado fuera el \u00eddolo de las multitudes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera que atrapa miradas es Yoko Ono, todav\u00eda en este siglo hay discusiones en la redes sociales se\u00f1al\u00e1ndola como la culpable de la separaci\u00f3n del grupo. Tanto Lennon como McCartney reiteraban que ella no tuvo nada que ver. Yoko fue la primera mujer en estudiar Filosof\u00eda en Gakush\u016bin, una prestigiada instituci\u00f3n educativa en Jap\u00f3n. Empez\u00f3 a filmar cuando pocas mujeres lo hac\u00edan. Uno de sus textos publicado en \u201cGrapefruit\u201d, su libro de arte conceptual, fue representativo para que Lennon escribiera \u201cImagina\u201d. En 2017, durante la Gala de la National Music Publishers Association, se anunci\u00f3 que se le dar\u00eda el cr\u00e9dito de coautora de esa gran canci\u00f3n. A sus 91 a\u00f1os Yoko sigue brillando por ella misma.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Linda Eastman, despu\u00e9s preferir\u00eda tener el apellido McCartney, estudi\u00f3 en la Universidad de Arizona historia del arte y ah\u00ed confirm\u00f3 su pasi\u00f3n por la fotograf\u00eda, herencia de su familia, fundadores de Kodak. Especializada en fotos a personalidades del mundo del espect\u00e1culo, conoci\u00f3 a Paul en el momento de m\u00e1s fama con los Beatles. Se casaron a los seis meses. Sin dejar la fotograf\u00eda, fue convencida por su esposo para formar parte de su banda Wings. Vegetariana, hizo libros de recetas y fue una gran activista por los derechos de los animales. Falleci\u00f3 en 1998, v\u00edctima de c\u00e1ncer de mama, ten\u00eda 56 a\u00f1os. Al iniciar el siglo XXI se fund\u00f3 el Centro Linda McCartney para personas enfermas de c\u00e1ncer.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maureen Starkey, mejor conocida Mo, y de soltera Mary Cox, trabajaba cortando el cabello y haciendo peinados. Sus visitas constantes a La Caverna le permitieron conocer a Ringo. La relaci\u00f3n se complic\u00f3 cuando su novio se hac\u00eda cada vez m\u00e1s famoso, pero se casaron en 1965. Solidaria, respond\u00eda las cartas que las fans escrib\u00edan a los cuatro de Liverpool. Entre infidelidades y largos desencuentros, acept\u00f3 el divorcio en 1975. Se dedic\u00f3 al cuidado de sus tres hijos. En 1980 se cas\u00f3 con el due\u00f1o de Hard Rock Caf\u00e9. A los 48 a\u00f1os ella muri\u00f3 por complicaciones de leucemia. Se le recuerda como una mujer dulce y generosa, bien querida por quienes la conocieron. Aquel d\u00eda en la azotea, al terminar de interpretar Get Back, Paul dice: <em>Thanks, Mo! <\/em>Un detalle<em> <\/em>de su parte al ver a Maureen aplaudirles efusiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pattie Boyd representa para m\u00ed la imagen cl\u00e1sica de una chica de la d\u00e9cada de los sesenta: largo flequillo, grandes ojos enmarcados por el oscuro y espeso rimel negro, vestidos psicod\u00e9licos y botas yeye. Modelo, conquist\u00f3 a George mientras filmaba \u201cLa noche de un d\u00eda dif\u00edcil\u201d. Creo que como a ninguna otra, se insiste en que fue una musa. Entre las canciones que le inspir\u00f3 a Harrison est\u00e1 \u201cSomething\u201d. Su esposo tambi\u00e9n fue Eric Clapton quien declar\u00f3 haberle escrito \u201cLeyla\u201d. A sus 80 a\u00f1os adem\u00e1s de ser fot\u00f3grafa ha escrito libros sobre su vida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y mientras los Beatles cantaban en una azoteca aquel 30 de enero de 1969, cuatro mujeres diferentes colgaban ante el fri\u00f3 sol londinense sus propias historias, sin estar detr\u00e1s de ning\u00fan hombre, brillando a su manera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Sal de ti.<\/em><em><br><\/em><em>Obs\u00e9rvate caminando en la calle.<\/em><em><br><\/em><em>Haz que tropieces con una piedra y caigas.<\/em><em><br><\/em><em>Observa.<\/em><em><br><\/em><em>Observa c\u00f3mo mira la otra gente.<\/em><em><br><\/em><em>Observa con cuidado c\u00f3mo caes,<\/em><em><br><\/em><em>cu\u00e1nto tardas y con qu\u00e9 ritmo caes.<\/em><em><br><\/em><em>Observa como si fuera una pel\u00edcula en blanco y negro.<\/em><em><br><\/em><em>Observa c\u00f3mo te levantas de la ca\u00edda.<\/em><em><br><\/em><em>Ve cu\u00e1nto tardas en levantarte, c\u00f3mo te paras<\/em><em><br><\/em><em>y qu\u00e9 haces despu\u00e9s.<\/em><em><br><\/em><em>Observa como si fuera una pel\u00edcula en tecnicolor.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yoko Ono<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elvira Hern\u00e1ndez Carballido&nbsp; SemM\u00e9xico, Pachuca, Hgo., 29 de enero, 2025.- El 30 de enero de 1969 el famoso cuarteto de Liverpool decidi\u00f3 dar un concierto en la parte alta de su estudio de grabaci\u00f3n. Testimonios reiteran que en esa \u00e9poca la fragmentaci\u00f3n del grupo estaba m\u00e1s que latente y dicho escenario represent\u00f3 una manera de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[202,35],"tags":[],"class_list":["post-92298","post","type-post","status-publish","format-standard","has-post-thumbnail","category-elvira-hernandez-carballido","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/92298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=92298"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/92298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/70197"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=92298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=92298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=92298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}