{"id":91842,"date":"2025-01-17T12:24:47","date_gmt":"2025-01-17T18:24:47","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=91842"},"modified":"2025-01-17T12:24:47","modified_gmt":"2025-01-17T18:24:47","slug":"tras-la-puerta-del-poder-monreal-pide-en-el-desierto-politico-unidad-ante-las-posibles-acciones-de-trump","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-monreal-pide-en-el-desierto-politico-unidad-ante-las-posibles-acciones-de-trump\/","title":{"rendered":"Tras la puerta del poder| Monreal pide -en el desierto pol\u00edtico- unidad ante las posibles acciones de Trump"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Roberto Vizca\u00edno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 17 de enero, 2025.- Ricardo Monreal, el \u00fanico l\u00edder dentro de la 4T que percibe el desastre que se nos viene con Trump<strong>,&nbsp;<\/strong>pide cerrar filas de diputados y senadores, junto a todos los mexicanos, ante las decisiones que pueda tomar el reciclado presidente de EU a partir del lunes al llegar por segunda vez a la Casa Blanca, y que afecten a M\u00e9xico y su Gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El llamado, \u00fanico entre morenistas y funcionarios del r\u00e9gimen, lo realiz\u00f3 el zacatecano como l\u00edder de la mayor\u00eda de Morena en San L\u00e1zaro y luego de la comparecencia ante comisiones legislativas de EU del senador de la Florida&nbsp;<strong>Marco Rubio<\/strong>, nominado como pr\u00f3ximo secretario de Estado por&nbsp;<strong>Donald Trump<\/strong>&nbsp;y de&nbsp;<strong>Pam Bondi<\/strong>, propuesta para ser la pr\u00f3xima Fiscal General de Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la tarde del mi\u00e9rcoles, en una&nbsp;comparecencia de ratificaci\u00f3n ante el Comit\u00e9 de Relaciones Exteriores del Senado,&nbsp;<strong>Rubio<\/strong>&nbsp;-senador republicano de La Florida y de origen cubano- reiter\u00f3 su convicci\u00f3n de que los narcos mexicanos deben ser considerados como grupos terroristas altamente sofisticados que no s\u00f3lo controlan vastas \u00e1reas en la frontera con Estados Unidos, sino que socavan al Gobierno mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstos grupos (criminales) no s\u00f3lo aterrorizan a EU y amplias franjas de la frontera con M\u00e9xico al tiempo que socavan al Gobierno mexicano, a la soberan\u00eda mexicana, y a la salud y el bienestar del pueblo mexicano\u00bb, subray\u00f3&nbsp;<strong>Rubio<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello se pronunci\u00f3 por ir por una \u201cnueva herramienta para combatirlos\u201d en forma conjunta con el gobierno de M\u00e9xico, aunque -dijo- igual podr\u00eda ser facultad personal del presidente&nbsp;<strong>Trump<\/strong>&nbsp;actuar en contra de estos grupos incluso militarmente, insisti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstos sofisticados grupos, estas organizaciones criminales, no s\u00f3lo amenazan a EU sino tambi\u00e9n al proceso pol\u00edtico mexicano. En las \u00faltimas elecciones, varios candidatos fueron asesinados. Hubo periodistas que fueron perseguidos y ejecutados por hablar en contra de estos grupos\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLamentablemente, tambi\u00e9n tienen un control operativo b\u00e1sico sobre grandes franjas de las regiones fronterizas entre M\u00e9xico y Estados Unidos. Ese es un hecho desafortunado, y es algo que tendremos que enfrentar con nuestros socios en M\u00e9xico&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPor eso, mi esperanza en un mundo perfecto es que podamos trabajar en estrecha colaboraci\u00f3n con las autoridades mexicanas para acabar con estos grupos\u00bb, dijo Rubio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PAM DE ACUERDO CON RUBIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez&nbsp;<strong>Pam Bondi&nbsp;<\/strong>nominada por&nbsp;<strong>Trump<\/strong>&nbsp;como pr\u00f3xima Fiscal General de Estados Unidos, coincidi\u00f3 con la visi\u00f3n del senador&nbsp;<strong>Rubio<\/strong>&nbsp;y, en una audiencia ante el Comit\u00e9 Judicial del Senado de EU acept\u00f3 que de ser ratificada apoyar\u00eda designar a los c\u00e1rteles mexicanos como terroristas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u2026 yo misma visit\u00e9 M\u00e9xico, yo misma lidi\u00e9 con estos c\u00e1rteles cuando era fiscal estatal. Son una amenaza grave y violenta para nuestro pa\u00eds. As\u00ed que s\u00ed\u00bb, respondi\u00f3&nbsp;<strong>Bondi<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momentos antes, en la sala Relaciones Exteriores del Senado de EU,&nbsp;<strong>Marco Rubio<\/strong>&nbsp;hab\u00eda dicho:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUna acci\u00f3n militar contra los c\u00e1rteles mexicanos, es una \u2018opci\u00f3n que est\u00e1 sobre la mesa a disposici\u00f3n de Trump\u2019\u201d, reiter\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y explic\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYa sea que usemos esta herramienta, que tal vez no sea la adecuada, o alguna nueva que se nos ocurra, es importante para nosotros no solo perseguir a estos grupos, sino identificarlos y llamarlos por lo que son, y eso es&nbsp;<strong>terroristas: terroristas<\/strong>&nbsp;de naturaleza, aterrorizan con migraci\u00f3n masiva y con el flujo de drogas\u201d, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente&nbsp;<strong>Trump<\/strong>&nbsp;dice, aplicar\u00e1 aranceles a exportaciones mexicanas hacia EU e iniciar\u00e1 una deportaci\u00f3n masiva de inmigrantes ilegales mexicanos lo que junto con el combate de carteles, forman la columna central de todo un accionar que podr\u00eda impactar en una crisis econ\u00f3mica interna, una crisis social y una crisis en las relaciones bilaterales en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>UNIDAD CLAMA EL ZACATECANO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto,&nbsp;<strong>Ricardo Monreal<\/strong>, presidente de la Junta d Coordinaci\u00f3n Pol\u00edtica de la C\u00e1mara de Diputados, convoc\u00f3 a la unidad sin &#8216;regateos&#8217; de todas las fuerzas y grupos parlamentarios en torno a la presidenta&nbsp;<strong>Sheinbaum<\/strong>&nbsp;ante las decisiones de&nbsp;<strong>Trump<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 que la presidenta est\u00e1 lista para hacerle frente al reto del nuevo gobierno norteamericano y confi\u00f3 en que sus medidas ayuden a paliar los efectos de las acciones anunciadas por el mandatario norteamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un momento en el que no debe regatearse la unidad nacional. Frente a presagios de distinta naturaleza, nosotros tenemos que reaccionar con temperancia, con prudencia, con serenidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA pesar del anuncio de esta oficina de aranceles que ha creado el presidente, nosotros tenemos que esperar y actuar en raz\u00f3n de las circunstancias\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ricardo Monreal<\/strong>&nbsp;pidi\u00f3 prepararse tambi\u00e9n para recibir con respeto a migrantes que seguramente ser\u00e1n deportados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo tengo confianza en que el di\u00e1logo va a superar las diferencias, pero es un momento de establecer un frente com\u00fan con la presidenta&nbsp;<strong>Claudia Sheinbaum<\/strong>, que es la jefa de Estado, que es la jefa de gobierno y que necesita a ella, fortaleza, fuerza de su pueblo, para poder enfrentar en una relaci\u00f3n de respeto y de di\u00e1logo la futura situaci\u00f3n frente a Estados Unidos, en una cooperaci\u00f3n entre ambas naciones que es lo deseable\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insisti\u00f3 en que los morenistas en San L\u00e1zaro respaldan a la Presidenta a quien dijo haberla visto, el pasado lunes cuando convers\u00f3 con ella, como suele hacerlo cada semana, serena, cuidadosa, prudente y \u201cpreparada\u201d para responder a las disposiciones de quien ser\u00e1 su hom\u00f3logo, en tres&nbsp;d\u00edas m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026 \/ Twitter: @_Vizcaino \/ Facebook<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Roberto Vizca\u00edno SemM\u00e9xico, Cd. de M\u00e9xico, 17 de enero, 2025.- Ricardo Monreal, el \u00fanico l\u00edder dentro de la 4T que percibe el desastre que se nos viene con Trump,&nbsp;pide cerrar filas de diputados y senadores, junto a todos los mexicanos, ante las decisiones que pueda tomar el reciclado presidente de EU a partir del lunes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-91842","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/91842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=91842"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/91842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=91842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=91842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=91842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}