{"id":9179,"date":"2019-06-25T17:09:05","date_gmt":"2019-06-25T17:09:05","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=9179"},"modified":"2023-07-21T14:49:40","modified_gmt":"2023-07-21T19:49:40","slug":"letra-clara-10","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/letra-clara-10\/","title":{"rendered":"Letra Clara"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Opiniones contrapuestas y\notro silencio\u2026&nbsp; <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Teresa Vald\u00e9s Betancourt <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. 25 de junio\n2019.- En una controversia los temas var\u00edan con el tiempo, la geograf\u00eda y las\nemociones pero siguen entre los m\u00e1s frecuentes, los asuntos de pol\u00edtica,\ndeportes, filosof\u00eda, sexualidad, perspectiva de g\u00e9nero y lenguaje incluyente, entre\notros, con argumentos y posiciones absolutamente parciales seg\u00fan el punto de\nvista de cada quien. Un motivo de esta ocasi\u00f3n ser\u00e1n los derechos que se\nreclamar\u00e1n en la <em>Marcha del Orgullo Gay<\/em>\nLGBTTTI, el pr\u00f3ximo s\u00e1bado 29 de junio convocada para el \u00c1ngel de la\nIndependencia en Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria recuerda que\npasaron 41 a\u00f1os desde la primera manifestaci\u00f3n p\u00fablica en CDMX a favor de los\nderechos homosexuales para conmemorar el <em>D\u00eda\nGay Pride<\/em> en ingl\u00e9s. Esta convocatoria&nbsp;\nen parte integra las expresiones de reclamo de derechos humanos de un\ngrupo discriminado por cuestiones de sexo y viejos prejuicios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante presencia de tales diferencias\ntambi\u00e9n hay que considerar adem\u00e1s de la orientaci\u00f3n sexual, la edad, la raza,\nla \u00e9tnica, la discapacidad y hasta la influencia econ\u00f3mica, junto con la\ndiscriminaci\u00f3n ancestral hacia las mujeres, quienes sufren m\u00e1s limitaciones\ncuando padecen de estas profundas brechas de desigualdad objetiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los derechos humanos y\nciviles se evidencian con el derecho al voto que los hombres alcanzaron primero\ny en 1953, las mujeres mexicanas, los derechos de reuni\u00f3n, de asociaci\u00f3n y de\nparticipaci\u00f3n pol\u00edtica que significa, expresarse libremente como un derecho\nhumano inalienable. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos argumentos se acude\na la historia de los Principios de La Libertad Pol\u00edtica que prev\u00e9n la libre\ncomunicaci\u00f3n del pensamiento y de las opiniones como los derechos m\u00e1s\npreciados. El Art\u00edculo XI de la Declaraci\u00f3n de los Derechos del Hombre, Paris,\n26 de agosto de 1789, se\u00f1ala que, \u201cTodo ciudadano puede, pues, hablar, escribir\ne imprimir libremente, aunque deber\u00e1 responder del abuso de esta libertad en\nlos casos que determine la ley\u201d. Argumentar esos derechos para la mujer y la\nciudadana, le cost\u00f3 la vida a Olimpia de Gougue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los Derechos Humanos como\nen la vida, la lucha por la igualdad implica aceptar las diferencias y la equidad,\nesa palabra m\u00e1gica que debe estar en el presente de hombres y mujeres, porque\njuntos, podemos alcanzar un mundo mejor. Con estos elementos vale se\u00f1alar\nalgunas consideraciones que determinadas palabras limitan su esclarecimiento. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la <em>Marcha de orgullo Gay<\/em> se inserta otro tema controversial a partir\nde la procedencia ling\u00fc\u00edstica. Voz tomada del ingl\u00e9s gay, que significa, como\nadjetivo, \u2018homosexual\u2019 o \u2018de (los) homosexuales\u2019 y, como sustantivo masculino,\n\u2018hombre homosexual\u2019, seg\u00fan la Real Academia Espa\u00f1ola. (DRAE), edici\u00f3n del 2001.En\nla Inglaterra victoriana, el t\u00e9rmino \u00abGay\u00bb se aplicaba a los hombres\nque ejerc\u00edan la prostituci\u00f3n y se convirti\u00f3 en sin\u00f3nimo de homosexual dentro de\nla lengua inglesa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tanto, Gay se refiere\ncasi exclusivamente al g\u00e9nero masculino, por lo tanto, no se aplica a las mujeres\nlesbianas o transexuales, otro aspecto a tener en cuenta en estas\ncontroversias, matizado por la inequidad de g\u00e9nero, donde la discriminaci\u00f3n y\nla violencia, silencia la influencia y presencia de las mujeres en los espacios\np\u00fablicos tradicionalmente ocupados por los hombres. Nuevamente las palabras omiten\nlo femenino del mensaje y las lesbianas desaparecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resulta clara la hist\u00f3rica Resoluci\u00f3n\nde ONU aprobada en Ginebra por el Consejo de Derechos Humanos de Naciones\nUnidas el 26 de septiembre de 2014, para combatir la violencia y la\ndiscriminaci\u00f3n por orientaci\u00f3n sexual, representa un importante logro en\ndefensa de los principios al abordar las violaciones de derechos humanos\nbasadas en la orientaci\u00f3n sexual y la identidad de g\u00e9nero, un fuerte compromiso\npara activistas de los derechos de las personas lesbianas, gays, bisexuales,\ntransg\u00e9nero, transexuales, travestis e intersexuales en la regi\u00f3n\u201d, <em>https:\/\/www.hrw.org\/es\/news\/2014\/<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta resoluci\u00f3n demuestra que\nlos espacios p\u00fablicos todav\u00eda siguen siendo de la cultura masculina que se\napropia de los medios de comunicaci\u00f3n. La Agenda del Consejo de Derechos\nHumanos env\u00eda un mensaje universal de apoyo a las personas, mujeres y hombres, de\ntodo el mundo que sufren este tipo de violencia y discriminaci\u00f3n en la\nreclamaci\u00f3n de sus justos derechos sin exclusiones sexistas innecesarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@Letra Clara<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maestra en Ciencias de la\nComunicaci\u00f3n&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opiniones contrapuestas y otro silencio\u2026&nbsp; Teresa Vald\u00e9s Betancourt SemM\u00e9xico. 25 de junio 2019.- En una controversia los temas var\u00edan con el tiempo, la geograf\u00eda y las emociones pero siguen entre los m\u00e1s frecuentes, los asuntos de pol\u00edtica, deportes, filosof\u00eda, sexualidad, perspectiva de g\u00e9nero y lenguaje incluyente, entre otros, con argumentos y posiciones absolutamente parciales seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,101,79],"tags":[],"class_list":["post-9179","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-letra-clara","category-teresa-valdes-betancourt"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=9179"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/9179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/9180"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=9179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=9179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=9179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}