{"id":91194,"date":"2024-12-19T15:46:21","date_gmt":"2024-12-19T21:46:21","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=91194"},"modified":"2024-12-19T15:46:21","modified_gmt":"2024-12-19T21:46:21","slug":"presidente-municipal-de-san-pedro-ixtlahuaca-agrede-a-una-mujer-en-oaxaca","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/presidente-municipal-de-san-pedro-ixtlahuaca-agrede-a-una-mujer-en-oaxaca\/","title":{"rendered":"Presidente municipal de San Pedro Ixtlahuaca agrede a una mujer en Oaxaca"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Diputada local Cony Rueda exige la intervenci\u00f3n de las autoridades<\/li>\n\n\n\n<li>La informaci\u00f3n trascendi\u00f3 gracias a un video, el mun\u00edcipe se dice \u201cintocable\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 19 de diciembre, 2024.- La diputada local morenista, Concepci\u00f3n Rueda G\u00f3mez conden\u00f3 en sus redes sociales la actuaci\u00f3n del presidente municipal de San Pedro Ixtlahuaca y excandidato al Senado de la Rep\u00fablica, Roberto P\u00e9rez Delgado, de quien previamente se divulg\u00f3 un video en el que ejerce violencia f\u00edsica en contra de una mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su publicaci\u00f3n en su cuenta de X, Cony Rueda G\u00f3mez exige que se investigue y se castigue a quien resulte responsable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente municipal P\u00e9rez Delgado fue exhibido en un video publicado en la cuenta de Jes\u00fas L\u00f3pez Allende, del portal Pol\u00edtica y Poder, mientras \u00e9l est\u00e1 rodeado de hombres, uno de ellos con machete, se acerca una mujer que es recibida a golpes por el mun\u00edcipe, a quien nadie le reclama sobre el hecho y exigen a la mujer que se calme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el video, se escuchan voces que cuestionan a la v\u00edctima del presidente municipal, la insultan y critican por meterse \u201cdonde no debe\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la publicaci\u00f3n del portal noticioso, la mujer trata de defender a una persona que est\u00e1 siendo golpeada por escoltas armados del presidente municipal, entonces el presidente municipal de San Pedro Ixtlahuaca le jala el cabello y le da un pu\u00f1etazo en la cara haci\u00e9ndola retroceder varios metros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acci\u00f3n es repetida en varias ocasiones por parte del presidente municipal Roberto P\u00e9rez Delgado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el portal que difundi\u00f3 el video, el mun\u00edcipe \u201cjura y perjura que nadie lo puede tocar, ya que es senador suplente de Laura Estrada quien busca la gubernatura y el mismo gobernador Salom\u00f3n Jara le debe favores, ya que, sin \u00e9l, el partido Morena y Verde Ecologista no hubieran ganado el Senado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante los hechos, la diputada local, tambi\u00e9n morenista, solicit\u00f3 la intervenci\u00f3n de las autoridades para sancionar al responsable de la agresi\u00f3n a esta mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VIDEO: <a href=\"https:\/\/www.facebook.com\/share\/1Dc4bfw2Nh\/\">https:\/\/www.facebook.com\/share\/1Dc4bfw2Nh\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n&nbsp; SemM\u00e9xico, Oaxaca, 19 de diciembre, 2024.- La diputada local morenista, Concepci\u00f3n Rueda G\u00f3mez conden\u00f3 en sus redes sociales la actuaci\u00f3n del presidente municipal de San Pedro Ixtlahuaca y excandidato al Senado de la Rep\u00fablica, Roberto P\u00e9rez Delgado, de quien previamente se divulg\u00f3 un video en el que ejerce violencia f\u00edsica en contra de una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":91195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[700,48],"tags":[],"class_list":["post-91194","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estados","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/91194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=91194"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/91194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/91195"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=91194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=91194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=91194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}