{"id":90957,"date":"2024-12-12T12:50:51","date_gmt":"2024-12-12T18:50:51","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=90957"},"modified":"2024-12-12T12:50:52","modified_gmt":"2024-12-12T18:50:52","slug":"abre-la-exposicion-exiliadas-de-espana-artistas-en-mexico-en-san-ildefonso-y-anuncian-catedra-maria-zambrano","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/abre-la-exposicion-exiliadas-de-espana-artistas-en-mexico-en-san-ildefonso-y-anuncian-catedra-maria-zambrano\/","title":{"rendered":"Abre la exposici\u00f3n \u201cExiliadas de Espa\u00f1a. artistas en M\u00e9xico\u201d, en San Ildefonso y anuncian c\u00e1tedra Mar\u00eda Zambrano"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Re\u00fane cerca de 200 obras de 30 artistas que encontraron en M\u00e9xico un nuevo hogar y un lienzo donde plasmar sus sue\u00f1os, se\u00f1al\u00f3 el rector Leonardo Lomel\u00ed Vanegas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se entiende Espa\u00f1a sin M\u00e9xico y a M\u00e9xico sin el exilio espa\u00f1ol, sostuvo el embajador Juan Duarte Cuadrado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico,&nbsp; Ciudad de M\u00e9xico, 12 de diciembre, 2024.- La exposici\u00f3n \u201cExiliadas de Espa\u00f1a. Artistas en M\u00e9xico\u201d, un homenaje a mujeres extraordinarias que transformaron el dolor del exilio en un acervo de reminiscencia, belleza y creatividad, fue inaugurada por el rector de la UNAM, Leonardo Lomel\u00ed Vanegas; el embajador de Espa\u00f1a en nuestro pa\u00eds, Juan Duarte Cuadrado; y el jefe de la Oficina de la Presidencia de la Rep\u00fablica, L\u00e1zaro C\u00e1rdenas Batel, entre otras autoridades.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante mujeres y hombres directamente involucrados con el exilio espa\u00f1ol, el rector Leonardo Lomel\u00ed afirm\u00f3 que la muestra es \u201cun testimonio de la valent\u00eda de quienes, obligadas a abandonar sus hogares por los horrores de la Guerra Civil Espa\u00f1ola y la dictadura franquista, hallaron en M\u00e9xico no solo un refugio, sino tambi\u00e9n un nuevo hogar y un lienzo donde plasmar sus sue\u00f1os, luchas y anhelos\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la muestra -que incluye cerca de 200 obras de 30 artistas y que estar\u00e1 abierta en el Colegio de San Ildefonso hasta fines de abril de 2025- acudi\u00f3 tambi\u00e9n el ingeniero Cuauht\u00e9moc C\u00e1rdenas Sol\u00f3rzano, hijo del presidente L\u00e1zaro C\u00e1rdenas del R\u00edo, a quien el rector record\u00f3 por abrir las puertas del pa\u00eds a las y los exiliados espa\u00f1oles, y con ello dar un ejemplo perdurable de solidaridad internacional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas mujeres artistas trajeron su talento y una voluntad inquebrantable para vivir con dignidad y contribuir al desarrollo de nuestro pa\u00eds\u201d. Sus creaciones no solo enaltecieron y nutrieron al arte mexicano, sino que reconfiguraron el significado de pertenencia, demostrando una gran virtud para conectar su pasado con un futuro pleno, lleno de posibilidades, a\u00f1adi\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rector de la UNAM tambi\u00e9n destac\u00f3 el valor de la exposici\u00f3n ante las constantes crisis migratorias y humanitarias, pues recuerda el inmenso valor que las personas desplazadas aportan a las sociedades donde construyen un hogar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que, en una \u00e9poca de divisiones, el arte tiene el potencial de ser enlace entre culturas, un recordatorio de nuestra humanidad compartida y una herramienta poderosa para construir redes de cooperaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Trabajo a favor<\/em><\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su oportunidad, el embajador Juan Duarte explic\u00f3 que la exposici\u00f3n concluye las diversas actividades con las que se conmemor\u00f3 el 85 aniversario del exilio espa\u00f1ol y los 75 a\u00f1os del Ateneo Espa\u00f1ol de M\u00e9xico, que simbolizan la reparaci\u00f3n y\/o reconocimiento a descendientes de los exiliados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La muestra permite tambi\u00e9n conocer el trabajo de mujeres que pudieron ser artistas aqu\u00ed y \u201cretomaron la antorcha de creatividad para poder hacer justicia por las que tuvieron que callar en Espa\u00f1a\u201d. Adem\u00e1s, se pronunci\u00f3 porque museos de esa naci\u00f3n exhiban tambi\u00e9n sus obras.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ado por Alonso Leal G\u00fcemes, vicetesorero y vocal de Asuntos Jur\u00eddicos del Ateneo Espa\u00f1ol de M\u00e9xico, el diplom\u00e1tico agradeci\u00f3 a la familia C\u00e1rdenas por haber acogido en M\u00e9xico a los exiliados. Sostuvo que Espa\u00f1a no se entiende sin M\u00e9xico y M\u00e9xico tampoco se entiende sin el exilio espa\u00f1ol.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, manifest\u00f3 su inter\u00e9s por seguir trabajando con nuestro pa\u00eds para mejorar la dignidad de las personas que se ven obligadas a abandonar su tierra, pues los exilios nunca acaban y M\u00e9xico es especialmente afectado por la movilidad humana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n de la presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, L\u00e1zaro C\u00e1rdenas Batel expres\u00f3 que fue un privilegio asistir a la inauguraci\u00f3n de la exposici\u00f3n que celebra a mujeres que mucho aportaron a nuestro pa\u00eds y a Espa\u00f1a. Tambi\u00e9n reconoce la fuerza cultural de ambas naciones y resalta la generosidad, solidaridad humana y la hermandad que une a sus pueblos y que nunca habr\u00e1 de romperse.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, la coordinadora de Difusi\u00f3n Cultural UNAM, Rosa Beltr\u00e1n \u00c1lvarez, agradeci\u00f3 a los descendientes de exiliados de la rep\u00fablica espa\u00f1ola haber apoyado la exposici\u00f3n que vindica a las pintoras espa\u00f1olas exiliadas en M\u00e9xico y su trabajo de gran calidad que la tradici\u00f3n patriarcal no visibiliz\u00f3 antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rememor\u00f3 que muchas llegaron siendo ni\u00f1as, otras nacieron aqu\u00ed y algunas m\u00e1s fueron v\u00edctimas de la guerra, a quienes \u201cesta naci\u00f3n les brind\u00f3 un nuevo comienzo, una nueva manera de ver la vida y la oportunidad de plasmarlo mediante el pincel\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Reconocimiento a Mar\u00eda Zambrano<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;<\/em>En el Anfiteatro Sim\u00f3n Bol\u00edvar, del Colegio de San Ildefonso, la secretaria de Desarrollo Institucional de la UNAM, Tamara Mart\u00ednez Ru\u00edz, anunci\u00f3 que se establecer\u00e1 la \u201cC\u00e1tedra Mar\u00eda Zambrano: filosof\u00eda, poes\u00eda, g\u00e9nero y exilio\u201d, a fin de resaltar la obra de quien se exili\u00f3 en nuestro pa\u00eds y en otras naciones, fue la primera mujer en ganar el Premio Cervantes, en 1988; y es considerada la figura femenina m\u00e1s importante del pensamiento espa\u00f1ol del siglo XX.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La C\u00e1tedra se realizar\u00e1 en conjunto con el Instituto Cervantes, de Espa\u00f1a, y la Universidad de La Habana, Cuba; y tendr\u00e1 entre sus objetivos: difundir los aportes de las mujeres del exilio espa\u00f1ol republicano, destacando su v\u00ednculo con nuestro pa\u00eds y Am\u00e9rica Latina. Dar\u00e1 a conocer la obra de Zambrano a las nuevas generaciones, y favorecer\u00e1 los estudios sobre los exilios del siglo XX y su impacto en la cultura y el pensamiento, entre otros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Zambrano, prosigui\u00f3 Mart\u00ednez Ru\u00edz, fue una \u201chabitante del pa\u00eds del exilio\u201d, visionaria, sensible y libre, que abri\u00f3 el pensamiento filos\u00f3fico a la intuici\u00f3n, al conocimiento m\u00edstico, a la poes\u00eda, a lo femenino, temas poco explorados por los fil\u00f3sofos. La C\u00e1tedra se abrir\u00e1 en el marco de los 120 a\u00f1os de su nacimiento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los curadores y catedr\u00e1ticos de la Facultad de Filosof\u00eda y Letras de la Universidad de Granada, Espa\u00f1a, Yolanda Guasch Mar\u00ed y Rafael L\u00f3pez Guzm\u00e1n, resaltaron el apoyo de las familias de las artistas para acceder a sus creaciones, que son parte de su intimidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n incluye obras de Lucinda Urrusti, Manuela Ballester, Paloma Altolaguirre, Mar\u00eda Teresa Toral, Elvira Gasc\u00f3n y Remedios Varo, Julia Gim\u00e9nez Cacho, Kati Horna, Loty de la Granja, Marta Palau, Mary Mart\u00edn, Montserrat Aleix, Nela Gaos, Regina Raull, Rosa Ballester, Soledad Mart\u00ednez, Teresa Mart\u00edn, Teresa Olabuenaga y Yani Pecanins, entre otras.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la inauguraci\u00f3n estuvieron tambi\u00e9n: Daniel Garza Usabiaga, director del Museo del Palacio de Bellas Artes; Julia Cabrera Sol\u00eds, directora de la Red de Museos de la Secretar\u00eda de Cultura de la Ciudad de M\u00e9xico; Eduardo V\u00e1zquez Mart\u00edn, coordinador Ejecutivo del Colegio de San Ildefonso; la directora del Instituto de Investigaciones Est\u00e9ticas de la UNAM, Ang\u00e9lica Vel\u00e1zquez Guadarrama, entre algunas autoridades del gobierno federal, de la Ciudad de M\u00e9xico, de Espa\u00f1a y de esta casa de estudios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Re\u00fane cerca de 200 obras de 30 artistas que encontraron en M\u00e9xico un nuevo hogar y un lienzo donde plasmar sus sue\u00f1os, se\u00f1al\u00f3 el rector Leonardo Lomel\u00ed Vanegas No se entiende Espa\u00f1a sin M\u00e9xico y a M\u00e9xico sin el exilio espa\u00f1ol, sostuvo el embajador Juan Duarte Cuadrado Redacci\u00f3n&nbsp; SemM\u00e9xico,&nbsp; Ciudad de M\u00e9xico, 12 de diciembre, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-90957","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=90957"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/90958"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=90957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=90957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=90957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}