{"id":90531,"date":"2024-12-03T08:38:50","date_gmt":"2024-12-03T14:38:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=90531"},"modified":"2024-12-03T08:38:50","modified_gmt":"2024-12-03T14:38:50","slug":"guardar-silencio-ante-la-violencia-es-normalizarla","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/guardar-silencio-ante-la-violencia-es-normalizarla\/","title":{"rendered":"Guardar silencio ante la violencia es normalizarla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Guadalupe Barrena N\u00e1jera, Miriam Camacho Valladares y D\u00e1maso Morales Ram\u00edrez\u00a0 actividades en los 16 d\u00edas de Activismo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Identificar el comportamiento negativo en las relaciones interpersonales\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Redacci\u00f3n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>16 d\u00edas de acci\u00f3n, 9\u00ba. D\u00eda &nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 3 de diciembre, 2024.-La violencia se construye, no sucede por \u201cgeneraci\u00f3n espont\u00e1nea\u201d; sus manifestaciones son cada d\u00eda m\u00e1s diversas, globalizadas y tecnologizadas.&nbsp; Para afrontarla y erradicarla, hay que aceptar que es un problema de salud p\u00fablica y atender sus se\u00f1ales de forma multidisciplinaria, afirm\u00f3 Miriam Camacho Valladares.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la titular de la Defensor\u00eda de los Derechos Universitarios, Igualdad y Atenci\u00f3n de la Violencia de G\u00e9nero de la UNAM, Guadalupe Barrena N\u00e1jera, la jefa del \u00e1rea de Atenci\u00f3n Psicol\u00f3gica a V\u00edctimas de Violencia de G\u00e9nero, de ese \u00f3rgano, tambi\u00e9n se\u00f1al\u00f3 que donde existe una relaci\u00f3n interpersonal puede haber ese comportamiento negativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, puntualiz\u00f3 Camacho Valladares, cada persona debe realizar una revisi\u00f3n y marcar una diferencia en las que establece, ya sean emocionales, familiares, laborales o profesionales; as\u00ed podremos dejar de percibirla como \u201cnormal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo importante no es tener una definici\u00f3n, sino conciencia de identificar c\u00f3mo ejercemos la violencia, hacia qui\u00e9n; c\u00f3mo los otros la aplican hacia nosotros, c\u00f3mo la observamos y qu\u00e9 reacciones tenemos ante ello, destac\u00f3 en la conferencia Prevenci\u00f3n de la Violencia de G\u00e9nero en la UNAM: desaf\u00edos y soluciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ocasi\u00f3n de las actividades por el 25N, D\u00eda Internacional para la Eliminaci\u00f3n de la Violencia contra las Mujeres, en la Facultad de Ciencias Pol\u00edticas y Sociales (FCPyS)<em>,&nbsp;<\/em>la ponente diferenci\u00f3 la agresi\u00f3n de la violencia; la primera se refiere a expresiones conductuales observables, medibles y registrables que tienen un fundamento biol\u00f3gico para sobrevivencia, defensa y ataque por competencia biol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, la segunda es el uso deliberado de actitudes de poder; son manifestaciones emocionales (verbales, f\u00edsicas, etc\u00e9tera) con el objetivo de causar da\u00f1o. Se trata de modelos aprendidos e imitados; genera una fractura en la percepci\u00f3n de seguridad de una persona, la cual va m\u00e1s all\u00e1 de la afectaci\u00f3n de la v\u00edctima directa, ya que se altera todo su entono emocional, familiar, etc\u00e9tera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abund\u00f3 que es una conducta, actitud o presencia como testigo (silencioso o no) que involucra dolo, planeaci\u00f3n, intenci\u00f3n focalizada y que tiene la finalidad de da\u00f1ar, causar dolor, desestabilizar o devaluar a una persona o grupo, de forma inmediata o a mediano o largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con sus afectaciones son: f\u00edsica (manazos, patadas, pellizcos, aventones, jaloneos); emocional (palabras altisonantes, miradas lascivas, sobrenombres, se\u00f1as, muecas); social (discriminaci\u00f3n, rechazo); econ\u00f3mica; acad\u00e9mica (burla por rendimiento); laboral (castigos no merecidos, etc\u00e9tera); y sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Camacho Valladares al quedarse en silencio cuando se vive o se observa una experiencia de esa naturaleza se estar\u00eda colaborando con ese acto y ayudando a concebir que la violencia es normal. Esta se recibe o se ejerce y tambi\u00e9n se puede fomentar. Por ello, hay que hacerla visible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacia mejor convivencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guadalupe Barrena mencion\u00f3 la m\u00e1xima voluntad de coordinaci\u00f3n, colaboraci\u00f3n y de engarzar esfuerzos y recursos para que las personas que siguen experimentando actos de ese tipo tengan a su alcance las herramientas que la Universidad en su conjunto ha dispuesto para que puedan ser atendidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso institucional por erradicarla articula la operaci\u00f3n de distintas instancias. La actuaci\u00f3n fluida de numerosas manos que intervienen en estos asuntos permite dar atenci\u00f3n y cauce a los planteamientos que las personas necesitan hacer llegar a las autoridades universitarias. \u201cPercibo que la confianza de la comunidad en ellas para hacerles saber las experiencias que viven en este tema se ha incrementado en los \u00faltimos a\u00f1os\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la sesi\u00f3n moderada por M\u00f3nica Amilpas Garc\u00eda, de la Unidad de G\u00e9nero de la FCPyS, D\u00e1maso Morales Ram\u00edrez, secretario General de la entidad, reconoci\u00f3: aunque hay avances, la tarea es todav\u00eda gigantesca en este \u00e1mbito. \u201cEn t\u00e9rminos de educaci\u00f3n y sensibilizaci\u00f3n hay mucho por hacer\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, anunci\u00f3 que se dotar\u00e1 a dicha instancia de m\u00e1s herramientas y mayor visibilidad, se fortalecer\u00e1n protocolos y el acompa\u00f1amiento, de tal manera que \u201cpodamos ser una comunidad sana, donde nos respetemos, libre de cualquier tipo de violencia, donde podamos convivir y podamos avanzar en nuestra profesionalizaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014o0o\u2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guadalupe Barrena N\u00e1jera, Miriam Camacho Valladares y D\u00e1maso Morales Ram\u00edrez\u00a0 actividades en los 16 d\u00edas de Activismo Identificar el comportamiento negativo en las relaciones interpersonales\u00a0 Redacci\u00f3n 16 d\u00edas de acci\u00f3n, 9\u00ba. D\u00eda &nbsp; SemM\u00e9xico, Cd. de M\u00e9xico, 3 de diciembre, 2024.-La violencia se construye, no sucede por \u201cgeneraci\u00f3n espont\u00e1nea\u201d; sus manifestaciones son cada d\u00eda m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[626],"tags":[],"class_list":["post-90531","post","type-post","status-publish","format-standard","has-post-thumbnail","category-16-dias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=90531"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/90532"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=90531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=90531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=90531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}