{"id":90336,"date":"2024-11-29T18:14:01","date_gmt":"2024-11-30T00:14:01","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=90336"},"modified":"2024-11-29T18:16:52","modified_gmt":"2024-11-30T00:16:52","slug":"la-comunidad-debe-estar-consciente-de-esa-problematica-es-una-prioridad-visibilizar-la-violencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-comunidad-debe-estar-consciente-de-esa-problematica-es-una-prioridad-visibilizar-la-violencia\/","title":{"rendered":"La comunidad debe estar consciente de esa problem\u00e1tica: es una prioridad visibilizar la violencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las coordinadoras de las Comisiones Internas para la Igualdad de G\u00e9nero de los cinco planteles del Colegio de Ciencias y Humanidades hablan sobre el significado del 25N y los 16 d\u00edas de activismo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n explican, cuentan sobre las diversas actividades realizadas &nbsp;para hacer conciencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16 d\u00edas de activismo, 5\u00ba. D\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 29 de noviembre, 2024.- Durante el ciclo escolar 2023-2024, las CInIG de los CCH organizaron m\u00faltiples actividades dirigidas a estudiantes, acad\u00e9micos y personal administrativo con el fin de seguir trabajando por espacios escolares m\u00e1s justos, seguros y comprometidos con la igualdad de g\u00e9nero, a partir de informar, formar, concientizar y reflexionar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"557\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02.jpg\" alt=\"\" class=\"wp-image-90337\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02-300x169.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02-768x432.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02-150x84.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-02-696x392.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para conmemorar el 25N, el Colegio de Ciencias y Humanidades (CCH) prepar\u00f3 una serie de actividades con el prop\u00f3sito de evidenciar y visibilizar la importancia de dicha efem\u00e9ride, afirm\u00f3 Hassibi Yessenia Romero, coordinadora de la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero (CInIG) en el plantel Azcapotzalco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs relevante que las y los j\u00f3venes reflexionen sobre el tema de la violencia, conducta considerada una problem\u00e1tica que debe atenderse\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, estas actividades permitir\u00e1n que los estudiantes identifiquen situaciones normalizadas en la sociedad y sepan qu\u00e9 hacer ante la violencia de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, Hassibi Yessenia Romero consider\u00f3 significativo visibilizar el problema para que el alumnado lo comprenda y ponga un alto a las violencias aprendidas culturalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDeben entender que estas conductas se pueden frenar al identificarse y al generar espacios seguros, de respeto y tolerancia dentro de la escuela, as\u00ed como para que el estudiantado vea la corresponsabilidad que se tiene como integrantes de una comunidad\u201d, indic\u00f3 la profesora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se trabaja \u201cpara generar conciencia en las y los alumnos. Por lo anterior, es relevante que cuenten con las herramientas que les ofrece la asignatura de Igualdad de G\u00e9nero, para que los aprendizajes no s\u00f3lo se apliquen en los espacios educativos, sino en todas las esferas de la vida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Talleres, conferencias\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa de la CInIg del plantel Azcapotzalco cont\u00f3 con actividades l\u00fadicas, talleres, muestras de cine, as\u00ed como un ciclo de conferencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro del mes se realiz\u00f3 la exposici\u00f3n fotogr\u00e1fica&nbsp;<em>Viviendo las violencias<\/em>&nbsp;y&nbsp;<em>Yo tambi\u00e9n tengo huellas de la violencia de g\u00e9nero<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, arranc\u00f3 el \u201cTaller de bordado y pintura para estudiantes\u201d, el cual busca identificar y abordar cuestiones de violencia de g\u00e9nero. En la secci\u00f3n de cine debate se organiz\u00f3 el acto \u201cIdentifica las violencias de g\u00e9nero\u201d. Asimismo, se efectu\u00f3 el concurso \u201cLa m\u00e1s draga\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, se llevaron a cabo las charlas \u201cPrevenci\u00f3n del suicidio\u201d e \u201cIdentificaci\u00f3n de violencias de g\u00e9nero en mis contextos\u201d, en la Sala Jos\u00e9 Sarukh\u00e1n y el Auditorio Ruy P\u00e9rez Tamayo del Siladin, respectivamente; en esta \u00e1rea de laboratorios tambi\u00e9n hubo un estand de la Defensor\u00eda de los Derechos Universitarios, Igualdad y Atenci\u00f3n a la Violencia de G\u00e9nero de la UNAM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se presentaron las conferencias \u201c\u00bfQu\u00e9 hago ante la violencia digital?\u201d, y \u201cRefrendando compromisos ante la prevenci\u00f3n y erradicaci\u00f3n de la violencia de g\u00e9nero\u201d, entre otras actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Porfirio Carrillo \/ Gaceta CCH<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"557\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03.jpg\" alt=\"\" class=\"wp-image-90338\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03-300x169.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03-768x432.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03-150x84.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-03-696x392.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el plantel Naucalpan se conmemor\u00f3 el D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer con la organizaci\u00f3n de diversas actividades acad\u00e9micas, culturales, cient\u00edficas y otras, surgidas desde su propia comunidad estudiantil, docente y administrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe trata de una serie de conferencias, talleres, demostraciones art\u00edsticas, de cine y dem\u00e1s actividades con el objetivo de concientizar, sensibilizar, informar a nuestra comunidad y erradicar actitudes, pensamientos, relaciones que fomentan cuestiones de poder y de violencia de g\u00e9nero\u201d, se\u00f1al\u00f3 Marcela Rojas Valero, coordinadora de la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero (CInIG) del plantel Naucalpan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La coordinadora dijo que \u201cse busca poner las bases de una comunidad en la que se d\u00e9 una relaci\u00f3n m\u00e1s emp\u00e1tica, menos violenta, m\u00e1s respetuosa, m\u00e1s amable; es un trabajo enorme que ya lleva bastante tiempo en nuestra Universidad, y nuestro plantel tambi\u00e9n se integra a esto; a\u00fan hay mucho por hacer, pero estamos en el camino y eso es muy importante\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que estas actividades se basaron en los cuatro ejes que la Coordinaci\u00f3n para la Igualdad de G\u00e9nero en la UNAM establece: la educaci\u00f3n para la igualdad; la inclusi\u00f3n y la seguridad; la corresponsabilidad en los cuidados, y el trabajo con hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>La comunidad se sensibiliza<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rojas dijo que en estas acciones participan especialistas de otras instituciones, asociaciones como las facultades de Estudios Superiores Iztacala y Acatl\u00e1n, Casa Gaviota, PEMBU, Instituto de las Mujeres Naucalpenses, as\u00ed como del plantel: el Departamento de Prog\u00e9nero, la Secretar\u00eda de Atenci\u00f3n a la Comunidad, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, la acad\u00e9mica resalt\u00f3 que la respuesta de los estudiantes ha sido relevante e interesante. Hay una buena recepci\u00f3n de la comunidad estudiantil, desde hace cinco a\u00f1os se han reforzado las jornadas del 25N y el 8M y la comunidad ha comenzado a sensibilizarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTan es as\u00ed \u2014 coment\u00f3\u2014, que se ha podido observar un cambio en las actitudes, incluso en el manejo del lenguaje del estudiantado, al referirse a conceptos como igualdad de g\u00e9nero, feminismo o micromachismos; quiero pensar que es resultado de todo este trabajo que se est\u00e1 haciendo en los planteles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, precis\u00f3, \u201chay una buena respuesta por parte de los profesores, por ejemplo, de quienes imparten la asignatura de Igualdad de G\u00e9nero. Nos estamos formando poco a poco, se est\u00e1n sensibilizando y hay cambios interesantes, como en la forma de relacionarse con el alumnado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, la secretaria general del plantel, Berenice Ruiz Melgarejo, destac\u00f3 que para la Universidad esta fecha es muy importante, y la comunidad del plantel Naucalpan lo toma muy en serio: \u201cde hecho, toda la comunidad se organiza, participa el alumnado, nuestros profesores y de manera muy destacada Prog\u00e9nero, la Secretar\u00eda de Atenci\u00f3n a la Comunidad, la CInIG de nuestro plantel y las Personas Orientadoras Comunitarias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hilda Villegas Gonz\u00e1lez \/ Gaceta CCH<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"557\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04.jpg\" alt=\"\" class=\"wp-image-90339\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04-300x169.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04-768x432.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04-150x84.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-04-696x392.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl 25N ha tomado mucha relevancia; antes se pensaba nada m\u00e1s en el D\u00eda de la Mujer como tal, pero hablar de un D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer es otra cosa. S\u00ed tiene que ver con el respeto, con reconocer la labor de las mujeres, pero adem\u00e1s es un d\u00eda para levantar la voz y terminar con esta violencia, que contin\u00faa desafortunadamente, sobre ellas\u201d, se\u00f1al\u00f3 Rebeca \u00c1ngeles L\u00f3pez, coordinadora de la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero (CInIG) en el plantel Vallejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSabemos que la violencia afecta a la poblaci\u00f3n en general; se dice que tambi\u00e9n los hombres, las diversidades sexuales y las infancias la viven, s\u00ed, es cierto, la violencia est\u00e1 en todos lados; sin embargo, hist\u00f3ricamente se ha visto que la agresi\u00f3n que se ejerce sobre las mujeres ha sido mucha y de distintas formas; entonces, es importante y vale mucho la pena reconocer ese d\u00eda\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La profesora del \u00c1rea de Matem\u00e1ticas a\u00f1adi\u00f3 que es relevante llamar la atenci\u00f3n sobre este d\u00eda para que se termine con la violencia que involucra a mujeres de todas las edades, de todas las clases sociales y en todos los aspectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay muchos tipos de violencia, no s\u00f3lo podemos hablar de agresiones f\u00edsicas, a veces pareciera que de repente se han eliminado, pero no, desafortunadamente vemos que las violencias psicol\u00f3gicas o econ\u00f3micas se mantienen\u201d, lament\u00f3 la coordinadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un d\u00eda para trascender<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTener un d\u00eda en el que se pueda alzar la voz y visibilizar esta violencia es de gran relevancia. Es un d\u00eda internacional; sin embargo, estamos en esta etapa escolar del bachillerato, as\u00ed que lo veo con m\u00e1s trascendencia porque estamos formando j\u00f3venes. (Buscamos) que ellas y ellos, desde estos niveles, lo visibilicen\u201d, agreg\u00f3 Rebeca \u00c1ngeles L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, dijo que \u201cdesde la CInIG del plantel Vallejo realizamos acciones y hay diversos medios para acercarnos a la comunidad y darles informaci\u00f3n; tenemos en los pasillos del plantel pizarras violeta, constantemente hacemos art\u00edculos para el bolet\u00edn Comunidad Vallejo y para esta fecha hubo, como cada a\u00f1o, varias actividades que involucran a distintas \u00e1reas del conocimiento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas y los docentes que pertenecemos a la Comisi\u00f3n somos de distintas asignaturas; esto nos ayuda a llegar a los estudiantes de diversas maneras\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPor ejemplo, yo soy del \u00c1rea de Matem\u00e1ticas y estoy en la parte tecnol\u00f3gica con Taller de C\u00f3mputo, por lo que realizaremos c\u00e1rteles e infograf\u00edas. Esto nos permite acercarnos con trabajos que las y los alumnos hacen a trav\u00e9s de las redes de manera digital, en las que las chicas y los chicos se mueven m\u00e1s y obtienen m\u00e1s informaci\u00f3n\u201d, explic\u00f3 la profesora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTambi\u00e9n hacemos p\u00f3dcast en los que se habla de estos temas y se visibilizan; asimismo, colaboramos con un seminario y se dar\u00e1n algunas pl\u00e1ticas durante esa semana del 25N, con temas relacionados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, mencion\u00f3 que los profesores de las \u00e1reas de Talleres de Lenguaje y Comunicaci\u00f3n y de Hist\u00f3rico-Social trabajan con los estudiantes; \u201cse hizo un p\u00f3dcast en una materia de Idiomas y algunos ser\u00e1n en ingl\u00e9s. Tratamos de acercarnos de todas las formas a la comunidad y contamos con el apoyo de varios departamentos\u201d, como el de Comunicaci\u00f3n y con las redes oficiales del plantel\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Yolanda Garc\u00eda \/ Gaceta CCH<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"557\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05.jpg\" alt=\"\" class=\"wp-image-90340\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05-300x169.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05-768x432.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05-150x84.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-05-696x392.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el plantel Oriente del CCH \u201cel 25 de noviembre es una conmemoraci\u00f3n muy importante. Lo que buscamos desde la CInIG es que la gente y toda nuestra comunidad haga conciencia para erradicar la violencia contra la mujer, pero no con m\u00e1s violencia, sino desde la educaci\u00f3n y una cultura de paz y de igualdad; esa es nuestra bandera\u201d, se\u00f1al\u00f3 Mar\u00eda del Carmen Mej\u00eda Sol\u00eds, coordinadora de la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero (CInIG) local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que a\u00f1o con a\u00f1o la CInIG implementa \u201cdiferentes acciones para hacer notoria esta fecha. En ocasiones empezamos a recordarles a la comunidad qu\u00e9 suceder\u00e1. Este a\u00f1o, una semana antes del 25N, comenzaron con algunas acciones para que el lunes arranquemos (que fue el d\u00eda de la efem\u00e9ride) con las actividades m\u00e1s importantes\u201d, adelant\u00f3 la profesora del \u00c1rea de Talleres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre lo que representa esta fecha, coment\u00f3 que \u201cel 25N es una conmemoraci\u00f3n, no celebraci\u00f3n, porque no hay nada que celebrar. Es concientizar acerca de la violencia que hay no s\u00f3lo hacia las mujeres mayores, sino a las peque\u00f1as, desde que la mujer empieza a tener uso de conciencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay muchas violencias normalizadas que afectan en la psique y en el desarrollo de las personas; no necesariamente hablamos de feminicidios, pese a que es importante mencionarlos. Hablamos de la violencia de g\u00e9nero que se suscita desde el hogar y se naturaliza, parece es algo cotidiano, y que ah\u00ed les toc\u00f3 vivir\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesde las acciones que hacemos, como conferencias, charlas y talleres, tratamos de visibilizarla, de hacer conciencia y reflexi\u00f3n para que el estudiantado pueda ver el mundo de otra forma, no para que lleguen a sus casas y traten de solucionarlo todo de la noche a la ma\u00f1ana, pero s\u00ed para que cuando ellas y ellos crezcan, sepan llevar una vida m\u00e1s sana en sus v\u00ednculos. Quitar esas relaciones de poder que implican dominaci\u00f3n; mejor que busquen una forma de convivencia m\u00e1s sana y arm\u00f3nica, sin este tipo de violencias\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La coordinadora de la CInIG a\u00f1adi\u00f3 que en t\u00e9rminos generales \u201csiempre estamos abiertas a recibir a las personas que necesiten apoyo y hablar del tema\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recalc\u00f3 que este a\u00f1o empezaron desde el viernes 22 de noviembre y siguieron toda la semana de actividades; \u201cen la entrada principal y en los auditorios de la escuela tendremos diferentes actos\u201d, revel\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQueremos sensibilizar a la gente para que sepa por qu\u00e9 se conmemora ese d\u00eda, qu\u00e9 sucedi\u00f3, hacer un poquito de historia y se enteren de d\u00f3nde viene, en qu\u00e9 momento se dio, desde cu\u00e1ndo se realiza y aunado a esto las violencias normalizadas hacia la mujer, pues queremos que esto termine\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Porfirio Carrillo \/ Gaceta CCH<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"557\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06.jpg\" alt=\"\" class=\"wp-image-90342\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06-300x169.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06-768x432.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06-150x84.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-06-696x392.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El 25 de noviembre, D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, \u201ces una oportunidad para educar sobre la importancia del respeto, la igualdad y la erradicaci\u00f3n de la violencia de g\u00e9nero, as\u00ed como para fomentar la reflexi\u00f3n entre el estudiantado sobre el papel que desempe\u00f1an en la prevenci\u00f3n de la violencia y promover el respeto mutuo\u201d, se\u00f1al\u00f3 Guadalupe Florido Araujo, coordinadora de la Comisi\u00f3n Interna para la Igualdad de G\u00e9nero (CInIG) en el plantel Sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la CInIG, dijo, \u201cnos sumamos a esta fecha que busca reconocer el movimiento feminista y a quienes con su lucha representan la reivindicaci\u00f3n de los derechos humanos de las mujeres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente, se busca concientizar sobre la violencia de g\u00e9nero, \u201cparticularmente hacia las mujeres y las ni\u00f1as, as\u00ed como promover la igualdad, enfatizando la importancia de erradicar la violencia hacia las mujeres en todas sus manifestaciones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, esta conmemoraci\u00f3n tambi\u00e9n nos permite pensar sobre los desaf\u00edos persistentes en torno al tema y la necesidad de trabajar juntas y juntos en la construcci\u00f3n de un mundo sin violencia de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de honrar la memoria de las hermanas Mirabal (Patria, Minerva y Mar\u00eda Teresa, las dominicanas que se opusieron a la dictadura de Rafael Le\u00f3nidas Trujillo y fueron asesinadas el 25 de noviembre de 1960), el 25N busca sensibilizar a la sociedad sobre la violencia de g\u00e9nero como un problema estructural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, permite promover el respeto y la igualdad entre las personas, as\u00ed como el dise\u00f1o de pol\u00edticas y acciones que prevengan y coadyuven a la erradicaci\u00f3n de este problema global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de actividades realizadas en el contexto de la Jornada 25N, la CInIG acerc\u00f3 al estudiantado y a la comunidad del plantel Sur en general a la reflexi\u00f3n sobre las m\u00faltiples manifestaciones de violencia contra las mujeres para visibilizar acciones que conduzcan a la construcci\u00f3n de una comunidad igualitaria, libre de roles, estereotipos, discriminaci\u00f3n y violencia por razones de g\u00e9nero, a trav\u00e9s de la promoci\u00f3n de la cultura de paz, cuidados compartidos, inclusi\u00f3n y respeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ello, se permite reconocer diversas manifestaciones de violencia de g\u00e9nero, as\u00ed como los mecanismos que tiene la Universidad Nacional para su atenci\u00f3n, adem\u00e1s de contribuir a su formaci\u00f3n como agentes de cambio en sus comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante las actividades, las alumnas y los alumnos fueron capaces de reflexionar sobre la importancia de la construcci\u00f3n de una sociedad igualitaria, a trav\u00e9s de la inclusi\u00f3n, el respeto y la cultura de paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada cont\u00f3 con proyectos art\u00edsticos, escritos, charlas, conferencias, proyecciones y actividades l\u00fadicas, que expresaron el rechazo a la violencia y promovieron la igualdad de g\u00e9nero, de manera que la participaci\u00f3n activa de la comunidad escolar contribuya a la conciencia y al cambio cultural necesarios para combatir este problema y promover la igualdad de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, conmemorar el 25N \u201ces esencial para la formaci\u00f3n del estudiantado porque se destaca la lucha contra la violencia de g\u00e9nero y promueve la conciencia sobre este problema en los \u00e1mbitos global y local; simboliza la resistencia y la valent\u00eda ante la violencia hacia las mujeres y las ni\u00f1as\u201d, concluy\u00f3 Florido Araujo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Porfirio Carrillo \/ Gaceta CCH<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"450\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07.jpg\" alt=\"\" class=\"wp-image-90341\" srcset=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07.jpg 990w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07-300x136.jpg 300w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07-768x349.jpg 768w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07-150x68.jpg 150w, https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/11\/comunidad-07-696x316.jpg 696w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fotos:\u00a0<em>Gaceta CCH<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/25n\/\">25N<\/a><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/colegio-de-ciencias-y-humanidades-cch\/\">Colegio de Ciencias y Humanidades (CCH)<\/a><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/comisiones-internas-para-la-igualdad-de-genero-cinig\/\">Comisiones Internas para la Igualdad de G\u00e9nero (CInIG)<\/a><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer\/\">D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer<\/a><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/g5525\/\">G5525<\/a><a href=\"https:\/\/www.gaceta.unam.mx\/tag\/igualdad-de-genero\/\">igualdad de g\u00e9nero<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las coordinadoras de las Comisiones Internas para la Igualdad de G\u00e9nero de los cinco planteles del Colegio de Ciencias y Humanidades hablan sobre el significado del 25N y los 16 d\u00edas de activismo Tambi\u00e9n explican, cuentan sobre las diversas actividades realizadas &nbsp;para hacer conciencia Redacci\u00f3n 16 d\u00edas de activismo, 5\u00ba. D\u00eda SemM\u00e9xico, Cd. de M\u00e9xico, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28,27],"tags":[],"class_list":["post-90336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-16-dias-de-activismo","category-cobertura-especial"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=90336"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/90344"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=90336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=90336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=90336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}