{"id":90056,"date":"2024-11-25T07:45:01","date_gmt":"2024-11-25T13:45:01","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=90056"},"modified":"2024-11-25T07:45:01","modified_gmt":"2024-11-25T13:45:01","slug":"sheinbaum-arranca-la-campana-permanente-tiempo-de-mujeres-sin-violencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/sheinbaum-arranca-la-campana-permanente-tiempo-de-mujeres-sin-violencia\/","title":{"rendered":"Sheinbaum arranca la campa\u00f1a permanente Tiempo de Mujeres sin Violencia"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>\u00a0No debe haber salarios distintos entre hombres y mujeres<\/li>\n\n\n\n<li>Ya qued\u00f3 atr\u00e1s eso de que \u201ccalladita te ves m\u00e1s bonita\u201d<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, \u00c1lvaro Obreg\u00f3n, Mich., 25 de noviembre, 2024.- La&nbsp;presidenta de M\u00e9xico, Claudia Sheinbaum Pardo&nbsp;anunci\u00f3 la campa\u00f1a nacional permanente&nbsp;Es tiempo de mujeres sin violencia, como parte de las acciones para garantizar la igualdad sustantiva, la cual ya est\u00e1 establecida en la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa en el 4o. constitucional dice que las mujeres deben tener igualdad sustantiva, que no debe haber salarios distintos para las mujeres y los hombres si hacemos el mismo trabajo y que no debe haber violencia contra las mujeres. Por eso, ya est\u00e1 en la Constituci\u00f3n, ya se public\u00f3, ya es parte de un decreto. Y, por eso, esta campa\u00f1a que inicia a partir del d\u00eda ma\u00f1ana, que es Tiempo de Mujeres, pero no solo es Tiempo de Mujeres, es Tiempo de Mujeres sin violencia\u201d, destac\u00f3 durante el evento Pensi\u00f3n Mujeres Bienestar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que la campa\u00f1a, que se pondr\u00e1 en marcha a partir de ma\u00f1ana en el marco del D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, forma parte de las acciones del Gobierno de M\u00e9xico para reconocer que mujeres, ni\u00f1as y j\u00f3venes deben tener acceso a todos sus derechos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa qued\u00f3 atr\u00e1s eso de que \u201ccalladita te ves m\u00e1s bonita\u201d. No, eso ya no. Las mujeres tenemos voz, tenemos participaci\u00f3n, entre todas y todos estamos construyendo un pa\u00eds m\u00e1s igualitario\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que gracias a que desde 2018 cambi\u00f3 el modelo econ\u00f3mico, actualmente se apoya a 35 millones de familias con los Programas para el Bienestar, los cuales el pr\u00f3ximo a\u00f1o tendr\u00e1n una inversi\u00f3n social de casi un bill\u00f3n de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAyer me coment\u00f3 la secretaria de Bienestar, Ariadna, que ya aprobaron todos los Congresos locales, el Congreso de la Uni\u00f3n: que todos los programas queden en la Constituci\u00f3n. As\u00ed que la pr\u00f3xima semana va a salir el decreto en el Diario Oficial de la Federaci\u00f3n de que todos los Programas de Bienestar ahora son constitucionales\u201d, inform\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que adem\u00e1s de que se continuar\u00e1n los apoyos ya existentes, se crear\u00e1n tres nuevos Programas del Bienestar: la Pensi\u00f3n Mujeres Bienestar de 60 a 64 a\u00f1os, que en 2025, en su primera etapa, apoyar\u00e1 a quienes tengan 63 y 64; la nueva beca universal de educaci\u00f3n b\u00e1sica \u201cRita Cetina Guti\u00e9rrez\u201d, que el pr\u00f3ximo a\u00f1o iniciar\u00e1 beneficiando a estudiantes de secundaria; as\u00ed como el programa Salud Casa por Casa para adultos mayores y personas con discapacidad, quienes recibir\u00e1n la visita en sus domicilios de 22 mil m\u00e9dicos, m\u00e9dicas, enfermeros y enfermeras que ser\u00e1n contratados. Dicha pol\u00edtica integral, se complementar\u00e1 a trav\u00e9s de las Farmacias para el Bienestar, que ser\u00e1n construidas el pr\u00f3ximo a\u00f1o, y donde podr\u00e1n ir por sus medicamentos de manera gratuita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante las y los michoacanos, inform\u00f3 que m\u00e1s de 9 mil j\u00f3venes de todo el pa\u00eds se han registrado a la convocatoria del Poder Ejecutivo como aspirantes para una candidatura para ser jueces, juezas, magistrados, magistradas, ministros y ministras, honestos y honestas, del Poder Judicial, cuya elecci\u00f3n ser\u00e1 el pr\u00f3ximo 1 de junio de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que como parte de los proyectos que se contemplan para Michoac\u00e1n, se encuentra la implementaci\u00f3n estufas para reducir el uso de le\u00f1a en comunidades de pueblos originarios; se apoyar\u00e1 al campo con Cosechando Soberan\u00eda, cuyos trabajos comenzar\u00e1n con la visita, dentro de dos semanas, del secretario de Agricultura y Desarrollo Rural, Julio Berdegu\u00e9 Sacrist\u00e1n; as\u00ed como con el fortalecimiento de los Centros de Salud de la regi\u00f3n a trav\u00e9s del IMSS Bienestar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ninguna mujer estar\u00e1 sola<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de la pr\u00f3xima Secretar\u00eda de las Mujeres, Citlalli Hern\u00e1ndez Mora detall\u00f3 que la campa\u00f1a permanente&nbsp;<strong>Es tiempo de mujeres sin violencia,<\/strong>&nbsp;tiene un mensaje muy claro: que es una tarea de todas y de todos el que la violencia hacia las mujeres disminuya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDurante este gobierno ninguna mujer estar\u00e1 sola, porque tenemos a una gran protectora y defensora, que es la Doctora Claudia Sheinbaum. As\u00ed que aqu\u00ed en \u00c1lvaro Obreg\u00f3n, Michoac\u00e1n, les presentaremos el arranque de esta campa\u00f1a permanente\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que el pr\u00f3ximo a\u00f1o iniciar\u00e1 la entrega de una Cartilla de los Derechos de las Mujeres, as\u00ed como la construcci\u00f3n de redes de apoyo en todo el territorio mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de Bienestar, Ariadna Montiel Reyes precis\u00f3 que en Michoac\u00e1n se van a sumar a 48 mil mujeres de 63 y 64 a\u00f1os al programa Pensi\u00f3n Mujeres Bienestar, por lo que a partir de enero recibir\u00e1n su tarjeta del Banco del Bienestar para recibir su apoyo bimestral de 3 mil pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico, \u00c1lvaro Obreg\u00f3n, Mich., 25 de noviembre, 2024.- La&nbsp;presidenta de M\u00e9xico, Claudia Sheinbaum Pardo&nbsp;anunci\u00f3 la campa\u00f1a nacional permanente&nbsp;Es tiempo de mujeres sin violencia, como parte de las acciones para garantizar la igualdad sustantiva, la cual ya est\u00e1 establecida en la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos. \u201cYa en el 4o. constitucional dice que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-90056","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=90056"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/90056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/90057"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=90056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=90056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=90056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}