{"id":88536,"date":"2024-10-25T14:43:06","date_gmt":"2024-10-25T20:43:06","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=88536"},"modified":"2024-10-25T14:43:16","modified_gmt":"2024-10-25T20:43:16","slug":"los-capitales-el-58-2-de-la-poblacion-mexicana-tienen-educacion-financiera-solo-el-1-invierte-sus-ahorros","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-el-58-2-de-la-poblacion-mexicana-tienen-educacion-financiera-solo-el-1-invierte-sus-ahorros\/","title":{"rendered":"Los Capitales| El 58.2 % de la poblaci\u00f3n mexicana tienen educaci\u00f3n financiera; s\u00f3lo el 1 % invierte sus ahorros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico. 25 de octubre 2024.- Nadie duda del avance en la educaci\u00f3n financiera, y ahora sabemos que el 58.2 % tiene conocimientos financieros, pero la verdad es que en M\u00e9xico menos del 1 % de la poblaci\u00f3n invierte sus ahorros. As\u00ed lo dio a conocer Janus Henderson Investors, en su m\u00e1s reciente informe, en donde explora las principales barreras para invertir, incluyendo la falta de conocimiento (48%) y las preocupaciones econ\u00f3micas. Adem\u00e1s, destaca c\u00f3mo las mujeres est\u00e1n rezagadas, con solo el 40% invirtiendo frente al 65% de los hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es m\u00e1s, seg\u00fan datos de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos (OCDE) destaca la necesidad de continuar fortaleciendo la educaci\u00f3n financiera y aprovechar los avances tecnol\u00f3gicos que han facilitado el acceso al mercado burs\u00e1til en M\u00e9xico. En efecto, entre las razones detr\u00e1s de la falta de inversi\u00f3n de muchos consumidores destacan la preferencia por mantener el dinero en cuentas de ahorro (38 %), las deudas financieras preexistentes (30 %) y una falta de comprensi\u00f3n sobre c\u00f3mo invertir (30 %). Estos factores se hacen a\u00fan m\u00e1s evidentes en las generaciones m\u00e1s j\u00f3venes. El 45 % de los miembros de la Generaci\u00f3n Z que a\u00fan no invierten se\u00f1alan que la falta de conocimiento es la principal barrera, aunque el 79 % de ellos tiene la intenci\u00f3n de comenzar a invertir en los pr\u00f3ximos tres a\u00f1os si mejoran sus ingresos o reciben asesoramiento financiero adecuado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio tambi\u00e9n resalta diferencias importantes por g\u00e9nero. Solo el 40 % de las mujeres posee inversiones, en contraste con el 65% de los hombres. Las mujeres tienden a ser m\u00e1s conservadoras en su enfoque de la inversi\u00f3n, con un 32 % destinando m\u00e1s del 10 % de su salario a inversiones, frente al 44 % de los hombres. Adem\u00e1s, el 23 % de las mujeres que no invierten citan una falta de comprensi\u00f3n sobre los m\u00e9todos de inversi\u00f3n, lo que sugiere una necesidad urgente de educaci\u00f3n financiera espec\u00edfica para este grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, Janus Henderson destaca que una mayor educaci\u00f3n financiera, acceso a informaci\u00f3n confiable y servicios de asesor\u00eda accesibles son esenciales para cerrar esta brecha de inversi\u00f3n. A trav\u00e9s de iniciativas como su programa \u00abDirect Advice\u00bb, la firma busca facilitar la entrada al mundo de la inversi\u00f3n, brindando herramientas claras y pr\u00e1cticas que ayuden a los consumidores a tomar decisiones financieras informadas. Pero tampoco debemos ignorar que los consumidores enfrentan preocupaciones econ\u00f3micas m\u00e1s amplias: el 42 % de los encuestados mencion\u00f3 el costo creciente de la vida como su principal preocupaci\u00f3n financiera, superando con creces el ahorro para la jubilaci\u00f3n 14 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culmina magistrado H\u00e9ctor Macedo el doctorado en cultura de derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Magistrado H\u00e9ctor Macedo, del Poder Judicial del Estado de M\u00e9xico (PJEM), ha logrado finalizar exitosamente su Doctorado en Cultura de Derechos Humanos, lo que refuerza su compromiso con la justicia y la defensa de los derechos fundamentales en el estado. Este t\u00edtulo no solo representa un logro acad\u00e9mico, sino tambi\u00e9n la reafirmaci\u00f3n de su dedicaci\u00f3n y responsabilidad en los 32 a\u00f1os que lleva desempe\u00f1\u00e1ndose como servidor judicial. Este doctorado refleja su convicci\u00f3n de que la formaci\u00f3n continua es clave en el \u00e1mbito judicial, donde la igualdad y la dignidad de las personas son fundamentales. A lo largo de su carrera, el Magistrado ha demostrado una firme vocaci\u00f3n hacia la defensa de los derechos humanos, buscando siempre mejorar sus conocimientos y habilidades para ofrecer un sistema judicial m\u00e1s justo y accesible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis financiera en la Boeing amenaza con un \u201caterrizaje\u201d de emergencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien la empresa aeron\u00e1utica acaba de publicar su reporte de sostenibilidad y responsabilidad social 2024, destacando progresos en su enfoque \u00abPeople, Planet, Profit\u00bb (Personas, Planeta, Beneficios), la verdad es que esta narrativa positiva contrasta con la reciente noticia de p\u00e9rdidas financieras multimillonarias y la amenaza de una huelga, que pone en jaque su estabilidad operativa. Esta dualidad entre el \u00e9xito en responsabilidad social y los retos econ\u00f3micos expone una compleja realidad para la empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En efecto, la empresa acaba de reportar p\u00e9rdidas de 6.1 mil millones de d\u00f3lares en el tercer trimestre de 2024, lo que ha generado una gran preocupaci\u00f3n entre los inversionistas y analistas financieros de S&amp;P Global. Esta ca\u00edda financiera se atribuye, en gran medida, a una huelga de cinco semanas por parte de sus trabajadores en una de sus plantas principales, lo que interrumpi\u00f3 la producci\u00f3n y afect\u00f3 directamente los resultados del trimestre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el informe financiero subraya que los costos de producci\u00f3n se han disparado debido a la escasez de suministros y materiales, exacerbada por la huelga. Este contexto revela una empresa que, a pesar de sus esfuerzos por mejorar su impacto ambiental y social, se encuentra en una encrucijada econ\u00f3mica que podr\u00eda comprometer sus esfuerzos en sostenibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S&amp;P Global nos dice que las tensiones entre la direcci\u00f3n de Boeing y sus empleados han escalado en los \u00faltimos meses, y la posibilidad de una nueva huelga pone en peligro cualquier recuperaci\u00f3n financiera a corto plazo. Este conflicto laboral, se\u00f1alan analistas de Expok, refleja una desconexi\u00f3n entre las metas corporativas de sostenibilidad y la realidad que enfrentan sus trabajadores. Boeing ha promovido una cultura de inclusi\u00f3n y bienestar en su informe, pero los problemas laborales en curso podr\u00edan contradecir esta imagen y deteriorar su reputaci\u00f3n interna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" target=\"_blank\" rel=\"noreferrer noopener\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.agendadeinversiones.com.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.agendadeinversiones.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @Edgar4712<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico. 25 de octubre 2024.- Nadie duda del avance en la educaci\u00f3n financiera, y ahora sabemos que el 58.2 % tiene conocimientos financieros, pero la verdad es que en M\u00e9xico menos del 1 % de la poblaci\u00f3n invierte sus ahorros. As\u00ed lo dio a conocer Janus Henderson Investors, en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[750,110,35],"tags":[],"class_list":["post-88536","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-la-opinion-columnas","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/88536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=88536"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/88536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=88536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=88536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=88536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}