{"id":8817,"date":"2019-06-17T17:23:12","date_gmt":"2019-06-17T17:23:12","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=8817"},"modified":"2023-07-21T14:49:12","modified_gmt":"2023-07-21T19:49:12","slug":"munoz-ledo-rompe-su-silencio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/munoz-ledo-rompe-su-silencio\/","title":{"rendered":"Mu\u00f1oz Ledo rompe su silencio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em> \u201cD\u00e9mosle tiempo\u201d, frase que frecuentemente se repite, pero\u2026<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Herrera\nValenzuela<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\"><em>Reciban una felicitaci\u00f3n amigos y compa\u00f1eros en el D\u00eda del Padre <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 17 junio\n2019.- Seis y medio meses del sexenio lopezobradorista, lapso en que se ha\nimpuesto un modelo, nada ortodoxo, para gobernar y administrar al pa\u00eds, porque\nen la realidad todo se improvisa, no hay un plan definido para iniciar el\ncamino a las soluciones integrales que urgen aplicar para devolver la seguridad\na la ciudadan\u00eda, que se requieren para incrementar la producci\u00f3n alimentaria,\nas\u00ed como acciones que restauren la imagen de M\u00e9xico en el exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ni un solo mexicano\nest\u00e1 en contra de que se exterminen la corrupci\u00f3n y la impunidad. Sin embargo,\nlas acciones hasta ahora no arrojan los resultados esperados por millones de\nmexicanos. Las conferencias ma\u00f1aneras, adaptadas a modo y gusto del n\u00famero uno,\nsirven para nombrar a presuntos responsables del saqueo que han sufrido las\narcas oficiales, desde hace tiempo, pero no hay detenidos y a \u00faltimas fechas el\nm\u00e1s renombrado es <strong>Emilio Lozoya Austin<\/strong>,\nquien fungi\u00f3 como director general de Petr\u00f3leos Mexicanos, la superendeudada\nempresa petrolera. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recortar\npresupuestos en \u00e1reas prioritarias, centralizar el poder presidencial en las\nadquisiciones de toda naturaleza incluyendo medicamentos y material para\nhospitales, restar categor\u00eda &nbsp;a la\ninvestidura presidencial, no asistir a eventos internacionales, viajar como\nciudadano com\u00fan y corriente, nombrar representantes personales en cada Estado (los\nllamados superdelegados), determinar la desaparici\u00f3n del Estado Mayor\nPresidencial e imponer ministros y consejeros, son, entre otras, las medidas\nque comprenden la Cuarta Transformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, todo ha\nrecibido la aprobaci\u00f3n popular. Hay quienes comentan que en un m\u00ednimo\nporcentaje ha disminuido el respaldo al presidente <strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>. Cierto es que todo ha creado un\nambiente de inquietud, de zozobra, de incertidumbre y ha despertado pol\u00e9mica,\ncomo el caso de la negociaci\u00f3n entre los gobiernos de M\u00e9xico y Estados Unidos,\npactada en los \u00faltimos d\u00edas que evitaron un rudo golpe a nuestra econom\u00eda. En\nsu momento el Senado de la Rep\u00fablica debe conocer \u00edntegro el texto del Acuerdo,\nque no Tratado, en el que se fijaron 45 d\u00edas de plazo para que M\u00e9xico cierre\npuertas en la frontera Sur. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay un retraso en la\nentrega de los apoyos econ\u00f3micos a la Tercera Edad, pero se asegura que en\njulio estar\u00e1n regularizados. El censo correspondiente fue terminado hace meses\ny se hizo entrega de tarjeta de d\u00e9bito, Banorte, a los beneficiarios, mismos\nque fueron fotografiados al recibirla y se fotografi\u00f3 su credencial de elector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En no pocas\nocasiones he o\u00eddo y he le\u00eddo a quienes dicen o escriben: \u201cDenle tiempo, est\u00e1\nempezando\u201d, \u201cNo quieran que arregle en unos meses el mal hecho durante tantos\na\u00f1os\u201d, \u201cEntiendan que le dejaron un cochinero\u201d. Por supuesto hay que procurar\nque el equipo se adapte, que conozca y que act\u00fae. El tabasque\u00f1o ha impuesto un\nestilo muy personal, ninguno de los gobiernos sexenales lo hab\u00eda hecho igual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, el pero que\nnunca falta, me surge una pregunta: \u00bfEn los doce a\u00f1os de campa\u00f1a que\nprecedieron a su arrollador triunfo electoral, no se percat\u00f3 de que pa\u00eds\nrecibir\u00eda? En los primeros cinco a\u00f1os de este Siglo XXI, <strong>L\u00f3pez Obrador<\/strong> fue jefe de Gobierno del Distrito Federal, por el\nvoto popular. Ese es el \u00fanico cargo que ha desempe\u00f1ado, no fue diputado ni\nsenador, tampoco form\u00f3 parte de un gabinete presidencial, sin embargo, se\nempap\u00f3 de la problem\u00e1tica nacional al recorrer, detenidamente, hasta los\npueblos m\u00e1s apartados y nunca visitados por los pol\u00edticos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuvo trato directo\ncon el pueblo aut\u00e9ntico, al que hoy, \u00e9l, <strong>Andr\u00e9s\nManuel<\/strong> califica de sabio y con el que sigue en contacto directo, al que en\nun principio le convoc\u00f3 a \u201cconsultas populares\u201d. Esos mexicanos, desde entonces,\nle plantearon sus problemas y le pidieron se los solucionara. Considero que por\nesos d\u00edas, el perseverante aspirante presidencial, debi\u00f3 integrar su agenda,\nindependientemente de que estaba enterado de la corrupci\u00f3n que exist\u00eda en todo\nel pa\u00eds y de la impunidad que gozaban los responsables de la situaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el primer\nPresidente de M\u00e9xico nacido en Tabasco, dispuso de cinco meses, despu\u00e9s del\ntriunfo en las urnas, para formular su programa inicial de trabajo con\nacciones, no con discursos ma\u00f1aneros. El Plan Nacional de Desarrollo, es el\nprograma sexenal y en \u00e9l participan los miembros del gabinete legal, as\u00ed como\nlos del ampliado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pregunta para meditar:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1nto tiempo m\u00e1s\nhay que esperar para que arranque el equipo como tal, porque ahora los miembros\ndel gabinete van desfilando en el escenario de las conferencias ma\u00f1aneras?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mu\u00f1oz Ledo rompe su silencio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volvi\u00f3 a o\u00edrse la\nvoz de uno de los m\u00e1s pol\u00e9micos pol\u00edticos mexicanos y creo que sus m\u00e1s\nrecientes afirmaciones, en el pleno de la Comisi\u00f3n Permanente del Congreso de\nla Uni\u00f3n, pueden acarrearle problemas. Despu\u00e9s de se\u00f1alar que se ha violado la\nLey Org\u00e1nica de la Administraci\u00f3n P\u00fablica, al otorgarle facultades de la\nSecretar\u00eda de Gobernaci\u00f3n a la de Relaciones Exteriores, en tareas migratorias,\n<strong>Porfirio Mu\u00f1oz Ledo <\/strong>expres\u00f3: \u201c<strong>La Guardia Nacional fue creada para\ncombatir delincuentes, no para combatir migrantes<\/strong>\u201d. El \u00fanico mexicano que\nha dirigido, nacionalmente, los comit\u00e9s del <strong>PRI <\/strong>y del <strong>PRD<\/strong>, y ahora\nes presidente de la C\u00e1mara de Diputados, sorprendi\u00f3 a sus correligionarios de <strong>Morena<\/strong>, al decir: \u201c<strong>El pa\u00eds viola la ley interna para satisfacer una demanda de los Estados\nUnidos<\/strong>\u201d. En el mitin de los morenistas en Tijuana, el s\u00e1bado 8, tambi\u00e9n fue\nduro cr\u00edtico del acuerdo celebrado entre los dos gobiernos, para evitar la\naplicaci\u00f3n del 5 por ciento en los aranceles a productos mexicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carolina Herrera, \u201ccopiona\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues, \u00bfqu\u00e9 creen?\nLa flamante Secretaria de Cultura, <strong>Alejandra\nFraustro Guerrero<\/strong>, decidi\u00f3 lanzarse contra la dise\u00f1adora internacional <strong>Carolina Herrera <\/strong>porque, sin el permiso\nde las comunidades ind\u00edgenas de Tenango de Doria, Hidalgo, y del Istmo de\nTehuantepec, Oaxaca, utiliz\u00f3 motivos de esos lugares para estamparlos en prendas\nfemeninas de la Colecci\u00f3n 2020. La funcionaria y estudiante de Derecho exige, a\nla dise\u00f1adora venezolana y al director de la marca, que \u201cexpliquen p\u00fablicamente\ncon qu\u00e9 fundamentos decidieron hacer uso de elementos culturales cuyo origen\nest\u00e1 plenamente documentado\u201d. Me hubiera gustado que est\u00e1 misma posici\u00f3n\nhubiese adoptado <strong>Alejandra<\/strong> en torno\nal alquiler del Palacio de Bellas Artes para el homenaje religioso al hoy preso\nl\u00edder de la Luz del Mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cMorir como perro III\u201d, en Chiapas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00edjense que mi\ncolega y fraternal amigo <strong>Armando Rojas\nAr\u00e9valo<\/strong> inici\u00f3 la serie period\u00edstica \u201c<strong>Morir\nComo Perro<\/strong>\u201d y ya vamos en el cap\u00edtulo tres, relacionado, como los\nanteriores, con hechos reales que se consuman en los hospitales del Sector\nSalud. El nuevo caso tiene como escenario el <strong>Hospital Gilberto G\u00f3mez Maza<\/strong>, de Tuxtla Guti\u00e9rrez, Chiapas. Sucede\nque a los pacientes que solicitan estudios de laboratorio o de radiolog\u00eda, no\nlos pueden atender o no quieren atender, pretextando que no hay material de\nreactivos&nbsp; como tampoco equipo para\nradiograf\u00edas. Los familiares de los enfermos son enviados a un laboratorio\nparticular, ubicado exactamente frente al hospital, donde tienen que pagar una\ncuota e igual sucede en el caso de requerir una radiograf\u00eda. Se trata de\npacientes de escasos recursos, pero nadie pone fin a la corrupci\u00f3n. Lo grave es\nque los propios empleados del referido hospital p\u00fablico, son los due\u00f1os de los\nestablecimientos donde \u201csi cuentan con todo el equipo\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P.D. <\/strong>Dos fallecimientos enlutan al medio art\u00edstico y a la familia\nperiod\u00edstica. La noche del domingo dej\u00f3 de existir <strong>Adri\u00e1n Ojeda Rom\u00e1n<\/strong>, reportero de larga trayectoria y con quien tuve\nel gusto de compartir, como comentarista pol\u00edtico, los micr\u00f3fonos de Radio\nChapultepec, en los tiempos que esa radiodifusora transmit\u00eda exclusivamente\nm\u00fasica instrumental y los noticieros dirigidos por mi querido <strong>Adri\u00e1n<\/strong>. Un abrazo solidario para todos\nsus familiares\u2026La actriz <strong>Edith Gonz\u00e1lez\nFuentes<\/strong>, a sus 54 a\u00f1os de edad, sucumbi\u00f3 ante el c\u00e1ncer. Vers\u00e1til en la\nvida art\u00edstica que comenz\u00f3 en 1976, cuando ten\u00eda 12 a\u00f1os, la defe\u00f1a fue la\nprimera que interpret\u00f3 a <strong>Elena Tejero,<\/strong>\nen la puesta de \u201cAventurera\u201d bajo la direcci\u00f3n de la coahuilense <strong>Carmelita Salinas<\/strong>.<strong> La rubia bailarina fue calificada como \u201cla m\u00e1s sensual (Aventurera) de\ntodos los tiempos\u201d<\/strong>. La extraordinaria g\u00fcera hizo historia en el cine, en el\nteatro y en la televisi\u00f3n. Deja a su hija <strong>Constanza<\/strong>,\na un paso de cumplir sus quince a\u00f1os. Descansen en paz ambos personajes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>jherrerav@live.com.mx<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2018 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cD\u00e9mosle tiempo\u201d, frase que frecuentemente se repite, pero\u2026 Jorge Herrera Valenzuela Reciban una felicitaci\u00f3n amigos y compa\u00f1eros en el D\u00eda del Padre SemM\u00e9xico, 17 junio 2019.- Seis y medio meses del sexenio lopezobradorista, lapso en que se ha impuesto un modelo, nada ortodoxo, para gobernar y administrar al pa\u00eds, porque en la realidad todo se [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,94,107],"tags":[],"class_list":["post-8817","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-jorge-herrera-valenzuela","category-rafaga"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/8817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=8817"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/8817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8818"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=8817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=8817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=8817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}