{"id":8766,"date":"2019-06-17T17:47:14","date_gmt":"2019-06-17T17:47:14","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=8766"},"modified":"2023-07-21T14:49:12","modified_gmt":"2023-07-21T19:49:12","slug":"austeridad-republicana-perjudica","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/austeridad-republicana-perjudica\/","title":{"rendered":"Austeridad republicana perjudica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Grave decisi\u00f3n, la de marginar a quienes hacen ciencia, investigan, inventan y artistas<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Jorge Herrera Valenzuela<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 17 junio 2019.- Resulta sorprendente e\nincre\u00edble que una de las prioridades de la Cuarta Transformaci\u00f3n, sea la de\nanular todo el apoyo material que requieren las y los cient\u00edficos, los\ninvestigadores y a la ni\u00f1ez triunfadora, mundialmente, en matem\u00e1ticas y en\nqu\u00edmica, as\u00ed como a estudiantes e inventores polit\u00e9cnicos. Bajo la afirmaci\u00f3n\npresidencial de \u201cse acab\u00f3 el turismo acad\u00e9mico\u201d, tambi\u00e9n se habla de desaparecer\nlas becas para artistas, porque son privilegios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comento que existe la posibilidad de que la\ndirectora del Consejo Nacional de Ciencia y Tecnolog\u00eda, el reconocido CONACYT,\nno le dio un informe objetivo, real y congruente al Presidente de M\u00e9xico, en\naras de la \u201causteridad republicana\u201d, perjudicando a quienes realizan trabajos\nque, por razones obvias, necesitan de viajar al extranjero para concretar sus\ninvestigaciones, lo cual no es \u201chacer turismo acad\u00e9mico\u201d. Espero que no anulen\nlas becas a estudiantes del Instituto Polit\u00e9cnico Nacional, que con inventos\nhan puesto muy en el alto el nombre de M\u00e9xico, a nivel mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este caso, como en todos los que se han\ndenunciado, en la tarea de terminar con la corrupci\u00f3n, no se conoce los nombres\nde funcionarios y beneficiarios que deban ser sancionados, administrativa o\npenalmente, por disponer del erario nacional. S\u00e9 que hay molestia, en Palacio\nNacional, porque el internacional Guillermo Del Toro patrocin\u00f3 a un grupo de ni\u00f1os\nque asistieron a una Olimpiada Cultural y por ello se corre el peligro de que\nya no veamos a nuestros ni\u00f1os en la pr\u00f3xima Olimpiada de Matem\u00e1ticas o no\npuedan asistir a la de Qu\u00edmica, donde los chiquitines mexicanos han sido\ntriunfadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por cierto, recientemente, el presidente L\u00f3pez\nObrador en relaci\u00f3n con el respaldo a los ni\u00f1os que van a las olimpiadas\nculturales, tuvo la desafortunada declaraci\u00f3n al decir que los ni\u00f1os\ntarahumaras son tan pobres que antes de que vayan a la escuela, deber\u00edan de\ntener comida. Tambi\u00e9n afirm\u00f3 que solo hay un maestro para impartir los\nconocimientos en los seis grados de primaria. Lo que sucede es que la poblaci\u00f3n\nescolar es muy escasa y por ello tanto la autoridad estatal como la federal, en\nmateria educativa, aplican el sistema multifuncional o de multigrado, aspecto\nque no le fue informado al tabasque\u00f1o. Ese plan ha arrojado los resultados\ndeseados, sin implicar omisiones en la ense\u00f1anza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, el panorama no es nada halagador para la\ncultura, la investigaci\u00f3n y la superaci\u00f3n en esta \u00e9poca de los avances\ncient\u00edficos y tecnol\u00f3gicos, pues inclusive ya hay un pronunciamiento para que\nni los artistas obtengan becas, porque \u201ces un privilegio que debe desaparecer\u201d.\nUna voz autorizada, de Morena, lanz\u00f3 la advertencia siguiente: \u201cSigan siendo\nexcelentes, pero v\u00e1yanse a la iniciativa privada, dejen de vivir del\npresupuesto\u201d, Cuauht\u00e9moc Medina en twitter escribi\u00f3: \u201cEsa declaraci\u00f3n es, en\nsuma, una radiograf\u00eda de una ideolog\u00eda emergida de prejuicios y resentimientos\u201d.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sonados triunfos internacionales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes abogan por marginar los apoyos presupuestarios\npara la investigaci\u00f3n en sus diferentes campos, demuestran pleno\ndesconocimiento de lo que ni\u00f1os y j\u00f3venes, estudiantes de planteles oficiales\ny\/o privados, han conquistado en olimpiadas y cert\u00e1menes internacionales\ncelebrados en Europa, colocando el nombre de M\u00e9xico en la c\u00faspide. Hay otros,\ncalificados como resentidos, que argumentan \u201chaberse hecho sin dinero del\ngobierno\u201d y por eso ahora proponen la desaparici\u00f3n de las becas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00f3venes como los jaliscienses Misael Covarrubias\nNavarro y Erick Rub\u00e9n Tapia Navarro, estudiantes del Centro de Estudios\nCient\u00edficos y Tecnol\u00f3gicos del IPN (filiales del Centro de Investigaci\u00f3n y\nEstudios Avanzados (CINESTAV) han obtenido triunfos tanto internacionales como\nnacionales. Erick Rub\u00e9n particip\u00f3 en el Mundial de Rob\u00f3tica ROBOCUP en Brasil y\nen torneos organizados por la Federaci\u00f3n Mexicana de Rob\u00f3tica, Misael cosech\u00f3\nmedallas en las competencias nacionales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah, pero nuestros peque\u00f1ines, de 5 a 7 a\u00f1os,\narrollaron en Malasia 2017 en la Olimpiada de Matem\u00e1ticas. El equipo infantil\ncompiti\u00f3 con 900 peque\u00f1os de 70 pa\u00edses. En un lapso de cinco minutos dieron\ncontestaci\u00f3n precisa y exacta a 70 operaciones. Entre los mexicanitos estaban\nSergio Chapa, Gustavo Garc\u00eda y Leonardo Torres, quienes tienen como profesora a\nBibiana Bojalil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la Olimpiada Internacional de Qu\u00edmica, celebrada\nen Bratislava y en Praga, la delegaci\u00f3n mexicana se enfrent\u00f3 a los\nrepresentantes de 70 pa\u00edses. Los nuestros obtuvieron el tercer lugar, es decir\nretornaron con medalla de bronce el michoacano Alejandro Valderrama Celestino,\nla capitalina (CDMX) Neyci Guti\u00e9rrez Valencia y los sonorenses Alexa Estefan\u00eda\nGarc\u00eda Rend\u00f3n y Alejandro Mungu\u00eda Aldapa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pregunta para meditar:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEl Presidente de M\u00e9xico mantendr\u00e1 durante todo el\nsexenio la orden de que investigadores y cient\u00edficos, as\u00ed como los ni\u00f1os y\nj\u00f3venes, no viajen al extranjero para participar en eventos culturales\ninternacionales, salvo su personal autorizaci\u00f3n? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">jherrerav@live.com.mx <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grave decisi\u00f3n, la de marginar a quienes hacen ciencia, investigan, inventan y artistas Jorge Herrera Valenzuela SemM\u00e9xico, 17 junio 2019.- Resulta sorprendente e incre\u00edble que una de las prioridades de la Cuarta Transformaci\u00f3n, sea la de anular todo el apoyo material que requieren las y los cient\u00edficos, los investigadores y a la ni\u00f1ez triunfadora, mundialmente, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,94,107],"tags":[],"class_list":["post-8766","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-jorge-herrera-valenzuela","category-rafaga"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/8766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=8766"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/8766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8767"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=8766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=8766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=8766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}