{"id":86580,"date":"2024-09-03T09:36:12","date_gmt":"2024-09-03T15:36:12","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=86580"},"modified":"2024-09-03T14:48:54","modified_gmt":"2024-09-03T20:48:54","slug":"entresemana-la-senorita-de-bucareli","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/entresemana-la-senorita-de-bucareli\/","title":{"rendered":"Entresemana | La se\u00f1orita de Bucareli\u2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u201cSe me desborda el coraz\u00f3n con solo o\u00edr tu voz, con solo pensar en ti, con verte pasar nom\u00e1s\u2026\u201d Javier Sol\u00eds<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MOIS\u00c9S S\u00c1NCHEZ LIM\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 3 de septiembre, 2024.-Me la present\u00f3 el din\u00e1mico Jos\u00e9 Manuel del R\u00edo Virgen.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFuma como chacuaco\u201d, dijo Del R\u00edo. Y s\u00ed, ella hab\u00eda salido a la plaza central del Palacio Legislativo de San L\u00e1zaro a calmar ansias de la nicotina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Menudita, delgada, pelo chino y hablar discreto, voz de adolescente sonri\u00f3 cuando Jos\u00e9 Manuel brome\u00f3 con eso de su afici\u00f3n por el tabaco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diputada plurinominal, entonces 2012, sin militancia en el partido que tiene escriturado Dante Delgado, se desenvolv\u00eda hiperactiva. Era secretaria de la Comisi\u00f3n de Trabajo y Previsi\u00f3n Social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPremonici\u00f3n?, porque luego ocupar\u00eda ese cargo, pero en el gabinete de Su Alteza Seren\u00edsima. Y m\u00e1s all\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, el pen\u00faltimo s\u00e1bado de agosto reciente cumpli\u00f3 37 a\u00f1os. La vida le ha sonre\u00eddo desde temprano y, en domingo de gloria y festejo, camina por el pasillo de honor en el sal\u00f3n de sesiones de la C\u00e1mara de Diputados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese pasillo por el que, diputada federal por Movimiento Ciudadano, debut\u00f3 en 2012 en las ligas intermedias del Congreso de la Uni\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viste albo traje sastre y se le desparrama al frente un pashmina con toque modelo de Vogue. Quiz\u00e1 un descuido en el corte del traje con botones negros: las mangas exceden el l\u00edmite que marca le haute Couture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfA poco no la vio usted por la tele el domingo, en el Canal del Congreso?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, va por el pasillo de honor y se deja querer, se sabe al centro de la atenci\u00f3n y sus compa\u00f1eros de partido la arropan.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEs la imagen de la sucesi\u00f3n adelantada?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luisa, joven pol\u00edtica cuya imagen cual usuaria del transporte p\u00fablico fue promocional proselitista. La melena china, la sonrisa de quien se sabe due\u00f1a del momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda, imagen dominical cuya enjundia contrasta con la nostalgia que no oculta el licenciado presidente quien tiene un mes para desalojar Palacio Nacional y se despacha una cascada de mentiras en su dizque \u00faltimo informe de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Ah!, primo hermano, dices que te jubilar\u00e1s con la conciencia tranquila y dejas tarea a tu sucesora, a quien tejiste el futuro como tal. Y ella, la doctora, es quien aplaud\u00eda tus palabras melosas el domingo en primera fila, en el Z\u00f3calo chilango.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas de poder, d\u00edas de j\u00fabilo import\u00e1ndote un bledo las protestas, el que las madres buscadoras estuvieran frente a ti, al pie de la asta bandera y que a padres y madres de los estudiantes de Ayotzinapa enga\u00f1aste con conjeturas de tu inventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Vaya!, Andr\u00e9s Manuel sin rubor dijiste:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe voy tambi\u00e9n tranquilo porque a quien entregar\u00e9 la banda presidencial por mandato del pueblo es una mujer excepcional, experimentada, honesta y, sobre todo, de buenos sentimientos, de buen coraz\u00f3n (\u2026)\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego arengaste: \u201c\u00a1Presidenta! \u00a1Presidenta! \u00a1Presidenta!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ah\u00ed estaba Luisa Mar\u00eda Alcalde Luj\u00e1n, la se\u00f1orita de Bucareli que ha operado en el papel de secretaria de Gobernaci\u00f3n bajo tu direcci\u00f3n, finalmente maestro de escena, que hace m\u00e1s de dos d\u00e9cadas encontraste en la doctor Sheinbaum Pardo a la perfecta prospecto para seguir tus pasos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A imagen y semejanza tuya. Fuiste jefe de gobierno del entonces Distrito Federal y ella fue jefa de Gobierno de la Ciudad de M\u00e9xico, aunque dice que gobern\u00f3 de manera diferente. Quiere asumir imagen propia, pero todos los d\u00edas la realidad la desdice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfAs\u00ed ser\u00e1 con Luisa Mar\u00eda? Pero\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primer domingo de septiembre de 2024 y los nuevos due\u00f1os del poder en M\u00e9xico emprenden la ruta sin reparo. Que nadie se oponga, que nadie se atreva siquiera a alzar un grito de protesta porque, ahora s\u00ed, \u00a1carajo!, la ley es la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Rec\u00e1spita, Arturo Zald\u00edvar!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, el oficialismo legislativo quiere, incluso, acusar penalmente a Martha Maga\u00f1a L\u00f3pez, jueza Quinta de Distrito en el estado de Morelos, porque se atrevi\u00f3 a otorgar suspensi\u00f3n provisional de amparo que apela ex profeso al Reglamento de la C\u00e1mara de Diputados para evitar que los asuntos previos a la Reforma del Poder Judicial sean analizados por la nueva LXVI Legislatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jueza esgrimi\u00f3 fundamentos legales, como el haberse excusado de conocer la solicitud de amparo para frenar la Reforma de marras, debi\u00f3 emitir la suspensi\u00f3n porque era de oficio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero eso era tema menor el domingo de gloria cuando Luisa Mar\u00eda Alcalde llevaba la encomienda de entregar en mano de Ifigenia Mart\u00ednez, presidenta por un mes de la C\u00e1mara de Diputados, el \u00faltimo informe del licenciado presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfAcaso ser\u00e9 yo, maestro?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y desde el centro de la mesa de la directiva cameral, la se\u00f1orita de Bucareli est\u00e1 en lo suyo y de corridito atenta contra el reglamento y rompe el protocolo import\u00e1ndole un pito. Total, abajo, la inmensa mayor\u00eda de las curules est\u00e1n ocupadas por los de casa, por esa soberbia y aplastante sobrerrepresentaci\u00f3n legislativa que inaugura temporada in\u00e9dita para hacer lo que le venga en gana con la Constituci\u00f3n y leyes secundarias y\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luisa Mar\u00eda est\u00e1 exultante y alza el brazo con el coro que retumba en los rincones del sal\u00f3n de plenos. \u00a1Qu\u00e9 chingaos! El espacio es de ellos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1Es un honor estar con Obrador!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ni en los mejores tiempos del entonces partidazo tricolor, la aplanadora que, no obstante, escuchaba a la oposici\u00f3n y negociaba con ella temas trascendentes, aunque al final llevara el sello de la casa, del Revolucionario Institucional, cuna de quienes hoy son los nuevos due\u00f1os del poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y s\u00ed, \u00bfpor qu\u00e9 no y la se\u00f1orita de Bucareli es el nuevo modelo para construir en la sucesi\u00f3n presidencial rumbo al 2030?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La liturgia pol\u00edtica refiere que la sucesi\u00f3n presidencial comienza cuando extiende el brazo con la palma abierta y rinde protesta el nuevo Presidente de la Rep\u00fablica. Pero ello no ocurre con la nueva presidenta que, de la mano de L\u00f3pez Obrador, atisba en esos terrenos que ma\u00f1ana recorrer\u00e1 sin el antecesor como gu\u00eda de turistas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Ajaj\u00e1, y qu\u00e9 con eso de \u201cel humanismo mexicano\u201d! \u00bfCon qu\u00e9 se come?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, bueno, Luisa Mar\u00eda Alcalde Luj\u00e1n est\u00e1 en pre campa\u00f1a y se sale del libreto y habla de los logros de su jefe puntualiza que \u201ctodo esto se ha logrado sin incrementar impuestos, sin endeudar al pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y frente a diputados y senadores, sin invitados del Poder Judicial de la Federaci\u00f3n, como marca la liturgia, sin rubor le dice a Ifigenia Mart\u00ednez:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHago entrega de este sexto y \u00faltimo informe de gobierno del mejor Presidente que ha tenido este pa\u00eds, Andr\u00e9s Manuel L\u00f3pez Obrador\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo falt\u00f3 la r\u00fabrica: p\u00e9sele a quien le pese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y as\u00ed, declama como en acto de campa\u00f1a. El breve mensaje que se dec\u00eda conforme al reglamento se qued\u00f3 en el archivo. Estos, s\u00ed, se\u00f1oras y se\u00f1ores, son otros tiempos en los que, irremediable y reiteradamente, los nuevos due\u00f1os del poder pueden hacer lo que les venga en gana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, como arrancar la sucesi\u00f3n presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en esa cruzada, se vale mentir porque, si el jefe lo ha hecho durante m\u00e1s de 3 d\u00e9cadas, hoy por qu\u00e9 no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que, la se\u00f1orita de Bucareli dice que, \u201cen tan solo seis a\u00f1os, se han logrado construir trenes, puertos, aeropuertos, carreteras, distritos de riego, hospitales, plazas, universidades\u201d. S\u00ed, en plural, aunque se trate de asuntos en singular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace 12 a\u00f1os me la present\u00f3 Jos\u00e9 Manuel del R\u00edo y fumaba como chacuaco. Hiperactiva lleg\u00f3 a las ligas mayores. Su futuro mediato est\u00e1 en la dirigencia del Corporativo Morena, el partido cuya presidencia vitalicia de administraci\u00f3n la tiene Andr\u00e9s Manuel y, d\u00edgase lo contrario, \u00e9l sabe tejer fino, como citan los cl\u00e1sicos y en seis a\u00f1os tendr\u00eda lista a la sucesora de la doctora Sheinbaum. \u00bfEs un honor? \u00a1Rec\u00f3rcholis, Drakko!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\">sanchezlimon@gmail.com<\/a>&nbsp; &nbsp; <a href=\"http:\/\/www.entresemana.mx\">www.entresemana.mx<\/a> &nbsp; @msanchezlimon1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSe me desborda el coraz\u00f3n con solo o\u00edr tu voz, con solo pensar en ti, con verte pasar nom\u00e1s\u2026\u201d Javier Sol\u00eds MOIS\u00c9S S\u00c1NCHEZ LIM\u00d3N SemM\u00e9xico, Cd. de M\u00e9xico, 3 de septiembre, 2024.-Me la present\u00f3 el din\u00e1mico Jos\u00e9 Manuel del R\u00edo Virgen.\u00a0 \u201cFuma como chacuaco\u201d, dijo Del R\u00edo. Y s\u00ed, ella hab\u00eda salido a la plaza [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[105,83,35],"tags":[],"class_list":["post-86580","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entresemana","category-moises-sanchez-limon","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/86580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=86580"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/86580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/69815"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=86580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=86580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=86580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}