{"id":86297,"date":"2024-08-28T10:29:49","date_gmt":"2024-08-28T16:29:49","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=86297"},"modified":"2024-08-28T10:29:49","modified_gmt":"2024-08-28T16:29:49","slug":"entresemana-chinguemonos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/entresemana-chinguemonos\/","title":{"rendered":"Entresemana | Chingu\u00e9monos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\u201cEl mundo siendo mundo\/ no me podr\u00e1 vencer\/ si cabe en cinco letras\/ muy grande no ha de ser\u2026\u201d<\/em>&nbsp;Pedro Infante<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mois\u00e9s S\u00e1nchez Lim\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 28 de agosto, 2024.- No hay peor ciego que el c\u00ednico que niega la realidad y se hace que la virgen le habla. Disculpe la ruda analog\u00eda, pero \u00a1como anillo al dedo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que \u00a1ah\u00ed viene Claudia Carlota de M\u00e9xico! As\u00ed la llam\u00f3 Su Alteza Seren\u00edsima con iron\u00eda en respuesta a un comentario de Enrique Krauze. \u00bfIron\u00eda?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfO ser\u00e1 Mam\u00e1 Carlota?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Palo dado ni la Constituci\u00f3n lo quita. Y s\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son due\u00f1os de M\u00e9xico, transitan entre la soberbia del triunfo y desprecian al derrotado, lo humillan y, f\u00edjese usted, asumen ese discurso que niega su frase \u201cno somos iguales\u201d, porque se hermanan en causa y efecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lea usted y saque sus conclusiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin filias ni fobias, como el ciudadano engatusado por sedicentes dem\u00f3cratas y honestos hombres y mujeres que son la viva imagen congruente de la pobreza franciscana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO sea \u2013dijo el licenciado L\u00f3pez Obrador&#8211;, es que lo que estamos viviendo ahora no es nuevo. Nada m\u00e1s que recordaba yo antes con\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRecordaba ayer con la presidenta electa, le dec\u00eda: \u00bfTe acuerdas c\u00f3mo gan\u00e1bamos en debate siempre? Siempre gan\u00e1bamos el debate en las c\u00e1maras, pero perd\u00edamos la votaci\u00f3n, pero nos quedaba ese consuelo, \u00bfno?, ganamos el debate, pero, bueno, perdimos la votaci\u00f3n.&nbsp;C\u00f3mo no \u00edbamos a perder la votaci\u00f3n si estaban unidos todos los conservadores, hab\u00eda coalici\u00f3n y nos pasaban la aplanadora, lo que no ven ahora, pues, ya se les olvid\u00f3, ya se les olvid\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces, le digo: Mira c\u00f3mo han cambiado las cosas, ahora les ganamos el debate y tambi\u00e9n les ganamos la votaci\u00f3n. Se avanz\u00f3, por eso estamos muy contentos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1S\u00ed! \u00a1por supuesto! Ahora que se chinguen estos senadores y diputados federales de la oposici\u00f3n y trabajadores del Poder Judicial de la Federaci\u00f3n y ministros, magistrados, jueces e integrantes de la carrera judicial y usted y yo como ciudadanos de este pa\u00eds que transita hacia estancos conocidos en los vecinos con gobiernos de dizque izquierda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed, que se jodan porque son los perdedores y habr\u00e1 reforma al Poder Judicial de la Federaci\u00f3n por obra y gracia y los cojones de Su Alteza Seren\u00edsima Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY los foros convocados por el Corporativo Morena y Asociados en el Congreso de la Uni\u00f3n dizque para explicar las razones por las que debe haber esa reforma a uno de los Tres Poderes de la Federaci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Ah!, f\u00edjese usted que fueron de convocatoria abierta, pero se reservaron el derecho de admisi\u00f3n. As\u00ed de cabrones y alzaditos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Claro!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfOpinaron magistrados, jueces, trabajadores del Poder Judicial de la Federaci\u00f3n, decir los interesados y principales afectados por la enmienda? \u00a1Nada!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah\u00ed tiene usted el caso&nbsp;Loretta Ortiz Ahlf, la ministra que hace un a\u00f1o se pronunci\u00f3 contra la elecci\u00f3n de jueces, magistrados y ministros, pero en un Foro Reforma al Poder Judicial, en M\u00e9rida, Yucat\u00e1n, el s\u00e1bado \u00faltimo, 24 de agosto de plano asumi\u00f3 p\u00fablicamente su filiaci\u00f3n morenista y fan\u00e1tica del Duce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo fui fundadora de Morena, camin\u00e9 por las calles\u201d, dijo y, sin rubor, elogi\u00f3 a Andr\u00e9s Manuel L\u00f3pez Obrador llam\u00e1ndolo \u201cel mejor presidente que ha tenido nuestro pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, entre los asistentes hubo una voz que se atrevi\u00f3 a increparla porque no explic\u00f3 de qu\u00e9 se trata la iniciativa de reforma al Poder Judicial de la Federaci\u00f3n \u2013cuyo dictamen fue aprobado, en lo general y particular, anoche lunes 26 de agosto, en comisiones de la C\u00e1mara de Diputados&#8211;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lea usted:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 nos miente, se\u00f1ora ministra?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1Me duele ver que nos mienta as\u00ed! Yo defiendo al pa\u00eds, defiendo a la democracia y usted por lo visto solo defiende al Presidente, solo viene a elogiarlo, solo viene a mentirnos como lo hace la cuarta transformaci\u00f3n. \u00bfTransformaci\u00f3n de d\u00f3nde?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEst\u00e1n destruyendo el pa\u00eds, est\u00e1n destruyendo la democracia, est\u00e1n destruyendo la independencia judicial\u201d, le espet\u00f3 la abogada Mildred Berr\u00f3n, oficial judicial del Segundo Juzgado de Distrito en M\u00e9rida, Yucat\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;\u00a1Por eso! \u2013respondi\u00f3 la ministra pillada cual panegirista de la 4T.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, la abogada Milldred Berr\u00f3n le record\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Poder Ejecutivo es quien usted representa, no el Poder Judicial de la Federaci\u00f3n. Sus intereses son hacia Morena no hacia la gente, deje de mentirnos. Es una verdadera pena que usted represente a los ciudadanos y nos venga a mentir a la cara, me duele\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya entrada en gastos, la ministra declarada morenista se atrevi\u00f3 a replicar:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo miento, no tengo porqu\u00e9 mentir, y no tengo porqu\u00e9 mentir, sencillamente llevo 44 a\u00f1os dando clase, pues no miento, es tu dicho contra el m\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi consideras que yo miento, pues no votes por m\u00ed. Y los que me tenga confianza voten por m\u00ed\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 tal? \u00bfNo que no se parecen a los de endenantes? \u00a1Ah!, porque la jurista Ortiz Ahlf le entrar\u00e1 al proceso de elecci\u00f3n como ministra. Seguro se reelige.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, bueno, est\u00e1bamos en que la Princesa Caramelo en v\u00edas de ser ungida, seg\u00fan el dicho ir\u00f3nico del licenciado presidente, en Claudia Carlos de M\u00e9xico, ya es presidenta electa y ch\u00ednguese la oposici\u00f3n incluida en algo as\u00ed como 94 millones de mexicanos, con todo y j\u00f3venes imberbes y lactantes que nada saben de sufragios, pero todos los d\u00edas comen y no votaron por la Princesa Caramelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salvo aquellos que, por supuesto, profesan la fe ciega con el manto del Santo Ni\u00f1o Fidencio de Palacio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y le juegan a ser dem\u00f3cratas, impolutos investidos con el manto del doble lenguaje. Ah\u00ed tiene usted a la ministra Loretta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo se parecen a los de antes? He aqu\u00ed que la Princesa Caramelo en la idea de quedar bien con el a\u00fan licenciado presidente meti\u00f3 la chancla de sat\u00edn bordado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00e1nimo de explicar por qu\u00e9 debe reformarse al Poder Judicial de la Federaci\u00f3n, olvid\u00f3 que Su Alteza Seren\u00edsima daba instrucciones al entonces presidente de la Suprema Corte de Justicia de la Naci\u00f3n, el pr\u00edstino e independiente Arturo Zald\u00edvar Lalo de Larrea, para que, en juzgados, se orientara favorablemente para su gobierno alg\u00fan caso en particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia Sheinbaum Pardo, en su singular conferencia ma\u00f1anera, declar\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl presidente, en su momento, no con el presidente L\u00f3pez Obrador, pero previo a ello le llamaba al presidente de la Suprema Corte para decirle qu\u00e9 quer\u00eda que se resolviera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 no hablan de eso los de la Comisi\u00f3n (Interamericana) de Derechos Humanos, los de los medios internacionales?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfPor qu\u00e9 no se habla de aquel periodo donde todo era\u2026? \u00bfO ustedes creen que Fox no le llamaba al presidente de la Suprema Corte, o Calder\u00f3n o Pe\u00f1a?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cBueno, est\u00e1 el caso que ha denunciado el ministro Zald\u00edvar, el de la guarder\u00eda ABC\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con matiz y todo, no pueden ni podr\u00e1n ocultar que llevan el ADN del PRI con mezcla del PAN y del PRD. \u00bfTambi\u00e9n de Movimiento Ciudadano? \u00a1Vaya usted a saber!, pero de que se parecen, se parecen. Y harto. Por de pronto hay que ir tom\u00e1ndoles el modito porque andan sobraditos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfDue\u00f1os del pa\u00eds por \u201cvoluntad\u201d de millones de votos comprados con recursos p\u00fablicos v\u00eda programas sociales? Ese es delito electoral disfrazado de democracia. \u00a1En la madre, Drakko&nbsp; ! Digo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\">sanchezlimon@gmail.com<\/a>&nbsp;&nbsp;&nbsp;<a href=\"http:\/\/www.entresemana.mx\/\">www.entresemana.mx<\/a>&nbsp;&nbsp; @sanchezlimon1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl mundo siendo mundo\/ no me podr\u00e1 vencer\/ si cabe en cinco letras\/ muy grande no ha de ser\u2026\u201d&nbsp;Pedro Infante Mois\u00e9s S\u00e1nchez Lim\u00f3n SemM\u00e9xico, Cd. de M\u00e9xico, 28 de agosto, 2024.- No hay peor ciego que el c\u00ednico que niega la realidad y se hace que la virgen le habla. Disculpe la ruda analog\u00eda, pero [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-86297","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/86297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=86297"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/86297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/69815"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=86297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=86297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=86297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}