{"id":85825,"date":"2024-08-19T14:04:46","date_gmt":"2024-08-19T20:04:46","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=85825"},"modified":"2024-08-19T14:04:47","modified_gmt":"2024-08-19T20:04:47","slug":"elaboran-macetas-compostables-y-acuarelas-con-materiales-sustentables-y-de-reciclaje","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/elaboran-macetas-compostables-y-acuarelas-con-materiales-sustentables-y-de-reciclaje\/","title":{"rendered":"Elaboran macetas compostables y acuarelas con materiales sustentables y de reciclaje"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Alumnas y alumnos de la Facultad de Ingenier\u00eda imparten talleres para crear esos productos, a fin de difundir la revalorizaci\u00f3n de lo que se considera basura<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Mar\u00eda Neftal\u00ed Rojas Valencia destac\u00f3 que la ventaja de dichos recipientes es que una vez que germina y crece la planta, no es necesario trasplantarla<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 19 de agosto, 2024.- Con residuos de cart\u00f3n, principalmente de empaques de huevo que las recicladoras no compran, estudiantes de la Facultad de Ingenier\u00eda (FI) de la UNAM producen macetas compostables, y acuarelas no t\u00f3xicas a base de desechos org\u00e1nicos como c\u00e1scaras de algunos vegetales, frutas y especias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daniela Garc\u00eda Granados, Arturo Fabi\u00e1n Renter\u00eda F\u00e9lix, Yolitzin Romero Ortiz, Paola Tapia Le\u00f3n y Ana Mar\u00eda Castro Hern\u00e1ndez, quienes integran la Sociedad de Ingenier\u00eda Ambiental (SIAFI), imparten talleres \u2013a trav\u00e9s de las redes sociales del grupo estudiantil y en la FI\u2013 para elaborar esos productos, cuyo fin es difundir la revalorizaci\u00f3n de aquello que se considera basura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de las macetas, son org\u00e1nicas y las plantas o semillas pueden trasplantarse de su recipiente de origen a la germinaci\u00f3n sin generarles ning\u00fan tipo de estr\u00e9s, lo que posibilita que crezcan de mejor manera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detallaron que son una agrupaci\u00f3n estudiantil universitaria, con apenas cinco a\u00f1os, los mismos que tiene la licenciatura que cursan. Realizamos una serie de actividades relacionadas con la carrera al interior de la Facultad y en eventos acad\u00e9micos universitarios vinculados con nuestra \u00e1rea de estudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de sus propuestas es el Taller de Macetas Compostables, que impartieron en el Primer Congreso Internacional de Ingenier\u00eda Ambiental (CIAMB) \u201cPerspectivas para la Sostenibilidad\u201d, organizado recientemente por el posgrado de Ingenier\u00eda y el Subcomit\u00e9 Acad\u00e9mico por Campo de Conocimiento en Ingenier\u00eda Ambiental de la UNAM.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"200\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-02.jpg\" alt=\"\" class=\"wp-image-85828\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los integrantes de la SIAFI puntualizaron que su elaboraci\u00f3n es a partir de la combinaci\u00f3n de cart\u00f3n de huevo, rollos interiores del papel de ba\u00f1o y de servitoallas de cocina, entre otros tipos de cart\u00f3n -excepto plastificado como el de los cereales-, que combinan con agua y grenetina para obtener una pasta que se moldea y se deja secar durante dos d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez secas, se siembran las semillas o peque\u00f1as pl\u00e1ntulas para que germinen, no es necesario trasplantarlas ya que desde un inicio se pueden colocar en sus macetas definitivas o en el suelo de siembra, con la ventaja de que el recipiente sustentable le aportar\u00e1 nutrientes a las plantas y a la tierra, indicaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ello se contribuye a la reducci\u00f3n de nuestra dependencia del pl\u00e1stico, as\u00ed como a disminuir la generaci\u00f3n de residuos y la contaminaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que para los colorantes naturales emplean betabel, zanahoria, col morada, paprika, c\u00farcuma, flores de buganvilia, hojas verdes de plantas, por ejemplo, que se maceran con agua, alcohol y bicarbonato para obtener las acuarelas sustentables. Pueden utilizarlas con toda seguridad ni\u00f1as y ni\u00f1os al tratarse de ingredientes org\u00e1nicos que no representan ning\u00fan riesgo, adem\u00e1s de ser econ\u00f3micas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aclararon que, si bien no inventaron estas opciones, pues se obtienen hace tiempo, su objetivo es mostrar que son numerosas las cosas que se pueden elaborar aprovechando materiales sustentables y de reciclaje, por lo que buscamos compartirlo con la comunidad universitaria y la sociedad en general.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-03.jpg\" alt=\"\" class=\"wp-image-85827\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>M\u00e1s iniciativas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigadora del Instituto de Ingenier\u00eda, Mar\u00eda Neftal\u00ed Rojas Valencia, organizadora del CIAMBI, donde el grupo estudiantil SIAFI imparti\u00f3 los talleres sustentables, recalc\u00f3 que la ventaja de los recipientes compostables es que una vez que germina y crece la planta no es necesario trasplantarla, ya que sus componentes son cien por ciento biol\u00f3gicos y se integran al suelo con facilidad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-04.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/08\/compostables-04.jpg\" alt=\"\" class=\"wp-image-85826\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista en Ciencias e Ingenier\u00eda Ambiental destac\u00f3 que los moldes convencionales que se venden y utilizan para el germinado son costosos y, adem\u00e1s, elaborados con pl\u00e1sticos. Con la propuesta universitaria se pueden sustituir y adem\u00e1s la inversi\u00f3n es m\u00ednima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, coment\u00f3 que con los empaques de cart\u00f3n de huevo y otras mezclas, ha conformado, adem\u00e1s de germinadores, la base de bancos o asientos, cuya estructura principal o soporte son botellas de PET. Tambi\u00e9n elabor\u00f3 bloques rojos con arcilla y cart\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ese tipo de art\u00edculos, nombrados Echerhirhu-Block, la investigadora, en convenio de colaboraci\u00f3n con el Instituto de Investigaciones Metal\u00fargicas, de la Universidad Michoacana de San Nicol\u00e1s de Hidalgo, ha fabricado muros y muretes, innovaci\u00f3n que ha funcionado bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El material de construcci\u00f3n se ha probado para garantizar los requerimientos b\u00e1sicos de la normatividad, como resistencia, erosi\u00f3n, absorci\u00f3n inicial y final, as\u00ed como intemperismo acelerado, y han pasado las pruebas. Los ladrillos ecol\u00f3gicos se han empleado en la construcci\u00f3n de una casa en esa entidad federativa. Los resultados de esta investigaci\u00f3n fueron publicados en el <em>Journal Case Studies in Construction Materials<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apunt\u00f3 que como parte de las actividades del congreso intervinieron otras asociaciones estudiantiles de la Facultad de Ingenier\u00eda, una de ellas es la Sociedad de Energ\u00eda y Medio Ambiente, que ofreci\u00f3 el taller Captaci\u00f3n de agua de lluvia como parte de la seguridad h\u00eddrica, con una participaci\u00f3n considerable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoci\u00f3 que la iniciativa, cien por ciento estudiantil, es \u00fatil para crear huertos urbanos. Sobre ese tema, hace poco m\u00e1s de una d\u00e9cada, la universitaria, en colaboraci\u00f3n con alumnos, trabaj\u00f3 en una propuesta de agricultura urbana sustentable, resultado de ello escribi\u00f3 el art\u00edculo internacional en ingl\u00e9s, \u201cUrban agriculture, using sustainable practices that involve the reuse of wastewater and solid waste\u201d, el cual se ha constituido en uno de los m\u00e1s citados a la fecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alumnas y alumnos de la Facultad de Ingenier\u00eda imparten talleres para crear esos productos, a fin de difundir la revalorizaci\u00f3n de lo que se considera basura Mar\u00eda Neftal\u00ed Rojas Valencia destac\u00f3 que la ventaja de dichos recipientes es que una vez que germina y crece la planta, no es necesario trasplantarla &nbsp;Redacci\u00f3n SemM\u00e9xico, Cd. de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":85829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[694,63],"tags":[],"class_list":["post-85825","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas","category-reportajes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/85825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=85825"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/85825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/85829"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=85825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=85825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=85825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}