{"id":85389,"date":"2024-08-09T13:11:25","date_gmt":"2024-08-09T19:11:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=85389"},"modified":"2024-08-09T13:11:59","modified_gmt":"2024-08-09T19:11:59","slug":"los-capitales-el-empeoramiento-del-entorno-geopolitico-presionara-la-politica-monetaria-mundial","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-el-empeoramiento-del-entorno-geopolitico-presionara-la-politica-monetaria-mundial\/","title":{"rendered":"Los capitales| El empeoramiento del entorno geopol\u00edtico presionar\u00e1 la pol\u00edtica monetaria mundial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 9 de agosto, 2024.- El Banco de M\u00e9xico recort\u00f3 en 25pb la tasa de inter\u00e9s bancario a 10.75% en una decisi\u00f3n dividida, en donde la Gobernadora Victoria Rodr\u00edguez, Galia Borja y Omar Mej\u00eda apoyaron el movimiento. Mientras que Irene Espinosa y Jonathan Heath favorec\u00edan dejarla en 11.00%. Seg\u00fan analistas de Banorte, la decisi\u00f3n contrajo se bas\u00f3 en el reconocimiento de la trayectoria descendente de la inflaci\u00f3n subyacente, especialmente incluyendo la expectativa de que seguir\u00e1 disminuyendo; adem\u00e1s, Sobre la trayectoria de inflaci\u00f3n, los ajustes para la general se concentraron en los trimestres m\u00e1s inmediatos y fueron de una magnitud relevante. No obstante, el momento estimado de la convergencia al objetivo se mantuvo en el 4T25. Mientras tanto, s\u00f3lo se realiz\u00f3 una revisi\u00f3n limitada a la subyacente (-10pb en el 3T24).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la trayectoria de inflaci\u00f3n, los ajustes para la general se concentraron en los trimestres m\u00e1s inmediatos y fueron de una magnitud m\u00e1s intensa. No obstante, el momento estimado de la convergencia al objetivo se mantuvo en el 4T25. Mientras tanto, s\u00f3lo se realiz\u00f3 una revisi\u00f3n limitada a la subyacente (-10pb en el 3T24).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Analistas de Banorte consideran que el entorno geopol\u00edtico en noviembre ser\u00e1 m\u00e1s complejo, en particular por las elecciones en EU. Por lo tanto, seguimos anticipando una pausa. No obstante, en caso de observarse condiciones m\u00e1s favorables a las que prevemos en los mercados tras dicho evento, podr\u00edamos ver otro recorte de la misma magnitud en ese mes. Esto no constituye nuestro caso base, pero consideramos que es un importante riesgo a la baja para la tasa de referencia. Finalmente, esperamos otra baja de 25pb en diciembre. Con ello, la tasa de referencia cerrar\u00eda el a\u00f1o en 10.25%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte analistas de INVEX coincidieron al se\u00f1alar que,&nbsp;si bien el panorama inflacionario a\u00fan amerita una postura restrictiva, la evoluci\u00f3n que \u00e9ste ha presentado permite un menor grado de apretamiento monetario.&nbsp;El descenso de la inflaci\u00f3n subyacente&nbsp;se utiliz\u00f3 uno de los principales argumentos para bajar la tasa este mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y por \u00faltimo, los analistas se\u00f1alan que la decisi\u00f3n de la mayor\u00eda de los miembros del banco central&nbsp;reduce la presi\u00f3n sobre el servicio de la deuda del pa\u00eds&nbsp;y por lo tanto sobre el saldo de las finanzas p\u00fablicas. Un riesgo importante que detectamos es&nbsp;una contaminaci\u00f3n hacia los precios de alimentos procesados y servicios&nbsp;en caso de que los precios no subyacentes vuelvan a repuntar. Asimismo, no descartamos un nuevo&nbsp;aumento en las expectativas de inflaci\u00f3n del mercado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todos a trabajar para aumentar la producci\u00f3n de alimentos: Ana Lilia Rivera.<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora Ana Lilia Rivera Rivera, presidenta de la Mesa Directiva del Senado de la Rep\u00fablica, particip\u00f3 en el evento preparatorio hacia el \u201cI Foro Iberoamericano y Caribe\u00f1o por la Seguridad Alimentaria y de cara a los retos y oportunidades en el camino al 2030\u201d.&nbsp;Es un honor para M\u00e9xico ser el pa\u00eds sede de esta reuni\u00f3n preparatoria hacia el Primer Foro Iberoamericano y del Caribe por la Seguridad Alimentaria, un evento que permitir\u00e1 a los pa\u00edses integrantes de la Alianza Parlamentaria Iberoamericana por la Seguridad Alimentaria para Todas y Todos presentar los avances en cada una de las regiones que conforman y definir las acciones principales para alcanzar nuestros objetivos. En estos tiempos, cuando la seguridad alimentaria se ha convertido en una preocupaci\u00f3n cr\u00edtica a nivel global, nuestra uni\u00f3n y cooperaci\u00f3n son m\u00e1s necesarias que nunca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\" target=\"_blank\" rel=\"noreferrer noopener\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.agendadeinveriones.com.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.agendadeinveriones.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @<a href=\"http:\/\/yahoo.com.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">yahoo.com.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico, 9 de agosto, 2024.- El Banco de M\u00e9xico recort\u00f3 en 25pb la tasa de inter\u00e9s bancario a 10.75% en una decisi\u00f3n dividida, en donde la Gobernadora Victoria Rodr\u00edguez, Galia Borja y Omar Mej\u00eda apoyaron el movimiento. Mientras que Irene Espinosa y Jonathan Heath favorec\u00edan dejarla en 11.00%. Seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[750,110,35],"tags":[],"class_list":["post-85389","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-la-opinion-columnas","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/85389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=85389"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/85389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=85389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=85389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=85389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}