{"id":84485,"date":"2024-07-19T15:20:46","date_gmt":"2024-07-19T21:20:46","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=84485"},"modified":"2024-07-19T15:20:47","modified_gmt":"2024-07-19T21:20:47","slug":"presentan-obras-de-rosario-castellanos-y-raul-ortiz-y-de-juan-garcia-ponce-en-la-sala-adamo-boari","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/presentan-obras-de-rosario-castellanos-y-raul-ortiz-y-de-juan-garcia-ponce-en-la-sala-adamo-boari\/","title":{"rendered":"Presentan obras de Rosario Castellanos y Ra\u00fal Ortiz, y de Juan Garc\u00eda Ponce en la Sala\u00a0Adamo Boari"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La actividad del Inbal tiene como prop\u00f3sito promover la obra y trayectoria de autores relevantes para la literatura nacional<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Redacci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 19 de julio, 2024.-<em> Cartas encontradas (1966-1974),&nbsp;<\/em>de Rosario Castellanos y Ra\u00fal Ortiz y Ortiz;<em>&nbsp;Doce y una, trece<\/em>&nbsp;y&nbsp;<em>Cat\u00e1logo razonado<\/em>, de Juan Garc\u00eda Ponce, obras presentadas &nbsp;en la Sala&nbsp;<em>Adamo Boari<\/em>&nbsp;del Palacio de Bellas Artes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo inform\u00f3 la Secretar\u00eda de Cultura del Gobierno de M\u00e9xico y el Instituto Nacional de Bellas Artes y Literatura (Inbal), a trav\u00e9s de la Coordinaci\u00f3n Nacional de Literatura (CNL), &nbsp;encargadas de la presentaci\u00f3n&nbsp; a unos d\u00edas de que se cumpla el 50 aniversario de la&nbsp; muerte de la poeta y escritora chiapaneca, promotora de la reflexi\u00f3n feminista de su tiempo, quien dej\u00f3&nbsp;&nbsp; una honda huella en las mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La charla se realiz\u00f3 con el fin de promover la obra y la trayectoria de autores relevantes para la literatura nacional. El pres\u00eddium \u2014moderado por el poeta, \u00c1ngel Cuevas\u2014 estuvo conformado por la poeta Alejandra Atala; el narrador Javier Garc\u00eda-Galiano; la investigadora de artes esc\u00e9nicas Ang\u00e9lica Garc\u00eda G\u00f3mez; el investigador Daniel Escoto y el documentalista \u00c1ngel Aurelio Gonz\u00e1lez Amozorrutia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1ngel Cuevas mencion\u00f3 que&nbsp;<em>Cartas encontradas (1966-1974)&nbsp;<\/em>es un epistolario entre Rosario Castellanos y Ra\u00fal Ortiz y Ortiz durante en ese periodo, editado por el poeta, ensayista y traductor Alfonso D\u2019Aquino, y publicado por el Fondo de Cultura Econ\u00f3mica, luego de sortear varias dificultades para su publicaci\u00f3n. Tambi\u00e9n, refiri\u00f3 que Ortiz y Ortiz trabaj\u00f3 devotamente en este libro durante sus \u00faltimos tres a\u00f1os de vida, revisando la edici\u00f3n, incluso, durante sus \u00faltimos d\u00edas en el hospital.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un libro que ten\u00eda el maestro Ortiz y Ortiz, sin saberlo, entre sus documentos. \u00c9l nunca pens\u00f3 que las cartas que intercambi\u00f3 con Rosario (Castellanos) se publicar\u00edan. Surgi\u00f3 la idea de poner estas misivas en manos de Alfonso D\u2019Aquino para lograr esta edici\u00f3n y as\u00ed se trabaj\u00f3 hasta que el libro qued\u00f3 listo para su publicaci\u00f3n\u201d, explic\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El poeta inform\u00f3 que&nbsp;<em>Cartas encontradas&nbsp;<\/em>es un epistolario que re\u00fane la correspondencia in\u00e9dita que Castellanos y Ortiz y Ortiz intercambiaron de 1966 a 1967 (mientras ella estaba en Estados Unidos), y de 1971 a 1974 (durante su estancia en Israel). Remarc\u00f3 que es una obra imprescindible, no solo por su alta calidad literaria, sino porque es un valioso documento que \u201crefleja los acontecimientos y los protagonistas hist\u00f3ricos y culturales m\u00e1s relevantes de los a\u00f1os sesenta y setenta, principalmente en M\u00e9xico, pero tambi\u00e9n, dado el car\u00e1cter cosmopolita de los autores, en el mundo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su turno, Alejandra Atala contextualiz\u00f3 la obra, la calific\u00f3 como imperdible, memorable y eminente, y explic\u00f3 que se encuentra dividida en cinco partes. En sus 282 p\u00e1ginas incluye: pr\u00f3logo, 51 cartas, una correspondencia dividida en dos tiempos (de 1966 a 1967 y de 1971 a 1974), anexos, iconograf\u00eda y agradecimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSin duda, este libro tambi\u00e9n es poes\u00eda. Llega desde alg\u00fan lugar de la nostalgia de Ortiz y Ortiz. No fue una obra pensada como tal por sus autores, pero es una especie de travesura del azar en la que el esp\u00edritu de la literatura se impone. Sobre este libro se pueden hacer muchas lecturas, desde varias perspectivas, \u00e1mbitos, lugares, \u00e9pocas, geograf\u00edas, razones, pensamientos o poes\u00edas\u201d, manifest\u00f3.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Javier Garc\u00eda-Galiano dijo que es un libro anacr\u00f3nico en el que perduran formas y pr\u00e1cticas placenteras en extinci\u00f3n, como la letra manuscrita y las cartas. El origen de este libro es la amistad, admiraci\u00f3n y devoci\u00f3n expresa que Ortiz y Ortiz demostraba por Rosario Castellanos. Tambi\u00e9n coment\u00f3 que, mientras avanza en la lectura, la persona que lee asiste a una conversaci\u00f3n perpetua, confiada, placentera y sin reservas entre dos amigos fraternos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esta correspondencia se descubre a una Rosario Castellanos que, asegura, ha dejado de escribir. Sin embargo, ella nunca dej\u00f3 de leer compulsivamente, no pudo dejar la cr\u00edtica, no dej\u00f3 de estar al tanto de lo que suced\u00eda en M\u00e9xico, a pesar de encontrarse en el extranjero. En este epistolario se descubre a una mujer felizmente insumisa y certera. Estas cartas incitan a volver a leer a Rosario, a pesar de todo lo que pueda decirse\u201d, sugiri\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, se presentaron dos obras de teatro de Juan Garc\u00eda Ponce:&nbsp;<em>Cat\u00e1logo razonado<\/em>&nbsp;y&nbsp;<em>Doce y una, trece,&nbsp;<\/em>editadas por D\u2019Aquino y publicadas por Ediciones Odradek.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/07\/cultura-feminista-02.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/07\/cultura-feminista-02-1024x682.jpg\" alt=\"\" class=\"wp-image-84487\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ang\u00e9lica Garc\u00eda reconoci\u00f3 el esfuerzo de Ediciones Odradek para la publicaci\u00f3n de estas obras, pues no solo se preocup\u00f3 por reeditar los textos de Garc\u00eda Ponce, sino que enriqueci\u00f3 esta edici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Cat\u00e1logo razonado<\/em>&nbsp;est\u00e1 dedicada a Juan Jos\u00e9 Gurrola. Los personajes principales son dos voces: la voz de quien escribe y la voz de un director de escena. Quien escribe es Garc\u00eda Ponce y, la segunda voz, Juan Jos\u00e9 Gurrola. Es una especie de juego de espejos, una obra muy autorreferencial\u201d, opin\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn la puesta en escena se desprende otra realidad, que se desprende de la literatura, pero que ya es experiencia, arte vivo. No existe ya fidelidad al texto y este se transfigura. Garc\u00eda Ponce dedica esta obra a Gurrola, es un juego privado entre ellos. Es un recuerdo de los a\u00f1os que compartieron, de cuando fueron c\u00f3mplices. Garc\u00eda Ponce sabe que no habr\u00e1 fidelidad al texto. Gurrola har\u00e1 su magia y surgir\u00e1 una realidad inusitada. Esta puesta en escena fue llevada a cabo en 1989, aunque el texto es de 1983\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, Daniel Escoto habl\u00f3 de&nbsp;<em>Doce y una, trece,&nbsp;<\/em>obra en la que se encarg\u00f3 del pr\u00f3logo, y a la que define como una obra curiosa y at\u00edpica, pues es una especie de despedida (moment\u00e1nea) de Garc\u00eda Ponce del mundo teatral. Subray\u00f3 que en esta obra se hace una valoraci\u00f3n de la realidad nacional que se refleja en un teatro costumbrista&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe gustar\u00eda que pens\u00e1ramos este texto como parte de una batalla cultural que se libraba en M\u00e9xico en esa d\u00e9cada y en la d\u00e9cada previa. Pens\u00e9moslo como el entrecruce de muchas tensiones, de c\u00f3mo se percib\u00edan las letras, el teatro y el arte en la generaci\u00f3n de Garc\u00eda Ponce. Me gusta pensarlo como un canto de molestia contra una manera de hacer las cosas\u201d, opin\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, \u00c1ngel Aurelio Gonz\u00e1lez al referirse a&nbsp;<em>Cat\u00e1logo razonado&nbsp;<\/em>y&nbsp;<em>Doce una, trece,&nbsp;<\/em>subray\u00f3 que su quehacer literario tiene un alto valor, independientemente de si se trata de cuento, novela o ensayo. Adem\u00e1s, comparti\u00f3 que una pol\u00edtica de Ediciones Odradek es que privilegia mucho el tema de la imagen y la palabra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, la actriz Susi Estrada realiz\u00f3 una lectura dramatizada de las obras que se presentaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad del Inbal tiene como prop\u00f3sito promover la obra y trayectoria de autores relevantes para la literatura nacional &nbsp;Redacci\u00f3n. SemM\u00e9xico, Cd. de M\u00e9xico, 19 de julio, 2024.- Cartas encontradas (1966-1974),&nbsp;de Rosario Castellanos y Ra\u00fal Ortiz y Ortiz;&nbsp;Doce y una, trece&nbsp;y&nbsp;Cat\u00e1logo razonado, de Juan Garc\u00eda Ponce, obras presentadas &nbsp;en la Sala&nbsp;Adamo Boari&nbsp;del Palacio de Bellas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":84486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-84485","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/84485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=84485"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/84485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/84486"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=84485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=84485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=84485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}