{"id":84298,"date":"2024-07-16T14:04:34","date_gmt":"2024-07-16T20:04:34","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=84298"},"modified":"2024-07-16T14:04:35","modified_gmt":"2024-07-16T20:04:35","slug":"mas-dulces-que-el-azucar","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mas-dulces-que-el-azucar\/","title":{"rendered":"M\u00e1s dulces que el az\u00facar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Los edulcorantes artificiales, son seguros y pueden ayudar a reducir o controlar el peso<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Son utilizados en diversos alimentos y bebidas<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Redacci\u00f3n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>SemM\u00e9xico, Ciudad de M\u00e9xico, 16 de julio de 2024<\/em>.- Algunas personas eligen edulcorantes artificiales, ya sea para reducir la cantidad de calor\u00edas que consumen, disminuir el uso de az\u00facar o perder y controlar el peso, y seg\u00fan afirma el Documento de Consenso de la Asociaci\u00f3n Americana de Diabetes (ADA), \u201cestos cambios diet\u00e9ticos podr\u00edan afectar de modo beneficioso al control gluc\u00e9mico, de peso y cardiometab\u00f3lico\u201d. (1)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El consumo de los edulcorantes artificiales en nuestro pa\u00eds ha crecido a una tasa anual de 10.7% y estos sustitutos del az\u00facar han ido ganando espacio en las preferencias del consumidor industrial y entre las personas que buscan productos bajos en calor\u00edas, de acuerdo con un informe de la SAGARPA, consultado por el Laboratorio de Datos contra la Obesidad (LabDO). (2)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA) ha aprobado edulcorantes como aspartamo, acesulfamo pot\u00e1sico, sucralosa, neotame, advantame y sacarina, que son de 200 a 20 mil veces m\u00e1s dulces que el az\u00facar. (3)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos productos son ingredientes utilizados en alimentos y bebidas, comercializados como \u201csin az\u00facar\u201d o \u201cdiet\u00e9ticos\u201d y tambi\u00e9n est\u00e1n disponibles para su uso en el hogar, para hornear o cocinar, seg\u00fan un art\u00edculo de la FDA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, son empleados en diversos alimentos y bebidas, entre ellos, pastillas para el aliento, bebidas refrescantes, cereales, chicle, siropes saborizados para caf\u00e9, productos de agua con sabor, hielo congelado, cremas de fruta para untar, caramelos duros, helado, t\u00e9, mermeladas, jaleas, mezclas de jugos, mousse, goma de mascar, as\u00ed como tortas, barras nutritivas, pud\u00edn, caramelos, galletas, c\u00e1tsup, yogures y gelatinas sin az\u00facar a\u00f1adida. (4)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <em>Food and Drug Administration<\/em>, as\u00ed como otras agencias de salud gubernamentales supervisan y controlan los ingredientes de los sustitutos de az\u00facar, y sugieren la cantidad que puede usarse de forma segura todos los d\u00edas, lo cual var\u00eda seg\u00fan el peso y las caracter\u00edsticas de la persona y el tipo de sustituto elegido.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y si bien nutri\u00f3logos y m\u00e9dicos especialistas se\u00f1alan a los edulcorantes como seguros en cantidades limitadas para la mayor\u00eda de los adultos sanos, coinciden en que lo m\u00e1s importantes llevar una alimentaci\u00f3n saludable y hacer ejercicio. (5)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. International Sweeteners Association. Edulcorantes bajos en calor\u00edas en la diabetes. https:\/\/www.sweeteners.org\/es\/latest-science-post\/edulcorantes-bajos-en-calorias-en-la-diabetes-informes-actualizados-de-diabetes-uk-la-asociacion-latinoamericana-de-diabetes-alad-y-la-asociacion-americana-de-diabetes-ada\/&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. The Food Tech. As\u00ed es el consumo de edulcorantes en el mercado mexicano.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/thefoodtech.com\/nutricion-y-salud\/asi-es-el-consumo-de-edulcorantes-en-el-mercado-mexicano\/#:~:text=El%20consumo%20de%20productos%20no,en%20el%20periodo%20de%20referencia.\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">SAGARPA, CONADESUCA y Universidad Aut\u00f3noma de Chapingo. Nota informativa.&nbsp; https:\/\/www.gob.mx\/cms\/uploads\/attachment\/file\/201026\/Nota_Febrero.pdf&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. FDA. Qu\u00e9 tan dulce es: todo sobre los edulcorantes.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.fda.gov\/consumers\/articulos-para-el-consumidor-en-espanol\/que-tan-dulce-es-todo-sobre-los-edulcorantes\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">4. Aspartamo. Productos de consumo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-aspartame-org wp-block-embed-aspartame-org\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"TKmH93YaUm\"><a href=\"https:\/\/www.aspartamo.es\/productos\/\">Productos de consumo<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Productos de consumo&#8221; &#8212; Aspartame.org\" src=\"https:\/\/www.aspartamo.es\/productos\/embed\/#?secret=YOK0QmF66m#?secret=TKmH93YaUm\" data-secret=\"TKmH93YaUm\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">5. Mayo Clinic. Nutrici\u00f3n y comida saludable<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.mayoclinic.org\/es\/healthy-lifestyle\/nutrition-and-healthy-eating\/in-depth\/artificial-sweeteners\/art-20046936#:~:text=Los%20edulcorantes%20pueden%20ser%20una,seguros%20para%20los%20adultos%20sanos.\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los edulcorantes artificiales, son seguros y pueden ayudar a reducir o controlar el peso Son utilizados en diversos alimentos y bebidas Redacci\u00f3n SemM\u00e9xico, Ciudad de M\u00e9xico, 16 de julio de 2024.- Algunas personas eligen edulcorantes artificiales, ya sea para reducir la cantidad de calor\u00edas que consumen, disminuir el uso de az\u00facar o perder y controlar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":84299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[682],"tags":[],"class_list":["post-84298","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/84298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=84298"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/84298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/84299"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=84298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=84298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=84298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}