{"id":83794,"date":"2024-07-04T08:21:30","date_gmt":"2024-07-04T14:21:30","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=83794"},"modified":"2024-07-04T08:21:30","modified_gmt":"2024-07-04T14:21:30","slug":"oceanos-generadores-naturales-de-energias-renovables","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/oceanos-generadores-naturales-de-energias-renovables\/","title":{"rendered":"Oc\u00e9anos, generadores naturales de energ\u00edas renovables"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las visibles como las que producen las olas y corrientes marinas, existen tambi\u00e9n el gradiente de temperatura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El de salinidad de los que se puede obtener electricidad, afirm\u00f3 Cecilia Enr\u00edquez Ortiz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 4 de julio, 2024.- Disponibles para ser estudiadas y aprovechadas, las energ\u00edas marinas renovables son un recurso que debemos considerar en M\u00e9xico, un pa\u00eds que, seg\u00fan datos de la Secretar\u00eda de Medio Ambiente y Recursos Naturales, 17 de sus 32 entidades federativas colindan con zonas mar\u00edtimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para indagar las posibilidades de extracci\u00f3n energ\u00e9tica, Cecilia Enr\u00edquez Ortiz, profesora de Oceanograf\u00eda y Procesos Costeros de la Escuela Nacional de Estudios Superiores, Unidad M\u00e9rida, de la UNAM, ha participado en iniciativas gubernamentales y acad\u00e9micas para hacer realidad la posibilidad de obtenerlas de los mares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHace casi una d\u00e9cada el gobierno de M\u00e9xico comenz\u00f3 a impulsar la indagaci\u00f3n en energ\u00edas renovables de varios tipos. Cuando se gener\u00f3 el Centro de Investigaci\u00f3n en Energ\u00edas Renovables del Oc\u00e9ano lo conformamos un grupo muy grande de acad\u00e9micos de todo el pa\u00eds para atender las distintas fuentes de energ\u00eda que hay en los mares\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que hay en las olas y en las corrientes marinas, como lo podemos ver y sentir cuando vamos a las costas. Pero hay otras fuentes que no son tan visibles, como los gradientes de temperatura que tienen una gran cantidad que, con la tecnolog\u00eda adecuada, puede ser aprovechada para convertirla en electricidad, y tambi\u00e9n los gradientes de salinidad, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La del oleaje es predecible, pues fluye hacia las costas donde puede ser captada y transformada, a trav\u00e9s de convertidores, en energ\u00eda \u00fatil. La de corrientes marinas (importantes en las zonas del golfo de California, las costas de Quintana Roo y la corriente de Cozumel, y el mar Caribe) aprovecha la velocidad del flujo del agua, mediante una turbina que genera electricidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista expuso que, para explotar cualquier recurso del planeta, primero hay que estudiarlo de forma precisa para saber cu\u00e1nto existe y c\u00f3mo var\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSabemos que el Sol sale todos los d\u00edas y que a lo largo del d\u00eda podemos tener, con la tecnolog\u00eda adecuada, energ\u00eda solar. Pero cada que pasa una nube el panel deja de generar; y hay semanas o meses en los que hay menos energ\u00eda. Contabilizar esas variaciones es fundamental para las renovables\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gradiente de algo es una diferencia que hay desde un l\u00edmite hasta el otro en un rango de variaci\u00f3n. Decimos que hay uno de colores cuando vamos de un extremo al otro pasando por distintos colores, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gradiente de temperatura o t\u00e9rmico consiste en bombear agua del fondo del mar (que est\u00e1 de 500 a mil metros de profundidad, con una temperatura de cuatro a siete grados Celsius), hacia la superficie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El agua superficial registra de 24 a 28 grados Celsius y por medio de intercambiadores de calor se transforma de l\u00edquido a gas. En el segundo estado se produce la energ\u00eda a trav\u00e9s de una turbina conectada a un generador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso del gradiente de salinidad se utiliza una membrana para poner en contacto agua dulce y salina. A partir del intercambio i\u00f3nico entre ambas se produce electricidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn t\u00e9rminos matem\u00e1ticos, el gradiente es el cambio de algo a lo largo de un espacio. En el caso del gradiente de salinidad, si tengo agua dulce chocando en un espacio muy chiquito, el gradiente es muy grande\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, en las desembocaduras de r\u00edos que hay en los oc\u00e9anos el agua dulce choca con la salina. Toda la energ\u00eda de ese choque se vierte en manera espont\u00e1nea en forma de calor y podr\u00eda utilizarse, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista destac\u00f3 que cada t\u00e9cnica requiere tecnolog\u00edas especializadas y trabajo de campo. En el caso de M\u00e9xico, la m\u00e1s aprovechable es aquella de las corrientes marinas, pues nuestro pa\u00eds tiene la fortuna de contar con una de las m\u00e1s atractivas para la extracci\u00f3n del recurso: la de Yucat\u00e1n. Es de las m\u00e1s intensas que hay en el mundo, con una direcci\u00f3n estable que fluye hacia el norte antes de entrar al golfo de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014o0o\u2014<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Conoce m\u00e1s de la&nbsp;Universidad Nacional,&nbsp;visita:&nbsp;<a href=\"http:\/\/www.dgcs.unam.mx\/\">www.dgcs.unam.mx<\/a><a href=\"http:\/\/www.unamglobal.unam.mx\/\">www.unamglobal.unam.mx<\/a>&nbsp;o sigue en Twitter a:&nbsp;<a href=\"https:\/\/twitter.com\/SalaPrensaUNAM?original_referer=http%3A\/www.dgcs.unam.mx\/&amp;profile_id=2434557408&amp;tw_i=602917707252531200&amp;tw_p=embeddedtimeline&amp;tw_w=479759932309254145\">@SalaPrensaUNAM<\/a>y&nbsp;<a href=\"https:\/\/twitter.com\/Gaceta_UNAM\">@Gaceta_UNAM<\/a><\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de las visibles como las que producen las olas y corrientes marinas, existen tambi\u00e9n el gradiente de temperatura El de salinidad de los que se puede obtener electricidad, afirm\u00f3 Cecilia Enr\u00edquez Ortiz Redacci\u00f3n SemM\u00e9xico, Ciudad de M\u00e9xico, 4 de julio, 2024.- Disponibles para ser estudiadas y aprovechadas, las energ\u00edas marinas renovables son un recurso [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":83795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[682],"tags":[],"class_list":["post-83794","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/83794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=83794"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/83794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/83795"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=83794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=83794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=83794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}