{"id":82770,"date":"2024-06-11T07:32:36","date_gmt":"2024-06-11T13:32:36","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=82770"},"modified":"2024-06-11T07:32:37","modified_gmt":"2024-06-11T13:32:37","slug":"avance-disparejo-de-la-paridad-electoral-en-2024-quedan-atras-a-los-ayuntamientos-mientras-subsisten-brechas-en-la-administracion-publica-el-salario-y-la-s","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/avance-disparejo-de-la-paridad-electoral-en-2024-quedan-atras-a-los-ayuntamientos-mientras-subsisten-brechas-en-la-administracion-publica-el-salario-y-la-s\/","title":{"rendered":"Avance disparejo\u00a0 de\u00a0 la paridad electoral\u00a0 en 2024:\u00a0 quedan\u00a0 atr\u00e1s a los ayuntamientos; mientras\u00a0 subsisten\u00a0 brechas en la administraci\u00f3n p\u00fablica, el salario y la salud;\u00a0 millones viven\u00a0 discriminaci\u00f3n y violencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ser\u00e1n en 2024,&nbsp; 13 gobernadoras simult\u00e1neas,&nbsp; 6 mujeres gobernar\u00e1n&nbsp; las ciudades m\u00e1s grandes y con dinero, 8 alcald\u00edas capitalinas,&nbsp; s\u00f3lo 30 por ciento en el cambio de ayuntamientos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paridad en el Congreso de la Uni\u00f3n y las c\u00e1maras de los Estados; dirigieron el proceso 6 mujeres y hubo Presidenta de la Rep\u00fablica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 11 de junio, 2024.- En el recuento final sobre las elecciones del 2 de junio,&nbsp; para elegir&nbsp; en 20 mil puestos de representaci\u00f3n, avanz\u00f3 la paridad, menos&nbsp; en los ayuntamientos, donde s\u00f3lo ser\u00e1n dirigidos el&nbsp; 30 por mujeres:&nbsp; habr\u00e1 &nbsp; 4 mujeres para&nbsp; las&nbsp; 9&nbsp; gubernaturas o jefatura de la Ciudad de M\u00e9xico que estuvieron en disputa, pero&nbsp; s\u00f3lo 6 ciudades importantes y con presupuesto, de m\u00e1s de 100, ser\u00e1n gobernadas por mujeres. En tanto se ha elegido una mujer a la presidencia,&nbsp; lo que significa un avance disparejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ello a pesar de que seg\u00fan datos de la empresa \u00c1ltiaca la elecci\u00f3n presidencial ganadora&nbsp; tuvo, por encima del 60 por ciento, la aprobaci\u00f3n de amas de casa, jubilados, trabajadores por cuenta propia, agricultores y maestros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposicionista X\u00f3chitl G\u00e1lvez Ru\u00edz&nbsp; fue m\u00e1s votada entre patrones, desempleados y profesionistas. Seg\u00fan la encuesta de El Pa\u00eds, de los votos de mujeres para la triunfadora, fueron 55 por ciento y para la oposici\u00f3n 31 por ciento. En las votaciones s\u00f3lo 1 por ciento de quienes votaron eran personas no binarias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados&nbsp; tambi\u00e9n lograron &nbsp; paridad&nbsp; en el Congreso de la Uni\u00f3n, en ambas c\u00e1maras y en la mayor\u00eda de los&nbsp; congresos locales. Podr\u00eda haber cambios luego del examen de resultados por&nbsp; impugnaciones y resoluciones&nbsp; en el Tribunal Electoral.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ello a pesar del ambiente de violencia pre, durante y post electoral. Se considera que 15 mujeres, candidatas o precandidatas fueron asesinadas, entre 35 hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resultados&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados del domingo pasado de las juntas de escrutinio, luego de la revisi\u00f3n de cada distrito electoral,&nbsp; deja en claro que la paridad electoral, no fue alcanzada, especialmente en los municipios, seg\u00fan el an\u00e1lisis de Soledad Jarqu\u00edn Edgar, publicado por SemM\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e9rate: <a href=\"https:\/\/redsemlac.com\/semmexico\/como-les-fue-a-las-mujeres-en-las-elecciones\/\">https:\/\/redsemlac.com\/semmexico\/como-les-fue-a-las-mujeres-en-las-elecciones\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gobernadoras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los comicios para los gobiernos estatales, aplicada la paridad, en 8 de las nueve entidades donde habr\u00e1 cambio, participaron candidatas. S\u00f3lo no hubo en el Estado de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera 13 de las 32 entidades de la Rep\u00fablica, estar\u00e1n&nbsp; gobernadas por mujeres este 2024; todav\u00eda menos del 50 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13 gobernadoras<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/docsz\/AD_4nXcLFtNsfymLz_g6OhELwKe1bQS3pHnj0kW-G15vfEnB4_vGeWWAdso7FEo4-rTKkfi1LsmH1hjbkrOf-pw5q8UWMeI0CHy92w5cLcd5XsQ8dd5zefCMChhwoV_19ACdXiDvCyTSyS9jv034PGIa9ArlkIotR5Zl7BFUvNEyagJG2oLiB7qldnw?key=qZaTo2JM-ZnIzPIB70pxHw\" alt=\"Interfaz de usuario gr\u00e1fica, Texto\n\nDescripci\u00f3n generada autom\u00e1ticamente\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Guanajuato, Morelos y Veracruz tendr\u00e1n por primera vez en su historia una mujer en la gubernatura, 2 del partido en el poder y una del Partido Acci\u00f3n Nacional en Guanajuato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy de las 13 gobernadora tres han sido elegidas por el Partido de Acci\u00f3n Nacional (PAN) y 10 por Morena.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y hasta el momento 6 principales ciudades de la Rep\u00fablica ser\u00e1n gobernadas por mujeres:&nbsp; Guadalajara, Jalisco, por&nbsp; Ver\u00f3nica Delgadillo de Movimiento Ciudadano; Guanajuato, capital por&nbsp; Samantha Smith Guti\u00e9rrez, de Acci\u00f3n Nacional; Le\u00f3n,&nbsp; Guanajuato, por&nbsp; Alejandra Guti\u00e9rrez Campos tambi\u00e9n del PAN; Centro Tabasco, por&nbsp; Yolanda Osuma, de Morena; M\u00e9rida, Yucat\u00e1n por&nbsp; Cecilia Padr\u00f3n Laviada del PAN y Chetumal, Quintana Roo por&nbsp; Yensunni Mart\u00ednez Hern\u00e1ndez, de la 4T. Esto es decir 4 de oposici\u00f3n y 2 del partido oficial.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/docsz\/AD_4nXfCyfcDuPxfsmFc0jrsdg7KUu7KMWkqdfZAY_p1T_WqRuTZyczgBTMmuHSKczVUN_kG4SvtJowl-brRL97OAKjRbQQDeBtlhH7cRy2dzLwvj5W4fo1_8aY-JP9TgcWKAUEnTinvcxUMK4Rmtju4JT3QpdfxwLjzDnPuGH4Cc3TLKiUHHbxGP50?key=qZaTo2JM-ZnIzPIB70pxHw\" alt=\"Las gobernadoras electas Margarita Gonz\u00e1lez (Morelos), Libia Garc\u00eda Mu\u00f1oz (Guanajuato) y Roc\u00edo Nahle (Veracruz).\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El proceso hist\u00f3rico de las mujeres<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que parece es un momento acelerado. Este octubre se cumplen 71 a\u00f1os&nbsp; desde que las mujeres pueden ejercer su derecho, en todos los cargos, como dir\u00eda la ex diputada Martha Tagle, y las que votaron, lo hicieron masivamente en&nbsp; 1955, cuando fueron elegidas 5 diputadas federales. Pasaron 24 a\u00f1os para que en 1979 se eligiera la primera gobernadora,&nbsp; Griselda \u00c1lvarez Ponce de Le\u00f3n, en el estado de Colima. Le siguieron 8, a cuenta gotas, hasta que en&nbsp; 2021,&nbsp; se sumaron 7 y una en 2023; hoy ser\u00e1n&nbsp; 13 quienes gobernar\u00e1n en&nbsp; forma simult\u00e1nea.&nbsp;La entidad de mayor rango en poblaci\u00f3n, recursos naturales y econ\u00f3micos&nbsp; es Veracruz que con Guanajuato, son dos entidades donde campea la violencia y la inseguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El avance de las mujeres&nbsp; en puestos de elecci\u00f3n popular y ejecutivos, considerado como cambio acelerado en igualdad num\u00e9rica, tiene que ver con la reforma de&nbsp; 2014, cuando se incluy\u00f3 en la Constituci\u00f3n el principio de paridad, que obliga a los partidos pol\u00edticos a postular el mismo n\u00famero de candidaturas de hombres que de mujeres para los Congresos y se discuti\u00f3 seguidamente la paridad vertical y horizontal en los municipios y en 2021 la paridad para las gubernaturas. Se discutir\u00e1 en breve la paridad presidencial para 2030.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy paridad en las gubernaturas, fue realidad a pesar de ser impugnada por senadores de Morena y el PAN&nbsp;que consideraban que la orden del Instituto Nacional Electoral (INE) de que ten\u00edan que presentar al menos a siete mujeres para las 15 gubernaturas de 2021era una injerencia. Mario Delgado, actual presidente de Morena, lleg\u00f3 a calificarlo de \u201cinvasi\u00f3n\u201d a las competencias de los partidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello en 2021, se dio&nbsp; el salto a tener siete entidades gobernadas por mujeres. Por Morena salieron elegidas: Marina del Pilar \u00c1vila, de Morena, por Baja California; Layda Sansores, en Campeche; \u00cdndira Vizca\u00edno, en Colima; Evelyn Salgado, en Guerrero, y Lorena Cu\u00e9llar, en Tlaxcala. Adem\u00e1s, Maru Campos sali\u00f3 electa en Chihuahua por el PAN. Ellas seis se sumaron a Claudia Sheinbaum, quien entonces gobernaba Ciudad de M\u00e9xico. En 2022, se a\u00f1adieron Teresa Jim\u00e9nez, del PAN, en Aguascalientes y Mara Lezama, de Morena, en Quintana Roo. En 2023 se lleg\u00f3 al r\u00e9cord de 10 con la morenista Delfina G\u00f3mez en el Estado de M\u00e9xico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y a pesar de que en 2019, se declar\u00f3 la paridad en todo constitucionalmente, lo que aval\u00f3 la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) para todos los cargos, no solo legislativos, las mujeres que en la administraci\u00f3n p\u00fablica representan 47 por ciento de las trabajadoras, tienen los puestos de menor jerarqu\u00eda, representando s\u00f3lo 33 por ciento de los de mando superior, incluidas las subsecretar\u00edas de estado, jefaturas de unidad y direcciones generales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el IMCO hasta 2023&nbsp; en la titularidad de las secretar\u00edas de Estado&nbsp;es donde existe paridad de g\u00e9nero, de 16, hay ocho secretar\u00edas encabezadas por una mujer: Bienestar, Cultura, Econom\u00eda, Educaci\u00f3n, Energ\u00eda, Gobernaci\u00f3n, Medio Ambiente y Relaciones Exteriores. Pero s\u00f3lo son 30 por ciento en las subsecretar\u00edas; 28 por ciento en jefaturas de unidad y 34 por ciento en direcciones generales. Es decir la paridad en todo, est\u00e1 por verse.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ciudad de M\u00e9xico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capital del pa\u00eds, con 16 alcald\u00edas, en 2024 ser\u00e1 gobernada paritariamente, 8 hombres y 8 mujeres.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/docsz\/AD_4nXf93FKuLedAhdfaSk35Go_LfaSwiCSHRMRTJmwPWdFLkyUqiuBwH9mQASZODvaQmxfJo-ar7Sg5490agc7nJ58Tx0Y-8itqBIwJLtisLBcljuPcgXdpEctUPnuWsBJiJFNtBbDzBxc9HX2pL_QJAk6DVE84Lfl8NlS3CWHjs-YGpuru93fIh20?key=qZaTo2JM-ZnIzPIB70pxHw\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Estos resultados, el avance de las mujeres \u201cEs una conquista cultural que llev\u00f3 muchos a\u00f1os y que se concretiza hoy, porque al inicio de esta administraci\u00f3n se pusieron de acuerdo\u201d, as\u00ed se consolid\u00f3 la paridad electoral y&nbsp; todas las mujeres de todas las fuerzas pol\u00edticas y exigieron la paridad en todo, en todos los&nbsp; cargos pol\u00edticos,&nbsp; y en todas las administraciones, reflexion\u00f3 la abogada&nbsp; Ana Laura Magaloni, cuando habl\u00f3&nbsp; la noche del domingo electoral&nbsp; en la televisi\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La abogada e investigadora conclu\u00eda: \u201cNing\u00fan pa\u00eds del mundo hace una revoluci\u00f3n de este calibre sin una legislaci\u00f3n capaz de romper las estructuras tradicionales para que las mujeres ense\u00f1en qu\u00e9 significa estar en posiciones de poder, y quiero decir no por ser mujer ya es buena, pero se rompe una creencia de que las mujeres no estamos dise\u00f1adas para estar en el poder y tomar buenas decisiones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed la haza\u00f1a de 2021, en la ciudad de M\u00e9xico se repite. Primero al elegir a Clara Brugada, en la jefatura de gobierno. La tercera en ocupar este puesto, desde que en el a\u00f1o 2000 lo tuviera Rosario Robles Berlanga, quien ya hab\u00eda sido legisladora y luego fue secretaria de estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mujeres alcaldesas en la ciudad de M\u00e9xico, son&nbsp; 7 del partido gobernante y una de oposici\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Azcapotzalco, <strong>Nancy N\u00fa\u00f1ez Res\u00e9ndiz (Morena, PT y PVEM)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es una comunic\u00f3loga y figura pol\u00edtica reconocida en M\u00e9xico, naci\u00f3 el 4 de abril de 1985 en la Ciudad de M\u00e9xico.&nbsp;Ocup\u00f3 el puesto de diputada en la C\u00e1mara de Diputados de la Ciudad de M\u00e9xico por el Distrito 3.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A lo largo de su carrera pol\u00edtica,&nbsp;N\u00fa\u00f1ez Res\u00e9ndiz ha consolidado su posici\u00f3n dentro del partido Morena, destacando como portavoz del Grupo Parlamentario de Morena en el Congreso de la Ciudad de M\u00e9xico, adem\u00e1s de ser una de sus fundadoras.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desde que fue elegida como concejal de Azcapotzalco en 2018,&nbsp;Nancy ha desempe\u00f1ado un papel activo en varias comisiones clave en la administraci\u00f3n p\u00fablica.<\/strong>&nbsp;Su labor en las comisiones de Planeaci\u00f3n del Desarrollo, Transparencia y Combate a la Corrupci\u00f3n, Administraci\u00f3n y Procuraci\u00f3n de Justicia, Derechos Humanos, Inclusi\u00f3n, Bienestar y Exigibilidad de Derechos Sociales, Igualdad de G\u00e9nero y Participaci\u00f3n Ciudadana, destaca su compromiso con la promoci\u00f3n de la integridad, la equidad y el bienestar social en la capital del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cuauht\u00e9moc, Alessandra Rojo de la Vega Piccolo (PAN, PRI Y PRD)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tiene experiencia en comunicaci\u00f3n y estrategia digital, as\u00ed como en participaci\u00f3n pol\u00edtica a trav\u00e9s de su trabajo en el Comit\u00e9 Directivo del<strong> <\/strong>Partido Revolucionario Institucional (PRI) en la Ciudad de M\u00e9xico.&nbsp;Su papel como fundadora y presidenta de Efecto M\u00e1s y Media y co-fundadora y presidenta de MUI M\u00e9xico tambi\u00e9n indican su involucramiento en iniciativas empresariales y sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Iztacalco, Lourdes Paz (Morena, PT y PVEM)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es licenciada en Derecho por la Universidad de Veracruz&nbsp;y se ha destacado por su apoyo al presidente Andr\u00e9s Manuel L\u00f3pez Obrador y al partido Morena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la fundadora del movimiento liderado por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador y fue Enlace Distrital Federal en la alcald\u00eda Iztacalco en 2015<strong>,<\/strong>&nbsp;donde se encarg\u00f3 de la organizaci\u00f3n de los trabajos del partido. Su labor incluy\u00f3 la formaci\u00f3n de comit\u00e9s de base seccionales, la implementaci\u00f3n de estructuras para la promoci\u00f3n y defensa del voto, as\u00ed como su participaci\u00f3n en la elecci\u00f3n del Congreso Constituyente de la Ciudad de M\u00e9xico. Obtuvo su primer esca\u00f1o en el Congreso de la Ciudad de M\u00e9xico, tras ganar las elecciones de 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Iztapalapa, Aleida Alavez (Morena, PT y PVEM)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es egresada de Ciencias de la Comunicaci\u00f3n egres\u00f3 de la Universidad Nacional Aut\u00f3noma de M\u00e9xico.&nbsp;Desde 1995, se desempe\u00f1\u00f3 como consejera del PRD en el Distrito Federal y posteriormente, entre 2000 y 2002, ocup\u00f3 el cargo de consejera nacional en el partido. Asimismo, asumi\u00f3 la Secretar\u00eda de Comunicaci\u00f3n del PRD en el Distrito Federal y fue Secretaria General del comit\u00e9 delegacional en Iztapalapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus responsabilidades, se destacan su papel como Subdelegada territorial del Paraje de San Juan de 1998 a 1999 y en Cabeza de Ju\u00e1rez de 1999 a 2000, ambas en Iztapalapa.&nbsp;Adem\u00e1s, ejerci\u00f3 como diputada a la Asamblea Legislativa del Distrito Federal por el XXIX Distrito Electoral Local del Distrito Federal desde 2003 hasta 2006.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tl\u00e1huac, Berenice Hern\u00e1ndez Calder\u00f3n (Morena)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Realiz\u00f3 sus estudios universitarios en la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), donde obtuvo su licenciatura en Derecho.&nbsp;Se dedica a la pol\u00edtica y es fundadora del partido Morena. En sus perfiles de redes sociales, se identifica como una mujer orgullosa de su origen en la alcald\u00eda Tl\u00e1huac, y destaca su compromiso con su familia, comunidad y responsabilidades como l\u00edder de la demarcaci\u00f3n. Adem\u00e1s, es madre de dos ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tlalpan Gabriela Osorio (Morena, PT y PVEM)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tiene una licenciatura en Ciencias Pol\u00edticas y Administraci\u00f3n P\u00fablica en la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), y m\u00e1s recientemente, finaliz\u00f3 una maestr\u00eda en Ciudades y Urbanismo en el Instituto de Arquitectura Avanzada de Catalu\u00f1a, ubicado en Barcelona, Espa\u00f1a.<\/li>\n\n\n\n<li><strong>En 2013,\u00a0comenz\u00f3 su participaci\u00f3n en la entonces Asociaci\u00f3n Morena para la defensa del petr\u00f3leo. Tras la fundaci\u00f3n del Movimiento Regeneraci\u00f3n Nacional como partido pol\u00edtico en 2014,\u00a0<\/strong>asumi\u00f3 el rol de coordinadora del Distrito 5 electoral y secretaria de J\u00f3venes en Tlalpan, ocupando ambos cargos en el partido. Adem\u00e1s, desempe\u00f1\u00f3 funciones como jefa del Departamento de Animaci\u00f3n Cultural de 2015 a 2016 en la alcald\u00eda de Tlalpan, y tambi\u00e9n fungi\u00f3 como diputada federal suplente en la LXIII Legislatura.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Venustiano Carranza, Evelyn Parra (Morena, PT y PVEM)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es graduada en derecho por la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) y tambi\u00e9n ha trabajado como educadora. Desde 2008 hasta 2010<strong>,<\/strong>\u00a0ocup\u00f3 el cargo de secretaria de Cultura, Educaci\u00f3n, Ciencia y Tecnolog\u00eda del PRD en el Distrito Federal.<\/li>\n\n\n\n<li>Adem\u00e1s, entre abril y agosto de 2008,<strong>\u00a0<\/strong>desempe\u00f1\u00f3 el puesto de subdirectora de Servicios Legales en la Direcci\u00f3n Jur\u00eddica de la Direcci\u00f3n General Jur\u00eddica y de Gobierno en Venustiano Carranza.<\/li>\n\n\n\n<li>Su experiencia incluye haber sido jefa de Unidad Departamental de Jur\u00eddica en la Direcci\u00f3n Ejecutiva Territorial Morelos en Venustiano Carranza de octubre de 2006 a mayo de 2007, as\u00ed como subdirectora Jur\u00eddica y de Gobierno en la Direcci\u00f3n Ejecutiva Territorial de Morelos en la misma demarcaci\u00f3n de junio de 2007 a marzo de 2008.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Xochimilco, Circe Camacho Bastida (Morena, PT, PVEM)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuenta con una trayectoria de 14 a\u00f1os como militante del Partido del Trabajo (PT), donde ejerci\u00f3 como diputada en el Congreso de la Ciudad de M\u00e9xico. Identificada como parte de la comunidad LGBTTTIQ+, tambi\u00e9n cuenta con estudios en psicolog\u00eda.<\/li>\n\n\n\n<li>Originaria del barrio de San Esteban en Xochimilco, tiene 33 a\u00f1os de edad y ha sido reconocida como una de las diputadas m\u00e1s j\u00f3venes en el Congreso de la Ciudad de M\u00e9xico. Adem\u00e1s,\u00a0<strong>ha cursado estudios en Psicolog\u00eda Social Comunitaria en la Facultad de Psicolog\u00eda de la UNAM<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tantas mujeres en el poder \u00a1 beneficia a todas las dem\u00e1s?<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/docsz\/AD_4nXeGuu-U-ZLZydNldPVuhPMxfHCU_V_EMY3yG98yHVGR8FCnZ9V8zTEcz_isSHXvkSUpyWAlw08hqDVheAGu-i3fA_5EEyd2xkmjtQlaFtEi2DY5HdwUs6tZI0QCEaOOjaRjxRsnSBZ5TNrlzViiF9wO3sYmzIq8AYuFES8VH9U-HGLuJ4h0Rg?key=qZaTo2JM-ZnIzPIB70pxHw\" alt=\"M\u00e1s mujeres en el poder: \u00bfQu\u00e9 reformas impulsaron la paridad de g\u00e9nero?\"\/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Foto: Cuartoscuro<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio ha sido lento y ha sido r\u00e1pido de pronto. Pero en M\u00e9xico las mujeres viven violencia, viven pobreza, discriminaci\u00f3n y marginaci\u00f3n; las mujeres siguen viviendo brechas en el trabajo, el salario y las representaciones sindicales y campesinas. Es decir la pura representaci\u00f3n electoral, no ha llegado a cerrar las brechas de desigualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No s\u00f3lo este 2 de junio, pero fue el que lleg\u00f3 m\u00e1s all\u00e1. Se puede decir que el mapa pol\u00edtico se transform\u00f3 o profundiz\u00f3, sobre todo con la llegada de una primera mujer presidenta de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde antes&nbsp; ya hab\u00eda otras&nbsp;<strong>mujeres, conquistando cargos no s\u00f3lo electorales, como publicamos, ellas, todas mujeres, tuvieron el tim\u00f3n en este proceso electoral.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Como <\/strong>&nbsp;como es el caso de la ministra&nbsp;Norma Lu\u00eda Pi\u00f1a Hern\u00e1ndez&nbsp;<strong>presidenta<\/strong>&nbsp;de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) Y&nbsp; la&nbsp;consejera <strong>presidenta<\/strong>&nbsp;del Instituto Nacional Electoral (INE, Guadalupe Taddei Zavala. Igual la&nbsp; presidencia de la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) M\u00f3nica Aral\u00ed Soto, donde llegar\u00e1n todas las quejas electorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Y este 2024, son presidentas de cada una de las c\u00e1maras del Congreso de la Uni\u00f3n en la c\u00e1mara baja Marcela Guerra y en el Senado, Ana Lilia Rivera Rivera.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el Instituto Belisario Dom\u00ednguez&nbsp; del Senado de la Rep\u00fablica Para entender c\u00f3mo llegamos a tener tantas mujeres en puestos de decisi\u00f3n&nbsp; en los tres poderes y en cargos de elecci\u00f3n popular, dice <strong>Lorena V\u00e1zquez Correa<\/strong>, investigadora de ese instituto&nbsp; tiene que ver con&nbsp; las reformas de 2014 y 2019. Y explica: \u201cYa ten\u00edamos paridad de g\u00e9nero desde 2014, pero era exclusiva para cargos legislativos. Hab\u00eda un conjunto de jurisprudencia que tambi\u00e9n inclu\u00eda a las presidencias municipales, a los ayuntamientos, pero los cargos ejecutivos como gubernaturas, que son el cargo ejecutivo m\u00e1s importante en las entidades federativas y la Presidencia de la Rep\u00fablica, estaban reservados tradicionalmente para hombres\u201d, esta l\u00f3gica se rompi\u00f3 y se rompi\u00f3 una parte del llamado Techo de Cristal.<strong><em> Paridad de g\u00e9nero<\/em><\/strong><em>. Foto: Cuartoscuro<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00e1zquez Correa hizo notar que hubo una larga traves\u00eda. Pero as\u00ed hace algunos a\u00f1os hay mujeres en el Poder Judicial, la primera ministra se eligi\u00f3 en 1966, nunca hubo m\u00e1s de dos. Tambi\u00e9n con los procesos de cuota y acci\u00f3n positiva, desde 1989&nbsp; en los \u00f3rganos internos de los partidos pol\u00edticos, se definieron esas cuotas, tanto que se cuentan al menos 5 dirigentes nacionales, 3 en el PRI, 2 en el PRD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan ella donde los resultados fueron&nbsp; m\u00e1s r\u00e1pidos fue en el Poder Ejecutivo, considerando gubernaturas y ayuntamientos. Un fen\u00f3meno ligado a los cambios Constitucionales, a los acuerdos del Instituto Nacional Electoral y porque hay sanciones si no se cumple. Eso es fundamental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La cr\u00f3nica de la llegada y como la paridad s\u00ed hizo que las mujeres tengan poder en la vida p\u00fablica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con informaci\u00f3n del Congreso de la Uni\u00f3n, en 1988 el 88.19% de los integrantes del congresos&nbsp; eran hombres y el 10.82%, mujeres. Para el a\u00f1o 2000, hab\u00eda 84.87% de hombres y 15.13% de mujeres.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos datos cambian con la llegada de la \u00abparidad electoral ) que se estableci\u00f3 en 2014. Para 2018, hab\u00eda 50.48% hombres en las dos c\u00e1maras (diputaciones y senadur\u00edas) y 49.52% de mujeres. En 2021, cuando se eligieron a diputados locales y federales, hab\u00eda 49.04% hombres y 50.96% mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su dimensi\u00f3n hist\u00f3rica es importante, desde&nbsp; la fundaci\u00f3n de la C\u00e1mara de Diputados&nbsp; en 1821 y la primera mujer en ser diputada federal,&nbsp; Martha Aurora Jim\u00e9nez en 1954, es decir, pasaron 133 a\u00f1os para que una mujer llegara al Congreso de la Uni\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que en 1824, se cre\u00f3 la C\u00e1mara de Senadores, pasaron 140 a\u00f1os y hasta 1964 las abogadas&nbsp; Alicia Arellano y Mar\u00eda Lavalle se convirtieron en las primeras&nbsp;<strong>senadoras<\/strong>&nbsp;del pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio ha sido lento y ha sido r\u00e1pido de pronto. Pero en M\u00e9xico las mujeres viven violencia, viven pobreza, discriminaci\u00f3n y marginaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1n en 2024,&nbsp; 13 gobernadoras simult\u00e1neas,&nbsp; 6 mujeres gobernar\u00e1n&nbsp; las ciudades m\u00e1s grandes y con dinero, 8 alcald\u00edas capitalinas,&nbsp; s\u00f3lo 30 por ciento en el cambio de ayuntamientos Paridad en el Congreso de la Uni\u00f3n y las c\u00e1maras de los Estados; dirigieron el proceso 6 mujeres y hubo Presidenta de la Rep\u00fablica Sara Lovera SemM\u00e9xico, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":82771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[694],"tags":[],"class_list":["post-82770","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacadas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/82770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=82770"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/82770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/82771"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=82770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=82770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=82770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}