{"id":82708,"date":"2024-06-10T08:32:22","date_gmt":"2024-06-10T14:32:22","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=82708"},"modified":"2024-06-10T08:32:22","modified_gmt":"2024-06-10T14:32:22","slug":"los-capitales-la-desigualdad-lastre-para-un-crecimiento-sano-inclusivo-y-sostenible-lomeli","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-la-desigualdad-lastre-para-un-crecimiento-sano-inclusivo-y-sostenible-lomeli\/","title":{"rendered":"Los capitales | La desigualdad, lastre para un crecimiento sano, inclusivo y sostenible: Lomel\u00ed"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de junio, 2024.-El Rector de la UNAM, Leonardo Lomel\u00ed, se pronunci\u00f3 a favor de impulsar en M\u00e9xico un crecimiento m\u00e1s alto, inclusivo y sostenible, mismo que puede ayudar a reducir la desigualdad y aumentar la movilidad y cohesi\u00f3n social, pero -advirti\u00f3- debe ir de la mano de la ampliaci\u00f3n de la protecci\u00f3n social y el Estado de bienestar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior se dijo en el marco del anunci\u00f3 de la creaci\u00f3n de la c\u00e1tedra Maestro Ricardo Torres Gait\u00e1n 2024, misma que estar\u00e1 a cargo de Jos\u00e9 Manuel Salazar-Xirinachs, Secretario Ejecutivo de la Comisi\u00f3n Econ\u00f3mica para Am\u00e9rica Latina y el Caribe (CEPAL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa Universidad Nacional Aut\u00f3noma de M\u00e9xico, mediante esta C\u00e1tedra, reconoce no solo su amplia experiencia e intachable trayectoria, sino tambi\u00e9n su profunda vinculaci\u00f3n con los valores que defiende nuestra misi\u00f3n educativa en la Universidad. De igual manera, la UNAM agradece su incesante dedicaci\u00f3n a la formaci\u00f3n de recursos humanos de excelencia, su defensa de la igualdad social, y su constante b\u00fasqueda de soluciones innovadoras y con un alto rigor acad\u00e9mico para los desaf\u00edos contempor\u00e1neos\u201d, dijo el Rector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, el director del Instituto de Investigaciones Econ\u00f3micas (IIEc) de la UNAM, Armando S\u00e1nchez Vargas, dijo que el comit\u00e9 t\u00e9cnico decidi\u00f3 en forma un\u00e1nime que la C\u00e1tedra se otorgara a Salazar-Xirinachs por sus notables m\u00e9ritos y destacada trayectoria en el estudio y aplicaci\u00f3n de pol\u00edticas de desarrollo, comercio, transformaci\u00f3n productiva, competitividad y empleo. Por su parte, Lorena Rodr\u00edguez Le\u00f3n, directora de la Facultad de Econom\u00eda de la UNAM, reconoci\u00f3 la trayectoria acad\u00e9mica y profesional del Secretario Ejecutivo de la CEPAL. En la ceremonia tambi\u00e9n hizo uso de la palabra Silvia Hern\u00e1ndez, Jefa de Gabinete de la Oficina del Secretario Ejecutivo de la CEPAL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Analistas de Banorte esperan un incremento en el sector industrial<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos -dijeron- un incremento de 0.1%, con el dato sesgado al alza por las distorsiones de la Semana Santa. Con ello, la producci\u00f3n hilar\u00eda dos meses de avances. El impulso provendr\u00eda de la construcci\u00f3n (1.1%), con los datos oportunos de empleo en el sector mostrando una expansi\u00f3n sustancial en el n\u00famero de plazas. La miner\u00eda continuar\u00eda su racha de debilidad (-0.8%), esperando un retroceso en el rubro petrolero por octavo mes al hilo. Finalmente, las manufacturas caer\u00edan 0.5%, enfrentando un efecto de base retador tras incrementos secuenciales relevantes en meses previos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El panorama para las manufacturas es relativamente m\u00e1s positivo en el corto plazo. Creemos que este componente mantendr\u00e1 una tendencia positiva, aunque con un comportamiento heterog\u00e9neo al interior. De manera general, los problemas en las cadenas de suministro parecen seguir mejorando, situaci\u00f3n que se ha reflejado en el \u00cdndice Global de Presiones en las Cadenas de Suministro del Fed de Nueva York, alcanzando su nivel m\u00e1s bajo desde mediados del a\u00f1o pasado. No obstante, algunos rubros con una mayor exposici\u00f3n al sector industrial de EU podr\u00edan ser m\u00e1s laterales ante se\u00f1ales de relativa aton\u00eda desde el exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, aquellos con una mayor dependencia a la demanda local podr\u00edan mantener una mayor resiliencia \u2013sin descartar una moderaci\u00f3n en el 3T24, en l\u00ednea con nuestra expectativa para la econom\u00eda en general. Sin embargo, el sector automotriz podr\u00eda mantenerse muy fuerte debido a determinantes claramente positivos. Los datos m\u00e1s oportunos \u2013a mayo\u2013 muestran avances secuenciales tanto en la producci\u00f3n (1.5% m\/m) como en las exportaciones (5.0%) de veh\u00edculos ligeros. Debemos recordar que dicho componente representa alrededor de 23% de la producci\u00f3n manufacturera \u2013y casi 4.5% del PIB nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una realidad, las inversiones que llegan al pa\u00eds como parte del nearshoring<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichas inversiones est\u00e1n m\u00e1s que evidenciadas, principalmente, por resultados muy positivos en la Inversi\u00f3n Extranjera Directa. El reporte del 1T24 de la Secretar\u00eda de Econom\u00eda (SE) mostr\u00f3 una llegada de US$20.3 mil millones, con el 42% destinado a las manufacturas (ver gr\u00e1fica abajo, derecha).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, la inversi\u00f3n y los anuncios han estado concentrados en el rubro automotriz. Considerando esto, la propia SE ha enfocado esfuerzos en el rubro, destacando que llevar\u00e1 a cabo una feria de proveedores del sector a mediados de junio (10 al 13) en Saltillo, Coahuila. Es relevante mencionar que algunas de las inversiones realizadas en meses y a\u00f1os previos ya se est\u00e1n materializando. Un ejemplo es la planta de Bendix en Saltillo que abri\u00f3 a finales de mayo y estar\u00e1 dedicada a la fabricaci\u00f3n de frenos y sistemas de aire comprimido. Otro es la f\u00e1brica de Siete Leguas Automotive en Durango, donde los productos estar\u00e1n orientados a la fase Tier 2 del proceso de producci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, persisten ciertos riesgos. Sobre esto, la Industria Nacional de Autopartes (INA) afirma que uno de los retos actuales son los costos y tiempos en las aduanas. Han mencionado que una iniciativa puntual es la creaci\u00f3n de un despacho aduanero conjunto con EU (que ayude al cumplimiento de procesos como \u2018just in time\u2019 y \u2018just in sequence\u2019). De acuerdo con su director general, Armando Cort\u00e9s, \u201c\u2026la idea es anticiparnos a este crecimiento que vemos con el nearshoring. Los flujos comerciales con EU van a incrementarse de manera importante y no tenemos que esperar a que se desencadenen problemas derivados del crecimiento en la producci\u00f3n\u2026\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SAT y ANAM facilitan transporte de mercanc\u00edas en el Istmo de Tehuantepec<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Servicio de Administraci\u00f3n Tributaria (SAT) y la Agencia Nacional de Aduanas de M\u00e9xico (ANAM) informan sobre las nuevas facilidades para transportar mercanc\u00edas v\u00eda terrestre y ferroviaria a trav\u00e9s del Corredor Interoce\u00e1nico del Istmo de Tehuantepec (CIIT), con el fin de mejorar la eficiencia y coadyuvar en posicionar esta ruta como punto clave de la log\u00edstica comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, se dio a conocer en la Primera Resoluci\u00f3n de Modificaciones a las Reglas Generales de Comercio Exterior para 2024, publicada en el Diario Oficial de la Federaci\u00f3n, que adiciona la regla 4.6.28. \u201cTr\u00e1nsito internacional de mercanc\u00edas por el Corredor Interoce\u00e1nico del Istmo de Tehuantepec entre las aduanas de Salina Cruz y Coatzacoalcos y viceversa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.agendadeinversiones.com.mx\/\">www.agendadeinversiones.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @Edgar4712<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez&nbsp; SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de junio, 2024.-El Rector de la UNAM, Leonardo Lomel\u00ed, se pronunci\u00f3 a favor de impulsar en M\u00e9xico un crecimiento m\u00e1s alto, inclusivo y sostenible, mismo que puede ayudar a reducir la desigualdad y aumentar la movilidad y cohesi\u00f3n social, pero -advirti\u00f3- debe ir de la mano de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[750,35],"tags":[],"class_list":["post-82708","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/82708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=82708"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/82708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=82708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=82708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=82708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}