{"id":81260,"date":"2024-05-10T14:03:35","date_gmt":"2024-05-10T20:03:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=81260"},"modified":"2024-05-10T14:03:35","modified_gmt":"2024-05-10T20:03:35","slug":"tras-la-puerta-del-poder-taddei-presidenta-chaira-del-ine-amenaza-con-tarjeta-roja-a-xochitl","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-taddei-presidenta-chaira-del-ine-amenaza-con-tarjeta-roja-a-xochitl\/","title":{"rendered":"Tras la puerta del poder | Taddei, presidenta\u00a0chaira\u00a0del INE, amenaza con tarjeta roja a X\u00f3chitl"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Roberto Vizca\u00edno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de mayo, 2024.- El terror de&nbsp;<strong>AMLO<\/strong>&nbsp;a ver tomado el Z\u00f3calo por una&nbsp;<strong><em>marea rosa<\/em><\/strong>&nbsp;encabezada por&nbsp;<strong>X\u00f3chitl G\u00e1lvez<\/strong>, ya se traslad\u00f3 al INE donde su presidenta&nbsp;<em>chaira&nbsp;<\/em>Guadalupe Taddei ya amenaz\u00f3 con aplicarle el costo del evento a los gastos de campa\u00f1a de la candidata presidencial de la oposici\u00f3n como lo reclama el oficialismo para intimidar a la hidalguense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso es que la concentraci\u00f3n del 19 de este mayo fue convocada por las agrupaciones civiles que ya hicieron anteriormente las 2 marchas y tomas del Z\u00f3calo -y otras muchas plazas de unas 100 ciudades m\u00e1s- y&nbsp;<strong>X\u00f3chitl G\u00e1lvez<\/strong>&nbsp;s\u00f3lo acudir\u00e1 como invitada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento no fue ni organizado por ella o su equipo de campa\u00f1a, ni estaba agendado en sus eventos de proselitismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero&nbsp;<strong>Taddei<\/strong>&nbsp;se alineo de inmediato al oficialismo y sali\u00f3 ayer a decir que si acude, entonces \u201cel INE lo juzgar\u00e1 como gasto proselitista\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ello, la sonorense&nbsp;<strong>Taddei<\/strong>&nbsp;-quien carga con una fuerte percepci\u00f3n ciudadana de sometimiento al&nbsp;<strong>lopezobradorismo<\/strong>&nbsp;debido a su afinidad ideol\u00f3gica con esa corriente y a que una veintena de sus familiares y parientes directos colaboran con Morena o la 4T-, reaccion\u00f3 casi autom\u00e1ticamente, sin siquiera otra consideraci\u00f3n, dentro de la l\u00ednea marcada por&nbsp;<strong>AMLO<\/strong>&nbsp;en su ma\u00f1anera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta l\u00ednea&nbsp;<strong>AMLO<\/strong>&nbsp;afirm\u00f3 que con el anuncio de la asistencia de&nbsp;<strong>G\u00e1lvez<\/strong>&nbsp;a la&nbsp;<strong><em>marea rosa<\/em><\/strong>&nbsp;del domingo 19 se confirmaba que todo este movimiento y sus marchas anteriores siempre estuvieron encubriendo su apoyo electoral a&nbsp;<strong>X\u00f3chitl<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo este principio y suspicacias, entonces el INE y&nbsp;<strong>Taddei<\/strong>&nbsp;deber\u00edan considerar actos de campa\u00f1a la Convenci\u00f3n Nacional Bancaria de Acapulco, a donde la candidata presidencial de la oposici\u00f3n fue invitada, al igual que&nbsp;<strong>Claudia Sheinbaum<\/strong>&nbsp;y el in\u00fatil de MC,&nbsp;<strong>M\u00e1ynez<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O las reuniones de ejecutivos de BBVA Bancomer, o de Banamex, o de las 18 universidades a que ha sido convocada, o del Episcopado Mexicano, donde ha hablado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O los encuentros en las organizaciones de arquitectos, ingenieros, m\u00e9dicos, campesinos, agricultores, aguacateros y otras decenas m\u00e1s de eventos en que ha sido invitada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es obvio que ni&nbsp;<strong>AMLO<\/strong>, ni&nbsp;<strong>Claudia Sheinbaum<\/strong>, ni&nbsp;<strong>Mario Delgado<\/strong>&nbsp;gerente de Morena, ni&nbsp;<strong>Taddei&nbsp;<\/strong>ahora, la quieren ver estar en el Z\u00f3calo de la CDMX ante cientos de miles de ciudadanos que l\u00edcitamente le quieren dar su apoyo, porque ello dejar\u00e1 la impresi\u00f3n de que tiene ya una base social que supera a la de la candidata del oficialismo y, que ya rebas\u00f3 en popularidad al mismo&nbsp;<strong>L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estar\u00eda retando de hecho a tener que realizar una concentraci\u00f3n similar o mayor de desagravio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEs un evento&nbsp;<strong>de ella<\/strong>. Es la candidata y&nbsp;<strong>tiene que tomar una decisi\u00f3n sobre c\u00f3mo trabaja sus eventos masivos<\/strong>\u00ab, sentenci\u00f3 la presidenta del INE en un acto abiertamente intimidatorio, con la tarjeta roja de expulsi\u00f3n casi en la mano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEntonces la fiscalizar\u00e1n?, se le pregunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u2026 nosotros trabajamos sobre la agenda presentada por las candidaturas\u00bb, respondi\u00f3 la consejera sonorense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cElla tiene que tomar una decisi\u00f3n con su equipo de campa\u00f1a, lo que les corresponde o no les corresponde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo es un tema que le corresponda al INE, es un tema que le corresponde a sus equipos, es un tema de ellos. Por lo tanto, entra en todos los eventos que se presentan (los candidatos) en el instituto\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falta sin embargo que os otros consejeros electorales se pronuncien y den su punto de vista respecto de este asunto. Porque -hay que recordarlo- a pesar de su evidente y no pocas veces obsceno&nbsp;<strong><em>chairismo<\/em><\/strong>,&nbsp;<strong>Taddei<\/strong>&nbsp;no se manda sola ni es voz \u00fanica en el INE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RIVERA, TRAS LOS ACUERDOS Y LOS EQUILIBRIOS EN EL SENADO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el contexto mexicano actual habr\u00eda que recordar que hoy, cuando la Presidencia de M\u00e9xico es fuertemente buscada por dos mujeres &#8211;<strong>Claudia Sheinbaum<\/strong>, por Morena y la 4T y por&nbsp;<strong>X\u00f3chitl G\u00e1lvez<\/strong>, la candidata de la oposici\u00f3n en una in\u00e9dita alianza PRI, PAN, PRD y organizaciones de la sociedad civil-, los poderes esenciales del Estado -salvo la del Presidente- son ocupados por mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca antes hab\u00eda ocurrido tal convergencia. Y hoy la presidencia del poder Judicial lo ocupa la ministra&nbsp;<strong>Norma Pi\u00f1a<\/strong>&nbsp;y el del Legislativo las presidentas del Senado,&nbsp;<strong>Ana Lilia Rivera<\/strong>&nbsp;y en la de Diputados la neolonesa&nbsp;<strong>Marcela Guerra<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos instituciones esenciales en este momento son las presidencias del INE, ocupada por&nbsp;<strong>Guadalupe Taddei<\/strong>&nbsp;y la del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, por la magistrada&nbsp;<strong>M\u00f3nica Soto<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No incluyo a la secretaria de Gobernaci\u00f3n&nbsp;<strong>Luisa Mar\u00eda Alcalde<\/strong>, otra mujer, por considerar que es pr\u00e1cticamente&nbsp;<em>un florero<\/em>. Un adorno dentro del equipo de YSQ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el grupo de poder real,&nbsp;<strong>Ana Lilia Rivera<\/strong>&nbsp;y&nbsp;<strong>Marcela Guerra<\/strong>&nbsp;buscan cada una su reelecci\u00f3n, como senadora por Morena la primera y como diputada por el PRI, la segunda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambas se han ganado el respeto de sus respectivas c\u00e1maras porque han realizado un trabajo equilibrado en la conducci\u00f3n de las tareas legislativas y la realizaci\u00f3n de los Plenos que no pocas veces suben de tono y que llegan casi a la confrontaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta tarea la tlaxcalteca Rivera, considera que todo para ella se basa en regular las intervenciones en la Tribuna para que todos los asuntos fluyan dentro del reglamento y la civilidad pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, a pesar de su afiliaci\u00f3n dentro de Morena, permite que participen todos los senadores y senadoras que deseen; con respeto al tiempo a que tienen derecho todas y todos los oradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ning\u00fan momento se ha limitado la participaci\u00f3n o se ha privilegiado a alg\u00fan Grupo Parlamentario, ya que se aplica la regla por igual para todas y todos; al igual que se les concede la palabra a quienes lo soliciten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tipo de medidas permiten una sana convivencia, tan necesaria en cualquier Asamblea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo no act\u00fao de manera arbitraria\u201d, subraya para avalar con sus hechos su reelecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026&nbsp;\/ Twitter: @_Vizcaino \/ Facebook<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Roberto Vizca\u00edno SemM\u00e9xico, Ciudad de M\u00e9xico, 10 de mayo, 2024.- El terror de&nbsp;AMLO&nbsp;a ver tomado el Z\u00f3calo por una&nbsp;marea rosa&nbsp;encabezada por&nbsp;X\u00f3chitl G\u00e1lvez, ya se traslad\u00f3 al INE donde su presidenta&nbsp;chaira&nbsp;Guadalupe Taddei ya amenaz\u00f3 con aplicarle el costo del evento a los gastos de campa\u00f1a de la candidata presidencial de la oposici\u00f3n como lo reclama el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-81260","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/81260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=81260"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/81260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=81260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=81260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=81260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}