{"id":81100,"date":"2024-05-07T07:22:13","date_gmt":"2024-05-07T13:22:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=81100"},"modified":"2024-05-07T07:22:54","modified_gmt":"2024-05-07T13:22:54","slug":"los-capitales-estable-la-deuda-soberana-de-mexico-hr-ratings","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/los-capitales-estable-la-deuda-soberana-de-mexico-hr-ratings\/","title":{"rendered":"Los capitales | \u201cEstable,\u201d la deuda soberana de M\u00e9xico: HR Ratings"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edgar Gonz\u00e1lez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 7 de mayo, 2024.- La deuda soberana de M\u00e9xico est\u00e1 dentro de los par\u00e1metros internacionales, y agencias especializadas como HR Ratings la consideran con \u201cperspectiva estable\u201d. Los analistas de esta calificadora se\u00f1alan que la ratificaci\u00f3n, en buena parte, es el resultado del desempe\u00f1o de la m\u00e9trica de deuda neta como porcentaje del PIB. Por ejemplo, el Saldo Hist\u00f3rico (SH) de los requerimientos financieros del sector p\u00fablico se ubic\u00f3 en 46.8%, porcentaje por debajo de la estimaci\u00f3n de 50.3% que anticipamos en la revisi\u00f3n anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto, el\u00a0resultado de 2023 estuvo apoyado por la apreciaci\u00f3n del tipo de cambio peso-d\u00f3lar (MXN-USD), que ayud\u00f3 a mitigar la tendencia m\u00e1s deficitaria de los principales balances financieros, as\u00ed como por la din\u00e1mica positiva de la actividad econ\u00f3mica, que permiti\u00f3 que la posici\u00f3n relativa del SH se situara en su menor nivel en los \u00faltimos tres a\u00f1os. Si bien para 2024 anticipamos que el SH registrar\u00e1 un alza como consecuencia de los mayores d\u00e9ficits fiscales aprobados en la LIF (Ley de Ingresos de la Federaci\u00f3n) y el PEF (Presupuesto de Egresos de la Federaci\u00f3n), sumado a una probable depreciaci\u00f3n del peso al cierre del a\u00f1o, HR Ratings<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">contempla que a partir de 2025 se observar\u00e1 una consolidaci\u00f3n fiscal en torno a los niveles de ingresos y gastos, lo que permitir\u00eda mantener una trayectoria relativamente estable en el avance del SH; con esto, los niveles de d\u00e9ficits reflejar\u00edan una trayectoria descendente en el mediano y largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suponemos que una parte importante del aumento en el gasto en 2024 se deriva de la terminaci\u00f3n de importantes proyectos de inversi\u00f3n, que en los pr\u00f3ximos a\u00f1os impulsar\u00e1n a la econom\u00eda. La resiliencia de la actividad econ\u00f3mica sorprendi\u00f3 en 2023 tras registrar un crecimiento de 3.20%, un resultado que representa m\u00e1s del doble de lo que hab\u00edamos anticipado en nuestro reporte de calificaci\u00f3n previo. Este crecimiento estuvo impulsado por el dinamismo de la demanda interna, especialmente a trav\u00e9s de la inversi\u00f3n p\u00fablica y privada, y adem\u00e1s por el consumo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El crecimiento econ\u00f3mico tambi\u00e9n estuvo acompa\u00f1ado de un s\u00f3lido mercado laboral que mantuvo la tasa de desempleo en niveles m\u00ednimos y con ganancias reales en los salarios a lo largo de 2023. La desaceleraci\u00f3n de la inflaci\u00f3n desde los m\u00e1ximos alcanzados en agosto de 2022 tambi\u00e9n contribuy\u00f3 al optimismo de los consumidores. En 2023, la inflaci\u00f3n general cerr\u00f3 el a\u00f1o en 4.66%, y aunque todav\u00eda se ubic\u00f3 por encima del rango objetivo del Banco de M\u00e9xico de 3.0% (+\/- 1.0%), estuvo por debajo del 5.20% que estimamos en el reporte anterior, lo que a su vez representa un descenso significativo desde el m\u00e1ximo nivel alcanzado en 2022 (8.70%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fortaleza institucional que ha mostrado el Banco Central y su compromiso por combatir la inflaci\u00f3n es uno de los factores que consideramos mantienen ancladas las expectativas de inflaci\u00f3n en el largo plazo. Consideramos que esta fortaleza ayud\u00f3 a la evoluci\u00f3n del tipo de cambio, el cual cerr\u00f3 el a\u00f1o en P$16.92\/USD. vs. su cierre en 2022 (P$19.41\/USD) y estuvo por debajo de nuestra expectativa de que cerrar\u00eda en P$19.10\/USD. Este movimiento permiti\u00f3 la consolidaci\u00f3n de la deuda denominada en moneda extranjera1, que representa el 23.9% del SH al cierre de 2023, mientras que la deuda interna alcanz\u00f3 76.1%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, entre los principales retos que estaremos monitoreando en el corto plazo est\u00e1n aquellos relacionados con la contenci\u00f3n del d\u00e9ficit dentro del l\u00edmite propuesto en los Pre-Criterios Generales de Pol\u00edtica Econ\u00f3mica (PreCGPE) de 2025; tambi\u00e9n estaremos atentos a la publicaci\u00f3n del Plan Nacional de Desarrollo para los pr\u00f3ximos seis a\u00f1os, el cual brindar\u00e1 una mejor perspectiva sobre la trayectoria del presupuesto en el mediano y largo plazo, as\u00ed como las decisiones de pol\u00edtica p\u00fablica respecto a la deuda de Pemex. Adicionalmente, consideramos que tanto la convergencia de la inflaci\u00f3n hacia la meta de 3.0% como el comportamiento del tipo de cambio continuar\u00e1n siendo algunos de los principales retos del entorno macroecon\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Demandan firmas de abogados mayor participaci\u00f3n de la mujer en el ejercicio del derecho.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La firma Santamarina y Steta&nbsp;analiz\u00f3 los avances y retrasos de las mujeres en el \u00e1mbito legal y en el ejercicio del derecho en M\u00e9xico, y destac\u00f3:&nbsp;<em>\u201cla apertura de espacios en despachos, departamentos legales de las empresas, el poder judicial y la academia es un hecho, pero falta una plataforma y comunidad de apoyo para que aumente el n\u00famero de mujeres en la pr\u00e1ctica\u201d<\/em>, dijeron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1ngela \u00c1lvarez, directora de la firma, se\u00f1al\u00f3 que el reto m\u00e1s grande para las mujeres en el ejercicio del derecho consiste en poder balancear la vida de mam\u00e1 y de ejecutiva.&nbsp;\u201cEs doloroso, dejar al ni\u00f1o con temperatura, para ir a la oficina a tomar decisiones y poderse concentrar. Ante eso, es muy importante creernos con el mismo nivel o incluso mayor que el de los hombres, que pueden desconectarse del hogar. En muchos casos, ellos lo pueden hacer porque tienen a una mujer en casa. Nosotras tambi\u00e9n necesitamos una mancuerna en la oficina, para nuestro desarrollo profesional y familiar. Siempre cargamos con la duda de si estamos siendo buenas mam\u00e1s, al mismo tiempo de si estamos siendo buenas ejecutivas\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ejecutivas consideraron que la cuota de g\u00e9nero es un mecanismo de transici\u00f3n que otorga la oportunidad a las profesionistas para pasar de ser mujeres de cuota a mujeres de m\u00e9rito.&nbsp;<em>\u201cY eso nadie lo desaprovecha. Las mujeres que llegan as\u00ed, se encargan de demostrar que tienen la capacidad. Lo asumen como un reto. Nadie quiere ser se\u00f1alada como mujer de cuota. Sin embargo, el mecanismo est\u00e1 sirviendo para que los prejuicios de g\u00e9nero se vayan derrumbando\u201d,<\/em>&nbsp;concluyeron.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:loscapitales@yahoo.com.mx\">loscapitales@yahoo.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.agendadeinversiones.com.mx\/\">www.agendadeinversiones.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twiter: @Edgar4712<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edgar Gonz\u00e1lez Mart\u00ednez SemM\u00e9xico, Ciudad de M\u00e9xico, 7 de mayo, 2024.- La deuda soberana de M\u00e9xico est\u00e1 dentro de los par\u00e1metros internacionales, y agencias especializadas como HR Ratings la consideran con \u201cperspectiva estable\u201d. Los analistas de esta calificadora se\u00f1alan que la ratificaci\u00f3n, en buena parte, es el resultado del desempe\u00f1o de la m\u00e9trica de deuda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[750,35],"tags":[],"class_list":["post-81100","post","type-post","status-publish","format-standard","has-post-thumbnail","category-edgar-gonzalez-martinez","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/81100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=81100"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/81100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/75979"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=81100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=81100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=81100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}