{"id":79048,"date":"2024-03-19T08:30:17","date_gmt":"2024-03-19T14:30:17","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=79048"},"modified":"2024-03-19T08:30:18","modified_gmt":"2024-03-19T14:30:18","slug":"cuba-emprender-siendo-mama-vencer-desafios","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cuba-emprender-siendo-mama-vencer-desafios\/","title":{"rendered":"Cuba: Emprender siendo mam\u00e1, vencer desaf\u00edos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Foto: Semlac\/Cuba<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Lisandra Fari\u00f1as*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/SemLac, La Habana, Cuba, 19 de marzo 2024.- Impulsar sus emprendimientos a la par que la maternidad, escucharse, apoyarse y tambi\u00e9n articularse en redes que les permitieran sortear obst\u00e1culos en ambas esferas de la vida fueron prop\u00f3sitos de un espacio de reflexi\u00f3n que reuni\u00f3 a una veintena de mujeres bajo el t\u00edtulo \u00abEmprender siendo mam\u00e1\u00bb.<br>El encuentro sirvi\u00f3 para hablar sobre experiencias diversas y desaf\u00edos que van, desde la gesti\u00f3n del tiempo hasta el autocuidado, la delegaci\u00f3n de tareas y la necesidad de promover espacios amigables con la infancia, donde las mujeres puedan participar sin que la presencia de hijas e hijos sea un impedimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEmprender siendo mam\u00e1\u00bb surge como una necesidad personal de contar con un espacio donde madres emprendedoras encuentren reflejadas sus realidades y vida cotidiana, explic\u00f3 Zailin P\u00e9rez Zald\u00edvar, l\u00edder del proyeto \u201cLos colores de Isa\u201d\u00bb, quien convoc\u00f3 a la cita el 6 de marzo, en la Casa de Orientaci\u00f3n a la Mujer y la Familia del municipio de Plaza de la Revoluci\u00f3n, en La Habana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuer\u00edamos vernos porque no estamos solas en nuestras luchas diarias; otras mujeres enfrentan desaf\u00edos similares y encuentran soluciones\u00bb, dijo a SEMlac en referencia a situaciones que suponen lidiar con el estr\u00e9s de la vida diaria, el trabajo, las responsabilidades laborales y la crianza de hijos e hijas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPese a nuestras diferencias, compartimos problemas similares y necesitamos conocer c\u00f3mo otras mujeres logran sobresalir, por encima de necesidades, carencias y desaf\u00edos\u00bb, dijo al t\u00e9rmino del encuentro, del cual salieron ya conectadas en un grupo de WhatsApp y con la aspiraci\u00f3n de reencontrase cada tres meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl enfoque principal fue el autocuidado y la necesidad de priorizarnos nosotras mismas, evitando castigarnos y culparnos excesivamente; adem\u00e1s de aprender a gestionar nuestros tiempos\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br><strong><em>Ellas cuentan sus vivencias<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varias emprendedoras reconocieron que es posible equilibrar la maternidad y los negocios, pero \u00abse necesita de un entorno m\u00e1s amigable para quienes emprenden y cuidan de sus hijos\u00bb, apunt\u00f3 P\u00e9rez Sald\u00edvar.<br>Yadira Rachel Vargas Orta, l\u00edder de Rizo Libre, asegura que ha encontrado la felicidad y el equilibrio al emprender mientras cuida de sus dos hijas, Melisa y Luc\u00eda. \u00abSer madre de mis dos ni\u00f1as es mi primer proyecto de vida\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDurante mi segundo embarazo logr\u00e9 terminar mi Maestr\u00eda en Conservaci\u00f3n. Decid\u00ed emprender cuando mi hija Luc\u00eda ten\u00eda apenas un mes de nacida y Melisa, un a\u00f1o. Aunque fue dif\u00edcil sin una gran red de apoyo, encontr\u00e9 mi tiempo, estabilidad y felicidad.<br>\u00abRizo Libre es un proyecto cultural y educativo que se centra en la afroest\u00e9tica. Desde all\u00ed he creado el\u00a0primer libro infantil cubano y una colecci\u00f3n de materiales did\u00e1cticos con esta tem\u00e1tica. Rizo Libre es mi filosof\u00eda de vida y lo aplico como m\u00e9todo de ense\u00f1anza, buscando un mundo sin prejuicios para mis hijas\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detr\u00e1s de cada emprendedora \u00abhay una ama de casa, trabajadora, cuidadora, pero no por eso hay que renunciar a ser una mujer con sue\u00f1os\u00bb, dijo Jennifer Mili\u00e1n Duany, l\u00edder de Universa, quien encontr\u00f3 en la bisuter\u00eda una forma de expresar su creatividad en los d\u00edas del confinamiento por la pandemia de covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ella coincide Madelaine Rodr\u00edguez Rojo, l\u00edder de Decoluz, quien comenz\u00f3 a crear l\u00e1mparas artesanales con tuber\u00edas de PVC en 2019. En su opini\u00f3n, esos sue\u00f1os tambi\u00e9n se logran si existen redes de apoyo entre las mujeres. Mediante Decoluz conoci\u00f3 a otras emprendedoras y juntas formaron el bazar Artesan\u00edas y Man\u00edas, que funciona asociado al Centro Loyola Reina, de filiaci\u00f3n religiosa, que realiza trabajo socio educativo en el municipio de Centro Habana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente explora nuevos caminos y coordina el proyecto InCubaEmpresas, del propio centro, que apoya otros emprendimientos. \u00abDecoLuz me salv\u00f3 de muchas cosas y me permiti\u00f3 volcar mi creatividad. Ahora me siento motivada trabajando en equipo para ayudar a quienes deciden emprender\u00bb, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yoana Hidalgo Parra, fundadora de Giulia Lazos, descubri\u00f3 su pasi\u00f3n por las manualidades al crear adornos para el cabello de su hija Yuliana. \u00abAunque requiere esfuerzo y tiempo, decid\u00ed seguir mi pasi\u00f3n. Pero reconozco que es un ritmo acelerado entre el trabajo y el hogar, que supone muchas veces cargas extras\u00bb.<br>Yainiris D\u00edaz, quien cre\u00f3 en 2020 SugieroCuba, para visibilizar el trabajo emergente en el pa\u00eds, estim\u00f3 que ser madre tambi\u00e9n es un emprendimiento y refiri\u00f3 que los tiempos con los ni\u00f1os y para una misma son fundamentales. \u00abHay que saber gestionarlos y autocuidarnos\u00bb, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUno de los mayores retos es equilibrar el tiempo dedicado a mi hijo y al emprendimiento; a veces es un conflicto que requiere tomar decisiones y priorizar\u00bb, apunt\u00f3 Liudmila Pe\u00f1a Herrera, de Elecreativa, dedicado a la producci\u00f3n audiovisual con un enfoque en los emprendimientos de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte,\u00a0Sara Hern\u00e1ndez, impulsora de Yo puedo emprender, vinculado a la Casa de Orientaci\u00f3n a la Mujer y la Familia, sostiene que emprender es un desaf\u00edo que las mujeres abordan enfrentando obst\u00e1culos adicionales, debido al patriarcado.<br>\u00abSer madre y emprendedora agrega una complejidad adicional\u00bb, sostuvo Hern\u00e1ndez, quien comparti\u00f3 sobre la ayuda que recibi\u00f3 de la Federaci\u00f3n de Mujeres Cubanas en momentos muy dif\u00edciles para ella, cuando m\u00e1s lo necesitaba. Ahora, mediante su proyecto, brinda apoyo y gu\u00eda a mujeres que desean emprender.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:lisycolor5@gmail.com\"><em>lisycolor5@gmail.com<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Semlac\/Cuba Lisandra Fari\u00f1as* SemM\u00e9xico\/SemLac, La Habana, Cuba, 19 de marzo 2024.- Impulsar sus emprendimientos a la par que la maternidad, escucharse, apoyarse y tambi\u00e9n articularse en redes que les permitieran sortear obst\u00e1culos en ambas esferas de la vida fueron prop\u00f3sitos de un espacio de reflexi\u00f3n que reuni\u00f3 a una veintena de mujeres bajo el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":79049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[53],"tags":[522,368,600],"class_list":["post-79048","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional","tag-cuba","tag-madres","tag-semlac"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/79048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=79048"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/79048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/79049"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=79048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=79048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=79048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}