{"id":78223,"date":"2024-03-06T10:00:15","date_gmt":"2024-03-06T16:00:15","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=78223"},"modified":"2024-03-06T10:00:16","modified_gmt":"2024-03-06T16:00:16","slug":"tras-la-puerta-del-poder-claudia-y-xochitl-chocan-con-sus-respectivos-programas-de-seguridad","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-claudia-y-xochitl-chocan-con-sus-respectivos-programas-de-seguridad\/","title":{"rendered":"Tras la puerta del poder| Claudia y X\u00f3chitl chocan con sus respectivos programas de seguridad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Roberto Vizca\u00edno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 6 de marzo, 2024.- En abierta defensa de la pol\u00edtica de seguridad de Abrazos no balazos de AMLO, que ella ha prometido continuar,&nbsp;<strong>Claudia Sheinbaum<\/strong>&nbsp;acus\u00f3 ayer a&nbsp;<strong>X\u00f3chitl G\u00e1lvez<\/strong>&nbsp;de proponer la guerra mientras ella busca la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Le\u00f3n, Guanajuato, la candidata presidencial del oficialismo indic\u00f3 que mientras ella propone al igual que el presidente&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>&nbsp;atender las causas de la inseguridad y la violencia la opositora G\u00e1lvez quiere megac\u00e1rceles y aplicar mano dura a delincuentes y narcos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSon dos proyectos contrapuestos lo que se va definir el pr\u00f3ximo 2 de junio. Un proyecto que es regresar al pasado, pasado de corrupci\u00f3n, ya escuchamos que tiene que ver con mano dura, con megac\u00e1rceles, con guerra, y nosotros lo que proponemos es construir la paz atendiendo las causas\u00bb, indic\u00f3 Sheinbaum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>X\u00f3chitl G\u00e1lvez<\/strong>&nbsp;por su parte fue a Ecatepec, Estado de M\u00e9xico, uno de los poblados m\u00e1s violentos e inseguros del pa\u00eds donde se reuni\u00f3 con agrupaciones de la sociedad civil y en especial con transportistas a quienes dijo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYo, como Presidenta, me voy a hacer responsable de su seguridad\u00bb, al se\u00f1alar que ah\u00ed el gobierno de Morena y en especial la Guardia Nacional les ha \u00abquedado a deber\u00bb a los mexicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La candidata presidencial de la oposici\u00f3n escuch\u00f3 el relato interminable de tropel\u00edas y desgobierno que prevalece en este municipio donde el pago de piso se aplica hasta a chicleros y boleros, y donde choferes de transporte p\u00fablico son secuestrados y ejecutados sin m\u00e1s dentro de la disputa de grupos delincuenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEs la anarqu\u00eda\u00bb, afirm\u00f3&nbsp;<strong>Miguel \u00c1ngel Rodr\u00edguez Zamudio<\/strong>, l\u00edder transportista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo hay mano dura para la delincuencia\u00bb, agreg\u00f3&nbsp;<strong>Iv\u00e1n Olgu\u00edn<\/strong>, de GP Cometa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ecatepec, gobernado por&nbsp;<strong>Luis Fernando Vilchis&nbsp;<\/strong>alcalde de Morena, adolece adem\u00e1s de otros graves problemas como el del agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante unos 250 simpatizantes y miembros del transporte p\u00fablico, X\u00f3chitl G\u00e1lvez les indic\u00f3 que con ella en Palacio Nacional, se notar\u00e1 la diferencia en la gesti\u00f3n de las pol\u00edticas de seguridad p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa se\u00f1ora de enfrente (<strong>Claudia Sheinbaum<\/strong>) oigan bien, dej\u00f3 el noventa y nueve por ciento de los delitos sin castigar en la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abY el treinta y seis por ciento de las defunciones no tienen causa. Cuando el promedio nacional es seis por ciento. Est\u00e1n escondiendo los muertos para decir que han bajado la inseguridad. Y eso no se vale. Eso es enga\u00f1ar a los mexicanos. T\u00e9nganos confianza, vamos a luchar\u00bb, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ya hay tiro<\/strong>. Ambas comenzaron as\u00ed a \u201cbajar\u201d a los ciudadanos sus respectivas propuestas de seguridad p\u00fablica con duras cr\u00edticas a las de la otra. Lo dem\u00e1s lo har\u00e1 la comunicaci\u00f3n de persona a persona. As\u00ed se hacen todas las campa\u00f1as aqu\u00ed y en China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mario Delgado pretende enga\u00f1ar a AMLO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicen los hechos que pretender hacerle chiles a Herdez es hacerle al T\u00edo Lolo. Es decir, hacerse pendejo solo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, eso es lo que anda haciendo ahora&nbsp;<strong>Mario Delgado<\/strong>, gerente en Morena, en busca de una&nbsp;<em>sobadita de lomo<\/em>&nbsp;por parte de su jefe m\u00e1ximo&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pleno inicio de la disputa por la presidencia de M\u00e9xico, el traicionero ex amigo de&nbsp;<strong>Marcelo Ebrard<\/strong>&nbsp;anuncio que buscar\u00e1 sentarse a hablar con los directivos de las redes sociales, en especial con el de X, para vere si los convence de que le entreguen el primer registro del mote de \u201c<strong><em>narcopresidente<\/em><\/strong>\u201d que se le aplic\u00f3 a&nbsp;<strong>AMLO<\/strong>&nbsp;en esas redes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Delgado<\/strong>&nbsp;quiere que el mandatario le aplauda su labor de&nbsp;<strong>Sherlock Holmes<\/strong>&nbsp;de Peralvillo a fin de dar con&nbsp;<strong><em>ese tal por cual<\/em><\/strong>&nbsp;que se le ocurri\u00f3 usar por primera vez el mote de \u201c<strong><em>narcopresidente<\/em><\/strong>\u201d con el que al parecer vivir\u00e1 el resto de su vida y morir\u00e1&nbsp;<strong>AMLO.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Delgado<\/strong>&nbsp;no ha dicho que har\u00eda en caso de encontrar al ingenioso y certero mexicano o extranjero que se le ocurri\u00f3 ese mote para aplic\u00e1rselo a&nbsp;<strong>L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfLo encadenar\u00eda y flagelar\u00eda en el Z\u00f3calo? \u00bfLo entregar\u00eda a una jaur\u00eda de rabiosos de&nbsp;<strong><em>chairos?<\/em><\/strong>&nbsp;\u00bfLo entregar\u00eda a un \u201c<strong><em>pozolero<\/em><\/strong>\u201d del narco, de esos que diluyen a sus v\u00edctimas en \u00e1cidos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfO de qu\u00e9 delito lo acusar\u00eda?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras ah\u00ed la lleva&nbsp;<strong>Delgado<\/strong>&nbsp;lami\u00e9ndole la herida a su jefe pol\u00edtico pa\u2019ver si le bajan los ardores y fuertes agruras que le causan cada que lee que sigue por millones en redes sociales el&nbsp;<strong><em>hashtag&nbsp;<\/em><\/strong>de<strong><em>&nbsp;narcopresidente.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Igualdad de ingresos, un derecho esencial<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El deporte es una actividad donde se confronta con mayor fuerza el reclamo de igualdad de g\u00e9nero. Y en este espacio el reclamo de la igualdad salarial es un tema que cobra cada vez mayor vigencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido&nbsp;<strong>Ana Lilia Rivera<\/strong>, presidenta del Senado mexicano, reconoci\u00f3 ayer -a unos d\u00edas de que se conmemore el D\u00eda Internacional de la Mujer-, que sus compa\u00f1eros de c\u00e1mara avancen en temas pendientes como las reformas a la Ley Federal del Trabajo que buscan cerrar la brecha salarial entre hombres y mujeres en el \u00e1mbito deportivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tlaxcalteca indic\u00f3 que como parte de los actos que el Senado llevar\u00e1 a cabo para celebrar este 8 de marzo, se abrir\u00e1 un espacio durante la sesi\u00f3n plenaria de hoy, a fin de hacer un recuento de los avances legislativos en la materia de los derechos de la mujer que se han registrado en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo se pondr\u00e1n a consideraci\u00f3n del Pleno del Senado diversos dict\u00e1menes en materia de igualdad, paridad y empoderamiento de las mujeres en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de las reformas a la Ley Federal del Trabajo, dijo, no hubo quien se opusiera al proyecto y s\u00f3lo hasta que se tocaron ciertos temas, se hicieron observaciones t\u00e9cnicas para empatar jur\u00eddicamente todo el andamiaje legal ya establecido, a fin de no crear excepciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a las declaraciones de algunos especialistas, que aseguran que no es igual el deporte femenil que el varonil, la presidenta del Senado indic\u00f3 que la obviedad indica que, a pesar de las diferencias biol\u00f3gicas, las mujeres y los hombres generan oportunidades que representan el mismo esfuerzo, por lo que no puede haber diferencias, ya que, en t\u00e9rminos de igualdad, eso es un mensaje de misoginia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026<a href=\"mailto:rvizcainoa@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">rvizcainoa@gmail.com<\/a>&nbsp;\/ Twitter: @_Vizcaino \/ Facebook<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En abierta defensa de la pol\u00edtica de seguridad de Abrazos no balazos de AMLO, que ella ha prometido continuar,\u00a0Claudia Sheinbaum\u00a0acus\u00f3 ayer a\u00a0X\u00f3chitl G\u00e1lvez\u00a0de proponer la guerra mientras ella busca la paz.<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[35,623,622],"tags":[],"class_list":["post-78223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/78223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=78223"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/78223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=78223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=78223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=78223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}