{"id":78045,"date":"2024-03-02T10:55:14","date_gmt":"2024-03-02T16:55:14","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=78045"},"modified":"2024-03-02T10:55:14","modified_gmt":"2024-03-02T16:55:14","slug":"mexico-ante-el-paradigma-de-un-gobierno-femenino-que-rompa-con-el-patriarcado-que-humilla-excluye-y-discrimina-ana-lilia-rivera-rivera","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mexico-ante-el-paradigma-de-un-gobierno-femenino-que-rompa-con-el-patriarcado-que-humilla-excluye-y-discrimina-ana-lilia-rivera-rivera\/","title":{"rendered":"M\u00e9xico ante el paradigma de un gobierno femenino que rompa con el patriarcado que humilla, excluye y discrimina: Ana Lilia Rivera Rivera\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Elda Montiel &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, &nbsp;1 de marzo, 2024.- Es momento de construir un nuevo paradigma de gobierno femenino, que rompa con la pol\u00edtica que hace da\u00f1o a la sociedad y que ejerce un poder que discrimina, que domina, humilla, excluye y genera diferencias afirm\u00f3 la legisladora Ana Lilia Rivera Rivera, presidenta de la Mesa Directiva del Senado de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el conversatorio \u201cOportunidades, desaf\u00edos y buenas pr\u00e1cticas parlamentarias para promover la participaci\u00f3n pol\u00edtica de las mujeres\u201d, la legisladora destac\u00f3 que M\u00e9xico tiene por primera vez la posibilidad de que una mujer sea presidenta lo que implica estar a prueba por el tipo de gobierno que se construir\u00e1 y que requiere un gran esfuerzo que permita a las mujeres construir su propia identidad en el ejercicio del poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante funcionarias y legisladoras de Honduras, Ana Lilia Rivera consider\u00f3 que se est\u00e1 ante una ruptura cultural importante, porque no basta llegar, sino mantenerse y lograr que los votos que se les den sean porque se ha convencido a las mayor\u00edas de que una mujer sabe gobernar muy bien, para todas y todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa clase pol\u00edtica que gobierna tiene que aprender a desprenderse de fueros y privilegios, y debe convertirse en un mexicano m\u00e1s, y aprender a ejercer la pol\u00edtica con \u00e9tica, moralidad, dignidad y decencia\u201d, manifest\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que las mujeres que ejercen el poder tienen la gran responsabilidad de convencer a los ciudadanos que s\u00ed conviene que los gobierne una mujer, \u201clo que implica mucho trabajo y una gran transformaci\u00f3n cultural\u201d, y tambi\u00e9n \u201cque corte de tajo el patriarcado que tanto hemos despreciado y combatido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfatiz\u00f3 que dicho paradigma se debe construir con base en una cultura de solidaridad y que genere alianzas verdaderas, pues es el momento para definir el tipo de gobierno que construir\u00e1n ellas, \u201ccon un enfoque que corte de tajo la manera en c\u00f3mo se ha ejercido el poder\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insisti\u00f3 que en M\u00e9xico se tiene la oportunidad de tener una presidenta, pero tambi\u00e9n de vivir un proceso de transformaci\u00f3n en el ejercicio del poder, m\u00e1s all\u00e1 del g\u00e9nero, pues se impulsa un modelo que combate la pol\u00edtica neoliberal implantada durante 36 a\u00f1os, lo que convoca a las fuerzas pol\u00edticas a renovarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de la Comisi\u00f3n para la Igualdad de G\u00e9nero, Martha Luc\u00eda Micher Camarena, destac\u00f3 que en el pa\u00eds existe paridad de g\u00e9nero en los cargos p\u00fablicos de toma de decisiones, gracias a la lucha de la izquierda por defender el derecho a la igualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que, se modificaron 11 art\u00edculos de la Constituci\u00f3n para establecer la paridad en los tres poderes de la Uni\u00f3n y los tres \u00f3rdenes de gobierno, a fin de que no se tratara de una cuota o por una resoluci\u00f3n de la Suprema Corte de Justicia de la Naci\u00f3n, sino que estuviera en la ley y los ordenamientos correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que, a partir de 2018, cuando se cambi\u00f3 a un nuevo r\u00e9gimen de gobierno los y las legisladoras de izquierda cumplieron su compromiso de trabajar para lograr la igualdad de los sectores de la poblaci\u00f3n m\u00e1s vulnerables, pero de manera especial, en materia de igualdad de las mujeres.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/03\/mexico-paradigma-02.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2024\/03\/mexico-paradigma-02-1024x683.jpg\" alt=\"\" class=\"wp-image-78047\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que la senadora&nbsp; morenista &nbsp;Freyda Marybel Villegas Canch\u00e9, hizo hincapi\u00e9 en ls reformas para que las mujeres tengan acceso a la justicia en casos de violencia pol\u00edtica, porque se debe garantizar que participen en los procesos electorales, sin sufrir violencia por razones de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Refiri\u00f3 tambi\u00e9n que se han aprobado marcos legales para que los hombres que hayan cometido violencia pol\u00edtica en contra de las mujeres se le suspendan sus derechos pol\u00edticos, adem\u00e1s de que, si tienen un juicio por violencia intrafamiliar o no paguen pensi\u00f3n alimenticia, queden inhabilitados para acceder a un cargo de elecci\u00f3n popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doris Guti\u00e9rrez, designada presidencial de Honduras, record\u00f3 que la titular del Poder Ejecutivo de su pa\u00eds, Xiomara Castro Sarmiento, gan\u00f3 con un mill\u00f3n 750 mil votos, lo cual no fue f\u00e1cil, pero afirm\u00f3 que continuar\u00e1n con su lucha para alcanzar la paridad en su pa\u00eds<strong><em>.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mujeres, continu\u00f3, tenemos que marcar la diferencia en todo, en transparencia, en compromisos con la gente, en el trato a todas las personas, estar cerca de las mujeres de los pueblos m\u00e1s vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escuchar a las legisladores mexicanas les motiva a trabajar juntas, \u201cbuscando los puntos que nos unen y no los que nos separan\u201d, expres\u00f3 Dor\u00eds Gutierrez.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es momento de construir un nuevo paradigma de gobierno femenino, que rompa con la pol\u00edtica que hace da\u00f1o a la sociedad y que ejerce un poder que discrimina, que domina, humilla, excluye y genera diferencias afirm\u00f3 la legisladora Ana Lilia Rivera Rivera, presidenta de la Mesa Directiva del Senado de la Rep\u00fablica.<\/p>\n","protected":false},"author":3,"featured_media":78046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[748],"tags":[],"class_list":["post-78045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-feminista"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/78045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=78045"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/78045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/78046"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=78045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=78045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=78045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}