{"id":77471,"date":"2024-02-19T14:49:16","date_gmt":"2024-02-19T20:49:16","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=77471"},"modified":"2024-02-19T14:49:17","modified_gmt":"2024-02-19T20:49:17","slug":"arzobispo-de-acapulco-no-podemos-quedar-en-silencio","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/arzobispo-de-acapulco-no-podemos-quedar-en-silencio\/","title":{"rendered":"Arzobispo de Acapulco \u201cno podemos quedar en silencio\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>N\u00e9stor Ortega Almeida Morales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Ceprovysa, Chilpancingo, Guerrero, 19 de febrero, 2024.- \u201cNo podemos quedar en silencio, porque como Obispos, estamos llamados a ser profetas y constructores de la justicia y de la paz, defensores del derecho a la vida, de la dignidad humana y de los d\u00e9biles\u201d se\u00f1al\u00f3 el Arzobispo de Acapulco, Monse\u00f1or Leopoldo Gonz\u00e1lez Gonz\u00e1lez al dar lectura a un comunicado que firman los Obispos de Guerrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Comunicado est\u00e1 firmado por los tres Obispos de Guerrero: Jos\u00e9 de Jes\u00fas Gonz\u00e1lez Hern\u00e1ndez, Di\u00f3cesis Chilpancingo \u2013 Chilapa; Joel Ocampo Gorostieta, Ciudad Altamirano; Dagoberto Sosa Arriaga, Tlapa; as\u00ed como por el propio Arzobispo, Leopoldo Gonz\u00e1lez Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el comunicado hacen un llamado \u201ca quienes han hecho del crimen un estilo de vida\u201d, y se\u00f1alan \u201cles pedimos que cesen en sus abusos en contra de las personas, familias, pueblos y ciudades\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dirigen tambi\u00e9n el mensaje a las familias a quienes les piden fomentar actitudes de paz y las convocan a evitar engrosar las filas de quienes promueven la cultura de la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reflexionan sobre el precepto de que \u201cnadie tiene derecho a matar, abusar sexualmente, robar, mentir, esclavizar, mucho menos convertirlo en un negocio o en un medio de intimidaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el papel que juegan en esta mediaci\u00f3n a favor de la paz, el Arzobispo Leopoldo Gonz\u00e1lez Gonz\u00e1lez resalta que el trabajo que realizan es \u201cimitando a Jesucristo, enviado de Dios para el bien de las y los humanos. Queremos ser voz de los que no tienen voz, de los oprimidos, perseguidos y humillados, para que sus derechos sean respetados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el comunicado el Prelado Cat\u00f3lico resalta \u201ctodos necesitamos un ambiente libre de intimidaci\u00f3n y violencia para conservar nuestra integridad f\u00edsica y psicol\u00f3gica\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obispos piden fomentar actitudes de paz y convocan a evitar engrosar las filas de quienes promueven la cultura de la muerte.<\/p>\n","protected":false},"author":3,"featured_media":77472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[751],"tags":[144,142],"class_list":["post-77471","post","type-post","status-publish","format-standard","has-post-thumbnail","category-crisis-de-violencia","tag-guerrero","tag-violencia"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=77471"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/77472"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=77471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=77471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=77471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}