{"id":77371,"date":"2024-02-16T12:55:21","date_gmt":"2024-02-16T18:55:21","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=77371"},"modified":"2024-02-16T12:55:22","modified_gmt":"2024-02-16T18:55:22","slug":"del-19-al-21-de-febrero-se-realizaran-actividades-culturales-por-el-dia-internacional-de-la-lengua-materna-en-juanacatlan-metlatonoc-sedepia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/del-19-al-21-de-febrero-se-realizaran-actividades-culturales-por-el-dia-internacional-de-la-lengua-materna-en-juanacatlan-metlatonoc-sedepia\/","title":{"rendered":"Del 19 al 21 de febrero se realizar\u00e1n actividades culturales por el \u201cD\u00eda Internacional de la Lengua Materna\u201d en Juanacatl\u00e1n, Metlatonoc: SEDEPIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Ceprovysa, Chilpancingo, Gro., 16 de febrero, 2024.- El Gobierno del Estado a trav\u00e9s de la Secretar\u00eda para el Desarrollo de los Pueblos Ind\u00edgenas y Afromexicano (SEDEPIA), realizar\u00e1 actividades culturales, conferencias, m\u00fasica y muestras gastron\u00f3micas del 19 al 21 de febrero por el \u201cD\u00eda Internacional de la Lengua Materna\u201d en Juanacatl\u00e1n, municipio de Metlatonoc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la SEDEPIA, dijo que estas acciones forman parte del Decenio Internacional de las Lenguas Ind\u00edgenas 2022-2032, decretado por la UNESCO, que tiene por objetivo sensibilizar sobre la situaci\u00f3n de las lenguas Ind\u00edgenas en todo el mundo para que adopten medidas inmediatas para salvaguardarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones se realizan en coordinaci\u00f3n con la Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena de la Secretar\u00eda de Educaci\u00f3n Guerrero y el Gobierno Federal, a trav\u00e9s de la Oficina de Representaci\u00f3n en Guerrero del Instituto Nacional de Pueblos Ind\u00edgenas (INPI), el Instituto Nacional de Lenguas Ind\u00edgenas (INALI), el ayuntamiento de Metlatonoc y el Comit\u00e9 del Fuego Ancestral de la Lengua Me\u2019phaa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades iniciar\u00e1n el d\u00eda 19 de febrero con la inauguraci\u00f3n y la presentaci\u00f3n de eventos socioculturales que se llevar\u00e1n a cabo en la cancha municipal. El d\u00eda 20 de febrero se exhibir\u00e1n muestras gastron\u00f3micas, presentaci\u00f3n de reconocidos personajes de la lengua Me\u2019phaa y 21 de febrero la Conferencia Lengua y Cultura en la Reforma Constitucional Ind\u00edgena y Afromexicana que ser\u00e1 impartida por el Director de Asuntos Internacionales del Instituto Nacional de los pueblos ind\u00edgenas (INPI), Marcos Mat\u00edas Alonso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este d\u00eda tambi\u00e9n se realizar\u00e1 la entrega del Fuego Ancestral al nuevo comit\u00e9 de la Localidad de Tierra Colorada, municipio de Malinaltepec quienes ser\u00e1n los encargados de realizar este mismo evento el pr\u00f3ximo a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estas acciones forman parte del Decenio Internacional de las Lenguas Ind\u00edgenas 2022-2032, decretado por la UNESCO.<\/p>\n","protected":false},"author":3,"featured_media":77372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[682],"tags":[144],"class_list":["post-77371","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-guerrero"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=77371"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/77371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/77372"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=77371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=77371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=77371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}